{"id":103976,"date":"2015-06-19T14:30:57","date_gmt":"2015-06-19T18:30:57","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?post_type=athletes&#038;p=103976"},"modified":"2024-07-30T16:12:05","modified_gmt":"2024-07-30T20:12:05","slug":"jessie-fleming","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jessie-fleming\/","title":{"rendered":"Jessie Fleming"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jessie Fleming a marqu\u00e9 plusieurs buts critiques \u00e0 Tokyo 2020 dans le parcours du Canada jusqu\u2019\u00e0 la m\u00e9daille d\u2019or. Elle a compt\u00e9 le premier but du Canada dans les tirs de p\u00e9nalit\u00e9 contre le Br\u00e9sil en quarts de finale. Elle a marqu\u00e9 en tirs de p\u00e9nalit\u00e9 \u00e0 la 74e minute de la demi-finale pour donner la victoire 1-0 au Canada contre les \u00c9tats-Unis. Elle a r\u00e9ussi un autre but en tir de p\u00e9nalit\u00e9 dans la 67e minute de match contre la Su\u00e8de pour \u00e9galiser le score du match de la m\u00e9daille d\u2019or. Elle a ensuite \u00e9t\u00e9 la premi\u00e8re \u00e0 atteindre le filet dans les tirs de p\u00e9nalit\u00e9 de cette finale. Fleming a jou\u00e9 \u00e0 temps complet dans cinq des six matchs du Canada du tournoi olympique et a totalis\u00e9 555 minutes de jeu, faisant d\u2019elle la deuxi\u00e8me joueuse avec le plus de minutes jou\u00e9es dans l\u2019\u00e9quipe..&nbsp;Elle a \u00e9t\u00e9 nomm\u00e9e Joueuse de l\u2019ann\u00e9e 2021 de Canada Soccer \u00e0 la suite de ses performances. Elle allait aussi \u00eatre proclam\u00e9e Joueuse de l\u2019ann\u00e9e en 2022 et 2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 ses d\u00e9buts olympiques aux Jeux de Rio 2016, Fleming a d\u00e9marr\u00e9 les six matchs du Canada, disputant les 90 minutes de quatre de ces rencontres, notamment dans le match pour la m\u00e9daille de bronze remport\u00e9 par le Canada contre le Br\u00e9sil.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fleming a particip\u00e9 aux \u00c9liminatoires\/Tournois de qualification olympique en 2016, 2020 et 2023, aidant alors le Canada \u00e0 assurer sa place \u00e0 Rio 2016, Tokyo 2020 et Paris 2024.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la suite de la retraite de Christine Sinclair en 2023, Fleming a \u00e9t\u00e9 nomm\u00e9e capitaine de l\u2019\u00e9quipe nationale f\u00e9minine \u00e0 l\u2019approche de la Gold Cup de la Concacaf 2024. Elle a \u00e9t\u00e9 choisie au sein du XI d\u2019\u00e9toiles du tournoi alors que le Canada a atteint les demi-finales. Elle avait d\u2019abord port\u00e9 le brassard de capitaine \u00e0 la Coupe Arnold Clark 2022. Fleming a particip\u00e9 \u00e0 trois \u00e9ditions de la Coupe du Monde F\u00e9minine de la FIFA \u2013 en 2015, 2019 et 2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Jessie Fleming avait 14 ans quand elle a int\u00e9gr\u00e9 le programme juv\u00e9nile canadien en 2012. Elle a alors remport\u00e9 une m\u00e9daille d\u2019argent au Championnat U-17 f\u00e9minin de la CONCACAF. \u00c0 15 ans, elle a fait ses d\u00e9buts dans l\u2019uniforme du Canada. Ceci faisait alors d\u2019elle la deuxi\u00e8me plus jeune joueuse \u00e0 se joindre \u00e0 l\u2019\u00e9quipe canadienne. En 2014, elle a repr\u00e9sent\u00e9 le Canada \u00e0 la Coupe du Monde F\u00e9minine U-17 de la FIFA et \u00e0 la Coupe du Monde F\u00e9minine U-20 de la FIFA&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2015, Jessie a aid\u00e9 le Canada \u00e0 remporter la m\u00e9daille d\u2019argent au tournoi de la Coupe de Chypre et a foul\u00e9 le terrain dans deux matchs de la Coupe du Monde F\u00e9minine de la FIFA disput\u00e9e en sol canadien. Aux Jeux panam\u00e9ricains de Toronto, elle ne s\u2019est pas retrouv\u00e9e sur le banc d\u2019\u00e9quipe une seule fois du tournoi o\u00f9 le Canada a pris le quatri\u00e8me rang. Dans la d\u00e9faite dans le match pour la m\u00e9daille de bronze, elle a marqu\u00e9 le seul but du Canada contre le Mexique sur un tir de p\u00e9nalit\u00e9. Toujours en 2015, elle a \u00e9t\u00e9 nomm\u00e9e Joueuse U-20 de l\u2019ann\u00e9e de Canada Soccer, la premi\u00e8re de trois conqu\u00eates cons\u00e9cutives de ce prix.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au Tournoi f\u00e9minin de qualification olympique de la CONCACAF de 2016, elle a marqu\u00e9 un but et contribu\u00e9 \u00e0 la deuxi\u00e8me place de l\u2019\u00e9quipe et \u00e0 l\u2019obtention d\u2019un laissez-passer olympique. Elle a ensuite aid\u00e9 l\u2019\u00e9quipe \u00e0 remporter la Coupe d\u2019Algarve de 2016.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fleming a \u00e9t\u00e9 une importante contributrice de la deuxi\u00e8me place du Canada au Championnat f\u00e9minin de la CONCACAF, qualifiant l\u2019\u00e9quipe pour la Coupe du Monde F\u00e9minine de la FIFA, France 2019. Elle a jou\u00e9 toutes les minutes de son \u00e9quipe \u00e0 ses quatre matchs au Mondial. Au d\u00e9but de 2020, elle a aid\u00e9 le Canada \u00e0 prendre le deuxi\u00e8me rang au Tournoi f\u00e9minin de qualification olympique de la CONCACAF, d\u00e9crochant un billet pour les Jeux de Tokyo 2020. Elle a particip\u00e9 \u00e0 une autre deuxi\u00e8me place du Canada au Championnat de la Concacaf en 2022.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fleming s\u2019est align\u00e9e avec le Canada au tournoi de la Coupe SheBelieves en 2021, 2023 et 2024; l\u2019\u00e9quipe a fini deuxi\u00e8me dans ce dernier cas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fleming a jou\u00e9 dans les rangs universitaires pour UCLA, o\u00f9 elle a \u00e9t\u00e9 deux fois finaliste pour le Troph\u00e9e Hermann remis \u00e0 la joueuse par excellence dans la NCAA. En 2016, elle a \u00e9t\u00e9 proclam\u00e9e Recrue de l\u2019ann\u00e9e Top Drawer et, l\u2019ann\u00e9e suivante en 2017, elle a men\u00e9 les Bruins jusqu\u2019en finale du tournoi national de la NCAA. Elle a \u00e9t\u00e9 choisie trois fois au sein de l\u2019\u00e9quipe d\u2019\u00e9toiles national am\u00e9ricaine et quatre fois dans la premi\u00e8re \u00e9quipe d\u2019\u00e9toiles de l\u2019Association PAC 12.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fleming est devenue joueuse professionnelle en 2020 avec le club anglais Chelsea. Elle a remport\u00e9 trois titres d\u2019affil\u00e9e de la Super League f\u00e9minine anglaise et de la Coupe d\u2019Angleterre de 2021 \u00e0 2023. En 2021, elle a aussi aid\u00e9 les Blues \u00e0 remporter la Super Coupe ainsi que le troph\u00e9e du Community Shield d\u2019Angleterre en plus d\u2019atteindre la finale de la Ligue des Championnes. Elle est revenue en Am\u00e9rique du Nord en 2024, rejoignant alors les rangs des Thorns de Portland.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0 propos de Jessie<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9buts :&nbsp;<\/strong>Elle a commenc\u00e9 \u00e0 jouer au soccer \u00e0 l\u2019\u00e2ge de trois&nbsp;ans\u2026 Elle a grandi en pratiquant le soccer, le hockey, l\u2019athl\u00e9tisme et le cross-country\u2026&nbsp;<strong>De tout et de rien :&nbsp;<\/strong>Ses dictons favoris sont : \u00ab&nbsp;Joue chaque match comme si c\u2019\u00e9tait ton dernier.&nbsp;\u00bb \/ \u00ab&nbsp;Sors de ta zone de confort, c\u2019est l\u00e0 que se produit la magie.&nbsp;\u00bb\u2026 Elle enfile toujours le c\u00f4t\u00e9 droit de son \u00e9quipement avant le gauche\u2026 On la surnomme \u00ab&nbsp;<em>Jess<\/em>&nbsp;\u00bb ou \u00ab&nbsp;<em>JFlem&nbsp;<\/em>\u00bb\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jessie Fleming avait 14\u00a0ans quand elle a int\u00e9gr\u00e9 le programme juv\u00e9nile canadien en 2012. Elle a alors remport\u00e9 une m\u00e9daille d\u2019argent au Championnat U-17 f\u00e9minin de la Concacaf. \u00c0 15\u00a0ans, elle a fait ses d\u00e9buts dans l\u2019uniforme du Canada. Ceci fait d\u2019elle la deuxi\u00e8me plus jeune joueuse \u00e0 se joindre \u00e0 l\u2019\u00e9quipe canadienne.<\/p>\n","protected":false},"featured_media":247694,"template":"","tags":[535718,1104411,1134,68909591,415985124,713425,1693,57868344,20292794],"hof-categories":[],"year-inducted":[],"gender":[23319],"season":[415983968],"sport":[8591],"game":[415985140,415984561,193413370,334881982],"team":[682166688,415983100,682163198,374096552],"event":[181822490],"province":[415983158],"class_list":["post-103976","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-concacaf","tag-equipe-canada","tag-football","tag-jessie-fleming","tag-paris-2024","tag-rio-2016","tag-soccer","tag-tokyo-2020","tag-toronto-2015","gender-feminin","season-ete","sport-football","game-paris-2024","game-2016-rio","game-tokyo-2020","game-2015-toronto","team-paris-2024-soccer-femmes","team-rio-2016-footballsoccer-femmes","team-tokyo-2020-soccer","team-toronto-2015-footballsoccer-femmes","event-equipes-femmes","province-ontario"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/MDB_20210806_5875-e1719494106775.jpg?quality=100","category_names":[],"tag_names":["CONCACAF","\u00c9quipe canada","football","Jessie Fleming","Paris 2024","Rio 2016","Soccer","Tokyo 2020","Toronto 2015"],"sport_names":[439],"game_names":["Paris 2024","Rio 2016","Tokyo 2020","Toronto 2015"],"season_names":["\u00c9t\u00e9"],"team_names":["Paris 2024 Soccer (Femmes)","Rio 2016 Football Femmes","Tokyo 2020 Soccer","Toronto 2015 - Football Femmes"],"province_names":["Ontario"],"social_facebook":"","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":" _jessflem","social_website":"","total_medal_count_gold":"1","total_medal_count_silver":"","total_medal_count_bronze":"1","athlete_headshot":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/Jessie-Fleming-1-e1624389818722.jpg?quality=100","athlete_height":"164","athlete_weight":"","athlete_hometown":"London, Ontario","athlete_birthplace":"London, Ontario","coc_gracenote_id":"","athlete_dob":"August 20, 1970","athlete_age":56,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/103976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":7,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/103976\/revisions"}],"predecessor-version":[{"id":251829,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/103976\/revisions\/251829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/247694"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=103976"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=103976"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=103976"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=103976"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=103976"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=103976"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=103976"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=103976"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=103976"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=103976"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=103976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}