{"id":104151,"date":"2015-06-21T17:21:18","date_gmt":"2015-06-21T21:21:18","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?post_type=athletes&#038;p=104151"},"modified":"2015-07-01T14:35:59","modified_gmt":"2015-07-01T18:35:59","slug":"jacob-koudys","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jacob-koudys\/","title":{"rendered":"Jacob Koudys"},"content":{"rendered":"<p><a href=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/06\/jacob-koudys.jpg?quality=100\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-104152 alignleft\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/06\/jacob-koudys.jpg?quality=100&amp;w=371\" alt=\"Jacob Koudys\" width=\"179\" height=\"179\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jacob-koudys.jpg 1044w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jacob-koudys.jpg?resize=158,158 158w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jacob-koudys.jpg?resize=371,371 371w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jacob-koudys.jpg?resize=768,768 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/jacob-koudys.jpg?resize=754,754 754w\" sizes=\"(max-width: 179px) 100vw, 179px\" \/><\/a><\/p>\n<p>Jacob Koudys est le barreur du huit de pointe qui a particip\u00e9 \u00e0 deux reprises aux Championnats du monde des moins de 23\u00a0ans et y a remport\u00e9 la m\u00e9daille d\u2019or \u00e0 l\u2019\u00e9preuve de quatre de pointe avec barreur en 2014. Cette ann\u00e9e-l\u00e0, il a \u00e9galement particip\u00e9 aux Championnats universitaires mondiaux o\u00f9 il a gagn\u00e9 la m\u00e9daille de bronze \u00e0 l\u2019\u00e9preuve de huit de pointe. Lorsqu\u2019il repr\u00e9sentait l\u2019Universit\u00e9 de Victoria, il a gagn\u00e9 la m\u00e9daille d\u2019or \u00e0 l\u2019\u00e9preuve de huit de pointe avec barreur et la m\u00e9daille de bronze au quatre de pointe poids l\u00e9ger aux Championnats universitaires canadiens d\u2019aviron. En 2012, il a remport\u00e9 la m\u00e9daille d\u2019or avec l\u2019\u00e9quipe de l\u2019Universit\u00e9 Queen\u2019s au quatre de pointe poids l\u00e9ger.<\/p>\n<h2><strong>\u00c0 PROPOS DE L\u2019ATHL\u00c8TE<\/strong><\/h2>\n<p><strong>Famille\u00a0: <\/strong>Ses parents se nomment Dave et Joanne. Sa s\u0153ur cadette s\u2019appelle Jessica. <strong>D\u00e9buts\u00a0:<\/strong> Il a commenc\u00e9 \u00e0 faire de l\u2019aviron \u00e0 l\u2019\u00e2ge de 14\u00a0ans. Il ne se souvient plus d\u2019avoir appris \u00e0 ramer, car il est toujours barreur. Au d\u00e9but, il n\u2019\u00e9tait pas trop s\u00fbr de ce qu\u2019il devait faire, et il a adopt\u00e9 l\u2019attitude de \u00ab\u00a0Faire semblant jusqu\u2019\u00e0 ce qu\u2019il ma\u00eetrise sa position\u00a0\u00bb. <strong>Autres int\u00e9r\u00eats\u00a0:<\/strong> Il fait pr\u00e9sentement son baccalaur\u00e9at en sciences avec sp\u00e9cialit\u00e9 en psychologie \u00e0 l\u2019Universit\u00e9 de Victoria. Il aime faire de la randonn\u00e9e en montagne, de l\u2019escalade et du camping, et il aime courir, penser et lire. <strong>De tout et de rien\u00a0:<\/strong> Sa citation pr\u00e9f\u00e9r\u00e9e\u00a0: \u00ab\u00a0L\u2019individu a toujours d\u00fb lutter pour ne pas \u00eatre submerg\u00e9 par la tribu. Si vous essayez, vous serez souvent seul, et parfois vous aurez peur. Mais aucun prix \u00e0 payer n\u2019est trop \u00e9lev\u00e9 pour avoir le privil\u00e8ge de se poss\u00e9der.\u00a0\u00bb \u2013 Nietzche.<\/p>\n<h2><strong>PALMAR\u00c8S INTERNATIONAL<\/strong><\/h2>\n<p>ChM FISA (M23)\u00a0: <strong>2014<\/strong> \u2013 OR (M4+); <strong>2013<\/strong> \u2013 5<sup>e<\/sup> (M4+)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jacob Koudys est le barreur du huit de pointe qui a particip\u00e9 \u00e0 deux reprises aux Championnats du monde des&#8230;<\/p>\n","protected":false},"featured_media":88525,"template":"","tags":[],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[],"sport":[392824],"game":[334881982],"team":[415982969],"event":[181822689],"province":[],"class_list":["post-104151","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","gender-masculin","sport-aviron","game-2015-toronto","team-toronto-2015-aviron","event-huit-en-pointe-avec-barreur-hommes"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/coc_men_feature_placeholder_1340x754.png","category_names":[],"tag_names":[],"sport_names":[515],"game_names":["Toronto 2015"],"season_names":[],"team_names":["Toronto 2015 Aviron"],"province_names":[],"social_facebook":"","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":"","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"","athlete_height":"172","athlete_weight":"53","athlete_hometown":"Fonthill (Ont.)","athlete_birthplace":"Fenwick (Ont.)","coc_gracenote_id":"","athlete_dob":"September 7, 1993","athlete_age":32,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/104151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":0,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/104151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/88525"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=104151"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=104151"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=104151"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=104151"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=104151"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=104151"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=104151"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=104151"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=104151"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=104151"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=104151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}