{"id":104175,"date":"2015-06-21T20:39:28","date_gmt":"2015-06-22T00:39:28","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?post_type=athletes&#038;p=104175"},"modified":"2015-07-01T13:57:58","modified_gmt":"2015-07-01T17:57:58","slug":"rosanne-deboef","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/rosanne-deboef\/","title":{"rendered":"Rosanne DeBoef"},"content":{"rendered":"<p><a href=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/06\/rosie-deboef.jpg?quality=100\"><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-104176 alignleft\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/06\/rosie-deboef.jpg?quality=100&amp;w=278\" alt=\"Rosie DeBoef\" width=\"196\" height=\"262\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/rosie-deboef.jpg 1500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/rosie-deboef.jpg?resize=118,158 118w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/rosie-deboef.jpg?resize=278,371 278w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/rosie-deboef.jpg?resize=768,1025 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/rosie-deboef.jpg?resize=565,754 565w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/rosie-deboef.jpg?resize=1151,1536 1151w\" sizes=\"(max-width: 196px) 100vw, 196px\" \/><\/a><\/p>\n<p>Rosanne DeBoef a connu une ann\u00e9e spectaculaire comme membre de l\u2019\u00e9quipe canadienne en 2014, saison o\u00f9 elle a fait partie de la tr\u00e8s redoutable \u00e9quipe de huit gagnante d\u2019une m\u00e9daille d\u2019or \u00e0 la Coupe du monde \u00e0 Lucerne et de m\u00e9dailles d\u2019argent \u00e0 la Coupe du monde \u00e0 Aiguebelette, en France, de m\u00eame que des Championnats du monde \u00e0 Amsterdam. Rosanne avait pr\u00e9c\u00e9demment repr\u00e9sent\u00e9 le Canada \u00e0 l\u2019occasion des Championnats du monde juniors et de deux Championnats du monde M23. Elle a fait de la comp\u00e9tition au niveau coll\u00e9gial \u00e0 l\u2019universit\u00e9 de Washington, o\u00f9 elle a remport\u00e9 une m\u00e9daille de bronze comme membre de l\u2019\u00e9quipe universitaire junior de huit en 2008. En 2007, lorsque Rosanne \u00e9tait \u00e9tudiante de premi\u00e8re ann\u00e9e, elle a remport\u00e9 le Championnat universitaire PAC-10 \u00e0 l\u2019\u00e9preuve de quatre de pointe, en plus de terminer en 5<sup>e<\/sup> place aux Championnats nationaux comme membre d\u2019un quatre de pointe compos\u00e9 exclusivement d\u2019\u00e9tudiantes de premi\u00e8re ann\u00e9e. En 2011, DeBoef a franchi un jalon dans sa carri\u00e8re apr\u00e8s avoir remport\u00e9 l\u2019\u00e9preuve de skiff \u00e0 la R\u00e9gate Royal Canadian Henley.<\/p>\n<h2><strong>\u00c0 PROPOS DE L\u2019ATHL\u00c8TE<\/strong><\/h2>\n<p><strong>Famille\u00a0: <\/strong>Ses parents se nomment Case et Corry DeBoef. Elle a un fr\u00e8re a\u00een\u00e9, Kevin, et deux s\u0153urs a\u00een\u00e9es, Christine et Naomi. <strong>D\u00e9buts\u00a0:<\/strong> Elle s\u2019est initi\u00e9e \u00e0 l\u2019aviron \u00e0 l\u2019\u00e2ge de 12 ans, car elle et son p\u00e8re voulaient essayer une activit\u00e9 nouvelle. Elle a particip\u00e9 \u00e0 sa premi\u00e8re comp\u00e9tition \u00e0 l\u2019occasion de la R\u00e9gate Royal Canadian Henley de 2005, o\u00f9 elle s\u2019est rendue en finale A de l\u2019\u00e9preuve de skiff par club. <strong>Autres int\u00e9r\u00eats\u00a0:<\/strong> Elle a obtenu son baccalaur\u00e9at en psychologie de l\u2019universit\u00e9 de Washington. Elle voudrait s\u2019inspirer des aptitudes \u00e0 la vie quotidienne apprises gr\u00e2ce au sport et au mentorat aupr\u00e8s de jeunes athl\u00e8tes afin de faire carri\u00e8re comme enseignante d\u2019\u00e9ducation physique et entra\u00eeneure d\u2019\u00e9cole interm\u00e9diaire ou secondaire. Elle aime faire du cyclisme sur route et de la lecture. Elle fait du b\u00e9n\u00e9volat aupr\u00e8s des Jeux olympiques sp\u00e9ciaux comme entra\u00eeneure de basketball et de tee-ball. Elle a \u00e9t\u00e9 joueuse et capitaine au sein de l\u2019\u00e9quipe de basketball \u00e0 l\u2019\u00e9cole secondaire. <strong>De tout et de rien\u00a0: <\/strong>Sa devise\u00a0: \u00ab\u00a0Je suis capable de tout faire gr\u00e2ce au Christ, qui me sert de source de force.\u00a0\u00bb \u2013 Philippiens 4:13. Son souvenir olympique favori a \u00e9t\u00e9 la victoire par ralliement de l\u2019\u00e9quipe de hockey f\u00e9minin \u00e0 Sotchi 2014. On la surnomme Rosie. Elle ne part jamais en voyage sans sa bible.<\/p>\n<h2><strong>PALMAR\u00c8S INTERNATIONAL<\/strong><\/h2>\n<p>ChM FISA\u00a0: <strong>2014<\/strong> \u2013 ARGENT (W8+)<\/p>\n<p>ChM FISA (M23)\u00a0: <strong>2010<\/strong> \u2013 6<sup>e<\/sup> (W8+); <strong>2009<\/strong> \u2013 4<sup>e<\/sup> (W8+)<\/p>\n<p>ChM FISA (juniors)\u00a0: <strong>2006<\/strong> \u2013 4<sup>e<\/sup> (W2-)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rosanne DeBoef a connu une ann\u00e9e spectaculaire comme membre de l\u2019\u00e9quipe canadienne en 2014, saison o\u00f9 elle a fait partie&#8230;<\/p>\n","protected":false},"featured_media":88525,"template":"","tags":[],"hof-categories":[],"year-inducted":[],"gender":[23319],"season":[],"sport":[392824],"game":[334881982],"team":[415982969],"event":[],"province":[],"class_list":["post-104175","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","gender-feminin","sport-aviron","game-2015-toronto","team-toronto-2015-aviron"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/coc_men_feature_placeholder_1340x754.png","category_names":[],"tag_names":[],"sport_names":[515],"game_names":["Toronto 2015"],"season_names":[],"team_names":["Toronto 2015 Aviron"],"province_names":[],"social_facebook":"","social_twitter":"RosieDeBoef","social_linkedin":"","social_gplus":"","social_instagram":"","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"","athlete_height":"177","athlete_weight":"80","athlete_hometown":"Victoria (C.-B.)","athlete_birthplace":"Victoria (C.-B.)","coc_gracenote_id":"","athlete_dob":"February 2, 1988","athlete_age":38,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/104175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":0,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/104175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/88525"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=104175"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=104175"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=104175"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=104175"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=104175"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=104175"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=104175"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=104175"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=104175"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=104175"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=104175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}