{"id":104545,"date":"2015-06-24T22:10:50","date_gmt":"2015-06-25T02:10:50","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?post_type=athletes&#038;p=104545"},"modified":"2015-08-10T14:09:35","modified_gmt":"2015-08-10T18:09:35","slug":"paul-wharton","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/","title":{"rendered":"Paul Wharton"},"content":{"rendered":"<p><a href=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/06\/paul-wharton.jpg?quality=100\"><img loading=\"lazy\" decoding=\"async\" class=\"  alignleft wp-image-104546 size-thumbnail\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/06\/paul-wharton.jpg?quality=100&amp;w=158\" alt=\"Paul-Wharton\" width=\"158\" height=\"158\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/paul-wharton.jpg 600w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/paul-wharton.jpg?resize=158,158 158w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/06\/paul-wharton.jpg?resize=371,371 371w\" sizes=\"(max-width: 158px) 100vw, 158px\" \/><\/a><\/p>\n<p>Paul Wharton a particip\u00e9 \u00e0 plus de 45 matchs au niveau international senior depuis ses d\u00e9buts en 2012. Il a remport\u00e9 la m\u00e9daille d\u2019argent avec le Canada aux Championnats panam\u00e9ricains juniors de 2012 et il a ensuite concouru \u00e0 la Coupe du monde junior de la FIH de 2013. En 2014, il a aid\u00e9 le Canada \u00e0 se classer en 2<sup>e<\/sup>\u00a0place au D\u00e9fi des champions 1, en Malaisie. Il a fait ses d\u00e9buts en comp\u00e9tition internationale multisport aux Jeux du Commonwealth \u00e0 Glasgow. Paul est devenu membre de l\u2019\u00e9quipe canadienne pour la Ligue mondiale de la FIH de 2015.<\/p>\n<h2><strong>\u00c0 PROPOS DE L\u2019ATHL\u00c8TE<\/strong><\/h2>\n<p><strong>Famille\u00a0: <\/strong>Ses parents se nomment Cheryl Wharton et Steacy Alexander. <strong>D\u00e9buts\u00a0:<\/strong> Il s\u2019est joint \u00e0 la ligue de printemps junior de Vancouver \u00e0 l\u2019\u00e2ge de 9\u00a0ans apr\u00e8s que sa m\u00e8re y a inscrit son fr\u00e8re, lui-m\u00eame et quelques-uns de ses amis. <strong>Autres int\u00e9r\u00eats\u00a0: <\/strong>Il a \u00e9tudi\u00e9 l\u2019\u00e9conomie et le commerce \u00e0 l\u2019Universit\u00e9 de la Colombie-Britannique. <strong>De tout et de rien\u00a0:<\/strong> Sa citation pr\u00e9f\u00e9r\u00e9e\u00a0: \u00ab\u00a0Notre peur la plus profonde n\u2019est pas d\u2019\u00eatre inad\u00e9quat. Notre peur est d\u2019\u00eatre puissant au-del\u00e0 de toute limite.\u00a0\u00bb On le surnomme Pauly.<\/p>\n<h2><strong>PALMAR\u00c8S INTERNATIONAL<\/strong><\/h2>\n<p>JCW\u00a0: <strong>2014<\/strong> \u2013 6<sup>e<\/sup><\/p>\n<p>CdM FIH (junior)\u00a0: <strong>2013<\/strong> \u2013 16<sup>e<\/sup><\/p>\n<p>CPA (juniors)\u00a0: <strong>2012<\/strong> &#8211; ARGENT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paul Wharton a particip\u00e9 \u00e0 plus de 45 matchs au niveau international senior depuis ses d\u00e9buts en 2012. Il a&#8230;<\/p>\n","protected":false},"featured_media":88525,"template":"","tags":[1840985],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[],"sport":[374048809],"game":[334881982],"team":[383427392],"event":[46639],"province":[],"class_list":["post-104545","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-paul-wharton","gender-masculin","sport-hockey-sur-gazon","game-2015-toronto","team-toronto-2015-hockey-sur-gazon-hommes","event-hommes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paul Wharton - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paul Wharton - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Paul Wharton a particip\u00e9 \u00e0 plus de 45 matchs au niveau international senior depuis ses d\u00e9buts en 2012. Il a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2015-08-10T18:09:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/coc_men_feature_placeholder_1340x754.png\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"joshsu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/paul-wharton\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/paul-wharton\\\/\",\"name\":\"Paul Wharton - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/paul-wharton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/paul-wharton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/coc_men_feature_placeholder_1340x754.png\",\"datePublished\":\"2015-06-25T02:10:50+00:00\",\"dateModified\":\"2015-08-10T18:09:35+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/paul-wharton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/paul-wharton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/coc_men_feature_placeholder_1340x754.png\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2013\\\/12\\\/coc_men_feature_placeholder_1340x754.png\",\"width\":670,\"height\":377},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paul Wharton - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/","og_locale":"fr_FR","og_type":"article","og_title":"Paul Wharton - \u00c9quipe Canada","og_description":"Paul Wharton a particip\u00e9 \u00e0 plus de 45 matchs au niveau international senior depuis ses d\u00e9buts en 2012. Il a...","og_url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/","og_site_name":"\u00c9quipe Canada","article_modified_time":"2015-08-10T18:09:35+00:00","og_image":[{"width":670,"height":377,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/coc_men_feature_placeholder_1340x754.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"joshsu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/","url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/","name":"Paul Wharton - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/coc_men_feature_placeholder_1340x754.png","datePublished":"2015-06-25T02:10:50+00:00","dateModified":"2015-08-10T18:09:35+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/paul-wharton\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/coc_men_feature_placeholder_1340x754.png","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/coc_men_feature_placeholder_1340x754.png","width":670,"height":377},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/12\/coc_men_feature_placeholder_1340x754.png","category_names":[],"tag_names":["Paul Wharton"],"sport_names":[434],"game_names":["Toronto 2015"],"season_names":[],"team_names":["Toronto 2015 - Hockey sur gazon (hommes)"],"province_names":[],"social_facebook":"","social_twitter":"WhartonP","social_linkedin":"","social_gplus":"","social_instagram":"","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"","athlete_height":"196","athlete_weight":"86","athlete_hometown":"Vancouver (C.-B.)","athlete_birthplace":"Vancouver (C.-B.)","coc_gracenote_id":"","athlete_dob":"November 27, 1993","athlete_age":32,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/104545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":0,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/104545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/88525"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=104545"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=104545"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=104545"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=104545"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=104545"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=104545"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=104545"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=104545"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=104545"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=104545"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=104545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}