{"id":152114,"date":"2021-07-17T14:00:00","date_gmt":"2021-07-17T18:00:00","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?post_type=athletes&#038;p=152114"},"modified":"2026-06-08T11:18:27","modified_gmt":"2026-06-08T15:18:27","slug":"oliver-scholfield","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/","title":{"rendered":"Oliver Scholfield"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Oliver Scholfield s\u2019est d\u2019abord joint au programme canadien de hockey sur gazon comme membre de l\u2019\u00e9quipe des moins de 21 ans en 2012. Apr\u00e8s une douzaine de matchs, notamment \u00e0 la Coupe du monde junior en 2013, il a rejoint l\u2019\u00e9quipe nationale senior en 2014. Il a depuis accumul\u00e9 plus de 75 matchs internationaux, en participant notamment \u00e0 la Coupe panam\u00e9ricaine de 2017 et \u00e0 la Coupe du monde de la FIH en 2018.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">En 2019, Scholfield a marqu\u00e9 trois buts \u00e0 la Finale de la S\u00e9rie de la FIH, aidant le Canada \u00e0 remporter l\u2019or sur la Malaisie, pays h\u00f4te, ouvrant la porte \u00e0 une qualification pour les Jeux de Tokyo 2020. Dans le tournoi de qualification olympique contre l\u2019Irlande, il a marqu\u00e9 un but crucial dans le deuxi\u00e8me match, qui a contribu\u00e9 \u00e0 provoquer une s\u00e9ance de tir pour rompre l\u2019\u00e9galit\u00e9. Le Canada a eu le dessus et a empoch\u00e9 son billet, se qualifiant pour ses deuxi\u00e8mes Jeux olympiques cons\u00e9cutifs. Plus t\u00f4t en 2019, il a particip\u00e9 aux Jeux panam\u00e9ricains \u00e0 Lima o\u00f9 il a pris le troisi\u00e8me rang des marqueurs l\u2019\u00e9quipe avec cinq buts, marqu\u00e9 par un tour du chapeau contre les h\u00f4tes p\u00e9ruviens, conduisant le Canada \u00e0 une m\u00e9daille d\u2019argent.\u00a0<\/span><\/p>\n<h4><b>\u00c0 propos d\u2019Oliver<\/b><\/h4>\n<p><b>D\u00e9buts : <\/b><span style=\"font-weight: 400\">A commenc\u00e9 \u00e0 pratiquer le hockey sur gazon \u00e0 l\u2019\u00e2ge de neuf ans dans le cadre de son cours d\u2019\u00e9ducation physique \u00e0 l\u2019\u00e9cole\u2026<\/span> <span style=\"font-weight: 400\">Il est presque devenu membre d\u2019une \u00e9quipe anglaise des moins de 16 ans avant de d\u00e9m\u00e9nager au Canada quelques ann\u00e9es plus tard\u2026 <\/span><b>Autres int\u00e9r\u00eats : <\/b><span style=\"font-weight: 400\">A compl\u00e9t\u00e9 une ma\u00eetrise en gestion des affaires \u00e0\u00a0UBC\u00a0en 2017\u2026\u00a0<\/span><span style=\"font-weight: 400\">Il aime faire des randonn\u00e9es, courir, marcher avec son chien, faire du <\/span><span style=\"font-weight: 400\">ski et du surf dans ses temps libres\u2026\u00a0<\/span><span style=\"font-weight: 400\"> Ambassadeur pour l\u2019organisme Sport Jeunesse de la Colombie-Britannique\u2026 <\/span><b>De tout et de rien : <\/b><span style=\"font-weight: 400\">N\u00e9 au Canada, mais il a <\/span><span style=\"font-weight: 400\">grandi au Royaume-Uni avant de revenir s\u2019installer au Canada afin d\u2019y poursuivre ses \u00e9tudes universitaires en\u00a02011\u2026 Collectionne la monnaie \u00e9trang\u00e8re des pays qu\u2019il visite \u00e0 l\u2019occasion de ses comp\u00e9titions\u2026<\/span><span style=\"font-weight: 400\"> Inspir\u00e9 par l\u2019\u00e9toile du soccer Thierry Henry qu\u2019il a vu jouer \u00e0 Arsenal quand il \u00e9tait enfant\u2026 Son dicton favori : \u201cSoit toujours le travailleur le plus acharn\u00e9 sur le terrain\u00a0\u00bb\u2026\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oliver Scholfield s\u2019est d\u2019abord joint au programme canadien de hockey sur gazon comme membre de l\u2019\u00e9quipe des moins de 21 ans en 2012. Apr\u00e8s une douzaine de matchs, notamment \u00e0 la Coupe du monde junior en 2013, il a rejoint l\u2019\u00e9quipe nationale senior en 2014. Il a depuis accumul\u00e9 plus de 70 matchs internationaux, notamment avec une Coupe panam\u00e9ricaine de 2017 et participant \u00e0 la Coupe du monde de la FIH en 2018.\u00a0<\/p>\n","protected":false},"featured_media":232878,"template":"","tags":[415984499,1104411,5565829,415987822,415988806,682165310,57868344],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[415983968],"sport":[374048809],"game":[415988487,682165315,193413370],"team":[415988497,682166133,682163203],"event":[],"province":[415983158],"class_list":["post-152114","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-commission-des-athletes","tag-equipe-canada","tag-hockey-sur-gazon","tag-lima-2019","tag-oliver-scholfield","tag-santiago-2023","tag-tokyo-2020","gender-masculin","season-ete","sport-hockey-sur-gazon","game-lima-2019","game-santiago-2023","game-tokyo-2020","team-lima-2019-hockey-sur-gazon-hommes","team-santiago-2023-hockey-sur-gazon-hommes","team-tokyo-2020-hockey-sur-gazon","province-ontario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oliver Scholfield - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"Une biographie de l&#039;athl\u00e8te de hockey sur gazon Oliver Scholfield.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oliver Scholfield - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Une biographie de l&#039;athl\u00e8te de hockey sur gazon Oliver Scholfield.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T15:18:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2019\/06\/DC_20231103_7699-e1699467998478.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1196\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Ellen McCann\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/oliver-scholfield\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/oliver-scholfield\\\/\",\"name\":\"Oliver Scholfield - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/oliver-scholfield\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/oliver-scholfield\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/DC_20231103_7699-e1699467998478.jpg?quality=100\",\"datePublished\":\"2021-07-17T18:00:00+00:00\",\"dateModified\":\"2026-06-08T15:18:27+00:00\",\"description\":\"Une biographie de l'athl\u00e8te de hockey sur gazon Oliver Scholfield.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/oliver-scholfield\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/oliver-scholfield\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/DC_20231103_7699-e1699467998478.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/DC_20231103_7699-e1699467998478.jpg?quality=100\",\"width\":1196,\"height\":674,\"caption\":\"Oliver Scholdfield #8 of Canada competes against the United States in the Men\u0092s Field Hockey Bronze Medal Finals during the Santiago 2023 Pan American Games on Friday, November 03, 2023. Photo by Darren Calabrese\\\/COC\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oliver Scholfield - \u00c9quipe Canada","description":"Une biographie de l'athl\u00e8te de hockey sur gazon Oliver Scholfield.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/","og_locale":"fr_FR","og_type":"article","og_title":"Oliver Scholfield - \u00c9quipe Canada","og_description":"Une biographie de l'athl\u00e8te de hockey sur gazon Oliver Scholfield.","og_url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/","og_site_name":"\u00c9quipe Canada","article_modified_time":"2026-06-08T15:18:27+00:00","og_image":[{"width":1196,"height":674,"url":"https:\/\/olympique.ca\/wp-content\/uploads\/sites\/2\/2019\/06\/DC_20231103_7699-e1699467998478.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes","Written by":"Ellen McCann"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/","url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/","name":"Oliver Scholfield - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/DC_20231103_7699-e1699467998478.jpg?quality=100","datePublished":"2021-07-17T18:00:00+00:00","dateModified":"2026-06-08T15:18:27+00:00","description":"Une biographie de l'athl\u00e8te de hockey sur gazon Oliver Scholfield.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/oliver-scholfield\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/DC_20231103_7699-e1699467998478.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/DC_20231103_7699-e1699467998478.jpg?quality=100","width":1196,"height":674,"caption":"Oliver Scholdfield #8 of Canada competes against the United States in the Men\u0092s Field Hockey Bronze Medal Finals during the Santiago 2023 Pan American Games on Friday, November 03, 2023. Photo by Darren Calabrese\/COC"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/DC_20231103_7699-e1699467998478.jpg?quality=100","category_names":[],"tag_names":["Commission des athletes","\u00c9quipe canada","hockey sur gazon","Lima 2019","Oliver Scholfield","Santiago 2023","Tokyo 2020"],"sport_names":[434],"game_names":["Lima 2019","Santiago 2023","Tokyo 2020"],"season_names":["\u00c9t\u00e9"],"team_names":["Lima 2019 Hockey sur gazon (hommes)","Santiago 2023 Hockey sur gazon (hommes)","Tokyo 2020 Hockey sur gazon"],"province_names":["Ontario"],"social_facebook":"","social_twitter":"oscholfield","social_linkedin":"","social_gplus":"","social_instagram":"oscholfield","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/Scholfield_Oliver.jpg?quality=100","athlete_height":"180","athlete_weight":"","athlete_hometown":"Scarborough, Ontario ","athlete_birthplace":"Scarborough, Ontario ","coc_gracenote_id":"","athlete_dob":"August 19, 1970","athlete_age":55,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/152114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":4,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/152114\/revisions"}],"predecessor-version":[{"id":255799,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/152114\/revisions\/255799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/232878"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=152114"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=152114"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=152114"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=152114"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=152114"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=152114"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=152114"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=152114"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=152114"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=152114"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=152114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}