{"id":19720,"date":"2011-09-18T22:26:50","date_gmt":"2011-09-19T02:26:50","guid":{"rendered":"http:\/\/develop.olympic.ca\/team-canada\/charlene-wong-2\/"},"modified":"2019-01-16T13:31:55","modified_gmt":"2019-01-16T18:31:55","slug":"charlene-wong","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/","title":{"rendered":"Charlene Wong"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":85861,"template":"","tags":[],"hof-categories":[],"year-inducted":[],"gender":[23319],"season":[415983969],"sport":[2636692],"game":[9300276],"team":[415983725],"event":[181823523],"province":[],"class_list":["post-19720","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","gender-feminin","season-hiver","sport-patinage-artistique","game-1988-calgary","team-calgary-1988-patinage-artistique","event-simple-femmes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Charlene Wong - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charlene Wong - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-16T18:31:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/09\/charlene-wong_1340px.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"1654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cdnolympicteam\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/charlene-wong\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/charlene-wong\\\/\",\"name\":\"Charlene Wong - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/charlene-wong\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/charlene-wong\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2011\\\/09\\\/charlene-wong_1340px.jpg?quality=100\",\"datePublished\":\"2011-09-19T02:26:50+00:00\",\"dateModified\":\"2019-01-16T18:31:55+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/charlene-wong\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/charlene-wong\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2011\\\/09\\\/charlene-wong_1340px.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2011\\\/09\\\/charlene-wong_1340px.jpg?quality=100\",\"width\":1340,\"height\":1654},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Charlene Wong - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/","og_locale":"fr_FR","og_type":"article","og_title":"Charlene Wong - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2019-01-16T18:31:55+00:00","og_image":[{"width":1340,"height":1654,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/09\/charlene-wong_1340px.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"cdnolympicteam"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/","url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/","name":"Charlene Wong - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/09\/charlene-wong_1340px.jpg?quality=100","datePublished":"2011-09-19T02:26:50+00:00","dateModified":"2019-01-16T18:31:55+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/charlene-wong\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/09\/charlene-wong_1340px.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/09\/charlene-wong_1340px.jpg?quality=100","width":1340,"height":1654},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2011\/09\/charlene-wong_1340px.jpg?quality=100","category_names":[],"tag_names":[],"sport_names":[207],"game_names":["Calgary 1988"],"season_names":["Hiver"],"team_names":["Calgary 1988 Patinage Artistique"],"province_names":[],"social_facebook":"","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":"","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"","athlete_height":"","athlete_weight":"","athlete_hometown":"","athlete_birthplace":"Montr\u00e9al, Quebec","coc_gracenote_id":"","athlete_dob":"March 4, 1966","athlete_age":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/19720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":0,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/19720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/85861"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=19720"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=19720"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=19720"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=19720"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=19720"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=19720"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=19720"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=19720"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=19720"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=19720"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=19720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}