{"id":222689,"date":"2023-06-28T10:00:00","date_gmt":"2023-06-28T14:00:00","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?post_type=athletes&#038;p=222689"},"modified":"2024-08-28T14:45:28","modified_gmt":"2024-08-28T18:45:28","slug":"alex-baldoni","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/","title":{"rendered":"Alex Baldoni"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Alex Baldoni a acc\u00e9d\u00e9 au podium \u00e0 sa premi\u00e8re pr\u00e9sence aux Jeux panam\u00e9ricains, alors qu\u2019il a mis la main sur la m\u00e9daille d\u2019argent en kayak cross chez les hommes \u00e0 Santiago 2023. Il a aussi particip\u00e9 \u00e0 l\u2019\u00e9preuve masculine&nbsp;du C-1, finissant en cinqui\u00e8me place. Il a \u00e9t\u00e9 accompagn\u00e9 \u00e0 Santiago par sa s\u0153ur a\u00een\u00e9e L\u00e9a, qui fait aussi partie de l\u2019\u00e9quipe nationale de cano\u00eb-kayak slalom du Canada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Baldoni sont tous les deux n\u00e9s en France et y ont grandi, mais ils avaient aussi la double citoyennet\u00e9 fran\u00e7aise et canadienne. Quand ils ont commenc\u00e9 \u00e0 concourir \u00e0 l\u2019\u00e9chelle internationale, ils ont choisi le pays d\u2019origine de leur m\u00e8re Christine, qui est originaire de Sault-Sainte-Marie, en Ontario, et faisait de la course \u00e0 pied de comp\u00e9tition. Quand Baldoni \u00e9tait plus jeune, sa famille passait un mois par ann\u00e9e au Canada, ce qui lui a permis d\u2019appr\u00e9cier au plus haut point les valeurs, la culture et la nature de ce pays.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Baldoni s\u2019est qualifi\u00e9 pour Paris 2024 en remportant l\u2019\u00e9preuve masculine de C-1 \u00e0 la rencontre de qualifications olympique des Am\u00e9riques de cano\u00eb slalom de la COPAC 2024. Il a ensuite termin\u00e9 quatri\u00e8me dans cette \u00e9preuve aux Championnats panam\u00e9ricains 2024. Baldoni avait remport\u00e9 l\u2019argent \u00e0 l\u2019\u00e9preuve masculine de C-1 des Championnats panam\u00e9ricains en 2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Baldoni a particip\u00e9 \u00e0 ses premiers Championnats du monde seniors de l\u2019ICF en 2021. Cette ann\u00e9e-l\u00e0, il a r\u00e9alis\u00e9 la meilleure performance dans&nbsp;l\u2019histoire du Canada en cano\u00eb masculin aux Championnats du monde juniors de l\u2019ICF quand il a pris la sixi\u00e8me place. En 2023, Baldoni a atteint la finale de l\u2019\u00e9preuve masculine du C-1 aux Championnats du monde des moins de 23 ans de l\u2019ICF, d\u00e9crochant la 10e place au total.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Baldoni a fait ses d\u00e9buts en Coupe du monde de l\u2019ICF dans sa ville d\u2019origine de Pau, en France, en novembre 2020 et il a alors atteint les demi-finales au C-1 ainsi qu\u2019au K-1.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0 propos d\u2019Alex<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9buts :<\/strong>&nbsp;A commenc\u00e9 \u00e0 pratiquer le kayak dans le cadre d\u2019un programme scolaire \u00e0 l\u2019\u00e2ge de 10 ans et a commenc\u00e9 \u00e0 faire de la comp\u00e9tition un an plus tard\u2026&nbsp;A \u00e9t\u00e9 initi\u00e9 au kayak dans le cadre d\u2019un programme offert par Aldric Estanguet, fr\u00e8re du triple champion olympique au C-1 Tony Estanguet\u2026 Au d\u00e9part, craignait de se retrouver \u00e0 l\u2019envers dans l\u2019eau et de devoir ramener son embarcation \u00e0 l\u2019endroit, mais a vite eu le coup de foudre pour la sensation de pagayer en eau vive&#8230; A d\u2019abord&nbsp;particip\u00e9 \u00e0 des comp\u00e9titions de kayak seulement jusqu\u2019\u00e0 ce qu\u2019un entra\u00eeneur lui dise qu\u2019il \u00e9tait naturellement dou\u00e9 pour le cano\u00eb\u2026&nbsp;&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alex Baldoni a acc\u00e9d\u00e9 au podium \u00e0 sa premi\u00e8re pr\u00e9sence aux Jeux panam\u00e9ricains, alors qu\u2019il a mis la main sur&#8230;<\/p>\n","protected":false},"featured_media":254892,"template":"","tags":[682165624,622441,1104411,415985124,682165310],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[415983968],"sport":[16966195],"game":[415985140,682165315],"team":[682166681,682165791],"event":[181822195],"province":[415983162],"class_list":["post-222689","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-alex-baldoni","tag-canoe-kayak","tag-equipe-canada","tag-paris-2024","tag-santiago-2023","gender-masculin","season-ete","sport-slalom","game-paris-2024","game-santiago-2023","team-paris-2024-canoe-kayak-slalom","team-santiago-canoe-kayak-slalom","event-c-1-hommes","province-autre"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alex Baldoni - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"Une biographie de l&#039;athl\u00e8te de cano\u00eb kayak Alex Baldoni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alex Baldoni - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Une biographie de l&#039;athl\u00e8te de cano\u00eb kayak Alex Baldoni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-28T18:45:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/06\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Caela Fenton\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/alex-baldoni\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/alex-baldoni\\\/\",\"name\":\"Alex Baldoni - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/alex-baldoni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/alex-baldoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100\",\"datePublished\":\"2023-06-28T14:00:00+00:00\",\"dateModified\":\"2024-08-28T18:45:28+00:00\",\"description\":\"Une biographie de l'athl\u00e8te de cano\u00eb kayak Alex Baldoni\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/alex-baldoni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/alex-baldoni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/06\\\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100\",\"width\":1200,\"height\":676,\"caption\":\"Team Canada\u2019s Alex Baldoni competes in men's canoe cross at the 2024 Paris Olympic Games in France on Saturday, August 3, 2024. Photo by Kevin Light\\\/COC *MANDATORY CREDIT*\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alex Baldoni - \u00c9quipe Canada","description":"Une biographie de l'athl\u00e8te de cano\u00eb kayak Alex Baldoni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/","og_locale":"fr_FR","og_type":"article","og_title":"Alex Baldoni - \u00c9quipe Canada","og_description":"Une biographie de l'athl\u00e8te de cano\u00eb kayak Alex Baldoni","og_url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/","og_site_name":"\u00c9quipe Canada","article_modified_time":"2024-08-28T18:45:28+00:00","og_image":[{"width":1200,"height":676,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/06\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes","Written by":"Caela Fenton"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/","url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/","name":"Alex Baldoni - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/06\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100","datePublished":"2023-06-28T14:00:00+00:00","dateModified":"2024-08-28T18:45:28+00:00","description":"Une biographie de l'athl\u00e8te de cano\u00eb kayak Alex Baldoni","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-baldoni\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/06\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/06\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100","width":1200,"height":676,"caption":"Team Canada\u2019s Alex Baldoni competes in men's canoe cross at the 2024 Paris Olympic Games in France on Saturday, August 3, 2024. Photo by Kevin Light\/COC *MANDATORY CREDIT*"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/06\/EDIT_KRL_20240803_05100-1-e1724870718999.jpg?quality=100","category_names":[],"tag_names":["Alex Baldoni","Cano\u00eb-kayak","\u00c9quipe canada","Paris 2024","Santiago 2023"],"sport_names":[378],"game_names":["Paris 2024","Santiago 2023"],"season_names":["\u00c9t\u00e9"],"team_names":["Paris 2024 Cano\u00eb-kayak - Slalom","Santiago 2023 Cano\u00eb-kayak - slalom"],"province_names":["Autre"],"social_facebook":"","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":"alex.baldoni","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/06\/Baldoni_Alex_Cred.jpg?quality=100","athlete_height":"","athlete_weight":"","athlete_hometown":"Pau (France)","athlete_birthplace":"Pau (France)","coc_gracenote_id":"","athlete_dob":"August 20, 1970","athlete_age":55,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/222689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":10,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/222689\/revisions"}],"predecessor-version":[{"id":254893,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/222689\/revisions\/254893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/254892"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=222689"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=222689"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=222689"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=222689"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=222689"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=222689"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=222689"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=222689"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=222689"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=222689"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=222689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}