{"id":247896,"date":"2024-07-01T11:10:00","date_gmt":"2024-07-01T15:10:00","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?post_type=athletes&#038;p=247896"},"modified":"2024-07-30T15:39:46","modified_gmt":"2024-07-30T19:39:46","slug":"simi-awujo","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/","title":{"rendered":"Simi Awujo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Simi Awujo a eu droit \u00e0 sa premi\u00e8re s\u00e9lection pour le Canada chez les seniors en septembre 2022 \u00e0 l\u2019occasion d\u2019un match amical contre l\u2019Australie. Elle a marqu\u00e9 son premier but \u00e0 l\u2019\u00e9chelle internationale en d\u00e9cembre 2023 dans un autre match amical contre les <em>Matildas<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e9e et \u00e9lev\u00e9e \u00e0 Atlanta, en G\u00e9orgie, Awujo a amorc\u00e9 sa carri\u00e8re internationale en repr\u00e9sentant les \u00c9tats-Unis, puis elle a opt\u00e9 pour le Canada \u00e0 l\u2019\u00e2ge de 18 ans. Dans la cat\u00e9gorie junior, elle a remport\u00e9 le bronze avec le Canada au Championnat U20 de la Concacaf, ce qui a permis au Canada d\u2019obtenir sa place \u00e0 la Coupe du monde U20 de la FIFA plus tard cette ann\u00e9e-l\u00e0. Elle a disput\u00e9 chacune des minutes de jeu des matchs du Canada \u00e0 la Coupe du monde U20 de 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Awujo a fait partie de l\u2019\u00e9quipe canadienne qui a particip\u00e9 \u00e0 l\u2019\u00e9dition inaugurale de la Gold Cup f\u00e9minine de la Concacaf en 2024 et a alors atteint les demi-finales. Elle avait obtenu son premier d\u00e9part au tournoi de la Coupe SheBelieves 2023, aidant le Canada \u00e0 terminer quatri\u00e8me. Elle a fait partie de l\u2019\u00e9quipe qui a perdu aux tirs au but en finale de l\u2019\u00e9dition 2024 du m\u00eame tournoi, contre les \u00c9tats-Unis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Awujo joue dans les rangs universitaires avec l\u2019Universit\u00e9 Southern California, o\u00f9 elle a \u00e9t\u00e9 choisie deux fois au sein de la premi\u00e8re \u00e9quipe d\u2019\u00e9toiles de l\u2019Association PAC 12 ainsi qu\u2019au sein de l\u2019\u00e9quipe d\u2019\u00e9toiles des recrues de l\u2019Association PAC 12.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0 propos de Simi<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9buts :<\/strong>&nbsp;A commenc\u00e9 \u00e0 jouer au soccer organis\u00e9 \u00e0 l\u2019\u00e2ge de sept ans\u2026&nbsp;A \u00e9t\u00e9 nomm\u00e9e&nbsp;Jeune joueuse de l\u2019ann\u00e9e&nbsp;2022 de&nbsp;Canada Soccer\u2026&nbsp;<strong>Autres int\u00e9r\u00eats :<\/strong>&nbsp;\u00c9tudie \u00e0 l\u2019Universit\u00e9 Southern California et pr\u00e9voit se sp\u00e9cialiser en neuroscience\u2026&nbsp;Aimerait devenir un jour une chirurgienne p\u00e9diatrique\u2026&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Simi Awujo a eu droit \u00e0 sa premi\u00e8re s\u00e9lection pour le Canada chez les seniors en septembre 2022 \u00e0 l\u2019occasion&#8230;<\/p>\n","protected":false},"featured_media":247897,"template":"","tags":[1104411,415985124,682166814,1693],"hof-categories":[],"year-inducted":[],"gender":[23319],"season":[415983968],"sport":[8591],"game":[415985140],"team":[682166688],"event":[181822490],"province":[415983162],"class_list":["post-247896","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-equipe-canada","tag-paris-2024","tag-simi-awujo","tag-soccer","gender-feminin","season-ete","sport-football","game-paris-2024","team-paris-2024-soccer-femmes","event-equipes-femmes","province-autre"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Simi Awujo - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"Une biographie de l&#039;athl\u00e8te de soccer Simi Awujo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simi Awujo - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Une biographie de l&#039;athl\u00e8te de soccer Simi Awujo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T19:39:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/CP171934233-1-e1719585941301.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"5715\" \/>\n\t<meta property=\"og:image:height\" content=\"3228\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Maxime Bernier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/simi-awujo\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/simi-awujo\\\/\",\"name\":\"Simi Awujo - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/simi-awujo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/simi-awujo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/06\\\/CP171934233-1-e1719585941301.jpg?quality=100\",\"datePublished\":\"2024-07-01T15:10:00+00:00\",\"dateModified\":\"2024-07-30T19:39:46+00:00\",\"description\":\"Une biographie de l'athl\u00e8te de soccer Simi Awujo.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/simi-awujo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/simi-awujo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/06\\\/CP171934233-1-e1719585941301.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/06\\\/CP171934233-1-e1719585941301.jpg?quality=100\",\"width\":5715,\"height\":3228,\"caption\":\"La Canadienne Simi Awujo tente un tir sous le regard de la Mexicaine Karla Nieto lors de la deuxi\u00e8me mi-temps d'un match amical international \u00e0 Toronto, le mardi 4 juin 2024.LA PRESSE CANADIENNE\\\/Chris Young\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simi Awujo - \u00c9quipe Canada","description":"Une biographie de l'athl\u00e8te de soccer Simi Awujo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/","og_locale":"fr_FR","og_type":"article","og_title":"Simi Awujo - \u00c9quipe Canada","og_description":"Une biographie de l'athl\u00e8te de soccer Simi Awujo.","og_url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/","og_site_name":"\u00c9quipe Canada","article_modified_time":"2024-07-30T19:39:46+00:00","og_image":[{"width":5715,"height":3228,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/CP171934233-1-e1719585941301.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes","Written by":"Maxime Bernier"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/","url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/","name":"Simi Awujo - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/CP171934233-1-e1719585941301.jpg?quality=100","datePublished":"2024-07-01T15:10:00+00:00","dateModified":"2024-07-30T19:39:46+00:00","description":"Une biographie de l'athl\u00e8te de soccer Simi Awujo.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/CP171934233-1-e1719585941301.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/CP171934233-1-e1719585941301.jpg?quality=100","width":5715,"height":3228,"caption":"La Canadienne Simi Awujo tente un tir sous le regard de la Mexicaine Karla Nieto lors de la deuxi\u00e8me mi-temps d'un match amical international \u00e0 Toronto, le mardi 4 juin 2024.LA PRESSE CANADIENNE\/Chris Young"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/CP171934233-1-e1719585941301.jpg?quality=100","category_names":[],"tag_names":["\u00c9quipe canada","Paris 2024","simi awujo","Soccer"],"sport_names":[439],"game_names":["Paris 2024"],"season_names":["\u00c9t\u00e9"],"team_names":["Paris 2024 Soccer (Femmes)"],"province_names":["Autre"],"social_facebook":"","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":"_simisolaa_","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"","athlete_height":"175","athlete_weight":"","athlete_hometown":"Atlanta, G\u00e9orgie (\u00c9tats-Unis)","athlete_birthplace":"Atlanta, G\u00e9orgie (\u00c9tats-Unis)","coc_gracenote_id":"","athlete_dob":"August 20, 1970","athlete_age":55,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/247896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":6,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/247896\/revisions"}],"predecessor-version":[{"id":251790,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/247896\/revisions\/251790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/247897"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=247896"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=247896"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=247896"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=247896"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=247896"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=247896"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=247896"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=247896"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=247896"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=247896"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=247896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}