{"id":248990,"date":"2024-07-10T13:00:00","date_gmt":"2024-07-10T17:00:00","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?post_type=athletes&#038;p=248990"},"modified":"2024-08-02T15:23:42","modified_gmt":"2024-08-02T19:23:42","slug":"melvin-ejim-2","status":"publish","type":"athletes","link":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/","title":{"rendered":"Melvin Ejim"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Melvin Ejim \u00e9tait le joueur le plus \u00e2g\u00e9 de l\u2019\u00e9quipe canadienne qui a remport\u00e9 une historique m\u00e9daille de bronze \u00e0 la Coupe du monde de basketball masculin de la FIBA 2023. Il s\u2019agissait de la toute premi\u00e8re m\u00e9daille que le Canada d\u00e9crochait \u00e0 ce tournoi. Ejim est un des joueurs qui se sont engag\u00e9s en 2022 \u00e0 s\u2019aligner avec l\u2019\u00e9quipe nationale dans l\u2019espoir de qualifier le Canada pour sa premi\u00e8re participation \u00e0 un tournoi olympique de basketball masculin depuis Sydney 2000.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ejim a port\u00e9 les couleurs de l\u2019\u00e9quipe nationale senior masculine en 2015, aidant alors le Canada \u00e0 d\u00e9crocher la m\u00e9daille d\u2019argent aux Jeux panam\u00e9ricains \u00e0 Toronto et la m\u00e9daille de bronze au Championnat des Am\u00e9riques de la FIBA. Il s\u2019agissait du tout premier podium que le Canada obtenait au basketball masculin \u00e0 des Jeux panam\u00e9ricains.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ejim a jou\u00e9 pour le Canada aux \u00c9liminatoires de la zone Am\u00e9riques de la Coupe du monde de basketball de la FIBA en 2019 et 2022, aidant son pays \u00e0 d\u00e9crocher sa place dans les deux tournois mondiaux. Il a aussi fait partie de l\u2019\u00e9quipe canadienne qui a jou\u00e9 au Tournoi de qualification olympique de la FIBA pour Rio 2016, o\u00f9 l\u2019\u00e9quipe s\u2019est inclin\u00e9e devant la France en finale, venant \u00e0 un rang pr\u00e8s de d\u00e9crocher son billet pour les Jeux olympiques.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fils d\u2019une m\u00e8re nig\u00e9riane, Ejim a pris part \u00e0 sa premi\u00e8re comp\u00e9tition internationale \u00e0 titre de membre de l\u2019\u00e9quipe nationale du Nig\u00e9ria en 2012. Il a repr\u00e9sent\u00e9 le Canada pour la premi\u00e8re fois aux Jeux mondiaux universitaires 2013, aidant l\u2019\u00e9quipe \u00e0 terminer quatri\u00e8me. Il a aussi particip\u00e9 \u00e0 la fiche parfaite de 9-0 que le Canada a enregistr\u00e9e au Tournoi international sur invitation des Quatre nations dans le cadre de sa pr\u00e9paration pour les Jeux mondiaux universitaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2014, Ejim a connu une des meilleures saisons dans l\u2019histoire de l\u2019\u00e9cole \u00e0 sa derni\u00e8re ann\u00e9e d\u2019admissibilit\u00e9 \u00e0 l\u2019Universit\u00e9 Iowa State. Il a men\u00e9 les Cyclones vers le titre du Tournoi de l\u2019Association Big 12 et jusqu\u2019en huiti\u00e8mes de finale du tournoi national de la NCAA.&nbsp;Il a \u00e9t\u00e9 nomm\u00e9 Joueur de l\u2019ann\u00e9e dans l\u2019Association Big 12 et finaliste pour le Troph\u00e9e Oscar Robertson remis au joueur par excellence de basketball masculin dans la NCAA.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la suite de sa carri\u00e8re dans les rangs universitaires, Ejim a sign\u00e9 un contrat avec une \u00e9quipe professionnelle en Italie. Il est revenu en Am\u00e9rique du Nord en tant que membre de l\u2019organisation du Magic d\u2019Orlando et il a pass\u00e9 une saison dans la ligue de d\u00e9veloppement de la NBA (&nbsp;G League) avant de retourner en Europe. En 2017, il a remport\u00e9 le titre dans la Ligue d\u2019Italie avec son club, le Reyer Venise, et a \u00e9t\u00e9 nomm\u00e9 joueur le plus utile \u00e0 son \u00e9quipe \u00e0 l\u2019issue des finales. Il a aussi \u00e9t\u00e9 nomm\u00e9 au sein de l\u2019\u00e9quipe d\u2019\u00e9toiles de la Ligue des Champions. Il s\u2019est arr\u00eat\u00e9 en Russie, en Espagne, au Mont\u00e9n\u00e9gro (o\u00f9 il a remport\u00e9 le championnat de ligue 2021 et la Coupe du Mont\u00e9n\u00e9gro avec le Budu\u0107nost) et en Slov\u00e9nie (Coupe de Slov\u00e9nie 2022 avec l\u2019Olympia), avant de retourner en Espagne, o\u00f9 il joue depuis. En 2024, son \u00e9quipe, l\u2019Unicaja, a remport\u00e9 la Ligue des Champions de la FIBA.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0 propos de Melvin<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autres int\u00e9rets :<\/strong>&nbsp;A compl\u00e9t\u00e9 ses \u00e9tudes \u00e0 l\u2019Universit\u00e9 Iowa State en&nbsp;2014,&nbsp;obtenant un dipl\u00f4me en histoire&#8230; Membre de la&nbsp;soci\u00e9t\u00e9 d\u2019honneur acad\u00e9mique Phi Kappa Phi&#8230;&nbsp;<strong>De tout et de rien :<\/strong>&nbsp;Sa s\u0153ur&nbsp;Yvonne Ejim&nbsp;fait partie de l\u2019\u00e9quipe canadienne de basketball f\u00e9minin \u00e0 Paris 2024\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Melvin Ejim \u00e9tait le joueur le plus \u00e2g\u00e9 de l\u2019\u00e9quipe canadienne qui a remport\u00e9 une historique m\u00e9daille de bronze \u00e0&#8230;<\/p>\n","protected":false},"featured_media":252581,"template":"","tags":[30961412,1104411,24395917,415985124],"hof-categories":[],"year-inducted":[],"gender":[42123],"season":[415983968],"sport":[1985],"game":[415985140],"team":[682166676],"event":[176925371],"province":[415983158],"class_list":["post-248990","athletes","type-athletes","status-publish","has-post-thumbnail","hentry","tag-basketball-2","tag-equipe-canada","tag-melvin-ejim","tag-paris-2024","gender-masculin","season-ete","sport-basketball","game-paris-2024","team-paris-2024-basketball-hommes","event-equipes-hommes","province-ontario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Melvin Ejim - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"Une biographie de l&#039;athl\u00e8te de basketball Melvin Ejim.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Melvin Ejim - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Une biographie de l&#039;athl\u00e8te de basketball Melvin Ejim.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T19:23:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/07\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"3600\" \/>\n\t<meta property=\"og:image:height\" content=\"2369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"gsimoneau\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/melvin-ejim-2\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/melvin-ejim-2\\\/\",\"name\":\"Melvin Ejim - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/melvin-ejim-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/melvin-ejim-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100\",\"datePublished\":\"2024-07-10T17:00:00+00:00\",\"dateModified\":\"2024-08-02T19:23:42+00:00\",\"description\":\"Une biographie de l'athl\u00e8te de basketball Melvin Ejim.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/melvin-ejim-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/team-canada\\\/melvin-ejim-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100\",\"width\":3600,\"height\":2369,\"caption\":\"Melvin Ejim (6) of Toronto in the gold men's gold medal basketball game at the Pan American Games in Toronto, Ont., Saturday, July 25, 2015. Photo by Mike Ridewood\\\/COC\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Melvin Ejim - \u00c9quipe Canada","description":"Une biographie de l'athl\u00e8te de basketball Melvin Ejim.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Melvin Ejim - \u00c9quipe Canada","og_description":"Une biographie de l'athl\u00e8te de basketball Melvin Ejim.","og_url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/","og_site_name":"\u00c9quipe Canada","article_modified_time":"2024-08-02T19:23:42+00:00","og_image":[{"width":3600,"height":2369,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/07\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes","Written by":"gsimoneau"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/","url":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/","name":"Melvin Ejim - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/07\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100","datePublished":"2024-07-10T17:00:00+00:00","dateModified":"2024-08-02T19:23:42+00:00","description":"Une biographie de l'athl\u00e8te de basketball Melvin Ejim.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melvin-ejim-2\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/07\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/07\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100","width":3600,"height":2369,"caption":"Melvin Ejim (6) of Toronto in the gold men's gold medal basketball game at the Pan American Games in Toronto, Ont., Saturday, July 25, 2015. Photo by Mike Ridewood\/COC"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/07\/CANvARG_m_silver_July-25_JasonRansomPhoto186.jpg?quality=100","category_names":[],"tag_names":["basketball","\u00c9quipe canada","Melvin Ejim","Paris 2024"],"sport_names":[360],"game_names":["Paris 2024"],"season_names":["\u00c9t\u00e9"],"team_names":["Paris 2024 Basketball (Hommes)"],"province_names":["Ontario"],"social_facebook":"","social_twitter":"","social_linkedin":"","social_gplus":"","social_instagram":"melvinejim3","social_website":"","total_medal_count_gold":"","total_medal_count_silver":"","total_medal_count_bronze":"","athlete_headshot":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/07\/Melvin-Ejim-e1720615012272.jpg?quality=100","athlete_height":"201","athlete_weight":"","athlete_hometown":"Toronto, Ontario","athlete_birthplace":"Toronto, Ontario","coc_gracenote_id":"","athlete_dob":"August 19, 1970","athlete_age":55,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/248990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/athletes"}],"version-history":[{"count":7,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/248990\/revisions"}],"predecessor-version":[{"id":250725,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes\/248990\/revisions\/250725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/252581"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=248990"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=248990"},{"taxonomy":"hof-categories","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/hof-categories?post=248990"},{"taxonomy":"year-inducted","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/year-inducted?post=248990"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/gender?post=248990"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/season?post=248990"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=248990"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=248990"},{"taxonomy":"team","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/team?post=248990"},{"taxonomy":"event","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/event?post=248990"},{"taxonomy":"province","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/province?post=248990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}