{"id":151821,"date":"2019-08-01T16:15:33","date_gmt":"2019-08-01T20:15:33","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?post_type=board-members&#038;p=151821"},"modified":"2020-05-14T09:49:56","modified_gmt":"2020-05-14T13:49:56","slug":"steve-podborski","status":"publish","type":"board-members","link":"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/","title":{"rendered":"Steve Podborski"},"content":{"rendered":"<p>Steve Podborski a particip\u00e9 aux Jeux olympiques d\u2019hiver \u00e0 deux reprises (1980 et 1984) et fut le premier homme nord-am\u00e9ricain \u00e0 remporter une m\u00e9daille olympique (bronze) en ski alpin, en 1980 \u00e0 Lake Placid. Deux fois vainqueur du Hahnenkamm \u00e0 Kitzb\u00fchel, Steve est devenu, en 1982, le premier homme non europ\u00e9en \u00e0 remporter le titre de la Coupe du monde de descente, une distinction qu\u2019il toujours le seul \u00e0 d\u00e9tenir. Profond\u00e9ment impliqu\u00e9 dans le mouvement olympique, Steve a \u00e9t\u00e9 directeur g\u00e9n\u00e9ral de la candidature olympique r\u00e9ussie des Jeux de Vancouver 2010, chef de mission adjoint aux Jeux de Vancouver et chef de mission aux Jeux olympiques d&rsquo;hiver de 2014 \u00e0 Sotchi, en Russie.<\/p>\n<p>Ses points saillants dans le domaine des affaires comprennent des postes de direction au sein de TELUS (initiatives strat\u00e9giques, affaires communautaires, mieux-\u00eatre) pendant 15 ans jusqu\u2019en 2016. \u00c0 ce moment-l\u00e0, Steve a \u00e9t\u00e9 recrut\u00e9 comme pr\u00e9sident et chef de la direction de Parachute, l&rsquo;organisme de bienfaisance national du Canada pour la pr\u00e9vention des blessures de 2016 \u00e0 2019. \u00c0 l&rsquo;heure actuelle, Steve est membre b\u00e9n\u00e9vole des conseils d&rsquo;administration de la Fondation olympique canadienne, de Parachute Canada, de l\u2019Association canadienne des sports d\u2019hiver, de la Fondation canadienne du ski et de Winterstart (\u00e9preuves de ski alpin de la Coupe du monde \u00e0 Lac Louise).<\/p>\n<p>Steve et son \u00e9pouse Cassandra r\u00e9sident sur l&rsquo;\u00eele Fogo, \u00e0 Terre-Neuve.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Steve Podborski a particip\u00e9 aux Jeux olympiques d\u2019hiver \u00e0 deux reprises (1980 et 1984) et fut le premier homme nord-am\u00e9ricain&#8230;<\/p>\n","protected":false},"featured_media":151811,"template":"","tags":[415984556],"board-level":[378780],"class_list":["post-151821","board-members","type-board-members","status-publish","has-post-thumbnail","hentry","tag-fondation","board-level-fondation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Steve Podborski - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steve Podborski - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Steve Podborski a particip\u00e9 aux Jeux olympiques d\u2019hiver \u00e0 deux reprises (1980 et 1984) et fut le premier homme nord-am\u00e9ricain...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T13:49:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/11\/steve-podborski.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"2106\" \/>\n\t<meta property=\"og:image:height\" content=\"1184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Elisa Iannarelli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/board-members\\\/steve-podborski\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/board-members\\\/steve-podborski\\\/\",\"name\":\"Steve Podborski - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/board-members\\\/steve-podborski\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/board-members\\\/steve-podborski\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/steve-podborski.jpg?quality=100\",\"datePublished\":\"2019-08-01T20:15:33+00:00\",\"dateModified\":\"2020-05-14T13:49:56+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/board-members\\\/steve-podborski\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/board-members\\\/steve-podborski\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/steve-podborski.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/steve-podborski.jpg?quality=100\",\"width\":2106,\"height\":1184},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steve Podborski - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/","og_locale":"fr_FR","og_type":"article","og_title":"Steve Podborski - \u00c9quipe Canada","og_description":"Steve Podborski a particip\u00e9 aux Jeux olympiques d\u2019hiver \u00e0 deux reprises (1980 et 1984) et fut le premier homme nord-am\u00e9ricain...","og_url":"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/","og_site_name":"\u00c9quipe Canada","article_modified_time":"2020-05-14T13:49:56+00:00","og_image":[{"width":2106,"height":1184,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/11\/steve-podborski.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"Elisa Iannarelli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/","url":"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/","name":"Steve Podborski - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/11\/steve-podborski.jpg?quality=100","datePublished":"2019-08-01T20:15:33+00:00","dateModified":"2020-05-14T13:49:56+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/board-members\/steve-podborski\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/11\/steve-podborski.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/11\/steve-podborski.jpg?quality=100","width":2106,"height":1184},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/board-members\/151821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/board-members"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/board-members"}],"version-history":[{"count":0,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/board-members\/151821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/151811"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=151821"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=151821"},{"taxonomy":"board-level","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/board-level?post=151821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}