{"id":107102,"date":"2015-07-15T23:13:56","date_gmt":"2015-07-16T03:13:56","guid":{"rendered":"http:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg"},"modified":"2015-07-16T01:00:21","modified_gmt":"2015-07-16T05:00:21","slug":"_32i8384-crop-2","status":"inherit","type":"attachment","link":"https:\/\/develop.olympic.ca\/olympique\/photos\/jour-3-toronto-2015\/_32i8384-crop-2\/#main","title":{"rendered":"Adam Van Koeverden"},"author":47195898,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-107102","attachment","type-attachment","status-inherit","hentry"],"acf":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/abmyEP-rRs","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?quality=100'><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"371\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?quality=100&amp;w=660\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg 1340w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?resize=280,158 280w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?resize=660,371 660w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?resize=768,432 768w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Adam Van Koeverden. Photo par Michael P. Hall<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1340,"height":753,"file":"2015\/07\/32i8384-crop1.jpg","sizes":{"thumbnail":{"file":"32i8384-crop1.jpg?resize=280,158","width":280,"height":158,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?quality=100&w=280"},"medium":{"file":"32i8384-crop1.jpg?resize=660,371","width":660,"height":371,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?quality=100&w=660"},"medium_large":{"file":"32i8384-crop1.jpg?resize=768,432","width":768,"height":432,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?quality=100&w=768"},"full":{"file":"32i8384-crop1.jpg?quality=100","width":1340,"height":753,"mime_type":"image\/jpeg","source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?quality=100"}},"image_meta":{"aperture":4,"credit":"Michael P. Hall\/Canadian Olympic Committee","camera":"Canon EOS-1D X","caption":"Canada's Adam Van Koeverden finished third in the K1 1000M race at the Pan Am Games in Toronto Monday, July 13, 2015. \nCOC Photo by Michael P. Hall","created_timestamp":1436812649,"copyright":"Michael P. Hall\/Canadian Olympic Committee","focal_length":"500","iso":"400","shutter_speed":"0.00025","title":"","orientation":1}},"post":106788,"source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2015\/07\/32i8384-crop1.jpg?quality=100","filename":"32i8384-crop1.jpg","filesize":170675,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/107102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/47195898"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=107102"}],"wp:attached-to":[{"embeddable":true,"post_type":"photos","id":106788,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/photos\/106788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}