{"id":151547,"date":"2019-05-21T11:08:37","date_gmt":"2019-05-21T15:08:37","guid":{"rendered":"http:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg"},"modified":"2019-05-21T11:45:31","modified_gmt":"2019-05-21T15:45:31","slug":"suzanne-lapl-2","status":"inherit","type":"attachment","link":"https:\/\/develop.olympic.ca\/olympique\/suzanne-lapl-2\/","title":{"rendered":"suzanne-lapl"},"author":96107080,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-151547","attachment","type-attachment","status-inherit","hentry"],"acf":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/abmyEP-Dqj","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?quality=100'><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"371\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?quality=100&amp;w=283\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg 610w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?resize=120,158 120w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?resize=283,371 283w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?resize=575,754 575w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Suzanne Lenglen posant dans sa tenue d&rsquo;avant-match. (Photo: cnn.com)<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":610,"height":800,"file":"2019\/05\/suzanne-lapl-1.jpg","sizes":{"thumbnail":{"file":"suzanne-lapl-1.jpg?resize=120,158","width":120,"height":158,"filesize":50853,"mime_type":"image\/jpeg","source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?quality=100&w=120"},"medium":{"file":"suzanne-lapl-1.jpg?resize=283,371","width":283,"height":371,"filesize":50853,"mime_type":"image\/jpeg","source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?quality=100&w=283"},"large":{"file":"suzanne-lapl-1.jpg?resize=575,754","width":575,"height":754,"filesize":50853,"mime_type":"image\/jpeg","source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?quality=100&w=575"},"full":{"file":"suzanne-lapl-1.jpg?quality=100","width":610,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?quality=100"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]},"filesize":50853},"post":null,"source_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/05\/suzanne-lapl-1.jpg?quality=100","filename":"suzanne-lapl-1.jpg","filesize":50853,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/151547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/96107080"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=151547"}]}}