{"id":113793,"date":"2016-03-31T16:11:12","date_gmt":"2016-03-31T20:11:12","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=113793"},"modified":"2021-10-21T16:16:41","modified_gmt":"2021-10-21T20:16:41","slug":"championnat-ncaa-de-basketball-cinq-joueuses-canadiennes-dans-le-final-four","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2016\/03\/31\/championnat-ncaa-de-basketball-cinq-joueuses-canadiennes-dans-le-final-four\/","title":{"rendered":"Championnat NCAA de basketball : cinq joueuses canadiennes dans le Final Four"},"content":{"rendered":"<p>Photo manchette\u00a0: <a href=\"http:\/\/develop.olympic.ca\/olympique\/2015\/03\/20\/21-canadiennes-en-action-au-tournoi-de-la-ncaa\/\">Kolbie Orum<\/a> (12) se rend au panier lors du match contre Troy le 18 mars 2016.<\/p>\n<p>La r\u00e9ussite du basketball canadien est \u00e9vidente au <a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/03\/24\/les-canadiens-en-evidence-au-march-madness\/\">March Madness<\/a>, encore plus au penchant f\u00e9minin de la comp\u00e9tition, o\u00f9 cinq joueuses canadiennes participeront au <em>Final Four<\/em>.<\/p>\n<p>Au\u00a0d\u00e9but du tournoi, le 18 mars, il y avait un total de 21 joueuses canadiennes r\u00e9parties en 12 \u00e9quipes diff\u00e9rentes. De ces 21 universitaires, cinq joueront en demi-finales du Championnat national le 3 avril prochain dans trois \u00e9quipes des quatre \u00e9quipes toujours en lice. Ceci assure d\u2019avoir au moins une joueuse canadienne lors de la grande finale du tournoi de la premi\u00e8re division de basketball f\u00e9minin.<\/p>\n<p>Lisa Thomaidis, entra\u00eeneure de l\u2019\u00e9quipe nationale de basketball f\u00e9minin qui sera des prochains Jeux olympiques, a gazouill\u00e9 son appui aux cinq comp\u00e9titrices restantes.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\">Amazing to see Canadians <a href=\"https:\/\/twitter.com\/KayNurse11\">@KayNurse11<\/a>, <a href=\"https:\/\/twitter.com\/jamieweisner\">@jamieweisner<\/a>, <a href=\"https:\/\/twitter.com\/ruthhamblin\">@ruthhamblin<\/a>, <a href=\"https:\/\/twitter.com\/KolbieOrum\">@KolbieOrum<\/a> and Julia Chandler advance to the NCAA Final Four! Congrats!!<\/p>\n<p>&mdash; Lisa Thomaidis (@LisaThomaidis) <a href=\"https:\/\/twitter.com\/LisaThomaidis\/status\/714657223377457152\">March 29, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<hr \/>\n<p><strong><em>Qui sont les joueuses encore dans le tournoi?<\/em><\/strong><\/p>\n<h2>Kia Nurse<\/h2>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1360\" height=\"765\" src=\"https:\/\/www.youtube.com\/embed\/yFnPmy3_8A4?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p><a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/kia-nurse\/\" target=\"_blank\" rel=\"noopener\">Nurse<\/a> est devenue une habitu\u00e9e des grands rendez-vous. Elle a r\u00e9ussi 33 points lors du match de la m\u00e9daille d\u2019or contre les \u00c9tats-Unis aux derniers Jeux panam\u00e9ricains, permettant au Canada de <a href=\"http:\/\/develop.olympic.ca\/olympique\/2015\/07\/20\/panam-jour-10-en-direct\/\">monter sur la plus haute marche du podium<\/a>. Elle a aussi permis au Canada de garantir sa place \u00e0 Rio et de remporter une m\u00e9daille d\u2019or au dernier Championnat des Am\u00e9riques de la FIBA. La semaine prochaine, elle tentera d\u2019aider l\u2019Universit\u00e9 du Connecticut \u00e0 remporter un quatri\u00e8me championnat national cons\u00e9cutif (un deuxi\u00e8me pour Nurse).<\/p>\n<h2>Kolbie Orum<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\">Keep calm Beaver Nation, we&#39;re still dancin \u2755\u2755\u2755 <a href=\"https:\/\/t.co\/gqZLy087ns\">pic.twitter.com\/gqZLy087ns<\/a><\/p>\n<p>&mdash; Kolbie\u2022Orum (@KolbieOrum) <a href=\"https:\/\/twitter.com\/KolbieOrum\/status\/711775421897912320\">March 21, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>La double m\u00e9daill\u00e9e de bronze dans les rangs juniors pour le Canada a jou\u00e9 sur\u00a0l\u2019\u00e9quipe nationale en 2012, lors du Championnat du monde des moins de 17 ans et aussi au Championnat des Am\u00e9riques des moins de 16 ans en 2011. Maintenant membre des Beavers de Oregon State, Orum tentera de remporter le Championnat national avec ses compatriotes Jamie Weisner et Ruth Hamblin.<\/p>\n<h2>Jamie Weisner<\/h2>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1360\" height=\"765\" src=\"https:\/\/www.youtube.com\/embed\/KXMNTLuoMQg?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>Consid\u00e9r\u00e9e comme une des marqueuses la plus efficace du basketball universitaire, Weisner a repr\u00e9sent\u00e9 le Canada au plus haut niveau. En 2014, elle a aid\u00e9 l\u2019\u00e9quipe de d\u00e9veloppement du Canada \u00e0 remporter la m\u00e9daille d\u2019or \u00e0 la Coupe Jones \u00e0 Taiwan. Cette saison, en NCAA, elle a remport\u00e9 les grands honneurs du All-Pac-12 en plus d\u2019aider les Beavers dans le tournoi avec une r\u00e9colte de 79 points, 27 rebonds et sept passes d\u00e9cisives.<\/p>\n<h2>Ruth Hamblin<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"und\" dir=\"ltr\">Joy.<a href=\"https:\/\/twitter.com\/ruthhamblin\">@ruthhamblin<\/a> <a href=\"https:\/\/twitter.com\/jamieweisner\">@jamieweisner<\/a> <a href=\"https:\/\/t.co\/qUAZCqRLqi\">pic.twitter.com\/qUAZCqRLqi<\/a><\/p>\n<p>&mdash; Oregon State WBB (@OregonStateWBB) <a href=\"https:\/\/twitter.com\/OregonStateWBB\/status\/706703204591861760\">March 7, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Oregon State compte un autre talent canadien dans sa formation avec Ruth Hamblin, consid\u00e9r\u00e9e comme une des joueuses de centre les plus pures du basketball universitaire. De plus, elle a \u00e9t\u00e9 une puissance d\u00e9fensive cette saison avec Oregon. Sa r\u00e9colte de 45 points, 55 rebonds et 14 tirs bloqu\u00e9s ont jusqu\u2019ici permis \u00e0 Oregon de se donner une chance pour le titre national. Hamblin joue pour \u00c9quipe Canada depuis 4 ans et a aid\u00e9 l\u2019\u00e9quipe de d\u00e9veloppement f\u00e9minine \u00e0 terminer deuxi\u00e8me aux Jeux FISU en 2015.<\/p>\n<h2>Julia Chandler<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\">Toronto&#39;s very own Julia Chandler running with the Orange as they take on Washington in the <a href=\"https:\/\/twitter.com\/hashtag\/FinalFour?src=hash\">#FinalFour<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/teamOalumni?src=hash\">#teamOalumni<\/a> <a href=\"https:\/\/t.co\/ihcFOKlL5N\">pic.twitter.com\/ihcFOKlL5N<\/a><\/p>\n<p>&mdash; Ontario Basketball (@OBANews) <a href=\"https:\/\/twitter.com\/OBANews\/status\/714873292356759552\">March 29, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Pr\u00e9sentement recrue \u00e0 l\u2019Universit\u00e9 de Syracuse, Julia Chandler est l\u2019un des plus grands espoirs du basketball canadien. Chandler a pass\u00e9 les trois derni\u00e8res ann\u00e9es \u00e0 jouer avec les \u00e9quipes canadiennes des moins de 19 ans, 18 ans, 17 ans et 16 ans.<\/p>\n<hr \/>\n<p><strong><em>Les joueuses canadiennes d\u00e9j\u00e0 \u00e9limin\u00e9es<\/em><\/strong><\/p>\n<h2>Adut Bulgak<\/h2>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1360\" height=\"765\" src=\"https:\/\/www.youtube.com\/embed\/IhSBeFJTG44?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>Adut Bulgak a \u00e9t\u00e9 une force dominante depuis qu\u2019elle s\u2019est jointe aux Seminoles de Florida State en 2014-2015. Bulgak a men\u00e9 les Seminoles au troisi\u00e8me tour du tournoi avec une r\u00e9colte de 38 points, 28 rebonds et sept tirs bloqu\u00e9s.<\/p>\n<h2>Quinn Dornstauder<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\">Quinn Dornstauder is a MAJOR \ud83d\udd11 for <a href=\"https:\/\/twitter.com\/SunDevilWBB\">@SunDevilWBB<\/a> and one to watch at the <a href=\"https:\/\/twitter.com\/hashtag\/Pac12WBB?src=hash\">#Pac12WBB<\/a> tourney: <a href=\"https:\/\/t.co\/HsRCAxOUZ9\">https:\/\/t.co\/HsRCAxOUZ9<\/a> <a href=\"https:\/\/t.co\/UA1DKzloQg\">pic.twitter.com\/UA1DKzloQg<\/a><\/p>\n<p>&mdash; Pac-12 Network (@Pac12Network) <a href=\"https:\/\/twitter.com\/Pac12Network\/status\/705262577836802048\">March 3, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>La joueuse de centre de 6 pieds 4 pouces a aid\u00e9 les Sun Devils de l\u2019Universit\u00e9 de l\u2019Arizona \u00e0 se rendre au deuxi\u00e8me tour avec 15 points et sept rebonds. Les Sun Devils ont \u00e9t\u00e9 \u00e9limin\u00e9s du tournoi dans une d\u00e9faite am\u00e8re contre les Lady Volunteers du Tennessee.<\/p>\n<h2>Kaili Lukan<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/HLWBB?src=hash\">#HLWBB<\/a> | <a href=\"https:\/\/twitter.com\/gbphoenixwbb\">@gbphoenixwbb<\/a> sr. Kaili Lukan led the 9th ranked defense in the nation to collect Def. Player of the Yr. <a href=\"https:\/\/t.co\/5ho8nzitHb\">pic.twitter.com\/5ho8nzitHb<\/a><\/p>\n<p>&mdash; HorizonLeague (@HorizonLeague) <a href=\"https:\/\/twitter.com\/HorizonLeague\/status\/707289461952880640\">March 8, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Le Phoenix de Green Bay a \u00e9t\u00e9 \u00e9limin\u00e9 au premier tour du tournoi, mais ce fut avec un excellent effort de Kaili Lukan, qui a r\u00e9colt\u00e9 12 points et 5 rebonds. L\u2019\u00e9quipe a \u00e9t\u00e9 d\u00e9faite\u00a059-53 par les Lady Volunteers du Tennessee.<\/p>\n<blockquote>\n<p style=\"text-align: center\"><a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/03\/24\/les-canadiens-en-evidence-au-march-madness\/\">Les Canadiens en \u00e9vidence au March Madness<\/a><\/p>\n<\/blockquote>\n<p>Voici la liste des joueuses canadiennes, et leur universit\u00e9 d\u2019appartennce, ayant particip\u00e9 au tournoi de premi\u00e8re division f\u00e9minine du basketball universitaire\u00a02016.<\/p>\n<p><strong>Huskies du Connecticut<\/strong><\/p>\n<p>Kia Nurse \u2013 Hamilton, ONT<\/p>\n<p><strong>Colonials de Robert Morris<\/strong><\/p>\n<p>Mikalah Mulrain \u2013 Brampton, ONT<\/p>\n<p>Megan Smith \u2013 Baden, ON<\/p>\n<p>Yasmyne Salhia \u2013 Toronto, ONT<\/p>\n<p><strong>Dukes de Duquesne<\/strong><\/p>\n<p>Brianna Thomas \u2013 Ajax, ON<\/p>\n<p>Tigers du Missouri<\/p>\n<p>Michelle Hudyn \u2013 Kitchener, ONT<\/p>\n<p><strong>Seminoles de Florida State<\/strong><\/p>\n<p>Adut Bulgak \u2013 Victoria, BC<\/p>\n<p>Beavers d\u2019Oregon State<\/p>\n<p>Kolbie Orum \u2013 Maple Ridge, BC<\/p>\n<p>Ruth Hamblin \u2013 Houston, BC<\/p>\n<p>Jamie Weisner \u2013 Clarkston, WA<\/p>\n<p><strong>Great Danes d\u2019Albany<\/strong><\/p>\n<p>Jessica\u00a0Fequiere \u2013 Montr\u00e9al, QC<\/p>\n<p>Veronika Lavergne \u2013 Ottawa, ONT<\/p>\n<p>Khara Keane \u2013 Toronto, ONT<\/p>\n<p>Cassandra Edwards \u2013 Brampton, ONT<\/p>\n<p><strong>Orange de Syracuse<\/strong><\/p>\n<p>Julia Chandler \u2013 Toronto, ONT<\/p>\n<p><strong>Bulls de Buffalo<\/strong><\/p>\n<p>Ayoleka Sodade \u2013 Windsor, ONT<\/p>\n<p><strong>Ph\u0153nix de Green Bay<\/strong><\/p>\n<p>Kaili Lukan \u2013 Barrie, ONT<\/p>\n<p>Sun Devils d\u2019Arizona State<\/p>\n<p>Quinn Dornstauder \u2013 Regina, SK<\/p>\n<p>Dons de San Francisco<\/p>\n<p>Cierra Roufosse \u2013 Abbotsford, BC<\/p>\n<p>Alicia Roufosse \u2013 Abbotsford, BC<\/p>\n<p>Zayn Dornstauder \u2013 Regina, SK<\/p>\n<p>Faites-nous savoir votre moment canadien pr\u00e9f\u00e9r\u00e9 jusqu\u2019ici au March Madness sur <a href=\"https:\/\/twitter.com\/OlympiqueCanada?lang=fr\">Twitter<\/a> ou <a href=\"https:\/\/www.facebook.com\/teamcanada\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Photo manchette\u00a0: Kolbie Orum (12) se rend au panier lors du match contre Troy le 18 mars 2016. La r\u00e9ussite&#8230;<\/p>\n","protected":false},"author":96107080,"featured_media":113795,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[415860779,415864357,185277949,415866923,415867729,119898416,415868108,99144891,415871830,415874303,25678],"post_format":"standard","sport":[1985],"game":[],"coauthors":[415804048],"class_list":["post-113793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-adut-bulgak","tag-final-four","tag-jamie-weisner","tag-julia-chandler","tag-kaili-lukan","tag-kia-nurse","tag-kolbie-orum","tag-lisa-thomaidis","tag-quinn-dornstauder","tag-ruth-hamblin","tag-team-canada","sport-basketball"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/03\/orum.jpg?quality=100","author_name":["Don Schram"],"category_names":["Nouvelles"],"tag_names":["Adut Bulgak","Final Four","Jamie Weisner","Julia Chandler","Kaili Lukan","Kia Nurse","Kolbie Orum","Lisa Thomaidis","Quinn Dornstauder","Ruth Hamblin","team canada"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-tBn","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/03\/orum.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/113793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/96107080"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=113793"}],"version-history":[{"count":4,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/113793\/revisions"}],"predecessor-version":[{"id":191505,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/113793\/revisions\/191505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/113795"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=113793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=113793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=113793"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=113793"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=113793"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=113793"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=113793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}