{"id":114907,"date":"2016-05-09T13:26:45","date_gmt":"2016-05-09T17:26:45","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=114907"},"modified":"2016-10-03T13:29:52","modified_gmt":"2016-10-03T17:29:52","slug":"mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/","title":{"rendered":"Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus"},"content":{"rendered":"<h1>D&rsquo;une m\u00e9daille aux Mondiaux de marche rapide \u00e0 \u00a0une qualification olympique en lutte, \u00c9quipe Canada continue de gravir les podiums en vue des <a href=\"http:\/\/develop.olympic.ca\/olympique\/games\/2016-rio\/\">Jeux olympiques de Rio<\/a>.<\/h1>\n<p>Un sport d&rsquo;hiver revient aussi sur notre radar alors que le Canada accumule les victoires au Mondial de hockey.<\/p>\n<h2>Cyclisme \u2014 BMX<\/h2>\n<div id=\"attachment_114908\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-114908\" class=\"wp-image-114908 size-full\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2016\/05\/nyhaug-papendal.jpg?quality=75\" alt=\"Tory Nyhaug c\u00e9l\u00e9bre sa troisi\u00e8me victoire cons\u00e9cutive \u00e0 Papendel, aux Pays Bas. (Photo : UCI BMX Supercross)\" width=\"1024\" height=\"576\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/nyhaug-papendal.jpg 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/nyhaug-papendal.jpg?resize=280,158 280w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/nyhaug-papendal.jpg?resize=660,371 660w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/nyhaug-papendal.jpg?resize=768,432 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-114908\" class=\"wp-caption-text\">Tory Nyhaug c\u00e9l\u00e9bre sa troisi\u00e8me victoire cons\u00e9cutive \u00e0 Papendal, aux Pays Bas. (Photo : UCI BMX Supercross)<\/p><\/div>\n<p>Le Canadien <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/tory-nyhaug-heinonen-1\/\">Tory Nyhaug<\/a> continue de dominer les \u00e9preuves du contre-la-montre sur le circuit de la Coupe du monde de BMX. \u00c0 Papendal, aux Pays-Bas, Nyhaug s\u2019est empar\u00e9 de sa troisi\u00e8me m\u00e9daille d\u2019or en autant de comp\u00e9tition cette saison. Son chrono de 36,861 secondes a \u00e9t\u00e9 le meilleur de la journ\u00e9e devant ceux de l\u2019\u00c9quatorien Alfredi Campo (37,185\u00a0s) et du Fran\u00e7ais Amidou Mir (37,276\u00a0s).<\/p>\n<h2>Athl\u00e9tisme \u2014 Marche rapide<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\">Canada celebrates winning team silver. Well done guys! <a href=\"https:\/\/twitter.com\/hashtag\/Rome2016?src=hash\">#Rome2016<\/a> <a href=\"https:\/\/t.co\/y2KYGSScVQ\">pic.twitter.com\/y2KYGSScVQ<\/a><\/p>\n<p>&mdash; IAAF (@iaaforg) <a href=\"https:\/\/twitter.com\/iaaforg\/status\/728978235715923969\">May 7, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>L\u2019\u00e9quipe canadienne form\u00e9e de <a href=\"http:\/\/develop.olympic.ca\/olympique\/2015\/08\/22\/les-canadiens-en-bonne-position-apres-le-1er-jour-des-mondiaux-dathletisme\/\">Ben Thorne<\/a>, <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/inaki-gomez-2\/\">Inaki Gomez<\/a> et <a href=\"http:\/\/develop.olympic.ca\/olympique\/2015\/12\/13\/dunfee-bat-un-record-canadien-vieux-de-34-ans-en-marche-rapide\/\">Evan Dunfee<\/a> a pris le deuxi\u00e8me rang de l\u2019\u00e9preuve de la marche rapide aux Mondiaux par \u00e9quipes tenus \u00e0 Rome ce week-end. Thorne a \u00e9t\u00e9 le premier de la formation canadienne \u00e0 franchir la ligne d\u2019arriv\u00e9e en parcourant les 20\u00a0km r\u00e8glementaires en un temps d\u2019une heure, 19 minutes et 55 secondes. <a href=\"http:\/\/develop.olympic.ca\/olympique\/2015\/08\/22\/les-canadiens-en-bonne-position-apres-le-1er-jour-des-mondiaux-dathletisme\/\">Celui qui avait remport\u00e9 le bronze aux Championnats du monde de 2015<\/a> avec un temps plus lent de deux secondes a pris le cinqui\u00e8me rang en Italie. Inaki Gomez a termin\u00e9 la course au septi\u00e8me rang (1\u00a0: 20,12\u00a0s) et Evan Dunffee a franchi la ligne d\u2019arriv\u00e9e peu de temps apr\u00e8s (1\u00a0: 21,26\u00a0s) pour prendre le 15<sup>e<\/sup> rang. Les Canadiens ont obtenu 27 points pour leurs performances pour terminer deuxi\u00e8mes, derri\u00e8re les Chinois (16 points).<\/p>\n<h2>Escrime<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"fr\" dir=\"ltr\">Gold in London! L&#39;Or \u00e0 Londres <a href=\"https:\/\/twitter.com\/hashtag\/RoadToRio?src=hash\">#RoadToRio<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/fencing?src=hash\">#fencing<\/a> <a href=\"https:\/\/twitter.com\/TeamCanada\">@TeamCanada<\/a> <a href=\"https:\/\/twitter.com\/FencingCanada\">@FencingCanada<\/a> <a href=\"https:\/\/twitter.com\/NikeTeamCanada\">@NikeTeamCanada<\/a> <a href=\"https:\/\/twitter.com\/OlympiqueCanada\">@OlympiqueCanada<\/a> <a href=\"https:\/\/t.co\/lCAQNHuJzz\">pic.twitter.com\/lCAQNHuJzz<\/a><\/p>\n<p>&mdash; Joseph Polossifakis (@Polo4Rio) <a href=\"https:\/\/twitter.com\/Polo4Rio\/status\/728993523106758656\">May 7, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p><a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/03\/30\/cinq-escrimeurs-officieusement-qualifies-pour-rio\/\">D\u00e9j\u00e0 qualifi\u00e9 pour Rio\u00a02016<\/a>, le sabreur <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/joseph-polossifakis\/\">Joseph Polossifakis<\/a> a ajout\u00e9 une autre m\u00e9daille \u00e0 sa collection au courant du week-end. Celui qu\u2019on a pu voir au <a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/04\/12\/devoilement-de-la-collection-officielle-dequipe-canada-pour-rio-2016\/\">d\u00e9voilement de la collection officielle d\u2019\u00c9quipe Canada<\/a> a d\u00e9croch\u00e9 l\u2019or \u00e0 la Coupe Cole \u00e0 Londres, au Royaume-Uni, en d\u00e9faisant le Britannique James Honeybone en finale. On retrouvera le double m\u00e9daill\u00e9 des Jeux panam\u00e9ricains en ao\u00fbt prochain \u00e0 l\u2019\u00e9preuve individuelle du sabre masculin.<\/p>\n<h2>Lutte libre<\/h2>\n<p>Le double olympien <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/haislan-garcia\/\">Haislan Garcia<\/a> ira \u00e0 ses troisi\u00e8mes Jeux olympiques en carri\u00e8re apr\u00e8s avoir remport\u00e9 l\u2019or au second\u00a0tournoi mondial de qualification olympique \u00e0 Istanbul en Turquie. L\u2019athl\u00e8te de 33 ans a r\u00e9ussi \u00e0 atteindre la finale des 65\u00a0kg, malgr\u00e9 une dislocation de l\u2019\u00e9paule au tour pr\u00e9c\u00e9dent. Le simple fait d\u2019atteindre la finale a permis \u00e0 Haislan de mettre la main sur une qualification olympique. Cependant, le lutteur canadien a eu le dessus sur le Bulgare Borislav Novachkov pour remporter l\u2019or.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/Hgarcia66\">@Hgarcia66<\/a> wins a close 2-2 match vs. Bucur (ROM) in the semis and qualifies for Rio! <a href=\"https:\/\/twitter.com\/hashtag\/LastChance2Rio?src=hash\">#LastChance2Rio<\/a> <a href=\"https:\/\/twitter.com\/TeamCanada\">@TeamCanada<\/a> <a href=\"https:\/\/t.co\/JRJjRAP2jp\">pic.twitter.com\/JRJjRAP2jp<\/a><\/p>\n<p>&mdash; WrestlingCanadaLutte (@WrestlingCanada) <a href=\"https:\/\/twitter.com\/WrestlingCanada\/status\/729311996378636288\">May 8, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Il rejoint le lutteur <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/korey-jarvis\/\">Korey Jarvis<\/a> (125\u00a0kg) et les lutteuses Jasmine Mian (48\u00a0kg), Jillian Gallays (53\u00a0kg), <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/michelle-fazzari\/\">Michelle Fazzari<\/a> (58\u00a0kg), Danielle Lappage (63\u00a0kg), Dori Yeats (69\u00a0kg) et Erica Wiebe (75\u00a0kg) au sein de l\u2019\u00e9quipe de Wresting Canada Lutte qui repr\u00e9sentera le pays \u00e0 Rio.<\/p>\n<h2>Taekwondo<\/h2>\n<p>[coc_content_zones zone=\u00a0\u00bbStory &#8211; Melissa Pagnotta s\u00e9lectionn\u00e9e pour Rio 2016 en Taekwondo\u00a0\u00bb]<\/p>\n<p>Taekwondo Canada a annonc\u00e9 que <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/melissa-pagnotta\/\">Melissa Pagnotta<\/a> \u00e9tait nomm\u00e9e \u00e0 la d\u00e9l\u00e9gation canadienne qui s\u2019envolera pour les Jeux olympiques de Rio en ao\u00fbt prochain. Celle qu\u2019on a pu voir sur la passerelle lors du\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/04\/12\/devoilement-de-la-collection-officielle-dequipe-canada-pour-rio-2016\/\">d\u00e9voilement de la collection officielle<\/a>\u00a0d\u2019\u00c9quipe Canada pour <a href=\"http:\/\/develop.olympic.ca\/olympique\/games\/2016-rio\/\">Rio\u00a02016 <\/a>repr\u00e9sentera le pays dans la cat\u00e9gorie des moins de 67\u00a0kg.<\/p>\n<h2>Tir<\/h2>\n<p>[coc_content_zones zone=\u00a0\u00bbStory &#8211; Les tireuses Cynthia Meyer et Lynda Kiejko s\u00e9lectionn\u00e9es pour Rio 2016&Prime;]<\/p>\n<p>Jeudi, <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/cynthia-meyer\/\">Cynthia Meyer<\/a> et <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/lynda-kiejko\/\">Lynda Kiejko<\/a> ont \u00e9t\u00e9 choisies pour se joindre \u00e0 la d\u00e9l\u00e9gation canadienne qui s\u2019envolera pour les Jeux olympiques de Rio. Les deux tireuses sont les 28e et 29e athl\u00e8tes nomm\u00e9es \u00e0 l\u2019\u00e9quipe olympique canadienne. Cynthia repr\u00e9sentera le pays dans l\u2019\u00e9preuve du tir \u00e0 la fosse alors que\u00a0Lynda sera sur la ligne de tir des \u00e9preuves du pistolet \u00e0 air comprim\u00e9 10\u00a0m et du pistolet 25\u00a0m.<\/p>\n<h2>Hockey<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-114909\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2016\/05\/cody-ceci.jpg?quality=100\" alt=\"cody-ceci\" width=\"670\" height=\"377\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/cody-ceci.jpg 670w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/cody-ceci.jpg?resize=280,158 280w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/cody-ceci.jpg?resize=660,371 660w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p>Le Canada poursuit son chemin sur l\u2019autoroute de la victoire au Mondial de Hockey. Apr\u00e8s avoir <a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/05\/06\/mondial-de-hockey-le-canada-bat-les-e-u-a-son-match-douverture\/\">battu les \u00c9tats-Unis \u00e0 son match d\u2019ouverture<\/a> au compte de 5 \u00e0 1, le Canada a ensuite d\u00e9fait la Hongrie par la marque de 7 \u00e0 1 dimanche. \u00c0 leur troisi\u00e8mes match, lundi , les repr\u00e9sentants de l\u2019unifoli\u00e9 \u00e9cras\u00e9 les\u00a0Bi\u00e9lorusses 8 \u00e0 0.<\/p>\n<p>Le Championnat du monde IIHF se poursuit jusqu\u2019au 22 mai et les Canadiens comptent d\u00e9fendre avec succ\u00e8s leur titre de champions.<\/p>\n<h2>Tennis<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Raonic?src=hash\">#Raonic<\/a> begins his Rome campaign with a 6-4, 4-6, 6-4 win over Cecchinato. Up next: Nick Kyrgios. <a href=\"https:\/\/twitter.com\/hashtag\/CdnTennis?src=hash\">#CdnTennis<\/a> <a href=\"https:\/\/t.co\/y75DljXBqB\">pic.twitter.com\/y75DljXBqB<\/a><\/p>\n<p>&mdash; Tennis Canada (@TennisCanada) <a href=\"https:\/\/twitter.com\/TennisCanada\/status\/729652262784643072\">May 9, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Quelques jours apr\u00e8s avoir baiss\u00e9 pavillon face au num\u00e9ro\u00a01 mondial Novak Djokovic en quarts de finale des Masters de Madrid, <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/milos-raonic\/\">Milos Raonic<\/a> est de retour sur les courts de terre battue, mais cette fois-ci \u00e0 Rome. Celui qui <a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/04\/28\/avril-a-aout-raonic-pret-pour-le-dernier-sprint-jusqua-rio\/\">peaufine sa pr\u00e9paration en vue du Grand Chelem de Roland Garros<\/a> est \u00e0\u00a0Rome pour les Internationaux d\u2019Italie. Il est pass\u00e9 au deuxi\u00e8me tour du tableau principal lundi en d\u00e9faisant le favori de la foule, Marco Cecchinato, en trois manches difficiles de 6-4, 4-6 et 6-4.<\/p>\n<p>Le Canadien affrontera l\u2019Australien Nick Kyrgios au prochain tour.<\/p>\n<h2>Volleyball de plage<\/h2>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Beach?src=hash\">#Beach<\/a> update: Binstock &amp; Schachter advance at the <a href=\"https:\/\/twitter.com\/hashtag\/SochiOpen?src=hash\">#SochiOpen<\/a> after def. ESP in Rnd 2. Pedlow &amp; O&#39;Gorman finish 9th. <a href=\"https:\/\/t.co\/k4WThNvIFJ\">pic.twitter.com\/k4WThNvIFJ<\/a><\/p>\n<p>&mdash; Volleyball Canada (@VBallCanada) <a href=\"https:\/\/twitter.com\/VBallCanada\/status\/728639292675870720\">May 6, 2016<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Le duo form\u00e9 de <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/josh-binstock-1\/\">Josh Binstock<\/a> et <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/sam-schachter\/\">Sam Schachter<\/a> a pris le cinqui\u00e8me rang de l\u2019Open de Sotchi samedi. Ce r\u00e9sultat permettra aux Canadiens d\u2019am\u00e9liorer leur classement mondial en vue d\u2019une possible qualification pour les Jeux de Rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D&rsquo;une m\u00e9daille aux Mondiaux de marche rapide \u00e0 \u00a0une qualification olympique en lutte, \u00c9quipe Canada continue de gravir les podiums&#8230;<\/p>\n","protected":false},"author":96107080,"featured_media":114910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[415983115,415983059,140282604,192281910,51059070,252055312,415737976,362729617,78161950,252338395,415785371,415642074,23905354,254466742,100611870],"post_format":"standard","sport":[48770,87705088,5515721,891977,415983001,19815,1999,117238,10149896],"game":[415984561],"coauthors":[209272438],"class_list":["post-114907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-ben-thorne","tag-cynthia-meyer","tag-danielle-lappage","tag-haislan-garcia","tag-inaki-gomez","tag-jasmine-mian","tag-jillian-gallays","tag-joseph-polossifakis","tag-josh-binstock","tag-korey-jarvis","tag-melissa-pagnotta","tag-michelle-fazzari","tag-milos-raonic","tag-sam-schachter","tag-tory-nyhaug","sport-athletisme","sport-bmx","sport-escrime","sport-hockey-sur-glace","sport-lutte","sport-taekwondo","sport-tennis","sport-tir","sport-volleyball-de-plage","game-2016-rio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"D&rsquo;une m\u00e9daille aux Mondiaux de marche rapide \u00e0 \u00a0une qualification olympique en lutte, \u00c9quipe Canada continue de gravir les podiums...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-09T17:26:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-03T17:29:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/garcia.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ariane Desrosiers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ariane Desrosiers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/\"},\"author\":{\"name\":\"Ariane Desrosiers\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\"},\"headline\":\"Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus\",\"datePublished\":\"2016-05-09T17:26:45+00:00\",\"dateModified\":\"2016-10-03T17:29:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/\"},\"wordCount\":952,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/05\\\/garcia.jpg?quality=100\",\"keywords\":[\"Ben Thorne\",\"Cynthia Meyer\",\"Danielle Lappage\",\"Haislan Garcia\",\"Inaki Gomez\",\"Jasmine Mian\",\"Jillian Gallays\",\"Joseph Polossifakis\",\"Josh Binstock\",\"Korey Jarvis\",\"Melissa Pagnotta\",\"Michelle Fazzari\",\"Milos Raonic\",\"Sam Schachter\",\"Tory Nyhaug\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/\",\"name\":\"Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/05\\\/garcia.jpg?quality=100\",\"datePublished\":\"2016-05-09T17:26:45+00:00\",\"dateModified\":\"2016-10-03T17:29:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2016\\\/05\\\/09\\\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/05\\\/garcia.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/05\\\/garcia.jpg?quality=100\",\"width\":670,\"height\":377,\"caption\":\"Haislan Garcia (en bleu) lors du second tournoi mondial de qualification olympique. (Gregory Bull)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\",\"name\":\"Ariane Desrosiers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=gbd92884420bbfa56539e46241678b7d5\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g\",\"caption\":\"Ariane Desrosiers\"},\"description\":\"Specialist, Social Sp\u00e9cialiste, M\u00e9dias num\u00e9riques\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/arianedesrosiers\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/","og_locale":"fr_FR","og_type":"article","og_title":"Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus - \u00c9quipe Canada","og_description":"D&rsquo;une m\u00e9daille aux Mondiaux de marche rapide \u00e0 \u00a0une qualification olympique en lutte, \u00c9quipe Canada continue de gravir les podiums...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2016-05-09T17:26:45+00:00","article_modified_time":"2016-10-03T17:29:52+00:00","og_image":[{"width":670,"height":377,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/garcia.jpg?quality=100","type":"image\/jpeg"}],"author":"Ariane Desrosiers","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ariane Desrosiers","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/"},"author":{"name":"Ariane Desrosiers","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2"},"headline":"Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus","datePublished":"2016-05-09T17:26:45+00:00","dateModified":"2016-10-03T17:29:52+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/"},"wordCount":952,"commentCount":0,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/garcia.jpg?quality=100","keywords":["Ben Thorne","Cynthia Meyer","Danielle Lappage","Haislan Garcia","Inaki Gomez","Jasmine Mian","Jillian Gallays","Joseph Polossifakis","Josh Binstock","Korey Jarvis","Melissa Pagnotta","Michelle Fazzari","Milos Raonic","Sam Schachter","Tory Nyhaug"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/","url":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/","name":"Mise \u00e0 jour olympique: M\u00e9daille aux Mondiaux, qualifications olympiques et bien plus - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/garcia.jpg?quality=100","datePublished":"2016-05-09T17:26:45+00:00","dateModified":"2016-10-03T17:29:52+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2016\/05\/09\/mise-a-jour-olympique-medaille-aux-mondiaux-qualifications-olympiques-et-bien-plus\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/garcia.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/garcia.jpg?quality=100","width":670,"height":377,"caption":"Haislan Garcia (en bleu) lors du second tournoi mondial de qualification olympique. (Gregory Bull)"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2","name":"Ariane Desrosiers","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=gbd92884420bbfa56539e46241678b7d5","url":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g","caption":"Ariane Desrosiers"},"description":"Specialist, Social Sp\u00e9cialiste, M\u00e9dias num\u00e9riques","url":"https:\/\/develop.olympic.ca\/olympique\/author\/arianedesrosiers\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/garcia.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2016\/05\/garcia.jpg?quality=100","author_name":["Ariane Desrosiers"],"category_names":["Nouvelles"],"tag_names":["Ben Thorne","Cynthia Meyer","Danielle Lappage","Haislan Garcia","Inaki Gomez","Jasmine Mian","Jillian Gallays","Joseph Polossifakis","Josh Binstock","Korey Jarvis","Melissa Pagnotta","Michelle Fazzari","Milos Raonic","Sam Schachter","Tory Nyhaug"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-tTl","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/114907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/96107080"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=114907"}],"version-history":[{"count":5,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/114907\/revisions"}],"predecessor-version":[{"id":124624,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/114907\/revisions\/124624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/114910"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=114907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=114907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=114907"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=114907"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=114907"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=114907"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=114907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}