{"id":125891,"date":"2017-01-09T17:08:20","date_gmt":"2017-01-09T22:08:20","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=125891"},"modified":"2017-01-09T22:38:42","modified_gmt":"2017-01-10T03:38:42","slug":"mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/","title":{"rendered":"Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force"},"content":{"rendered":"<h1>Les athl\u00e8tes d&rsquo;\u00c9quipe Canada \u00e9taient de retour \u00e0\u00a0l&rsquo;action ce week-end alors que\u00a0plusieurs d&rsquo;entre eux ont mis la main sur\u00a0les premi\u00e8res m\u00e9dailles de 2017.<\/h1>\n<p>Voici les plus r\u00e9centes nouvelles:<\/p>\n<h2>Bobsleigh<\/h2>\n<p><strong>\u00c0 LIRE :\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/2017\/01\/06\/reunies-a-altenberg-humphries-et-lotholz-signent-leur-premiere-victoire-de-2017\/\">Humphries et Lotholz signent leur premi\u00e8re victoire de 2017<\/a><\/strong><\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BO9IJLXAEeX\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/BO9IJLXAEeX\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/BO9IJLXAEeX\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Kaillie Humphries   OLY (@kailliehumphries)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<p>Les bobeuses canadiennes\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/kaillie-humphries\/\">Kaillie Humphries<\/a>\u00a0et\u00a0Melissa Lothloz ont renou\u00e9 avec le podium au cours du week-end. Les championnes en titre de la derni\u00e8re campagne de coupe du monde ont fait \u00e9quipe pour la premi\u00e8re fois cette saison \u00e0 Altenberg, en Allemagne, vendredi. Leur victoire a procur\u00e9 \u00e0 Humphries son troisi\u00e8me podium cons\u00e9cutif de la saison apr\u00e8s avoir r\u00e9colt\u00e9 <a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/12\/04\/kaillie-humphries-raflent-lor-a-whistler\/\">l&rsquo;or \u00e0 Whistler<\/a> et <a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/12\/16\/bobsleigh-trois-medailles-pour-les-equipages-canadiens-a-lake-placid\/\">le bronze \u00e0 Lake Placid<\/a> avec\u00a0Cynthia Appiah.<\/p>\n<h2>Snowboard \u2013 Big Air<\/h2>\n<p><strong>\u00c0 LIRE :\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/2017\/01\/07\/big-air-antoine-truchon-renoue-avec-le-podium-a-moscou\/\">Antoine Truchon renoue avec le podium \u00e0 Moscou<\/a><\/strong><\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1360\" height=\"765\" src=\"https:\/\/www.youtube.com\/embed\/u0c4QPi1pM0?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>Antoine Truchon s&rsquo;est illustr\u00e9 lors de son retour sur le circuit de la coupe du monde, remportant l&rsquo;argent \u00e0 l&rsquo;\u00e9preuve big air de Moscou. \u00a0Il s&rsquo;agissait d&rsquo;un premier podium en coupe du monde en presque trois ans pour le planchiste canadien.<\/p>\n<h2>Ski de fond<\/h2>\n<p><strong>\u00c0 LIRE:\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/2017\/01\/04\/premier-podium-de-la-saison-pour-alex-harvey-au-tour-de-ski\/\">Premier podium de la saison pour Alex Harvey au Tour de Ski<\/a><\/strong><\/p>\n<div id=\"attachment_149195\" style=\"width: 1370px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-149195\" class=\"wp-image-149195 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/01\/14017530.jpg?quality=100\" alt=\"Alex Harvey lors du tour de ski d'Oberstdorf, en Allemagne, le 4 janvier 2017. (Karl-Josef Hildenbrand\/dpa via AP)\" width=\"1360\" height=\"910\" \/><p id=\"caption-attachment-149195\" class=\"wp-caption-text\">Alex Harvey lors du tour de ski d&rsquo;Oberstdorf, en Allemagne, le 4 janvier 2017. (Karl-Josef Hildenbrand\/dpa via AP)<\/p><\/div>\n<p><a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-harvey\/\">Alex Harvey<\/a> s&rsquo;est fray\u00e9 un chemin vers son premier podium de la saison \u00e0\u00a0Oberstdorf, en Allemangne, terminant au troisi\u00e8me \u00e9chelon en poursuite. Sa m\u00e9daille de bronze est survenue \u00e0 l&rsquo;occasion du quatri\u00e8me arr\u00eat du Tour de ski, un \u00e9v\u00e9nement\u00a0o\u00f9 les skieurs prennent part \u00e0 sept types de courses se d\u00e9roulant sur quatre sites dans trois pays diff\u00e9rents, le tout \u00e9tal\u00e9 sur neuf jours.<\/p>\n<h2>Tennis<\/h2>\n<div id=\"attachment_149238\" style=\"width: 1350px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-149238\" class=\"wp-image-149238 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/01\/raonic2.jpg?quality=100\" alt=\"Milos Raonic c\u00e9l\u00e8bre sa victoire face \u00e0 Rafa Nadal au tournoi de Brisbane, le 6 janvier 2017.\" width=\"1340\" height=\"754\" \/><p id=\"caption-attachment-149238\" class=\"wp-caption-text\">Milos Raonic c\u00e9l\u00e8bre sa victoire face \u00e0 Rafa Nadal au tournoi de Brisbane, le 6 janvier 2017.<\/p><\/div>\n<p>Aux Internationaux de Brisbane, <a href=\"http:\/\/develop.olympic.ca\/olympique\/2016\/07\/04\/raonic-accede-aux-quarts-de-finale-a-wimbledon\/\">Milos Raonic<\/a> m\u00e8ne la charge du c\u00f4t\u00e9 canadien. Raonic est revenu de l&rsquo;arri\u00e8re pour l&#8217;emporter\u00a04-6, 6-3, 6-4 face \u00e0 l\u2019Espagnol Rafael Nadal et acc\u00e9der aux demi-finales.<\/p>\n<p>Au tournoi f\u00e9minin de Sydney, <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/eugenie-bouchard\/\">Eugenie Bouchard<\/a> a sign\u00e9 sa premi\u00e8re victoire de la saison en battant la Chinoise\u00a0Zhang Shuai pour passer au second tour.<\/p>\n<p><a href=\"https:\/\/twitter.com\/OlympiqueCanada\"><img decoding=\"async\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2016\/09\/twitter_frsocial-ads.png\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les athl\u00e8tes d&rsquo;\u00c9quipe Canada \u00e9taient de retour \u00e0\u00a0l&rsquo;action ce week-end alors que\u00a0plusieurs d&rsquo;entre eux ont mis la main sur\u00a0les premi\u00e8res&#8230;<\/p>\n","protected":false},"author":82363705,"featured_media":125900,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[5407300,415681950,14359971,26998573,23905354],"post_format":"standard","sport":[41495,181823552,18758654,1999],"game":[],"coauthors":[361304908],"class_list":["post-125891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-alex-harvey","tag-antoine-truchon","tag-eugenie-bouchard","tag-kaillie-humphries","tag-milos-raonic","sport-bobsleigh","sport-ski-ski-de-fond","sport-snowboard","sport-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Les athl\u00e8tes d&rsquo;\u00c9quipe Canada \u00e9taient de retour \u00e0\u00a0l&rsquo;action ce week-end alors que\u00a0plusieurs d&rsquo;entre eux ont mis la main sur\u00a0les premi\u00e8res...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-09T22:08:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-10T03:38:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/humphries-lotholz.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Wallace\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Wallace\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/\"},\"author\":{\"name\":\"camillecw\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/a54bcce73a540b75e1ecc8278380dbad\"},\"headline\":\"Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force\",\"datePublished\":\"2017-01-09T22:08:20+00:00\",\"dateModified\":\"2017-01-10T03:38:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/\"},\"wordCount\":404,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/01\\\/humphries-lotholz.jpg?quality=100\",\"keywords\":[\"alex harvey\",\"Antoine Truchon\",\"Eugenie Bouchard\",\"Kaillie Humphries\",\"Milos Raonic\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/\",\"name\":\"Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/01\\\/humphries-lotholz.jpg?quality=100\",\"datePublished\":\"2017-01-09T22:08:20+00:00\",\"dateModified\":\"2017-01-10T03:38:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/a54bcce73a540b75e1ecc8278380dbad\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/09\\\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/01\\\/humphries-lotholz.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/01\\\/humphries-lotholz.jpg?quality=100\",\"width\":1010,\"height\":568},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/a54bcce73a540b75e1ecc8278380dbad\",\"name\":\"camillecw\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g28bb7f2a5d773e6db038cfb832182831\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g\",\"caption\":\"camillecw\"},\"sameAs\":[\"http:\\\/\\\/camillecw.wordpress.com\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/camillecw\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/","og_locale":"fr_FR","og_type":"article","og_title":"Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Les athl\u00e8tes d&rsquo;\u00c9quipe Canada \u00e9taient de retour \u00e0\u00a0l&rsquo;action ce week-end alors que\u00a0plusieurs d&rsquo;entre eux ont mis la main sur\u00a0les premi\u00e8res...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2017-01-09T22:08:20+00:00","article_modified_time":"2017-01-10T03:38:42+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/humphries-lotholz.jpg?quality=100","type":"image\/jpeg"}],"author":"Camille Wallace","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Wallace","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/"},"author":{"name":"camillecw","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/a54bcce73a540b75e1ecc8278380dbad"},"headline":"Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force","datePublished":"2017-01-09T22:08:20+00:00","dateModified":"2017-01-10T03:38:42+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/"},"wordCount":404,"commentCount":0,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/humphries-lotholz.jpg?quality=100","keywords":["alex harvey","Antoine Truchon","Eugenie Bouchard","Kaillie Humphries","Milos Raonic"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/","url":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/","name":"Mise \u00e0 jour olympique: les athl\u00e8tes canadiens amorcent 2017 en force - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/humphries-lotholz.jpg?quality=100","datePublished":"2017-01-09T22:08:20+00:00","dateModified":"2017-01-10T03:38:42+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/a54bcce73a540b75e1ecc8278380dbad"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/mise-a-jour-olympique-les-athletes-canadiens-amorcent-2017-en-force\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/humphries-lotholz.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/humphries-lotholz.jpg?quality=100","width":1010,"height":568},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/a54bcce73a540b75e1ecc8278380dbad","name":"camillecw","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g28bb7f2a5d773e6db038cfb832182831","url":"https:\/\/secure.gravatar.com\/avatar\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g","caption":"camillecw"},"sameAs":["http:\/\/camillecw.wordpress.com"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/camillecw\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/humphries-lotholz.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/humphries-lotholz.jpg?quality=100","author_name":["Camille Wallace"],"category_names":["Uncategorized"],"tag_names":["alex harvey","Antoine Truchon","Eugenie Bouchard","Kaillie Humphries","Milos Raonic"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-wKv","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/82363705"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=125891"}],"version-history":[{"count":4,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125891\/revisions"}],"predecessor-version":[{"id":125911,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125891\/revisions\/125911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/125900"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=125891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=125891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=125891"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=125891"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=125891"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=125891"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=125891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}