{"id":125922,"date":"2017-01-11T11:06:09","date_gmt":"2017-01-11T16:06:09","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=125922"},"modified":"2017-01-11T11:09:09","modified_gmt":"2017-01-11T16:09:09","slug":"eugenie-bouchard-en-demi-finale-a-sydney","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/","title":{"rendered":"Eugenie Bouchard en demi-finale \u00e0 Sydney"},"content":{"rendered":"<h1><a href=\"http:\/\/Eugenie Bouchard\">Eugenie Bouchard<\/a> continue d&rsquo;accumuler les victoires en Australie. La Canadienne a dispos\u00e9 de la Russe Anastasia Pavlyuchenkova 6-2, 6-3 pour se tailler une place dans le\u00a0carr\u00e9 d&rsquo;as des Internationaux de Sydney.<\/h1>\n<p>Bouchard a poursuivi sa pr\u00e9paration en vue des Internationaux d&rsquo;Australie, premier Grand Chelem de la saison, en r\u00e9coltant sa troisi\u00e8me victoire face \u00e0 une adversaire du top 30 au classement de la WTA. Sa plus r\u00e9cente conqu\u00eate fut aux d\u00e9pens de la 27e joueuse mondiale.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\">.<a href=\"https:\/\/twitter.com\/geniebouchard\">@GenieBouchard<\/a> sails into <a href=\"https:\/\/twitter.com\/SydneyTennis\">@SydneyTennis<\/a> Semifinals with 6-2, 6-3 win over Pavlyuchenkova! <a href=\"https:\/\/t.co\/qAuHXohioX\">pic.twitter.com\/qAuHXohioX<\/a><\/p>\n<p>&mdash; WTA (@WTA) <a href=\"https:\/\/twitter.com\/WTA\/status\/819067516911689730\">January 11, 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p><strong>\u00c0 LIRE :\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/eugenie-bouchard-atteint-ses-premiers-quarts-de-finale-de-2017-a-sydney\/\">Eugenie Bouchard atteint ses premiers quarts de finale de 2017 \u00e0 Sydney<\/a><\/strong><\/p>\n<p>Bouchard, 47e raquette au monde, connait un parcours exceptionnel jusqu&rsquo;\u00e0 pr\u00e9sent. Plus t\u00f4t en semaine, la Qu\u00e9b\u00e9coise de Westmount <a href=\"http:\/\/develop.olympic.ca\/olympique\/2017\/01\/09\/eugenie-bouchard-atteint-ses-premiers-quarts-de-finale-de-2017-a-sydney\/\">a \u00e9cart\u00e9\u00a0la d\u00e9tentrice du 6e rang mondial, la Slovaque Dominika Cibulkova<\/a>, en deux sets pour atteindre les quarts de finale. Bouchard avait amorc\u00e9 le tournoi de Sydney avec une victoire face \u00e0 la Chinoise\u00a0Zhang Shuai (27e).<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\">\n<p lang=\"en\" dir=\"ltr\">.<a href=\"https:\/\/twitter.com\/geniebouchard\">@GenieBouchard<\/a> with the beautiful backhand! \ud83d\udc4c <a href=\"https:\/\/twitter.com\/hashtag\/SydneyTennis?src=hash\">#SydneyTennis<\/a> <a href=\"https:\/\/t.co\/ux4vqZn1JY\">pic.twitter.com\/ux4vqZn1JY<\/a><\/p>\n<p>&mdash; WTA (@WTA) <a href=\"https:\/\/twitter.com\/WTA\/status\/819052593691271168\">January 11, 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p><strong>Related:\u00a0<a href=\"http:\/\/develop.olympic.ca\/2017\/01\/07\/bouchard-bags-first-win-of-the-season-in-sydney-over-zhang\/\">Bouchard bags first win of the season in Sydney over Zhang<\/a><\/strong><\/p>\n<p>Avec trois victoires convaincantes en poche, Bouchard croisera maintenant le fer face \u00e0 la Britannique Johanna Konta (10e) dans l&rsquo;espoir d&rsquo;obtenir son billet pour la grande finale.<\/p>\n<p><a href=\"https:\/\/twitter.com\/OlympiqueCanada\"><img decoding=\"async\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2016\/09\/twitter_frsocial-ads.png\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eugenie Bouchard continue d&rsquo;accumuler les victoires en Australie. La Canadienne a dispos\u00e9 de la Russe Anastasia Pavlyuchenkova 6-2, 6-3 pour&#8230;<\/p>\n","protected":false},"author":82363705,"featured_media":125923,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[14359971,2608,7422531,2781325],"post_format":"standard","sport":[1999],"game":[],"coauthors":[361304908],"class_list":["post-125922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-eugenie-bouchard","tag-sydney","tag-tennis-2","tag-tennis-canada","sport-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eugenie Bouchard en demi-finale \u00e0 Sydney - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eugenie Bouchard en demi-finale \u00e0 Sydney - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Eugenie Bouchard continue d&rsquo;accumuler les victoires en Australie. La Canadienne a dispos\u00e9 de la Russe Anastasia Pavlyuchenkova 6-2, 6-3 pour...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-11T16:06:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-11T16:09:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/eugenie-bouchard.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Wallace\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Wallace\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/\"},\"author\":{\"name\":\"camillecw\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/a54bcce73a540b75e1ecc8278380dbad\"},\"headline\":\"Eugenie Bouchard en demi-finale \u00e0 Sydney\",\"datePublished\":\"2017-01-11T16:06:09+00:00\",\"dateModified\":\"2017-01-11T16:09:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/\"},\"wordCount\":211,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/01\\\/eugenie-bouchard.jpg?quality=100\",\"keywords\":[\"Eugenie Bouchard\",\"sydney\",\"tennis\",\"Tennis Canada\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/\",\"name\":\"Eugenie Bouchard en demi-finale \u00e0 Sydney - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/01\\\/eugenie-bouchard.jpg?quality=100\",\"datePublished\":\"2017-01-11T16:06:09+00:00\",\"dateModified\":\"2017-01-11T16:09:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/a54bcce73a540b75e1ecc8278380dbad\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/01\\\/11\\\/eugenie-bouchard-en-demi-finale-a-sydney\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/01\\\/eugenie-bouchard.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/01\\\/eugenie-bouchard.jpg?quality=100\",\"width\":1010,\"height\":568},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/a54bcce73a540b75e1ecc8278380dbad\",\"name\":\"camillecw\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g28bb7f2a5d773e6db038cfb832182831\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g\",\"caption\":\"camillecw\"},\"sameAs\":[\"http:\\\/\\\/camillecw.wordpress.com\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/camillecw\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eugenie Bouchard en demi-finale \u00e0 Sydney - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/","og_locale":"fr_FR","og_type":"article","og_title":"Eugenie Bouchard en demi-finale \u00e0 Sydney - \u00c9quipe Canada","og_description":"Eugenie Bouchard continue d&rsquo;accumuler les victoires en Australie. La Canadienne a dispos\u00e9 de la Russe Anastasia Pavlyuchenkova 6-2, 6-3 pour...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2017-01-11T16:06:09+00:00","article_modified_time":"2017-01-11T16:09:09+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/eugenie-bouchard.jpg?quality=100","type":"image\/jpeg"}],"author":"Camille Wallace","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Wallace","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/"},"author":{"name":"camillecw","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/a54bcce73a540b75e1ecc8278380dbad"},"headline":"Eugenie Bouchard en demi-finale \u00e0 Sydney","datePublished":"2017-01-11T16:06:09+00:00","dateModified":"2017-01-11T16:09:09+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/"},"wordCount":211,"commentCount":0,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/eugenie-bouchard.jpg?quality=100","keywords":["Eugenie Bouchard","sydney","tennis","Tennis Canada"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/","url":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/","name":"Eugenie Bouchard en demi-finale \u00e0 Sydney - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/eugenie-bouchard.jpg?quality=100","datePublished":"2017-01-11T16:06:09+00:00","dateModified":"2017-01-11T16:09:09+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/a54bcce73a540b75e1ecc8278380dbad"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/01\/11\/eugenie-bouchard-en-demi-finale-a-sydney\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/eugenie-bouchard.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/eugenie-bouchard.jpg?quality=100","width":1010,"height":568},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/a54bcce73a540b75e1ecc8278380dbad","name":"camillecw","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g28bb7f2a5d773e6db038cfb832182831","url":"https:\/\/secure.gravatar.com\/avatar\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/578ce92849aedd0edca0d15b9d11b736cd1f056e9ab9139611bbdeecca368811?s=96&d=identicon&r=g","caption":"camillecw"},"sameAs":["http:\/\/camillecw.wordpress.com"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/camillecw\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/eugenie-bouchard.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/01\/eugenie-bouchard.jpg?quality=100","author_name":["Camille Wallace"],"category_names":["Uncategorized"],"tag_names":["Eugenie Bouchard","sydney","tennis","Tennis Canada"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-wL0","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/82363705"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=125922"}],"version-history":[{"count":2,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125922\/revisions"}],"predecessor-version":[{"id":125925,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/125922\/revisions\/125925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/125923"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=125922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=125922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=125922"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=125922"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=125922"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=125922"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=125922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}