{"id":127021,"date":"2017-03-14T12:22:14","date_gmt":"2017-03-14T16:22:14","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=127021"},"modified":"2017-03-14T12:24:03","modified_gmt":"2017-03-14T16:24:03","slug":"les-canadiens-a-surveiller-pendant-la-folie-du-march-madness","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/","title":{"rendered":"Les Canadiens \u00e0 surveiller pendant la folie du March Madness"},"content":{"rendered":"<h1>Certains diront que mars est le pire mois de l\u2019ann\u00e9e alors que d\u2019autres affirmeront haut et fort le contraire \u00e0 cause du March Madness!<\/h1>\n<h1>En tant qu&rsquo;ancienne joueuse de <a href=\"http:\/\/fr.usports.ca\/landing\/index\">basketball universitaire<\/a>, rien ne me rend plus f\u00e9brile\u00a0qu&rsquo;une petite comp\u00e9tition amicale. Le mois de mars est en plein essor, ce qui pour les fans de basketball comme moi, ne signifie qu&rsquo;une seule chose: que la folie du March Madness commence.<\/h1>\n<p>Dimanche avait lieu la s\u00e9lection des \u00e9quipes, ce qui signifie que les tableaux sont pr\u00eats \u00e0 \u00eatre remplis! Faites vos jeux!<\/p>\n<p>Pour voir la liste compl\u00e8te des jumelages, <a href=\"http:\/\/www.ncaa.com\/interactive-bracket\/basketball-men\/d1\/\">cliquez ici<\/a>.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BRjfLHtF8lD\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/BRjfLHtF8lD\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<p><\/a> <\/p>\n<p style=\" margin:8px 0 0 0; padding:0 4px;\"> <a href=\"https:\/\/www.instagram.com\/p\/BRjfLHtF8lD\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#000; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none; word-wrap:break-word;\" target=\"_blank\">The Bracket. #SelectionSunday<\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\">A post shared by <a href=\"https:\/\/www.instagram.com\/marchmadness\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px;\" target=\"_blank\"> NCAA March Madness<\/a> (@marchmadness) on <time style=\" font-family:Arial,sans-serif; font-size:14px; line-height:17px;\" datetime=\"2017-03-12T22:15:46+00:00\">Mar 12, 2017 at 3:15pm PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<p>Selon la plus r\u00e9cente publication du classement, il y a 13 joueurs canadiens qui \u00e9voluent parmi les dix meilleures \u00e9quipes de la ligue. Troisi\u00e8me de la section Ouest, l\u2019\u00e9quipe de l\u2019Oregon a trois Canadiens dans son alignement (dont deux en bonne forme), qui joueront tous un r\u00f4le crucial dans le succ\u00e8s de leur tournoi.<\/p>\n<p>Encore une fois, la formation qui compte le plus de Canadiens dans ses rangs est celle de New Mexico State,\u00a0class\u00e9e 14e dans la section Est, qui en compte quatre.<\/p>\n<p>En tout ce sont 25 Canadiens qui pourraient avoir du temps de jeu sur le court du tournoi de la NCAA qui d\u00e9bute le 14 mars avec la ronde\u00a0\u00ab\u00a0<em>at large \u00bb<\/em>.<\/p>\n<p>Dans l\u2019ensemble, trois provinces sont repr\u00e9sent\u00e9es au tournoi de cette ann\u00e9e\u00a0: le Qu\u00e9bec, l\u2019Ontario et la Colombie-Britannique.<\/p>\n<p>Passons sous la loupe les meilleurs espoirs canadiens du tournoi\u00a0:<\/p>\n<h2>Dillon Brooks, Mississauga (Ontario)<br \/>\nOregon<\/h2>\n<div id=\"attachment_151388\" style=\"width: 2493px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151388\" class=\"wp-image-151388 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/dillon-brooks-3.jpg?quality=100\" alt=\"\" width=\"2483\" height=\"2521\" \/><p id=\"caption-attachment-151388\" class=\"wp-caption-text\">Le joueur PAC-12 de l&rsquo;ann\u00e9e Dillon Brooks (24) tentera de mener les Ducks, troisi\u00e8mes t\u00eates de s\u00e9rie, jusqu&rsquo;en finale du championnat.\u00a0(AP Photo\/Ben Margot)<\/p><\/div>\n<p>M\u00e9daill\u00e9 d\u2019argent aux <a href=\"http:\/\/develop.olympic.ca\/olympique\/2015\/07\/25\/panam-jour-15-en-direct\/\">Jeux panam\u00e9ricains de Toronto\u00a02015<\/a>, Brooks a r\u00e9cemment \u00e9t\u00e9 nomm\u00e9 <a href=\"http:\/\/www.tsn.ca\/canada-s-dillon-brooks-earns-pac-12-basketball-honours-for-oregon-ducks-1.689240\">joueur\u00a0PAC-12 de l\u2019ann\u00e9e<\/a>. Moyennant plus de 16 points par match, Brooks a men\u00e9 les Ducks \u00e0 une fiche de 29-5 dans la saison\u00a02016-2017. Lors de la finale\u00a0PAC-12, il a remis la meilleure fiche de son \u00e9quipe (25 points) apr\u00e8s une d\u00e9faite en finale face \u00e0 l\u2019Arizona, deuxi\u00e8me t\u00eate de s\u00e9rie. Faisant partie de la troisi\u00e8me meilleure \u00e9quipe de la section Ouest, l\u2019allier junior esp\u00e8re pousser son \u00e9quipe au-del\u00e0 des finales r\u00e9gionales, o\u00f9 ils ont \u00e9t\u00e9 \u00e9limin\u00e9s par l\u2019Oklahoma l\u2019an dernier.<\/p>\n<h2>Dylan Ennis, Brampton (Ontario)<br \/>\nOregon<\/h2>\n<div id=\"attachment_151375\" style=\"width: 5010px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151375\" class=\"wp-image-151375 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/dylan-ennis.jpg?quality=100\" alt=\"\" width=\"5000\" height=\"3389\" \/><p id=\"caption-attachment-151375\" class=\"wp-caption-text\">Dylan Ennis de l&rsquo;Oregon aura beaucoup de temps de jeu avec les\u00a0Ducks dans leur affrontement de premier tour contre Iowa. (AP Photo\/Chris Pietsch)<\/p><\/div>\n<p>Fr\u00e8re cadet du membre de l\u2019\u00e9quipe nationale Tyler Ennis, Dylan suit les traces de son fr\u00e8re apr\u00e8s une saison stellaire. Le meneur senior de 6&rsquo;2&Prime; a r\u00e9alis\u00e9 en moyenne pr\u00e8s de 11 points par match cette saison et a \u00e9t\u00e9 le meneur au nombre des minutes jou\u00e9es par match chez les Ducks avec 30,7.<\/p>\n<h2>Chris Boucher, Montr\u00e9al (Qu\u00e9bec)<br \/>\nOregon<\/h2>\n<div id=\"attachment_151382\" style=\"width: 2549px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151382\" class=\"wp-image-151382 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/oregon-canadians.jpg?quality=100\" alt=\"\" width=\"2539\" height=\"1495\" \/><p id=\"caption-attachment-151382\" class=\"wp-caption-text\">Chris Boucher (25) de l&rsquo;Oregon devra encourager ses co\u00e9quipiers\u00a0Dylan Ennis (31) et\u00a0Dillon Brooks (24) des estrades cette ann\u00e9e. (AP Photo\/Elaine Thompson)<\/p><\/div>\n<p>Le troisi\u00e8me et dernier joueur canadien avec les Ducks est Chris Boucher. Le joueur de 6&rsquo;10\u00a0\u00bb de Montr\u00e9al a \u00e9t\u00e9 nomm\u00e9 pour la deuxi\u00e8me ann\u00e9e cons\u00e9cutive \u00e0 la <em>All-Defensive Team<\/em> du PAC-12. Boucher a \u00e9t\u00e9 dominant dans la bouteille, avec une moyenne de 2,6 blocs, 6,1 rebonds et 11,9 points par match. Cependant, lors de la demi-finale du PAC-12 vendredi soir, Boucher a subi une d\u00e9chirure du ligament crois\u00e9 ant\u00e9rieur, mettant ainsi fin a sa saison plus t\u00f4t que pr\u00e9vu.<\/p>\n<h2>Kimbal Mackenzie, Oakville (Ontario)<br \/>\nBucknell<\/h2>\n<div id=\"attachment_151379\" style=\"width: 472px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151379\" class=\"wp-image-151379 size-large\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/kimbal-mackenzie.jpg?quality=100&amp;w=462\" alt=\"\" width=\"462\" height=\"754\" \/><p id=\"caption-attachment-151379\" class=\"wp-caption-text\">Apr\u00e8s avoir \u00e9t\u00e9 le h\u00e9ros de la Finale de la conf\u00e9rence de la ligue des Patriotes, Kimbal Mackenzie (1) de Bucknell\u00a0aura affaire \u00e0 West Virginia au premier tour du Championnat NCAA. (AP Photo\/Chris Knight)<\/p><\/div>\n<p>Avec une moyenne de 11,3 points par match cette saison, le meneur de 6&rsquo;1&Prime; a \u00e9t\u00e9 l\u2019\u00e9toile du match lors de la Finale de conf\u00e9rence de la ligue des Patriotes avec ses 18 points. Bien que Bucknell n\u2019est pas la favorite dans le duel l\u2019opposant \u00e0 West-Virginia (quatri\u00e8me t\u00eate de s\u00e9rie) en premi\u00e8re ronde de la section Ouest, une victoire serait possible pour l\u2019\u00e9quipe de Mackenzie si le Canadien continue \u00e0 faire pleuvoir les points.<\/p>\n<h2>Elijah Long, Mississauga (Ontario)<br \/>\nMont Sainte-Marie<\/h2>\n<div id=\"attachment_151376\" style=\"width: 5719px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151376\" class=\"wp-image-151376 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/eli-long-2.jpg?quality=100\" alt=\"\" width=\"5709\" height=\"3730\" \/><p id=\"caption-attachment-151376\" class=\"wp-caption-text\">Elijah Long (55) de Mount St. Mary entamera son Championnat contre l&rsquo;Universit\u00e9 de la Nouvelle-Orl\u00e9an dans l&rsquo;espoir d&rsquo;atteindre le premier tour. (AP Photo\/Steve Ruark)<\/p><\/div>\n<p>Elijah Long est un autre Canadien qui pourrait \u00eatre \u00e0 l\u2019origine d\u2019une victoire surprise en premi\u00e8re ronde. Meneur de deuxi\u00e8me ann\u00e9e, Long fait partie de la 16e t\u00eate de s\u00e9rie de la section Est. Les Mountaineers et lui feront face \u00e0 l\u2019Universit\u00e9 de la Nouvelle-Orl\u00e9ans le 14 mars lors de la ronde \u00ab\u00a0<em>at large \u00bb<\/em>. Le vainqueur de la rencontre disputera le premier tour contre la premi\u00e8re t\u00eate de s\u00e9rie, l\u2019\u00e9quipe de Villanova, le 16 mars dans la section Est. Dans les finales de conf\u00e9rence, Long a \u00e9t\u00e9 un joueur cl\u00e9, marquant 24 points pour mener les Mountaineers \u00e0 une victoire de 71 contre 61. Elijah n\u2019est pas le seul Long du tournoi. Son fr\u00e8re Naz est un meneur avec les Cyclones de l\u2019Iowa State.<\/p>\n<h2>Naz Mitrou-Long, Mississauga (Ontario)<br \/>\nIowa State<\/h2>\n<div id=\"attachment_151380\" style=\"width: 3510px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151380\" class=\"wp-image-151380 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/naz-long-2.jpg?quality=100\" alt=\"\" width=\"3500\" height=\"2333\" \/><p id=\"caption-attachment-151380\" class=\"wp-caption-text\">Nazareth Mitrou-Long (15) de l&rsquo;Iowa State University n&rsquo;en est pas \u00e0 son premier Championnat NCAA. (AP Photo\/Scott Morgan)<\/p><\/div>\n<p>Le meneur des Cyclones cherche \u00e0 terminer sa carri\u00e8re de la NCAA sur une bonne note. L\u2019a\u00een\u00e9 des Long a termin\u00e9 la saison avec une moyenne de 15,9 points par match et a men\u00e9 son \u00e9quipe \u00e0 une fiche de 23-10. Ce qui attend Long? Un match de premi\u00e8re ronde contre le Nevada, 12e t\u00eate de s\u00e9rie dans la section Midwest. Les Cyclones, cinqui\u00e8mes t\u00eates de s\u00e9rie, cherchent \u00e0 aller au-del\u00e0 du <em>Sweet Sixteen<\/em>, o\u00f9 ils ont \u00e9t\u00e9 \u00e9limin\u00e9s l\u2019an dernier par les Cavaliers de la Virginie.<\/p>\n<h2>Xavier Rathan-Mayes, Scarborough (Ontario)<br \/>\nFlorida State<\/h2>\n<div id=\"attachment_151384\" style=\"width: 2498px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151384\" class=\"wp-image-151384 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/xavier-rathan-mayes-2.jpg?quality=100\" alt=\"\" width=\"2488\" height=\"2304\" \/><p id=\"caption-attachment-151384\" class=\"wp-caption-text\">Xavier Rathan-Mayes moyenne\u00a05 aides\u00a0par match avec les Semioles de Florida State. (AP Photo\/Steve Cannon)<\/p><\/div>\n<p>Troisi\u00e8mes favoris de la section Ouest, Rathan-Mayes et les S\u00e9mioles disputeront la premi\u00e8re manche du tournoi face \u00e0 la 14e t\u00eate de s\u00e9rie, la Florida Gulf Coast, le 16 mars. Forts d\u2019une fiche de 25-8, les S\u00e9minoles disputeront leur premier affrontement au tournoi NCAA depuis 2012. Rathan-Mayes joue un r\u00f4le cl\u00e9 dans le succ\u00e8s de l\u2019\u00e9quipe, avec une moyenne de 10,3 points, 3,0 rebonds et 4,8 passes par match.<\/p>\n<h2>Trae Bell-Haynes, Toronto (Ontario)<br \/>\nVermont<\/h2>\n<div id=\"attachment_151391\" style=\"width: 587px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151391\" class=\"wp-image-151391 size-large\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/trae-bell-haynes-e1489430726809.jpg?quality=100&amp;w=577\" alt=\"\" width=\"577\" height=\"754\" \/><p id=\"caption-attachment-151391\" class=\"wp-caption-text\">Le meneur de Vermont et le joueur de l&rsquo;ann\u00e9e de l&rsquo;America East Trae Bell-Haynes (2) tentera l&rsquo;impossible devant la redoutable \u00e9quipe de Purdue. (AP Photo\/Doug McSchooler)<\/p><\/div>\n<p>En plus de remporter le prix de l\u2019America East Player of the Year, Bell-Haynes a aid\u00e9 son \u00e9quipe \u00e0 capturer le titre de l\u2019America East, assurant ainsi sa place dans le tournoi de la NCAA. Moyennant 11,2 points, 2,5 rebonds et 3,8 passes par match, Bell-Haynes et les Catamounts ont fini la saison avec une fiche de 29-5 pour se classer au 13e rang dans la section Midwest. La Florida State affrontera Purdue, la quatri\u00e8me t\u00eate de s\u00e9rie, le 16 mars.<\/p>\n<h2>Justin Jackson, East York (Ontario)<br \/>\nMaryland<\/h2>\n<div id=\"attachment_151378\" style=\"width: 5218px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151378\" class=\"wp-image-151378 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/justin-jackson.jpg?quality=100\" alt=\"\" width=\"5208\" height=\"3522\" \/><p id=\"caption-attachment-151378\" class=\"wp-caption-text\">Le joueur de premier ann\u00e9e\u00a0Justin Jackson a \u00e9t\u00e9 l&rsquo;un des joueurs partants lors de la majorit\u00e9 des parties jou\u00e9es par l&rsquo;\u00e9quipe du Maryland cette saison.\u00a0(AP Photo\/Patrick Semansky)<\/p><\/div>\n<p>Allier de premi\u00e8re ann\u00e9e, Justin Jackson participera \u00e0 son premier tournoi NCAA class\u00e9 au sixi\u00e8me rang de la section Ouest. Le Maryland affrontera l\u2019\u00e9quipe de Xavier, 11e t\u00eate de s\u00e9rie, au premier tour. Jackson a mis en place des statistiques impressionnantes pour une recrue. L\u2019attaquant de 6&rsquo;7&Prime; a aid\u00e9 son \u00e9quipe a compl\u00e9ter la saison avec une fiche de 24-8 avec une moyenne de 10,7 points, 6,2 rebonds et 27,5 minutes par match.<\/p>\n<h2>Avis Duane, Toronto (Ontario)<br \/>\nSouth Carolina<\/h2>\n<div id=\"attachment_151373\" style=\"width: 5868px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-151373\" class=\"wp-image-151373 size-full\" src=\"https:\/\/cdnolympic.files.wordpress.com\/2017\/03\/duane-notice-2.jpg?quality=100\" alt=\"\" width=\"5858\" height=\"3910\" \/><p id=\"caption-attachment-151373\" class=\"wp-caption-text\">Le meneur de South Carolina Avis Duane (10) tentera d&rsquo;\u00e9carter l&rsquo;\u00e9quipe de Marquette au premier tour. (AP Photo\/Sean Rayford)<\/p><\/div>\n<p>Avis Duane et les Gamecocks, septi\u00e8mes t\u00eates de s\u00e9rie du tournoi, affronteront l\u2019\u00e9quipe de Marquette (11e t\u00eate de s\u00e9rie) le 17 mars dans le but d\u2019atteindre le deuxi\u00e8me tour de la section Est. Le meneur de 6&rsquo;2&Prime; qui en est \u00e0 sa derni\u00e8re ann\u00e9e sur le circuit a effectu\u00e9 en moyenne 10,4 points, 2,3 rebonds, 2,3 passes et presque 33 minutes de jeu par match cette saison pour porter la fiche des Gamecocks \u00e0 22-10.<\/p>\n<p>Si vous n\u2019avez toujours pas arr\u00eat\u00e9 votre choix <a href=\"http:\/\/www.ncaa.com\/interactive-bracket\/basketball-men\/d1\/\">sur l\u2019\u00e9quipe gagnante du tournoi<\/a>, pourquoi ne pas miser sur une formation qui compte un Canadien dans ses rangs?<\/p>\n<p>Voici la liste compl\u00e8te de tous les Canadiens dans le tournoi de la NCAA, par section.<\/p>\n<p><strong>Section Est<\/strong><\/p>\n<p>Virginia (#5)\u00a0: Mariol Shayok \u2014 M<\/p>\n<p>South Carolina (#7) : Duane Notice \u2014 M<\/p>\n<p>Providence (#11)\u00a0: Kalif Young \u2014 A<\/p>\n<p>New Mexico State (#14) : Jermaine Haley \u2014 A, Tanveer Bhuller \u2014 P, Matt Taylor \u2014 M, Jalyn Pennie \u2014 M<\/p>\n<p>Troy (#15)\u00a0: Aaron Ariri \u2014 A<\/p>\n<p>Mount Saint Mary\u2019s (#16)\u00a0: Elijah Long \u2013 M<\/p>\n<p><strong>Section Ouest<\/strong><\/p>\n<p>Gonzaga (#1) : Dustin Triano \u2014 M<\/p>\n<p>Florida St. (#3)\u00a0: Xavier Rathan-Mayes \u2014 M, Mfiondu Kabengele \u2014 A<\/p>\n<p>Notre Dame (#5)\u00a0: Nikola Djogo \u2014 A<\/p>\n<p>Maryland (#6)\u00a0: Justin Jackson \u2014 A<\/p>\n<p>VCU (#10)\u00a0: Marquell Fraser \u2014 M<\/p>\n<p>Bucknell (#13) : Kimbal Mackenzie \u2014 M<\/p>\n<p><strong>Section\u00a0Midwest<\/strong><\/p>\n<p>Oregon (#3)\u00a0: Dillon Brooks \u2014 M, Dylan Ennis \u2014 M, Chris Boucher \u2014 A (bless\u00e9)<\/p>\n<p>Iowa St. (#5)\u00a0: Naz Long \u2014 M, Ray Kasongo \u2014 A<\/p>\n<p>Vermont (#13)\u00a0: Trae Bell-Haynes &#8211; M, Drew Urquhart &#8211; A<\/p>\n<p><b>Section Sud<\/b><\/p>\n<p>Kentucky (#2)\u00a0: Mychal Mulder \u2014 M<\/p>\n<p>Kent St. (#14)\u00a0: Kevin Zabo &#8211; M, Alonzo Walker &#8211; A<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Certains diront que mars est le pire mois de l\u2019ann\u00e9e alors que d\u2019autres affirmeront haut et fort le contraire \u00e0&#8230;<\/p>\n","protected":false},"author":115369211,"featured_media":127024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[415984664,415984672,415984671,70348476,73684936,415984669,415984673,415984665,415984670,78332,415984668,42681,415984666,415984667],"post_format":"standard","sport":[1985],"game":[],"coauthors":[415984588],"class_list":["post-127021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-avis-duane","tag-championnat-ncaa","tag-chris-boucher","tag-dillon-brooks","tag-dylan-ennis","tag-elijah-long","tag-folie-du-march-madness","tag-justin-jackson","tag-kimbal-mackenzie","tag-march-madness","tag-naz-mitrou-long","tag-ncaa","tag-trae-bell-haynes","tag-xavier-rathan-mayes","sport-basketball"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Canadiens \u00e0 surveiller pendant la folie du March Madness - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Canadiens \u00e0 surveiller pendant la folie du March Madness - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Certains diront que mars est le pire mois de l\u2019ann\u00e9e alors que d\u2019autres affirmeront haut et fort le contraire \u00e0...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-14T16:22:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-14T16:24:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/03\/dillon-brooks-2-e1489425901665.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kellie Ring\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kellie Ring\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/\"},\"author\":{\"name\":\"Kellie Ring\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/f91f38a99a336138a4f4f35085e3563e\"},\"headline\":\"Les Canadiens \u00e0 surveiller pendant la folie du March Madness\",\"datePublished\":\"2017-03-14T16:22:14+00:00\",\"dateModified\":\"2017-03-14T16:24:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/\"},\"wordCount\":1700,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/03\\\/dillon-brooks-2-e1489425901665.jpg?quality=100\",\"keywords\":[\"Avis Duane\",\"championnat NCAA\",\"Chris Boucher\",\"Dillon Brooks\",\"Dylan Ennis\",\"Elijah Long\",\"Folie du March Madness\",\"Justin Jackson\",\"Kimbal Mackenzie\",\"March Madness\",\"Naz Mitrou-Long\",\"NCAA\",\"Trae Bell-Haynes\",\"Xavier Rathan-Mayes\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/\",\"name\":\"Les Canadiens \u00e0 surveiller pendant la folie du March Madness - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/03\\\/dillon-brooks-2-e1489425901665.jpg?quality=100\",\"datePublished\":\"2017-03-14T16:22:14+00:00\",\"dateModified\":\"2017-03-14T16:24:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/f91f38a99a336138a4f4f35085e3563e\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/03\\\/14\\\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/03\\\/dillon-brooks-2-e1489425901665.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/03\\\/dillon-brooks-2-e1489425901665.jpg?quality=100\",\"width\":1010,\"height\":568},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/f91f38a99a336138a4f4f35085e3563e\",\"name\":\"Kellie Ring\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1b768ecd4e2d0a9fe7ecf631430472135e9246be9aa4d11fee2659661030e40?s=96&d=identicon&r=gf07fb576d9828f56ab248db6937b8512\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1b768ecd4e2d0a9fe7ecf631430472135e9246be9aa4d11fee2659661030e40?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1b768ecd4e2d0a9fe7ecf631430472135e9246be9aa4d11fee2659661030e40?s=96&d=identicon&r=g\",\"caption\":\"Kellie Ring\"},\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/kellieintern\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Canadiens \u00e0 surveiller pendant la folie du March Madness - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Canadiens \u00e0 surveiller pendant la folie du March Madness - \u00c9quipe Canada","og_description":"Certains diront que mars est le pire mois de l\u2019ann\u00e9e alors que d\u2019autres affirmeront haut et fort le contraire \u00e0...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2017-03-14T16:22:14+00:00","article_modified_time":"2017-03-14T16:24:03+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/03\/dillon-brooks-2-e1489425901665.jpg?quality=100","type":"image\/jpeg"}],"author":"Kellie Ring","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Kellie Ring","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/"},"author":{"name":"Kellie Ring","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/f91f38a99a336138a4f4f35085e3563e"},"headline":"Les Canadiens \u00e0 surveiller pendant la folie du March Madness","datePublished":"2017-03-14T16:22:14+00:00","dateModified":"2017-03-14T16:24:03+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/"},"wordCount":1700,"commentCount":0,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/03\/dillon-brooks-2-e1489425901665.jpg?quality=100","keywords":["Avis Duane","championnat NCAA","Chris Boucher","Dillon Brooks","Dylan Ennis","Elijah Long","Folie du March Madness","Justin Jackson","Kimbal Mackenzie","March Madness","Naz Mitrou-Long","NCAA","Trae Bell-Haynes","Xavier Rathan-Mayes"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/","url":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/","name":"Les Canadiens \u00e0 surveiller pendant la folie du March Madness - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/03\/dillon-brooks-2-e1489425901665.jpg?quality=100","datePublished":"2017-03-14T16:22:14+00:00","dateModified":"2017-03-14T16:24:03+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/f91f38a99a336138a4f4f35085e3563e"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/03\/14\/les-canadiens-a-surveiller-pendant-la-folie-du-march-madness\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/03\/dillon-brooks-2-e1489425901665.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/03\/dillon-brooks-2-e1489425901665.jpg?quality=100","width":1010,"height":568},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/f91f38a99a336138a4f4f35085e3563e","name":"Kellie Ring","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c1b768ecd4e2d0a9fe7ecf631430472135e9246be9aa4d11fee2659661030e40?s=96&d=identicon&r=gf07fb576d9828f56ab248db6937b8512","url":"https:\/\/secure.gravatar.com\/avatar\/c1b768ecd4e2d0a9fe7ecf631430472135e9246be9aa4d11fee2659661030e40?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1b768ecd4e2d0a9fe7ecf631430472135e9246be9aa4d11fee2659661030e40?s=96&d=identicon&r=g","caption":"Kellie Ring"},"url":"https:\/\/develop.olympic.ca\/olympique\/author\/kellieintern\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/03\/dillon-brooks-2-e1489425901665.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/03\/dillon-brooks-2-e1489425901665.jpg?quality=100","author_name":["Kellie Ring"],"category_names":["Uncategorized"],"tag_names":["Avis Duane","championnat NCAA","Chris Boucher","Dillon Brooks","Dylan Ennis","Elijah Long","Folie du March Madness","Justin Jackson","Kimbal Mackenzie","March Madness","Naz Mitrou-Long","NCAA","Trae Bell-Haynes","Xavier Rathan-Mayes"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-x2J","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/127021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/115369211"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=127021"}],"version-history":[{"count":10,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/127021\/revisions"}],"predecessor-version":[{"id":127032,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/127021\/revisions\/127032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/127024"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=127021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=127021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=127021"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=127021"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=127021"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=127021"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=127021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}