{"id":128783,"date":"2017-06-25T09:24:31","date_gmt":"2017-06-25T13:24:31","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=128783"},"modified":"2020-06-30T17:10:59","modified_gmt":"2020-06-30T21:10:59","slug":"le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/","title":{"rendered":"Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l&rsquo;inclusion John Fennell partage son histoire"},"content":{"rendered":"<p><em>L&rsquo;olympien de Sotchi 2014 <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/john-fennell\/\">John Fennell<\/a> est l&rsquo;un des ambassadeurs de l&rsquo;inclusion dans le sport d&rsquo;\u00c9quipe Canada. \u00c0 l&rsquo;occasion du Mois de la Fiert\u00e9, Fennell a partag\u00e9 ses exp\u00e9riences en tant qu&rsquo;athl\u00e8te LGBTQ+.<\/em><\/p>\n<p>\u00ab\u00a0Je me souviens des Jeux comme d\u2019une exp\u00e9rience d\u00e9routante. En tant que jeune athl\u00e8te cachant son homosexualit\u00e9, je ne me sentais pas \u00e0 ma place\u00a0\u00bb, raconte John \u00e0 propos de son exp\u00e9rience comme jeune lugeur de 19\u00a0ans aux Jeux de 2014.<\/p>\n<p>En pr\u00e9paration pour les Jeux de Sotchi, John s\u2019est tourn\u00e9 vers <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/mark-tewksbury\/\">Mark Tewksbury<\/a>, aujourd\u2019hui son mentor, qui s\u2019\u00e9tait d\u00e9j\u00e0 ouvertement identifi\u00e9 comme \u00e9tant gai.<\/p>\n<p>\u00ab\u00a0Mark Tewksbury est un de mes plus grands alli\u00e9s dans ma qu\u00eate d\u2019identit\u00e9 dans le sport. Quand j\u2019ai rencontr\u00e9 Mark pour la premi\u00e8re fois, je ne pouvais pas mentionner ces mots\u00a0: \u201cje suis gai\u201d. Il m\u2019a aid\u00e9 \u00e0 me construire un r\u00e9seau de gens en qui j\u2019ai confiance afin d\u2019\u00eatre \u00e9paul\u00e9 dans une des \u00e9tapes les plus difficiles de ma vie. Il a \u00e9t\u00e9 un mod\u00e8le dans tous les sens du terme. Jamais je ne saurais assez le remercier.\u00a0\u00bb<\/p>\n<div id=\"attachment_83316\" style=\"width: 873px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-83316\" class=\"size-large wp-image-83316\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2013\/07\/30_07_1992_mark_tewksbury-2_r.jpg?quality=75&amp;w=863\" alt=\"\" width=\"863\" height=\"754\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/30_07_1992_mark_tewksbury-2_r.jpg 1000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/30_07_1992_mark_tewksbury-2_r.jpg?resize=181,158 181w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/30_07_1992_mark_tewksbury-2_r.jpg?resize=424,371 424w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/30_07_1992_mark_tewksbury-2_r.jpg?resize=768,671 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2013\/07\/30_07_1992_mark_tewksbury-2_r.jpg?resize=863,754 863w\" sizes=\"(max-width: 863px) 100vw, 863px\" \/><p id=\"caption-attachment-83316\" class=\"wp-caption-text\">Mark Tewksbury lors de la c\u00e9r\u00e9monie des m\u00e9dailles aux Jeux olympiques de Barcelonne en 1992.<\/p><\/div>\n<p>Son parcours olympique a aussi \u00e9t\u00e9 une le\u00e7on d\u2019authenticit\u00e9. Il a appris \u00e0 affirmer ses convictions plut\u00f4t que de se laisser dicter la mesure.<\/p>\n<p>\u00ab\u00a0En tant qu\u2019olympien, j\u2019ai la chance de partager mon histoire et peut-\u00eatre ainsi d\u2019inspirer d\u2019autres gens \u00e0 faire comme moi. Je savais que les Jeux de Sotchi allaient engendrer une importante conversation \u00e0 propos des athl\u00e8tes LGBT. Le probl\u00e8me, c\u2019est que cette conversation excluait exactement ces athl\u00e8tes. J\u2019\u00e9tais surpris de constater qu\u2019aucun athl\u00e8te canadien ne s\u2019\u00e9tait ouvertement prononc\u00e9 pour engager la conversation et j\u2019\u00e9tais plus qu\u2019heureux de jouer ce r\u00f4le. J\u2019ai d\u00e9cid\u00e9 que je voulais changer les choses.\u00a0\u00bb<\/p>\n<p>Selon lui, on l\u2019a alors per\u00e7u comme un mod\u00e8le. \u00ab\u00a0Des gens de partout au pays, des inconnus pour la plupart, m\u2019ont approch\u00e9 pour me dire \u00e0 quel point ils avaient \u00e9t\u00e9 inspir\u00e9s en me voyant concourir. Je savais que je ne pouvais pas jouer ce r\u00f4le si je n\u2019\u00e9tais pas tout d\u2019abord honn\u00eate avec moi-m\u00eame.\u00a0\u00bb<\/p>\n<p>En tant qu\u2019athl\u00e8te, participer aux Jeux olympiques a \u00e9t\u00e9 le plus grand succ\u00e8s de la carri\u00e8re de John. Il s\u2019est entra\u00een\u00e9 pendant huit ans pour quatre minutes de comp\u00e9tition. John croit que le chemin qui l\u2019a men\u00e9 jusque-l\u00e0 lui en a aussi appris \u00e9norm\u00e9ment sur le succ\u00e8s et l\u2019\u00e9chec, la pers\u00e9v\u00e9rance et l\u2019engagement.<\/p>\n<div id=\"attachment_128975\" style=\"width: 1141px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-128975\" class=\"wp-image-128975 size-large\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/20140606_wc_coe_parade-16.jpg?quality=100&amp;w=1131\" alt=\"John Fennell accroupi devant un jeune gar\u00e7on\" width=\"1131\" height=\"754\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/20140606_wc_coe_parade-16.jpg 2913w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/20140606_wc_coe_parade-16.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/20140606_wc_coe_parade-16.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/20140606_wc_coe_parade-16.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/20140606_wc_coe_parade-16.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/20140606_wc_coe_parade-16.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/20140606_wc_coe_parade-16.jpg?resize=2048,1365 2048w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><p id=\"caption-attachment-128975\" class=\"wp-caption-text\">John Fennell discute avec un fan lors d&rsquo;une d\u00e9jeuner du Calgary Stampede \u00e0 la C\u00e9l\u00e9bration de l&rsquo;Excellence 2014 \u00e0 Calgary, le 6 juin 2014. (COC\/Winston Chow)<\/p><\/div>\n<p>En mai\u00a02014, un mercredi matin au retour des Jeux, un article a paru dans le <em>Calgary Herald<\/em> pour laisser savoir au monde qu\u2019il \u00e9tait gay.<\/p>\n<p>\u00ab\u00a0Je me suis rendu en classe \u00e0 l\u2019Universit\u00e9 de Calgary. J\u2019\u00e9tais \u00e0 peine install\u00e9 que mon t\u00e9l\u00e9phone \u00e9tait d\u00e9j\u00e0 \u00e0 sec. On m\u2019inondait de messages de soutien. J\u2019avais peine \u00e0 suivre le fil. Toute la journ\u00e9e, je recevais l\u2019appui de mes coll\u00e8gues de classe, de mes pairs et d\u2019\u00e9trangers de partout sur la plan\u00e8te. La conversation devait s\u2019entamer et je suis fier d\u2019y avoir particip\u00e9.\u00a0\u00bb<\/p>\n<p>Lorsqu\u2019on lui demande comment il a fait pour avoir le courage de s\u2019affirmer en tant qu\u2019homosexuel, John utilise son sport pour s\u2019expliquer. \u00ab\u00a0La bravoure est au c\u0153ur de mon sport. Il faut trouver l\u2019\u00e9quilibre entre la zone de confort et la perte de contr\u00f4le. On peut difficilement \u00eatre brave lorsqu\u2019on a peur de soi-m\u00eame.\u00a0\u00bb<\/p>\n<p>Dans les mois suivants, John a pris contact avec d\u2019autres athl\u00e8tes LGBTQ+ au Canada. Il a construit un r\u00e9seau de gens qui sont devenus quelques-uns de ses meilleurs amis.<\/p>\n<p>\u00ab Ce qui me pla\u00eet le plus dans le fait de partager mon exp\u00e9rience, c\u2019est que j\u2019ai \u00e9t\u00e9 pour plusieurs le catalyseur qui les a incit\u00e9s \u00e0 partager leur histoire. Nos histoires se sont \u00e9crites sous les m\u00eames th\u00e8mes : la peur d\u2019\u00eatre rejet\u00e9s par notre \u00e9quipe; la peur d\u2019\u00eatre jug\u00e9s par nos partisans et nos entra\u00eeneurs; les distractions de notre sport; le sentiment de ne pas \u00eatre authentiques. Je me rappelle du moment o\u00f9 j\u2019ai entendu parler du programme #Une\u00c9quipe qui en \u00e9tait \u00e0 ses balbutiements. J\u2019\u00e9tais avec Anastasia Bucsis. On s\u2019est regard\u00e9 pendant la rencontre et \u00e0 ce moment nous savions que la donne avait chang\u00e9.<\/p>\n<p><strong>\u00c0 LIRE : <\/strong><a href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/08\/16\/anastasia-bucsis-vainc-la-depression-avec-lamour-et-le-travail-dequipe\/\">Anastasia Bucsis vainc la d\u00e9pression avec l\u2019amour et le travail d\u2019\u00e9quipe<\/a><\/p>\n<p>\u00ab\u00a0Les efforts du Comit\u00e9 olympique canadien pour promouvoir la diversit\u00e9 et l\u2019inclusion \u00e0 la suite de Sotchi ont chang\u00e9 ma vie. Je suis si fier de faire partie d\u2019un mouvement qui laisse sa marque dans la vie d\u2019autant de gens. Les commentaires les plus touchants sont ceux que je re\u00e7ois d\u2019\u00e9tudiants qui disent avoir \u00e9t\u00e9 inspir\u00e9s \u00e0 changer leur propre vie.\u00a0\u00bb<\/p>\n<p>John se souvient de son premier d\u00e9fil\u00e9. \u00ab\u00a0La c\u00e9l\u00e9bration mondiale de la Fiert\u00e9 \u00e0 Toronto en 2014 a sans doute \u00e9t\u00e9 la plus belle journ\u00e9e de ma vie.\u00a0\u00bb Le Comit\u00e9 olympique canadien y avait envoy\u00e9 plus d\u2019une cinquantaine d\u2019athl\u00e8tes pour y participer afin de manifester son soutien envers ses athl\u00e8tes.<\/p>\n<p>John se rappelle s\u2019y \u00eatre senti si libre et accept\u00e9 que c\u2019est \u00e0 ce moment qu\u2019il s\u2019est mis r\u00e9ellement \u00e0 \u00ab\u00a0faire partie d\u2019\u00c9quipe Canada.\u00a0\u00bb<\/p>\n<p>Il transpose ses talents en dehors de la piste. En tant qu\u2019ambassadeur #Une\u00c9quipe, il continue de faire entendre sa voix pour la jeunesse homosexuelle dans le sport et de cr\u00e9er un environnement sportif s\u00e9curitaire et inclusif.<\/p>\n<p>Merci, John.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;olympien de Sotchi 2014 John Fennell est l&rsquo;un des ambassadeurs de l&rsquo;inclusion dans le sport d&rsquo;\u00c9quipe Canada. \u00c0 l&rsquo;occasion du&#8230;<\/p>\n","protected":false},"author":145751812,"featured_media":128785,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[368602839,56276,415988264,1104411,415984955,415986517,415988263,58938269,415984546,682163538,415826381,415984952,682163461,22277118,825,415983398],"post_format":"standard","sport":[44481],"game":[191933058],"coauthors":[415987663],"class_list":["post-128783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-uneequipe","tag-canadien","tag-diversite","tag-equipe-canada","tag-fierte","tag-histoire","tag-inclusion","tag-john-fennell","tag-luge","tag-lugeur","tag-mark-tewksbury","tag-one-team","tag-recit","tag-sotchi-2014","tag-sport","tag-une-equipe","sport-luge","game-2014-sotchi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l&#039;inclusion John Fennell partage son histoire - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l&#039;inclusion John Fennell partage son histoire - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;olympien de Sotchi 2014 John Fennell est l&rsquo;un des ambassadeurs de l&rsquo;inclusion dans le sport d&rsquo;\u00c9quipe Canada. \u00c0 l&rsquo;occasion du...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-25T13:24:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-30T21:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/05807734.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"4176\" \/>\n\t<meta property=\"og:image:height\" content=\"2396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blake Blondeel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blake Blondeel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/\"},\"author\":{\"name\":\"Blake Blondeel\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/c2f7c219b8d845da7197e2f48e64150d\"},\"headline\":\"Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l&rsquo;inclusion John Fennell partage son histoire\",\"datePublished\":\"2017-06-25T13:24:31+00:00\",\"dateModified\":\"2020-06-30T21:10:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/\"},\"wordCount\":1044,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/06\\\/05807734.jpg?quality=100\",\"keywords\":[\"#uneequipe\",\"Canadien\",\"diversit\u00e9\",\"\u00c9quipe canada\",\"Fiert\u00e9\",\"histoire\",\"inclusion\",\"John Fennell\",\"Luge\",\"Lugeur\",\"Mark Tewksbury\",\"One Team\",\"R\u00e9cit\",\"Sotchi 2014\",\"Sport\",\"Une \u00c9quipe\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/\",\"name\":\"Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l'inclusion John Fennell partage son histoire - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/06\\\/05807734.jpg?quality=100\",\"datePublished\":\"2017-06-25T13:24:31+00:00\",\"dateModified\":\"2020-06-30T21:10:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/c2f7c219b8d845da7197e2f48e64150d\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/06\\\/25\\\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/06\\\/05807734.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/06\\\/05807734.jpg?quality=100\",\"width\":4176,\"height\":2396},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/c2f7c219b8d845da7197e2f48e64150d\",\"name\":\"Blake Blondeel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56968dfa152e95a3411a08928ec8ad5a5bcda006b5bb235e5d2ba0089ed6f3f7?s=96&d=identicon&r=g68cfd1b5533f7cd6e98d284c2b71eb9f\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56968dfa152e95a3411a08928ec8ad5a5bcda006b5bb235e5d2ba0089ed6f3f7?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56968dfa152e95a3411a08928ec8ad5a5bcda006b5bb235e5d2ba0089ed6f3f7?s=96&d=identicon&r=g\",\"caption\":\"Blake Blondeel\"},\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/blondeet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l'inclusion John Fennell partage son histoire - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/","og_locale":"fr_FR","og_type":"article","og_title":"Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l'inclusion John Fennell partage son histoire - \u00c9quipe Canada","og_description":"L&rsquo;olympien de Sotchi 2014 John Fennell est l&rsquo;un des ambassadeurs de l&rsquo;inclusion dans le sport d&rsquo;\u00c9quipe Canada. \u00c0 l&rsquo;occasion du...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2017-06-25T13:24:31+00:00","article_modified_time":"2020-06-30T21:10:59+00:00","og_image":[{"width":4176,"height":2396,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/05807734.jpg?quality=100","type":"image\/jpeg"}],"author":"Blake Blondeel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Blake Blondeel","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/"},"author":{"name":"Blake Blondeel","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/c2f7c219b8d845da7197e2f48e64150d"},"headline":"Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l&rsquo;inclusion John Fennell partage son histoire","datePublished":"2017-06-25T13:24:31+00:00","dateModified":"2020-06-30T21:10:59+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/"},"wordCount":1044,"commentCount":0,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/05807734.jpg?quality=100","keywords":["#uneequipe","Canadien","diversit\u00e9","\u00c9quipe canada","Fiert\u00e9","histoire","inclusion","John Fennell","Luge","Lugeur","Mark Tewksbury","One Team","R\u00e9cit","Sotchi 2014","Sport","Une \u00c9quipe"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/","url":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/","name":"Fiert\u00e9 &amp; Sport : Le lugeur et ambassadeur de l'inclusion John Fennell partage son histoire - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/05807734.jpg?quality=100","datePublished":"2017-06-25T13:24:31+00:00","dateModified":"2020-06-30T21:10:59+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/c2f7c219b8d845da7197e2f48e64150d"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/06\/25\/le-lugeur-john-fennell-revient-sur-sa-sortie-du-placard-peu-de-temps-apres-sotchi-2014\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/05807734.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/05807734.jpg?quality=100","width":4176,"height":2396},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/c2f7c219b8d845da7197e2f48e64150d","name":"Blake Blondeel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/56968dfa152e95a3411a08928ec8ad5a5bcda006b5bb235e5d2ba0089ed6f3f7?s=96&d=identicon&r=g68cfd1b5533f7cd6e98d284c2b71eb9f","url":"https:\/\/secure.gravatar.com\/avatar\/56968dfa152e95a3411a08928ec8ad5a5bcda006b5bb235e5d2ba0089ed6f3f7?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56968dfa152e95a3411a08928ec8ad5a5bcda006b5bb235e5d2ba0089ed6f3f7?s=96&d=identicon&r=g","caption":"Blake Blondeel"},"url":"https:\/\/develop.olympic.ca\/olympique\/author\/blondeet\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/05807734.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/06\/05807734.jpg?quality=100","author_name":["Blake Blondeel"],"category_names":["Uncategorized"],"tag_names":["#uneequipe","Canadien","diversit\u00e9","\u00c9quipe canada","Fiert\u00e9","histoire","inclusion","John Fennell","Luge","Lugeur","Mark Tewksbury","One Team","R\u00e9cit","Sotchi 2014","Sport","Une \u00c9quipe"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-xv9","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/128783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/145751812"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=128783"}],"version-history":[{"count":7,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/128783\/revisions"}],"predecessor-version":[{"id":161660,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/128783\/revisions\/161660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/128785"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=128783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=128783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=128783"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=128783"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=128783"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=128783"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=128783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}