{"id":131741,"date":"2017-11-02T16:36:06","date_gmt":"2017-11-02T20:36:06","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=131741"},"modified":"2017-11-05T09:12:52","modified_gmt":"2017-11-05T14:12:52","slug":"le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/","title":{"rendered":"Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole"},"content":{"rendered":"<h1>Avec moins de 100 jours \u00e0 faire avant les Jeux de <a href=\"http:\/\/develop.olympic.ca\/olympique\/games\/2018-pyeongchang\/\">PyeongChang\u00a02018<\/a>, le Programme scolaire olympique canadien am\u00e8ne les Jeux olympiques d\u2019hiver dans les salles de classe \u00e0 travers le Canada. Et \u00e7a, c\u2019est vraiment cool!<\/h1>\n<p>D\u00e8s aujourd\u2019hui, vous pouvez trouver toutes nouvelles ressources sur les sports d\u2019hiver sur la page du <a href=\"http:\/\/bit.ly\/2zqXixB\">Programme scolaire olympique canadien<\/a>. Ces outils sont le v\u00e9hicule id\u00e9al pour \u00e9duquer les jeunes sur les Jeux olympiques, de faire d\u2019eux des passionn\u00e9es et surtout de les inspirer. Qu\u2019attendez-vous! Proposez-les \u00e0 un enseignant ou un leader de votre communaut\u00e9.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1360\" height=\"765\" src=\"https:\/\/www.youtube.com\/embed\/RtHn9cJpgss?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>V\u00e9ritable h\u00e9ritage des Jeux olympiques de <a href=\"http:\/\/develop.olympic.ca\/olympique\/games\/1988-calgary\/\">Calgary\u00a01988<\/a>, le Programme scolaire vise \u00e0 enseigner aux enfants canadiens les valeurs olympiques \u2014 excellence, amiti\u00e9 et respect \u2014, \u00e0 leur faire d\u00e9couvrir de nouveaux sports et \u00e0 cr\u00e9er un lien unique avec \u00c9quipe Canada.<\/p>\n<h2 style=\"text-align:center;\"><a href=\"http:\/\/bit.ly\/1f0VWvA\">Inscrivez-vous au Club olympique canadien<\/a><\/h2>\n<p>R\u00e9dig\u00e9 par des enseignants pour les enseignants, le programme offre une occasion unique d\u2019inciter les jeunes Canadiens \u00e0 atteindre leur plein potentiel, en partageant les incroyables parcours des meilleurs athl\u00e8tes du pays.<\/p>\n<p>Du ski alpin au curling, les enseignants et leur classe seront initi\u00e9s aux diff\u00e9rents sports d\u2019hiver. Les ressources donnent une tournure olympique aux mati\u00e8res scolaires telles que l\u2019histoire, l\u2019\u00e9criture et l\u2019\u00e9ducation physique, alors que les \u00e9l\u00e8ves d\u00e9couvriront les origines de chaque sport d\u2019hiver, le fonctionnement des comp\u00e9titions, en plus de susciter des r\u00e9flexions et plus encore.<\/p>\n<p>Les \u00e9l\u00e8ves d\u00e9couvriront \u00e9galement les athl\u00e8tes d\u2019\u00c9quipe Canada qui se rendront \u00e0 PyeongChang\u00a02018 pour faire des prochains Jeux d\u2019hiver des Jeux encore plus excitants.<\/p>\n<p>Les enseignants et les parents peuvent trouver les <a href=\"http:\/\/bit.ly\/2zqXixB\">nouvelles ressources ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec moins de 100 jours \u00e0 faire avant les Jeux de PyeongChang\u00a02018, le Programme scolaire olympique canadien am\u00e8ne les Jeux&#8230;<\/p>\n","protected":false},"author":127468989,"featured_media":131752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[415985296,415985297,415985298,415984572,415985301,415985299,1104411,415985295,415985302,415985300,25678],"post_format":"standard","sport":[],"game":[],"coauthors":[415985142],"class_list":["post-131741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-ecoles","tag-ecoles-primaires","tag-ecoles-secondaires","tag-education","tag-eleves","tag-enseignants","tag-equipe-canada","tag-programme-scolaire-olympique-canadien","tag-students","tag-teachers","tag-team-canada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Avec moins de 100 jours \u00e0 faire avant les Jeux de PyeongChang\u00a02018, le Programme scolaire olympique canadien am\u00e8ne les Jeux...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-02T20:36:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-05T14:12:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/11\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rachal Shanahan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rachal Shanahan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/\"},\"author\":{\"name\":\"rachalshanahan\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/cc24b1c0779dbc0f2f86087b9e759e10\"},\"headline\":\"Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole\",\"datePublished\":\"2017-11-02T20:36:06+00:00\",\"dateModified\":\"2017-11-05T14:12:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/\"},\"wordCount\":308,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100\",\"keywords\":[\"\u00e9coles\",\"\u00e9coles primaires\",\"\u00e9coles secondaires\",\"\u00e9ducation\",\"\u00e9l\u00e8ves\",\"enseignants\",\"\u00c9quipe canada\",\"Programme scolaire olympique canadien\",\"students\",\"teachers\",\"team canada\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/\",\"name\":\"Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100\",\"datePublished\":\"2017-11-02T20:36:06+00:00\",\"dateModified\":\"2017-11-05T14:12:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/cc24b1c0779dbc0f2f86087b9e759e10\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/11\\\/02\\\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/11\\\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100\",\"width\":1010,\"height\":568},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/cc24b1c0779dbc0f2f86087b9e759e10\",\"name\":\"rachalshanahan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b180d4c46ff08d25fa36385f28d7b94bd686858ac33f279444ee518bb5e0aed2?s=96&d=identicon&r=g73317fd529a6a51ad9e721cd1fef2482\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b180d4c46ff08d25fa36385f28d7b94bd686858ac33f279444ee518bb5e0aed2?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b180d4c46ff08d25fa36385f28d7b94bd686858ac33f279444ee518bb5e0aed2?s=96&d=identicon&r=g\",\"caption\":\"rachalshanahan\"},\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/rachalshanahan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole - \u00c9quipe Canada","og_description":"Avec moins de 100 jours \u00e0 faire avant les Jeux de PyeongChang\u00a02018, le Programme scolaire olympique canadien am\u00e8ne les Jeux...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2017-11-02T20:36:06+00:00","article_modified_time":"2017-11-05T14:12:52+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/11\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100","type":"image\/jpeg"}],"author":"Rachal Shanahan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rachal Shanahan","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/"},"author":{"name":"rachalshanahan","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/cc24b1c0779dbc0f2f86087b9e759e10"},"headline":"Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole","datePublished":"2017-11-02T20:36:06+00:00","dateModified":"2017-11-05T14:12:52+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/"},"wordCount":308,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/11\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100","keywords":["\u00e9coles","\u00e9coles primaires","\u00e9coles secondaires","\u00e9ducation","\u00e9l\u00e8ves","enseignants","\u00c9quipe canada","Programme scolaire olympique canadien","students","teachers","team canada"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/","url":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/","name":"Le Programme scolaire olympique canadien am\u00e8ne les sports d\u2019hiver sur les bancs d\u2019\u00e9cole - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/11\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100","datePublished":"2017-11-02T20:36:06+00:00","dateModified":"2017-11-05T14:12:52+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/cc24b1c0779dbc0f2f86087b9e759e10"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/02\/le-programme-scolaire-olympique-canadien-amene-les-sports-dhiver-sur-les-bancs-decole\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/11\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/11\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100","width":1010,"height":568},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/cc24b1c0779dbc0f2f86087b9e759e10","name":"rachalshanahan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b180d4c46ff08d25fa36385f28d7b94bd686858ac33f279444ee518bb5e0aed2?s=96&d=identicon&r=g73317fd529a6a51ad9e721cd1fef2482","url":"https:\/\/secure.gravatar.com\/avatar\/b180d4c46ff08d25fa36385f28d7b94bd686858ac33f279444ee518bb5e0aed2?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b180d4c46ff08d25fa36385f28d7b94bd686858ac33f279444ee518bb5e0aed2?s=96&d=identicon&r=g","caption":"rachalshanahan"},"url":"https:\/\/develop.olympic.ca\/olympique\/author\/rachalshanahan\/"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/11\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100","author_name":["Rachal Shanahan"],"category_names":["Uncategorized"],"tag_names":["\u00e9coles","\u00e9coles primaires","\u00e9coles secondaires","\u00e9ducation","\u00e9l\u00e8ves","enseignants","\u00c9quipe canada","Programme scolaire olympique canadien","students","teachers","team canada"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-ygR","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/11\/adam-pulicicchio-oct-3-17-hbc-canada-launch-kit-17.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/131741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/127468989"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=131741"}],"version-history":[{"count":2,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/131741\/revisions"}],"predecessor-version":[{"id":131743,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/131741\/revisions\/131743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/131752"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=131741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=131741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=131741"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=131741"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=131741"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=131741"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=131741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}