{"id":132887,"date":"2017-12-06T10:12:17","date_gmt":"2017-12-06T15:12:17","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=132887"},"modified":"2017-12-06T10:12:17","modified_gmt":"2017-12-06T15:12:17","slug":"saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/","title":{"rendered":"Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0"},"content":{"rendered":"<h1><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-127097\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2017\/03\/canadian_press_fr_horz_rgb.jpg?quality=100\" alt=\"\" width=\"175\" height=\"11\" \/><\/h1>\n<h1>Jillian Saulnier a touch\u00e9 la cible alors qu&rsquo;il ne restait que 3:10 secondes \u00e0 \u00e9couler au match, permettant au Canada de blanchir les \u00c9tats-Unis 2-0, mardi, dans un duel pr\u00e9paratoire mettant en vedette les deux meilleures \u00e9quipes de hockey f\u00e9minin.<\/h1>\n<p>Saulnier a tromp\u00e9 la vigilance de la gardienne Alex Rigsby gr\u00e2ce \u00e0 un lancer du revers. Quelques instants plus tard, Laura Fortino a envoy\u00e9 un long tir dans un filet d\u00e9sert.<\/p>\n<p>La gardienne du Canada Genevi\u00e8ve Lacasse a r\u00e9alis\u00e9 32 arr\u00eats. Rigsby a stopp\u00e9 21 des 22 tirs dirig\u00e9s vers elle.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Thank you, Winnipeg! <a href=\"https:\/\/twitter.com\/hashtag\/RedWhiteUnite?src=hash&amp;ref_src=twsrc%5Etfw\">#RedWhiteUnite<\/a> <a href=\"https:\/\/t.co\/PWuefTZQjW\">pic.twitter.com\/PWuefTZQjW<\/a><\/p>\n<p>&mdash; Team Canada Women (@HC_Women) <a href=\"https:\/\/twitter.com\/HC_Women\/status\/938260080704749568?ref_src=twsrc%5Etfw\">December 6, 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Il s&rsquo;agissait du quatri\u00e8me affrontement d&rsquo;une s\u00e9rie de six qui m\u00e8nera l\u2019\u00e9quipe canadienne de hockey f\u00e9minin aux Jeux olympiques de Pyeongchang, au mois de f\u00e9vrier. Le Canada m\u00e8ne la s\u00e9rie 3-1.<\/p>\n<p>Les Canadiennes ont \u00e9t\u00e9 blanchies en trois avantages num\u00e9riques alors que les Am\u00e9ricaines n&rsquo;ont pas enfil\u00e9 l&rsquo;aiguille en cinq occasions avec une joueuse en plus.<\/p>\n<p>Le Canada, qui a gagn\u00e9 2-1 en prolongation dimanche, compte 26 joueuses dans sa formation et il doit en lib\u00e9rer trois afin de cr\u00e9er son \u00e9quipe olympique.<\/p>\n<p>Les deux nations se retrouveront le 15 d\u00e9cembre, \u00e0 San Jose, en Californie.<\/p>\n<h6>Nouvelles de \u00a9 La Presse Canadienne, 2017. Tous droits r\u00e9serv\u00e9s. Ce mat\u00e9riel ne peut pas \u00eatre publi\u00e9, diffus\u00e9, r\u00e9\u00e9crit ou redistribu\u00e9.<br \/>\n<a href=\"https:\/\/twitter.com\/Equipe_Canada\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2016\/09\/twitter_frsocial-ads.png\" alt=\"\" width=\"1180\" height=\"100\" \/><\/a><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Jillian Saulnier a touch\u00e9 la cible alors qu&rsquo;il ne restait que 3:10 secondes \u00e0 \u00e9couler au match, permettant au Canada&#8230;<\/p>\n","protected":false},"author":96107080,"featured_media":132893,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[50002748,116050,31548591,415984841,160029043,415985422],"post_format":"standard","sport":[891977],"game":[],"coauthors":[415984657],"class_list":["post-132887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-genevieve-lacasse","tag-hockey-canada","tag-hockey-feminin","tag-jillian-saulnier","tag-laura-fortino","tag-match-preparatoire","sport-hockey-sur-glace"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0 - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0 - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Jillian Saulnier a touch\u00e9 la cible alors qu&rsquo;il ne restait que 3:10 secondes \u00e0 \u00e9couler au match, permettant au Canada...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-06T15:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"755\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"PC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/\"},\"author\":{\"name\":\"Ariane Desrosiers\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\"},\"headline\":\"Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0\",\"datePublished\":\"2017-12-06T15:12:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/\"},\"wordCount\":243,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/12\\\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100\",\"keywords\":[\"Genevi\u00e8ve Lacasse\",\"Hockey Canada\",\"Hockey f\u00e9minin\",\"Jillian Saulnier\",\"Laura Fortino\",\"match pr\u00e9paratoire\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/\",\"name\":\"Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0 - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/12\\\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100\",\"datePublished\":\"2017-12-06T15:12:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2017\\\/12\\\/06\\\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/12\\\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/12\\\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100\",\"width\":1340,\"height\":755,\"caption\":\"Genevi\u00e8ve Lacasse garde le but canadien alors que Jillian Saulnier effectue la mise au jeu lors d'un match pr\u00e9paratoire Canada-\u00c9tats-Unis en vue de PyeongChang2018. (Photo : Twitter\\\/Hockey Canada)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\",\"name\":\"Ariane Desrosiers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=gbd92884420bbfa56539e46241678b7d5\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g\",\"caption\":\"Ariane Desrosiers\"},\"description\":\"Specialist, Social Sp\u00e9cialiste, M\u00e9dias num\u00e9riques\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/arianedesrosiers\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0 - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/","og_locale":"fr_FR","og_type":"article","og_title":"Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0 - \u00c9quipe Canada","og_description":"Jillian Saulnier a touch\u00e9 la cible alors qu&rsquo;il ne restait que 3:10 secondes \u00e0 \u00e9couler au match, permettant au Canada...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2017-12-06T15:12:17+00:00","og_image":[{"width":1340,"height":755,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100","type":"image\/jpeg"}],"author":"PC","twitter_card":"summary_large_image","twitter_misc":{"Written by":"PC","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/"},"author":{"name":"Ariane Desrosiers","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2"},"headline":"Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0","datePublished":"2017-12-06T15:12:17+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/"},"wordCount":243,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100","keywords":["Genevi\u00e8ve Lacasse","Hockey Canada","Hockey f\u00e9minin","Jillian Saulnier","Laura Fortino","match pr\u00e9paratoire"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/","url":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/","name":"Saulnier et Lacasse aident le Canada \u00e0 blanchir les \u00c9tats-Unis 2-0 - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100","datePublished":"2017-12-06T15:12:17+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/06\/saulnier-et-lacasse-aident-le-canada-a-blanchir-les-etats-unis-2-0\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100","width":1340,"height":755,"caption":"Genevi\u00e8ve Lacasse garde le but canadien alors que Jillian Saulnier effectue la mise au jeu lors d'un match pr\u00e9paratoire Canada-\u00c9tats-Unis en vue de PyeongChang2018. (Photo : Twitter\/Hockey Canada)"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2","name":"Ariane Desrosiers","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=gbd92884420bbfa56539e46241678b7d5","url":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g","caption":"Ariane Desrosiers"},"description":"Specialist, Social Sp\u00e9cialiste, M\u00e9dias num\u00e9riques","url":"https:\/\/develop.olympic.ca\/olympique\/author\/arianedesrosiers\/"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100","author_name":["PC"],"category_names":["Uncategorized"],"tag_names":["Genevi\u00e8ve Lacasse","Hockey Canada","Hockey f\u00e9minin","Jillian Saulnier","Laura Fortino","match pr\u00e9paratoire"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-yzl","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/equipe-canada-hokcey-fecc81minin-saulnier-lacasse-2017.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/132887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/96107080"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=132887"}],"version-history":[{"count":2,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/132887\/revisions"}],"predecessor-version":[{"id":133052,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/132887\/revisions\/133052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/132893"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=132887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=132887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=132887"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=132887"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=132887"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=132887"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=132887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}