{"id":132986,"date":"2017-12-08T12:15:02","date_gmt":"2017-12-08T17:15:02","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=132986"},"modified":"2017-12-08T13:16:49","modified_gmt":"2017-12-08T18:16:49","slug":"skeleton-vathje-glisse-jusqua-la-medaille-dargent-a-winterberg","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2017\/12\/08\/skeleton-vathje-glisse-jusqua-la-medaille-dargent-a-winterberg\/","title":{"rendered":"Skeleton: Vathje et Greszczyszyn glissent jusqu&rsquo;au podium \u00e0 Winterberg"},"content":{"rendered":"<h2 class=\"lead\">Elisabeth Vathje et Dave Greszczyszyn sont mont\u00e9s sur le podium de la Coupe du monde IBSF, remportant respectivement l\u2019argent et le bronze en skeleton en Allemagne, vendredi matin.<\/h2>\n<h2>Skeleton f\u00e9minin<\/h2>\n<p>La Canadienne a termin\u00e9 avec un temps combin\u00e9 d\u2019une minute 56,10 secondes pour monter sur la deuxi\u00e8me marche du podium. La championne du monde Jacqueline Loelling s\u2019est assur\u00e9 l\u2019or \u00e0 la maison avec un temps combin\u00e9 de 1:55,86s. Elena Nikitina de la Russie qui \u00e9tait \u00e0 \u00e9galit\u00e9 en premi\u00e8re position apr\u00e8s la premi\u00e8re descente a termin\u00e9 avec un retard de 0,01 seconde derri\u00e8re Vathje pour le bronze.<\/p>\n<p>\u00c0 LIRE\u00a0: <a href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/09\/skeleton-elisabeth-vathje-sempare-de-largent-a-la-premiere-coupe-du-monde-de-la-saison\/\">Elisabeth Vathje s\u2019empare de l\u2019argent \u00e0 la premi\u00e8re Coupe du monde de la saison<\/a><\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BbzmgEgH9jR\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/BbzmgEgH9jR\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/BbzmgEgH9jR\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by OLYMPIC ATHLETE &#8211; WIFE &#8211; MOM (@skellyelisabeth)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><\/p>\n<p>Malgr\u00e9 l\u2019hiver qui se d\u00e9chainait en Allemagne, Vathje a r\u00e9ussi \u00e0 revenir dans la course apr\u00e8s sa quatri\u00e8me place \u00e0 l\u2019issue de la premi\u00e8re ronde. \u00abAvec la neige, la premi\u00e8re descente \u00e9tait tr\u00e8s difficile. Mais, mon \u00e9quipement course toujours bien, ici, \u00e0 Winterberg; le traineau vole vraiment!\u00bb, a d\u00e9clar\u00e9 Vathje.<\/p>\n<p>\u00c0 LIRE: <a href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/07\/apercu-hiver-2017-18-les-bobeurs-et-skeletoneurs-veulent-marquer-lhistoire-a-pyeongchang-2018\/\">Les bobeurs et skeletoneurs veulent marquer l\u2019histoire \u00e0 PyeongChang 2018<\/a><\/p>\n<p>La comp\u00e9tition \u00e0 Winterberg marque le quatri\u00e8me arr\u00eat du circuit de la Coupe du monde IBSF et la seconde m\u00e9daille d\u2019argent pour Vathje cette saison. Elisabeth Vathje est pr\u00e9sentement en deuxi\u00e8me position du classement de la Coupe du monde, les Canadiennes Mirela Rahneva et Jane Channell sont respectivement quatri\u00e8me et cinqui\u00e8me.<\/p>\n<h2>Skeleton masculin<\/h2>\n<p>Les conditions m\u00e9t\u00e9orologiques se sont d\u00e9grad\u00e9es pour la comp\u00e9tition masculine menant \u00e0 l\u2019annulation des deuxi\u00e8mes descentes en raison de la neige. Cependant, Dave Greszczyszyn a r\u00e9ussi \u00e0 tirer le meilleur de sa course \u00e0 Winterberg, arr\u00eatant le chrono \u00e0 56,88 secondes lui assurant la troisi\u00e8me place et sa premi\u00e8re m\u00e9daille en carri\u00e8re en Coupe du monde.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">What a day here in Winterberg with\ud83e\udd49for Canada Dave!!! First World Cup top 3 for the Grizz \ud83d\udcaa\ud83c\udffc\ud83d\ude03 <a href=\"https:\/\/t.co\/WV7GFmj9dN\">https:\/\/t.co\/WV7GFmj9dN<\/a> <a href=\"https:\/\/t.co\/aAwZwVAUgC\">pic.twitter.com\/aAwZwVAUgC<\/a><\/p>\n<p>&mdash; IBSF (@IBSFsliding) <a href=\"https:\/\/twitter.com\/IBSFsliding\/status\/939173189246177280?ref_src=twsrc%5Etfw\">December 8, 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>\u00abJe connais la piste de Winterberg et j\u2019ai connu quelques bons r\u00e9sultats, ici, en Coupe europ\u00e9enne et en Coupe internationale. J\u2019ai eu un bon d\u00e9part \u00e0 la premi\u00e8re descente et j\u2019ai ensuite voulu rester calme et laisser le traineau faire son travail. Je ne peux pas me plaindre aujourd\u2019hui\u00bb, a d\u00e9clar\u00e9 Greszczyszyn apr\u00e8s sa course.<\/p>\n<p>L\u2019or est all\u00e9 \u00e0 Sungbin Yun de la Cor\u00e9e, qui s\u2019est assur\u00e9 sa troisi\u00e8me victoire cette saison avec un temps de 56,62s. L\u2019argent a \u00e9t\u00e9 remport\u00e9 par le champion du monde Martins Dukurs de la Lettonie qui a arr\u00eat\u00e9 le chrono \u00e0 56,68s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elisabeth Vathje et Dave Greszczyszyn sont mont\u00e9s sur le podium de la Coupe du monde IBSF, remportant respectivement l\u2019argent et&#8230;<\/p>\n","protected":false},"author":82363705,"featured_media":132998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[415984431,1104411,54771154,415984537],"post_format":"standard","sport":[3761],"game":[415985119],"coauthors":[361304908],"class_list":["post-132986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-elisabeth-vathje","tag-equipe-canada","tag-pyeongchang-2018","tag-skeleton","sport-skeleton","game-2018-pyeongchang"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/dave-greszczyszyn-team-canada-skeleton.jpg?quality=100","author_name":["Camille Wallace"],"category_names":["Uncategorized"],"tag_names":["elisabeth vathje","\u00c9quipe canada","pyeongchang 2018","Skeleton"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-yAW","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2017\/12\/dave-greszczyszyn-team-canada-skeleton.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/132986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/82363705"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=132986"}],"version-history":[{"count":9,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/132986\/revisions"}],"predecessor-version":[{"id":133000,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/132986\/revisions\/133000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/132998"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=132986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=132986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=132986"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=132986"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=132986"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=132986"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=132986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}