{"id":133722,"date":"2018-01-08T07:00:25","date_gmt":"2018-01-08T12:00:25","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=133722"},"modified":"2018-01-10T19:09:19","modified_gmt":"2018-01-11T00:09:19","slug":"apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/","title":{"rendered":"Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018"},"content":{"rendered":"<h2 class=\"lead\">Les premi\u00e8res images de la Maison olympique du Canada de PyeongChang 2018 ont \u00e9t\u00e9 d\u00e9voil\u00e9es lundi matin.<\/h2>\n<p>La Maison olympique du Canada servira de lieu de rassemblement pour \u00c9quipe Canada aux Jeux, et accueillera les athl\u00e8tes, entra\u00eeneurs ainsi que leurs familles et amis. Pour la toute premi\u00e8re fois, la Maison olympique du Canada ouvrira ses portes aux Canadiens et \u00e0 tous les partisans d&rsquo;\u00c9quipe Canada \u00e0 PyeongChang 2018.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1360\" data-carousel-extra='null' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1360px; height: 562px;\" data-original-width=\"1360\" data-original-height=\"562\" > <div class=\"gallery-group images-1\" style=\"width: 891px; height: 562px;\" data-original-width=\"891\" data-original-height=\"562\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/20180103_bell_space-v6\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"887\"> <meta itemprop=\"height\" content=\"558\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"133726\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg?quality=100\" data-orig-size=\"1340,843\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Espace Bell Maison olympique du Canada 2018\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg?quality=100&#038;w=590\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg?quality=100&#038;w=1199\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg?quality=100&#038;w=887&#038;h=558&#038;strip&#038;resize=887%2C558\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg 1340w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg?resize=251,158 251w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg?resize=590,371 590w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg?resize=768,483 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180103_bell_space-v6-e1515384838193.jpg?resize=1199,754 1199w\" width=\"887\" height=\"558\" loading=\"lazy\" data-original-width=\"887\" data-original-height=\"558\" itemprop=\"http:\/\/schema.org\/image\" title=\"Espace Bell Maison olympique du Canada 2018\" alt=\"Espace Bell dans la Maison olympique du Canada \u00e0 PyeongChang 2018\" style=\"width: 887px; height: 558px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Espace Bell dans la Maison olympique du Canada \u00e0 PyeongChang 2018 <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 469px; height: 562px;\" data-original-width=\"469\" data-original-height=\"562\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/20180104_entree-v4\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"465\"> <meta itemprop=\"height\" content=\"310\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"133727\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg?quality=100\" data-orig-size=\"1340,893\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;carl.antonyn&quot;,&quot;camera&quot;:&quot;Canon EOS 6D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1502850873&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Entr\u00e9e Maison olympique du Canada 2018\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg?quality=100&#038;w=557\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg?quality=100&#038;w=1131\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg?quality=100&#038;w=465&#038;h=310&#038;strip&#038;resize=465%2C310\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg 1340w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180104_entree-v4-e1515384904856.jpg?resize=1131,754 1131w\" width=\"465\" height=\"310\" loading=\"lazy\" data-original-width=\"465\" data-original-height=\"310\" itemprop=\"http:\/\/schema.org\/image\" title=\"Entr\u00e9e Maison olympique du Canada 2018\" alt=\"Entr\u00e9e de la Maison olympique du Canada \u00e0 PyeongChang 2018\" style=\"width: 465px; height: 310px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Entr\u00e9e de la Maison olympique du Canada \u00e0 PyeongChang 2018 <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/coh_gradins\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"465\"> <meta itemprop=\"height\" content=\"244\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"133731\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_gradins.jpg?quality=100\" data-orig-size=\"1200,630\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"COH_Gradins\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_gradins.jpg?quality=100&#038;w=660\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_gradins.jpg?quality=100&#038;w=1200\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_gradins.jpg?quality=100&#038;w=465&#038;h=244&#038;strip&#038;resize=465%2C244\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_gradins.jpg 1200w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_gradins.jpg?resize=280,147 280w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_gradins.jpg?resize=660,347 660w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_gradins.jpg?resize=768,403 768w\" width=\"465\" height=\"244\" loading=\"lazy\" data-original-width=\"465\" data-original-height=\"244\" itemprop=\"http:\/\/schema.org\/image\" title=\"COH_Gradins\" alt=\"Espace de c\u00e9l\u00e9brations de la Maison olympique du Canada \u00e0 PyeongChang 2018\" style=\"width: 465px; height: 244px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Espace de c\u00e9l\u00e9brations de la Maison olympique du Canada \u00e0 PyeongChang 2018 <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p>La Maison olympique du Canada sera situ\u00e9e sur la c\u00f4te est de la Cor\u00e9e du Sud, pr\u00e8s du parc olympique de Gangneung. La maison devrait accueillir plus de 10 000 invit\u00e9s au cours des prochains Jeux olympiques d&rsquo;hiver.<\/p>\n<p style=\"text-align:center;\"><strong>Vous serez de passage \u00e0 PyeongChang 2018 ?<br \/>\n<\/strong><strong>Venez faire un tour \u00e0 la Maison olympique du Canada!<\/strong><br \/>\n<strong>I<a href=\"https:\/\/canadaolympichouse.ca\/register\/\">nscrivez-vous ici<\/a><\/strong><\/p>\n<p>Les partisans peuvent s&rsquo;attendre \u00e0 un avant-go\u00fbt de la culture canadienne et \u00e0 des \u00e9v\u00e9nements excitants \u00e0 la Maison olympique du Canada. Si vous avez la chance de la visiter, vous pourrez y regarder \u00c9quipe Canada en comp\u00e9tition, savourer des repas et boissons typiquement canadiens, participer aux c\u00e9l\u00e9brations des athl\u00e8tes et voir vos athl\u00e8tes pr\u00e9f\u00e9r\u00e9s alors qu&rsquo;ils seront de passage au Studio Facebook Live d&rsquo;\u00c9quipe Canada pr\u00e9sent\u00e9 par Sport Chek.<\/p>\n<div id=\"attachment_133725\" style=\"width: 1141px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-133725\" class=\"wp-image-133725 size-large\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2018\/01\/20180106_terrace-v3-e1515384932744.jpg?quality=100&amp;w=1131\" alt=\"\" width=\"1131\" height=\"754\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180106_terrace-v3-e1515384932744.jpg 1340w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180106_terrace-v3-e1515384932744.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180106_terrace-v3-e1515384932744.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180106_terrace-v3-e1515384932744.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/20180106_terrace-v3-e1515384932744.jpg?resize=1131,754 1131w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><p id=\"caption-attachment-133725\" class=\"wp-caption-text\">Terrasse de la Maison olympique du Canada \u00e0 PyeongChang 2018<\/p><\/div>\n<p>Les partisans qui souhaitent visiter la Maison olympique du Canada peuvent se rendre le site canadaolympichouse.ca pour acheter des billets avant les Jeux. Seul un nombre limit\u00e9 de billets sera disponible, alors achetez vos billets maintenant!<\/p>\n<p>La Maison olympique du Canada sera officiellement ouverte le 10 f\u00e9vrier 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les premi\u00e8res images de la Maison olympique du Canada de PyeongChang 2018 ont \u00e9t\u00e9 d\u00e9voil\u00e9es lundi matin. La Maison olympique&#8230;<\/p>\n","protected":false},"author":96107080,"featured_media":133730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1104411,184355117,54771154],"post_format":"standard","sport":[],"game":[415985119],"coauthors":[209272438],"class_list":["post-133722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-equipe-canada","tag-maison-olympique-du-canada","tag-pyeongchang-2018","game-2018-pyeongchang"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Les premi\u00e8res images de la Maison olympique du Canada de PyeongChang 2018 ont \u00e9t\u00e9 d\u00e9voil\u00e9es lundi matin. La Maison olympique...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-08T12:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-11T00:09:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_scene-v2.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ariane Desrosiers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ariane Desrosiers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/\"},\"author\":{\"name\":\"Ariane Desrosiers\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\"},\"headline\":\"Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018\",\"datePublished\":\"2018-01-08T12:00:25+00:00\",\"dateModified\":\"2018-01-11T00:09:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/\"},\"wordCount\":288,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/coh_scene-v2.jpg?quality=100\",\"keywords\":[\"\u00c9quipe canada\",\"Maison Olympique du Canada\",\"pyeongchang 2018\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/\",\"name\":\"Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/coh_scene-v2.jpg?quality=100\",\"datePublished\":\"2018-01-08T12:00:25+00:00\",\"dateModified\":\"2018-01-11T00:09:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/08\\\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/coh_scene-v2.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/coh_scene-v2.jpg?quality=100\",\"width\":1200,\"height\":630,\"caption\":\"Gradins de la Maison olympique du Canada \u00e0 PyeongChang 2018\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/b1f02c0e9401652f763191612edde4e2\",\"name\":\"Ariane Desrosiers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=gbd92884420bbfa56539e46241678b7d5\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g\",\"caption\":\"Ariane Desrosiers\"},\"description\":\"Specialist, Social Sp\u00e9cialiste, M\u00e9dias num\u00e9riques\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/arianedesrosiers\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/","og_locale":"fr_FR","og_type":"article","og_title":"Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Les premi\u00e8res images de la Maison olympique du Canada de PyeongChang 2018 ont \u00e9t\u00e9 d\u00e9voil\u00e9es lundi matin. La Maison olympique...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2018-01-08T12:00:25+00:00","article_modified_time":"2018-01-11T00:09:19+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_scene-v2.jpg?quality=100","type":"image\/jpeg"}],"author":"Ariane Desrosiers","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ariane Desrosiers","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/"},"author":{"name":"Ariane Desrosiers","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2"},"headline":"Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018","datePublished":"2018-01-08T12:00:25+00:00","dateModified":"2018-01-11T00:09:19+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/"},"wordCount":288,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_scene-v2.jpg?quality=100","keywords":["\u00c9quipe canada","Maison Olympique du Canada","pyeongchang 2018"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/","url":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/","name":"Aper\u00e7u de la Maison olympique du Canada \u00e0 PyeongChang 2018 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_scene-v2.jpg?quality=100","datePublished":"2018-01-08T12:00:25+00:00","dateModified":"2018-01-11T00:09:19+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/08\/apercu-de-la-maison-olympique-du-canada-a-pyeongchang-2018\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_scene-v2.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_scene-v2.jpg?quality=100","width":1200,"height":630,"caption":"Gradins de la Maison olympique du Canada \u00e0 PyeongChang 2018"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/b1f02c0e9401652f763191612edde4e2","name":"Ariane Desrosiers","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=gbd92884420bbfa56539e46241678b7d5","url":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7248cc9e6971153fdd196741b079c0229522d18a24f1fb69fb73c510aa6e189?s=96&d=identicon&r=g","caption":"Ariane Desrosiers"},"description":"Specialist, Social Sp\u00e9cialiste, M\u00e9dias num\u00e9riques","url":"https:\/\/develop.olympic.ca\/olympique\/author\/arianedesrosiers\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_scene-v2.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/coh_scene-v2.jpg?quality=100","author_name":["Ariane Desrosiers"],"category_names":["Uncategorized"],"tag_names":["\u00c9quipe canada","Maison Olympique du Canada","pyeongchang 2018"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-yMO","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/133722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/96107080"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=133722"}],"version-history":[{"count":3,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/133722\/revisions"}],"predecessor-version":[{"id":133891,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/133722\/revisions\/133891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/133730"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=133722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=133722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=133722"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=133722"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=133722"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=133722"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=133722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}