{"id":134667,"date":"2018-01-24T11:38:37","date_gmt":"2018-01-24T16:38:37","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=134667"},"modified":"2018-01-28T14:06:51","modified_gmt":"2018-01-28T19:06:51","slug":"deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/","title":{"rendered":"Deux athl\u00e8tes composent l&rsquo;\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018"},"content":{"rendered":"<h2 class=\"lead\">Les <a href=\"https:\/\/develop.olympic.ca\/olympique\/sports\/ski-saut-a-ski\/\">sauteurs \u00e0 ski<\/a> s\u00e9lectionn\u00e9s pour repr\u00e9senter le Canada aux prochains Jeux olympiques d&rsquo;hiver sont\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/mackenzie-boyd-clowes\/\">Mackenzie Boyd-Clowes\u00a0<\/a>et <b>\u00a0<\/b><a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/taylor-henrich\/\">Taylor Henrich.<\/a><\/h2>\n<p><a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/taylor-henrich\/\">Taylor Henrich<\/a> en sera \u00e0 ses deuxi\u00e8mes Jeux olympiques d&rsquo;hiver. Elle a fait ses d\u00e9buts olympiques au saut \u00e0 ski f\u00e9minin aux <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2014-sotchi\/\">Jeux de Sotchi<\/a> en 2014, alors qu&rsquo;elle est arriv\u00e9e 13e \u00e0 l&rsquo;\u00e9preuve de tremplin normal individuel. En 2015, elle est devenue la premi\u00e8re femme canadienne \u00e0 remporter une m\u00e9daille de Coupe du monde de saut \u00e0 ski avec sa troisi\u00e8me place \u00e0 Oberstdorf en Allemagne.<\/p>\n<p>\u00c0 LIRE:\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/2017\/11\/16\/apercu-hiver-2017-2018-les-sauteurs-a-ski-dequipe-canada-prets-a-senvoler\/\">Aper\u00e7u hiver 2017-2018: les sauteurs \u00e0 ski canadiens en qu\u00eate de qualifications olympiques<\/a><\/p>\n<p>Avant d&rsquo;atterrir en Cor\u00e9e du Sud, Henrich participera aux comp\u00e9titions de Ljubno en Slov\u00e9nie du 26 au 28 janvier, et de Hinzenbach en Autriche du 2 au 4 f\u00e9vrier.<\/p>\n<div id=\"attachment_134671\" style=\"width: 1146px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-134671\" class=\"wp-image-134671 size-large\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2018\/01\/05823419.jpg?quality=100&amp;w=1136\" alt=\"Equipe Canada Team Canada Taylor Henrich\" width=\"1136\" height=\"754\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/05823419.jpg 3000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/05823419.jpg?resize=238,158 238w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/05823419.jpg?resize=559,371 559w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/05823419.jpg?resize=768,510 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/05823419.jpg?resize=1136,754 1136w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/05823419.jpg?resize=1536,1019 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/05823419.jpg?resize=2048,1359 2048w\" sizes=\"(max-width: 1136px) 100vw, 1136px\" \/><p id=\"caption-attachment-134671\" class=\"wp-caption-text\">La Canadienne Taylor Henrich \u00e0 l&rsquo;\u00e9preuve de tremplin normal de saut \u00e0 ski aux Jeux de Sotchi 2014. THE CANADIAN PRESS\/Nathan Denette<\/p><\/div>\n<p>Du c\u00f4t\u00e9 de\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/mackenzie-boyd-clowes\/\">Mackenzie Boyd-Clowes<\/a>, PyeongChang 2018 seront ses troisi\u00e8mes Jeux, apr\u00e8s <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2014-sotchi\/\">Sotchi 2014<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2010-vancouver\/\">Vancouver 2010<\/a>. Premier sauteur \u00e0 ski canadien \u00e0 d\u00e9passer la marque de 200 m\u00e8tres, il a battu son record personnel en 2016 en sautant \u00e0 224 m. Avant de s&rsquo;envoler pour PyeongChang, Boyd-Clowes participera du 26 au 28 janvier aux \u00e9preuves de la Coupe du monde se d\u00e9roulant \u00e0 Zakopane en Pologne, et \u00e0 Willingen en Allemagne du 2 au 4 f\u00e9vrier.<\/p>\n<div id=\"attachment_134672\" style=\"width: 1172px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-134672\" class=\"wp-image-134672 size-large\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2018\/01\/14513920.jpg?quality=100&amp;w=1162\" alt=\"\" width=\"1162\" height=\"754\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/14513920.jpg 3624w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/14513920.jpg?resize=243,158 243w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/14513920.jpg?resize=572,371 572w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/14513920.jpg?resize=768,498 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/14513920.jpg?resize=1162,754 1162w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/14513920.jpg?resize=1536,997 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/14513920.jpg?resize=2048,1329 2048w\" sizes=\"(max-width: 1162px) 100vw, 1162px\" \/><p id=\"caption-attachment-134672\" class=\"wp-caption-text\">Le Canadien Mackenzie Boyd-Clowes durant les qualifications de la Coupe du monde masculine de saut \u00e0 ski de la FIS \u00e0 PyeongChang en f\u00e9vrier 2017. (AP Photo\/Lee Jin-man)<\/p><\/div>\n<p>Les \u00e9preuves de saut \u00e0 ski se d\u00e9rouleront du 8 au 19 f\u00e9vrier au <a href=\"https:\/\/develop.olympic.ca\/olympique\/venues\/zone-alpine-2\/\">Centre de saut \u00e0 ski d\u2019Alpensia<\/a>.<\/p>\n<p><a href=\"https:\/\/develop.olympic.ca\/olympique\/composition-dequipe-canada\/\">Voyez\u00a0tous les athl\u00e8tes faisant partie de l&rsquo;\u00c9quipe Canada pour PyeongChang 2018<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les sauteurs \u00e0 ski s\u00e9lectionn\u00e9s pour repr\u00e9senter le Canada aux prochains Jeux olympiques d&rsquo;hiver sont\u00a0Mackenzie Boyd-Clowes\u00a0et \u00a0Taylor Henrich. Taylor Henrich&#8230;<\/p>\n","protected":false},"author":133630547,"featured_media":134788,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[1104411,206670794,31926240,415655544,415985114,12670004,7478,44475,210296583,25678],"post_format":"standard","sport":[181823548],"game":[415985119],"coauthors":[415985984],"class_list":["post-134667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-equipe-canada","tag-jeux-olympiques-dhiver-2","tag-mackenzie-boyd-clowes","tag-pyeongchang","tag-pyeongchang2018","tag-saut-a-ski","tag-ski","tag-ski-jumping","tag-taylor-henrich","tag-team-canada","sport-ski-saut-a-ski","game-2018-pyeongchang"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deux athl\u00e8tes composent l&#039;\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018 - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deux athl\u00e8tes composent l&#039;\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018 - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Les sauteurs \u00e0 ski s\u00e9lectionn\u00e9s pour repr\u00e9senter le Canada aux prochains Jeux olympiques d&rsquo;hiver sont\u00a0Mackenzie Boyd-Clowes\u00a0et \u00a0Taylor Henrich. Taylor Henrich...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-24T16:38:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-28T19:06:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/ski-jumping-announcement-header-1.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1340\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00c9lise Mad\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00c9lise Mad\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/\"},\"author\":{\"name\":\"\u00c9lise Mad\u00e9\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/ca5094026a745e2f6fc1b9c2f7a91a90\"},\"headline\":\"Deux athl\u00e8tes composent l&rsquo;\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018\",\"datePublished\":\"2018-01-24T16:38:37+00:00\",\"dateModified\":\"2018-01-28T19:06:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/\"},\"wordCount\":313,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/ski-jumping-announcement-header-1.jpg?quality=100\",\"keywords\":[\"\u00c9quipe canada\",\"Jeux Olympiques d'hiver\",\"Mackenzie Boyd-Clowes\",\"PyeongChang\",\"pyeongchang2018\",\"saut \u00e0 ski\",\"ski\",\"Ski jumping\",\"Taylor Henrich\",\"team canada\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/\",\"name\":\"Deux athl\u00e8tes composent l'\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018 - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/ski-jumping-announcement-header-1.jpg?quality=100\",\"datePublished\":\"2018-01-24T16:38:37+00:00\",\"dateModified\":\"2018-01-28T19:06:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/ca5094026a745e2f6fc1b9c2f7a91a90\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/01\\\/24\\\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/ski-jumping-announcement-header-1.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/01\\\/ski-jumping-announcement-header-1.jpg?quality=100\",\"width\":1340,\"height\":754},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/ca5094026a745e2f6fc1b9c2f7a91a90\",\"name\":\"\u00c9lise Mad\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45dbeb59ae5d11604151de4d2816715d11dd903ff28d1a04854fe7a35288acfa?s=96&d=identicon&r=ga147d6616ae67e7186c819e64d9170da\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45dbeb59ae5d11604151de4d2816715d11dd903ff28d1a04854fe7a35288acfa?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45dbeb59ae5d11604151de4d2816715d11dd903ff28d1a04854fe7a35288acfa?s=96&d=identicon&r=g\",\"caption\":\"\u00c9lise Mad\u00e9\"},\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/elisemade2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deux athl\u00e8tes composent l'\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018 - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/","og_locale":"fr_FR","og_type":"article","og_title":"Deux athl\u00e8tes composent l'\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018 - \u00c9quipe Canada","og_description":"Les sauteurs \u00e0 ski s\u00e9lectionn\u00e9s pour repr\u00e9senter le Canada aux prochains Jeux olympiques d&rsquo;hiver sont\u00a0Mackenzie Boyd-Clowes\u00a0et \u00a0Taylor Henrich. Taylor Henrich...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2018-01-24T16:38:37+00:00","article_modified_time":"2018-01-28T19:06:51+00:00","og_image":[{"width":1340,"height":754,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/ski-jumping-announcement-header-1.jpg?quality=100","type":"image\/jpeg"}],"author":"\u00c9lise Mad\u00e9","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u00c9lise Mad\u00e9","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/"},"author":{"name":"\u00c9lise Mad\u00e9","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/ca5094026a745e2f6fc1b9c2f7a91a90"},"headline":"Deux athl\u00e8tes composent l&rsquo;\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018","datePublished":"2018-01-24T16:38:37+00:00","dateModified":"2018-01-28T19:06:51+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/"},"wordCount":313,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/ski-jumping-announcement-header-1.jpg?quality=100","keywords":["\u00c9quipe canada","Jeux Olympiques d'hiver","Mackenzie Boyd-Clowes","PyeongChang","pyeongchang2018","saut \u00e0 ski","ski","Ski jumping","Taylor Henrich","team canada"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/","url":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/","name":"Deux athl\u00e8tes composent l'\u00e9quipe canadienne de saut \u00e0 ski pour PyeongChang 2018 - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/ski-jumping-announcement-header-1.jpg?quality=100","datePublished":"2018-01-24T16:38:37+00:00","dateModified":"2018-01-28T19:06:51+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/ca5094026a745e2f6fc1b9c2f7a91a90"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/01\/24\/deux-athletes-composent-lequipe-canadienne-de-saut-a-ski-pour-pyeongchang-2018\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/ski-jumping-announcement-header-1.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/ski-jumping-announcement-header-1.jpg?quality=100","width":1340,"height":754},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/ca5094026a745e2f6fc1b9c2f7a91a90","name":"\u00c9lise Mad\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/45dbeb59ae5d11604151de4d2816715d11dd903ff28d1a04854fe7a35288acfa?s=96&d=identicon&r=ga147d6616ae67e7186c819e64d9170da","url":"https:\/\/secure.gravatar.com\/avatar\/45dbeb59ae5d11604151de4d2816715d11dd903ff28d1a04854fe7a35288acfa?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45dbeb59ae5d11604151de4d2816715d11dd903ff28d1a04854fe7a35288acfa?s=96&d=identicon&r=g","caption":"\u00c9lise Mad\u00e9"},"url":"https:\/\/develop.olympic.ca\/olympique\/author\/elisemade2\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/ski-jumping-announcement-header-1.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/01\/ski-jumping-announcement-header-1.jpg?quality=100","author_name":["\u00c9lise Mad\u00e9"],"category_names":["Uncategorized"],"tag_names":["\u00c9quipe canada","Jeux Olympiques d'hiver","Mackenzie Boyd-Clowes","PyeongChang","pyeongchang2018","saut \u00e0 ski","ski","Ski jumping","Taylor Henrich","team canada"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-z23","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/134667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/133630547"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=134667"}],"version-history":[{"count":10,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/134667\/revisions"}],"predecessor-version":[{"id":135120,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/134667\/revisions\/135120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/134788"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=134667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=134667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=134667"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=134667"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=134667"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=134667"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=134667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}