{"id":142391,"date":"2018-08-26T16:47:29","date_gmt":"2018-08-26T20:47:29","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=142391"},"modified":"2018-10-08T11:06:26","modified_gmt":"2018-10-08T15:06:26","slug":"brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/","title":{"rendered":"Brooke Henderson remporte l&rsquo;Omnium canadien et marque l&rsquo;histoire"},"content":{"rendered":"<h2 class=\"lead\"><a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/brooke-henderson\/\">Brooke Henderson<\/a> n&rsquo;en a pas termin\u00e9 d&rsquo;accomplir des exploits. Sa plus r\u00e9cente victoire s&rsquo;est d\u00e9roul\u00e9e ce week-end, \u00e0 Regina, alors qu&rsquo;elle est devenue la premi\u00e8re Canadienne \u00e0 remporter l&rsquo;Omnium canadien depuis Jocelyne Bourassa, en 1973, ann\u00e9e de la premi\u00e8re \u00e9dition du tournoi. Elle a termin\u00e9 avec un score de -21.<\/h2>\n<p>Du haut de ses 20 ans, Henderson est aussi la plus jeune Canadienne \u00e0 gagner ce tournoi. Elle a jou\u00e9 devant une foule locale enthousiaste qui s&rsquo;est agglutin\u00e9e pr\u00e8s des athl\u00e8tes du premier au dernier trou, malgr\u00e9 la temp\u00e9rature plut\u00f4t froide et de forts vents. Si, pour certains, jouer devant les siens avec une possibilit\u00e9 de faire l&rsquo;histoire peut impliquer une grande pression, Henderson a amorc\u00e9 la dernier journ\u00e9e du tournoi avec calme, r\u00e9coltant neuf oiselets et un boguey. Dans le deuxi\u00e8me neuf seulement, elle a encha\u00een\u00e9 quatre oiselets, solidifiant son avance.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udc25\ud83d\udc25\ud83d\udc25\ud83d\udc25 in a row and a par putt gives <a href=\"https:\/\/twitter.com\/BrookeHenderson?ref_src=twsrc%5Etfw\">@BrookeHenderson<\/a> a 3 stroke lead and has all of Canada holding their breath with only 2 holes to go \ud83d\ude2c<br \/> <a href=\"https:\/\/t.co\/x5MlscpcmD\">pic.twitter.com\/x5MlscpcmD<\/a><\/p>\n<p>&mdash; Golf Canada (@TheGolfCanada) <a href=\"https:\/\/twitter.com\/TheGolfCanada\/status\/1033803960706973697?ref_src=twsrc%5Etfw\">August 26, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Henderson a commenc\u00e9 la ronde finale, dimanche, avec une avance d&rsquo;un coup devant la Japonaise Nasa Hataoka et l&rsquo;Am\u00e9ricaine Angel Yin. \u00ab Je suis d\u00e9finitivement en bonne position pour la ronde finale, ce qui est tr\u00e8s excitant, a-t-elle dit. Je trouve que les foules cette semaine ont \u00e9t\u00e9 vraiment incroyables, j&rsquo;ai bien jou\u00e9 pour elles, alors \u00e7a me rend heureuse. \u00bb<\/p>\n<div id=\"attachment_142393\" style=\"width: 1141px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-142393\" class=\"wp-image-142393 size-large\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-2.jpg?quality=100&amp;w=1131\" alt=\"Brooke Henderson joue lors de la troisi\u00e8me ronde de l'Omnium canadien, le 25 ao\u00fbt 2018, \u00e0 Regina, en Saskatchewan. Photo Bernard Brault, Golf Canada\" width=\"1131\" height=\"754\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-2.jpg 1360w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-2.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-2.jpg?resize=556,371 556w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-2.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-2.jpg?resize=1131,754 1131w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><p id=\"caption-attachment-142393\" class=\"wp-caption-text\">Brooke Henderson joue lors de la troisi\u00e8me ronde de l&rsquo;Omnium canadien, le 25 ao\u00fbt 2018, \u00e0 Regina, en Saskatchewan. Photo Bernard Brault, Golf Canada<\/p><\/div>\n<p>Henderson a une fiche de 66, 66, 70 et 65 pour les quatre jours du tournoi. Cette victoire est sa septi\u00e8me en carri\u00e8re sur le circuit de la LPGA et sa deuxi\u00e8me de la saison. Elle a <a href=\"http:\/\/develop.olympic.ca\/olympique\/2018\/04\/15\/brooke-henderson-obtient-sa-sixieme-victoire-lpga-en-carriere\/\">remport\u00e9 le Championnat de Lotte<\/a> plus t\u00f4t cette ann\u00e9e, en avril.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brooke Henderson n&rsquo;en a pas termin\u00e9 d&rsquo;accomplir des exploits. Sa plus r\u00e9cente victoire s&rsquo;est d\u00e9roul\u00e9e ce week-end, \u00e0 Regina, alors&#8230;<\/p>\n","protected":false},"author":132655687,"featured_media":142394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[84908545,415987523,1104411,2306,415986517,23309513],"post_format":"standard","sport":[415984036],"game":[],"coauthors":[415985478,415985452],"class_list":["post-142391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-brooke-henderson","tag-cp-open","tag-equipe-canada","tag-sport-golf","tag-histoire","tag-omnium-canadien","sport-golf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brooke Henderson remporte l&#039;Omnium canadien et marque l&#039;histoire - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brooke Henderson remporte l&#039;Omnium canadien et marque l&#039;histoire - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Brooke Henderson n&rsquo;en a pas termin\u00e9 d&rsquo;accomplir des exploits. Sa plus r\u00e9cente victoire s&rsquo;est d\u00e9roul\u00e9e ce week-end, \u00e0 Regina, alors...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-26T20:47:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-08T15:06:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camille Laventure, Ellen McCann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camille Laventure, Ellen McCann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/\"},\"author\":{\"name\":\"Camille Laventure\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/20ac103fca93b616e9650326fae451dc\"},\"headline\":\"Brooke Henderson remporte l&rsquo;Omnium canadien et marque l&rsquo;histoire\",\"datePublished\":\"2018-08-26T20:47:29+00:00\",\"dateModified\":\"2018-10-08T15:06:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/\"},\"wordCount\":319,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/08\\\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100\",\"keywords\":[\"Brooke Henderson\",\"CP Open\",\"\u00c9quipe canada\",\"Golf\",\"histoire\",\"omnium canadien\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/\",\"name\":\"Brooke Henderson remporte l'Omnium canadien et marque l'histoire - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/08\\\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100\",\"datePublished\":\"2018-08-26T20:47:29+00:00\",\"dateModified\":\"2018-10-08T15:06:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/20ac103fca93b616e9650326fae451dc\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2018\\\/08\\\/26\\\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/08\\\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/08\\\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100\",\"width\":1010,\"height\":568},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/20ac103fca93b616e9650326fae451dc\",\"name\":\"Camille Laventure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g3507809f2fadbf7af37995cf88fe9675\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g\",\"caption\":\"Camille Laventure\"},\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/camillelaventure\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brooke Henderson remporte l'Omnium canadien et marque l'histoire - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Brooke Henderson remporte l'Omnium canadien et marque l'histoire - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Brooke Henderson n&rsquo;en a pas termin\u00e9 d&rsquo;accomplir des exploits. Sa plus r\u00e9cente victoire s&rsquo;est d\u00e9roul\u00e9e ce week-end, \u00e0 Regina, alors...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2018-08-26T20:47:29+00:00","article_modified_time":"2018-10-08T15:06:26+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100","type":"image\/jpeg"}],"author":"Camille Laventure, Ellen McCann","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camille Laventure, Ellen McCann","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/"},"author":{"name":"Camille Laventure","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/20ac103fca93b616e9650326fae451dc"},"headline":"Brooke Henderson remporte l&rsquo;Omnium canadien et marque l&rsquo;histoire","datePublished":"2018-08-26T20:47:29+00:00","dateModified":"2018-10-08T15:06:26+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/"},"wordCount":319,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100","keywords":["Brooke Henderson","CP Open","\u00c9quipe canada","Golf","histoire","omnium canadien"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/","url":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/","name":"Brooke Henderson remporte l'Omnium canadien et marque l'histoire - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100","datePublished":"2018-08-26T20:47:29+00:00","dateModified":"2018-10-08T15:06:26+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/20ac103fca93b616e9650326fae451dc"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/26\/brooke-henderson-remporte-lomnium-canadien-et-marque-lhistoire\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100","width":1010,"height":568},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/20ac103fca93b616e9650326fae451dc","name":"Camille Laventure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g3507809f2fadbf7af37995cf88fe9675","url":"https:\/\/secure.gravatar.com\/avatar\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae75c5158b8f12e220a16c2e0aca48a6565d667459c675ad7d3a5b421fe06603?s=96&d=identicon&r=g","caption":"Camille Laventure"},"url":"https:\/\/develop.olympic.ca\/olympique\/author\/camillelaventure\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/team-canada-brooke-henderson-5-e1535314439498.jpg?quality=100","author_name":["Camille Laventure","Ellen McCann"],"category_names":["Uncategorized"],"tag_names":["Brooke Henderson","CP Open","\u00c9quipe canada","Golf","histoire","omnium canadien"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-B2D","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/142391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/132655687"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=142391"}],"version-history":[{"count":2,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/142391\/revisions"}],"predecessor-version":[{"id":142395,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/142391\/revisions\/142395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/142394"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=142391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=142391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=142391"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=142391"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=142391"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=142391"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=142391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}