{"id":142455,"date":"2018-08-31T22:04:35","date_gmt":"2018-09-01T02:04:35","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=142455"},"modified":"2018-08-31T22:15:55","modified_gmt":"2018-09-01T02:15:55","slug":"us-open-place-au-quatrieme-tour-pour-milos-raonic","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2018\/08\/31\/us-open-place-au-quatrieme-tour-pour-milos-raonic\/","title":{"rendered":"US Open: Place au quatri\u00e8me tour pour Milos Raonic"},"content":{"rendered":"<h2 class=\"lead\">Milos Raonic a dispos\u00e9 du Suisse Stanislas Wawrinka en trois manches de 7-6, 6-4 et 6-3 au troisi\u00e8me tour des Internationaux des \u00c9tats-Unis, vendredi soir \u00e0 New York.<\/h2>\n<p>Si le Canadien a d&rsquo;abord eu besoin du bris d&rsquo;\u00e9galit\u00e9 pour remporter le premier set, il a su accentuer son avance en se sauvant avec la manche suivante au compte de 6-4.\u00a0 Raonic n&rsquo;a pas ralenti et a boucl\u00e9 la boucle 6-3 pour acc\u00e9der au quatri\u00e8me tour du US Open pour la premi\u00e8re fois de sa carri\u00e8re.<\/p>\n<p>Milos Raonic blanchit donc son opposant pour une deuxi\u00e8me rencontre de suite. Il avait jou\u00e9 le tour au Fran\u00e7ais Gilles Simon mercredi apr\u00e8s-midi. Avec quatorze as aujourd&rsquo;hui, Raonic en compte pas moins 57 depuis le d\u00e9but de la comp\u00e9tition. Les partisans risquent d&rsquo;avoir droit \u00e0 deux performances grandioses au service au prochain tour, alors que Milos Raonic fera face \u00e0 l&rsquo;Am\u00e9ricain John Isner. Ce dernier avait \u00e9limin\u00e9 le Canadien lors des quarts de finale de Wimbledon, en juillet dernier. Lors de ce duel, Raonic et Isner avait respectivement cumul\u00e9 31 et 25 as.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Not to be for Denis Shapovalov against last year\u2019s <a href=\"https:\/\/twitter.com\/hashtag\/USOpen?src=hash&amp;ref_src=twsrc%5Etfw\">#USOpen<\/a>\u2060 finalist Kevin Anderson. He goes down 4-6, 6-3, 6-4, 4-6, 6-4.<\/p>\n<p>It might not have been the result he wanted, but he thrilled the crowd with his charisma and fought until the very end. <\/p>\n<p>You made Canada proud, Denis. <a href=\"https:\/\/t.co\/seEgY3RVgB\">pic.twitter.com\/seEgY3RVgB<\/a><\/p>\n<p>&mdash; Tennis Canada (@TennisCanada) <a href=\"https:\/\/twitter.com\/TennisCanada\/status\/1035662548576681984?ref_src=twsrc%5Etfw\">August 31, 2018<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p><strong>\u00c0 LIRE:<\/strong>\u00a0<a href=\"http:\/\/develop.olympic.ca\/olympique\/2018\/08\/29\/us-open-raonic-et-shapovalov-sinvitent-au-troisieme-tour\/\">Raonic et Shapovalov s&rsquo;invitent au troisi\u00e8me tour<\/a><\/p>\n<p>Milos Raonic est donc le seul Canadien restant aux Internationaux des \u00c9tats-Unis. Un peu plus t\u00f4t, Denis Shapovalov s&rsquo;est avou\u00e9 vaincu face \u00e0 la cinqui\u00e8me raquette mondiale, Kevin Anderson. Pour un deuxi\u00e8me match cons\u00e9cutif, Shapo a pris part \u00e0 un v\u00e9ritable marathon de tennis, qui a toutefois perdu cette fois.<\/p>\n<p>Apr\u00e8s avoir eu le dessus sur Andreas Seppi en cinq manches mercredi, le Canadien s&rsquo;est inclin\u00e9 en autant de sets contre Anderson au compte de 6-4, 3-6, 4-6, 6-4 et 6-4. Si l&rsquo;affrontement de mercredi avait dur\u00e9 3 heures et 47 minutes, celui-ci a \u00e9t\u00e9 d&rsquo;une dur\u00e9e de 3 heures et 43 minutes. Denis Shapovalov a cumul\u00e9 13 as durant la partie, mais a \u00e9galement commis huit doubles fautes.<\/p>\n<p>Milos Raonic est donc le seul Canadien restant aux Internationaux des \u00c9tats-Unis. Il reprendra l&rsquo;action au quatri\u00e8me tour face \u00e0 l&rsquo;Am\u00e9ricain John Isner. Ce dernier avait \u00e9limin\u00e9 Raonic lors des quarts de finale de Wimbledon, en juillet dernier.<\/p>\n<p><a href=\"https:\/\/twitter.com\/Equipe_Canada\" target=\"_blank\" rel=\"noopener\"><img \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-140428 size-full\" src=\"https:\/\/develop.olympic.ca\/wp-content\/uploads\/sites\/2\/2018\/05\/twitter_frsocial-ads.png\" alt=\"\" width=\"1340\" height=\"100\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/05\/twitter_frsocial-ads.png 1340w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/05\/twitter_frsocial-ads.png?resize=280,21 280w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/05\/twitter_frsocial-ads.png?resize=660,49 660w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/05\/twitter_frsocial-ads.png?resize=768,57 768w\" sizes=\"(max-width: 1340px) 100vw, 1340px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milos Raonic a dispos\u00e9 du Suisse Stanislas Wawrinka en trois manches de 7-6, 6-4 et 6-3 au troisi\u00e8me tour des&#8230;<\/p>\n","protected":false},"author":133364213,"featured_media":142462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[415984198,1104411,260778387,23905354,415987519,7422531,117413],"post_format":"standard","sport":[1999],"game":[],"coauthors":[415985536],"class_list":["post-142455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-denis-shapovalov","tag-equipe-canada","tag-internationaux-des-etats-unis","tag-milos-raonic","tag-shapo","tag-tennis-2","tag-us-open","sport-tennis"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/raonic1.jpg?quality=100","author_name":["Luc Turgeon"],"category_names":["Uncategorized"],"tag_names":["Denis Shapovalov","\u00c9quipe canada","internationaux des \u00c9tats-Unis","Milos Raonic","Shapo","tennis","us open"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-B3F","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2018\/08\/raonic1.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/142455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/133364213"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=142455"}],"version-history":[{"count":5,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/142455\/revisions"}],"predecessor-version":[{"id":142461,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/142455\/revisions\/142461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/142462"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=142455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=142455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=142455"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=142455"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=142455"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=142455"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=142455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}