{"id":154672,"date":"2019-08-10T16:03:34","date_gmt":"2019-08-10T20:03:34","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=154672"},"modified":"2019-08-10T16:04:12","modified_gmt":"2019-08-10T20:04:12","slug":"bianca-andrescuu-atteint-la-finale-a-toronto","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/","title":{"rendered":"Bianca Andreescu atteint la finale \u00e0 Toronto!"},"content":{"rendered":"<h1>Bianca Andreescu est la premi\u00e8re Canadienne en 50 ans \u00e0 atteindre la finale de la Coupe Rogers \u00e0 Toronto.<\/h1>\n<p>Andreescu a offert un tr\u00e8s beau spectacle \u00e0 la foule partisane en d\u00e9faisant l\u2019Am\u00e9ricaine Sofia Kenin en deux manches de 6-4, 7-6 (5). Malgr\u00e9 une longue deuxi\u00e8me manche, elle n\u2019a pas eu recours \u00e0 une troisi\u00e8me manche pour remporter le match, une premi\u00e8re pour elle, dans ce tournoi.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">TORONTO HAS A CANADIAN FINALIST. \ud83c\udf41<\/p>\n<p>Bianca Andreescu defeats Sofia Kenin 6-4, 7-6(5) to reach the <a href=\"https:\/\/twitter.com\/hashtag\/RC19?src=hash&amp;ref_src=twsrc%5Etfw\">#RC19<\/a> final, bringing her home crowd to their feet and writing history along the way. <\/p>\n<p>Congratulations, <a href=\"https:\/\/twitter.com\/Bandreescu_?ref_src=twsrc%5Etfw\">@Bandreescu_<\/a>! <a href=\"https:\/\/t.co\/R30NCfGUlA\">pic.twitter.com\/R30NCfGUlA<\/a><\/p>\n<p>&mdash; Rogers Cup (@rogerscup) <a href=\"https:\/\/twitter.com\/rogerscup\/status\/1160269944577306624?ref_src=twsrc%5Etfw\">August 10, 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>&nbsp;<\/p>\n<p>\u00c0 LIRE : <a href=\"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/03\/faq-tout-ce-que-vous-devez-savoir-sur-la-coupe-rogers\/\">Tout ce que vous devez savoir sur la Coupe Rogers<\/a><\/p>\n<p>Kenin et Andreescu se sont affront\u00e9es trois fois cette ann\u00e9e, Kenin remportant \u00e0 deux reprises et Andreescu l&#8217;emportant une fois au Open de Miami.<\/p>\n<p>Dimanche, elle affrontera la gagnante du duel opposant la Tch\u00e8que Marie Bouzkova et \u00a0l\u2019Am\u00e9ricaine Serena Williams.<\/p>\n<p>Andreescu tentera de devenir la premi\u00e8re canadienne \u00e0 remporter la Coupe Rogers depuis Faye Urban en 1969. La jeune joueuse de tennis a d\u00e9j\u00e0 marqu\u00e9 l\u2019histoire cette semaine en devenant la premi\u00e8re canadienne \u00e0 atteindre les demi-finales depuis le triomphe d\u2019Urban.<\/p>\n<p>Plus \u00e0 venir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bianca Andreescu est la premi\u00e8re Canadienne en 50 ans \u00e0 atteindre la finale de la Coupe Rogers \u00e0 Toronto. Andreescu&#8230;<\/p>\n","protected":false},"author":112974483,"featured_media":154675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[415988420,1104411,7422531,2444],"post_format":"standard","sport":[1999],"game":[],"coauthors":[415988788],"class_list":["post-154672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-andreescu","tag-equipe-canada","tag-tennis-2","tag-toronto","sport-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bianca Andreescu atteint la finale \u00e0 Toronto! - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bianca Andreescu atteint la finale \u00e0 Toronto! - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Bianca Andreescu est la premi\u00e8re Canadienne en 50 ans \u00e0 atteindre la finale de la Coupe Rogers \u00e0 Toronto. Andreescu...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-10T20:03:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-10T20:04:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/08\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oph\u00e9lie Fortin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oph\u00e9lie Fortin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/\"},\"author\":{\"name\":\"Oph\u00e9lie Fortin\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/1236d6d549bfe8370e678fb9897f8d93\"},\"headline\":\"Bianca Andreescu atteint la finale \u00e0 Toronto!\",\"datePublished\":\"2019-08-10T20:03:34+00:00\",\"dateModified\":\"2019-08-10T20:04:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/\"},\"wordCount\":184,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100\",\"keywords\":[\"Andreescu\",\"\u00c9quipe canada\",\"tennis\",\"Toronto\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/\",\"name\":\"Bianca Andreescu atteint la finale \u00e0 Toronto! - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100\",\"datePublished\":\"2019-08-10T20:03:34+00:00\",\"dateModified\":\"2019-08-10T20:04:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/1236d6d549bfe8370e678fb9897f8d93\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2019\\\/08\\\/10\\\/bianca-andrescuu-atteint-la-finale-a-toronto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/08\\\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100\",\"width\":1010,\"height\":568,\"caption\":\"Bianca Andreescu, of Canada, celebrates after defeating Sofia Kenin, of the United States, in Rogers Cup tennis tournament semifinal action in Toronto on Saturday, Aug. 10, 2019. THE CANADIAN PRESS\\\/Frank Gunn\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/1236d6d549bfe8370e678fb9897f8d93\",\"name\":\"Oph\u00e9lie Fortin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=ge0503e975a6e55c1c1c01f55b9c366de\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=g\",\"caption\":\"Oph\u00e9lie Fortin\"},\"sameAs\":[\"http:\\\/\\\/lecalculot.wordpress.com\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/opheliefortin23\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bianca Andreescu atteint la finale \u00e0 Toronto! - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/","og_locale":"fr_FR","og_type":"article","og_title":"Bianca Andreescu atteint la finale \u00e0 Toronto! - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Bianca Andreescu est la premi\u00e8re Canadienne en 50 ans \u00e0 atteindre la finale de la Coupe Rogers \u00e0 Toronto. Andreescu...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2019-08-10T20:03:34+00:00","article_modified_time":"2019-08-10T20:04:12+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/08\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100","type":"image\/jpeg"}],"author":"Oph\u00e9lie Fortin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Oph\u00e9lie Fortin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/"},"author":{"name":"Oph\u00e9lie Fortin","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/1236d6d549bfe8370e678fb9897f8d93"},"headline":"Bianca Andreescu atteint la finale \u00e0 Toronto!","datePublished":"2019-08-10T20:03:34+00:00","dateModified":"2019-08-10T20:04:12+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/"},"wordCount":184,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/08\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100","keywords":["Andreescu","\u00c9quipe canada","tennis","Toronto"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/","url":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/","name":"Bianca Andreescu atteint la finale \u00e0 Toronto! - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/08\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100","datePublished":"2019-08-10T20:03:34+00:00","dateModified":"2019-08-10T20:04:12+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/1236d6d549bfe8370e678fb9897f8d93"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2019\/08\/10\/bianca-andrescuu-atteint-la-finale-a-toronto\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/08\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/08\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100","width":1010,"height":568,"caption":"Bianca Andreescu, of Canada, celebrates after defeating Sofia Kenin, of the United States, in Rogers Cup tennis tournament semifinal action in Toronto on Saturday, Aug. 10, 2019. THE CANADIAN PRESS\/Frank Gunn"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/1236d6d549bfe8370e678fb9897f8d93","name":"Oph\u00e9lie Fortin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=ge0503e975a6e55c1c1c01f55b9c366de","url":"https:\/\/secure.gravatar.com\/avatar\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=g","caption":"Oph\u00e9lie Fortin"},"sameAs":["http:\/\/lecalculot.wordpress.com"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/opheliefortin23\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/08\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/08\/team-canada-bianca-andreescu-rogers-cup.jpg?quality=100","author_name":["Oph\u00e9lie Fortin"],"category_names":["Uncategorized"],"tag_names":["Andreescu","\u00c9quipe canada","tennis","Toronto"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-EeI","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/154672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/112974483"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=154672"}],"version-history":[{"count":4,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/154672\/revisions"}],"predecessor-version":[{"id":154677,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/154672\/revisions\/154677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/154675"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=154672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=154672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=154672"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=154672"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=154672"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=154672"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=154672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}