{"id":165230,"date":"2020-12-16T10:39:10","date_gmt":"2020-12-16T15:39:10","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=165230"},"modified":"2021-05-05T16:46:38","modified_gmt":"2021-05-05T20:46:38","slug":"ou-sont-ils-rendus-marc-gagnon","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2020\/12\/16\/ou-sont-ils-rendus-marc-gagnon\/","title":{"rendered":"O\u00f9 sont-ils rendus? : Marc Gagnon"},"content":{"rendered":"<hr \/>\n<p><em>Dans la s\u00e9rie\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/tag\/ou-sont-ils-rendus\/\">O\u00f9 sont-ils rendus?<\/a>, Olympique.ca se penche sur l\u2019apr\u00e8s-carri\u00e8re sportive de certains des plus grands olympiens d\u2019\u00c9quipe Canada. Bref, on prend des nouvelles de nos champions!<\/em><\/p>\n<hr \/>\n<h2 class=\"lead\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/marc-gagnon\/\">Marc Gagnon<\/a> figure peut-\u00eatre parmi les athl\u00e8tes canadiens les plus d\u00e9cor\u00e9s aux Jeux olympiques, mais sa carri\u00e8re ne s&rsquo;est certainement pas arr\u00eat\u00e9e lorsqu&rsquo;il a pris sa retraite de la comp\u00e9tition. Apr\u00e8s avoir domin\u00e9 la courte piste en patinage de vitesse pendant de longues ann\u00e9es, que fait-il aujourd&rsquo;hui?<\/h2>\n<p>Lorsqu&rsquo;il a mis fin \u00e0 sa brillante carri\u00e8re de patineur en 2002, Marc Gagnon s&rsquo;est retrouv\u00e9 avec de nombreuses opportunit\u00e9s telles que des partenariats d&rsquo;affaires (avec La Cage aux Sports et \u00c9nergie Cardio, notamment) et de nombreuses apparitions dans les m\u00e9dias et \u00e0 la t\u00e9l\u00e9vision.<\/p>\n<p>Le quintuple m\u00e9daill\u00e9 olympique a d&rsquo;ailleurs \u00e9t\u00e9 intronis\u00e9 au Temple de la renomm\u00e9e olympique du Canada en 2007. On a m\u00eame baptis\u00e9 un ar\u00e9na en son nom, le Centre Marc Gagnon, qui accueille les jeunes athl\u00e8tes de la rel\u00e8ve et le club de patinage de vitesse de sa ville natale, Chicoutimi.<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/marc-gagnon\/\">Tous les exploits de Marc Gagnon<\/a><\/strong><\/p>\n<p>Le patinage de vitesse est une histoire de famille pour Marc Gagnon, qui avait suivi les traces de son fr\u00e8re <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/sylvain-gagnon\/\">Sylvain Gagnon<\/a>, m\u00e9daill\u00e9 des <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/1992-albertville\/\">Jeux d&rsquo;Albertville 1992<\/a>. Aujourd&rsquo;hui \u00e2g\u00e9 de 45 ans, Marc est p\u00e8re de deux enfants et continue d&rsquo;inspirer les prochaines g\u00e9n\u00e9rations de patineurs.<\/p>\n<div id=\"attachment_165260\" style=\"width: 1090px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-165260\" class=\"wp-image-165260 size-full\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/CP2794255-e1607711647286.jpg?quality=100\" alt=\"Marc Gagnon, m\u00e9daill\u00e9 olympique en patinage de vitesse de courte piste, signe des autographes lors d'un hommage aux m\u00e9daill\u00e9s olympiques et paralympiques canadiens au Mus\u00e9e de la civilisation de Gatineau, QC. Le lundi 15 avril 2002.(CP PHOTO\/Jonathan Hayward)\" width=\"1080\" height=\"764\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/CP2794255-e1607711647286.jpg 1080w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/CP2794255-e1607711647286.jpg?resize=223,158 223w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/CP2794255-e1607711647286.jpg?resize=524,371 524w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/CP2794255-e1607711647286.jpg?resize=768,543 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/CP2794255-e1607711647286.jpg?resize=1066,754 1066w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><p id=\"caption-attachment-165260\" class=\"wp-caption-text\">Marc Gagnon, m\u00e9daill\u00e9 olympique en patinage de vitesse de courte piste, signe des autographes lors d&rsquo;un hommage aux m\u00e9daill\u00e9s olympiques et paralympiques canadiens au Mus\u00e9e de la civilisation de Gatineau, QC. Le lundi 15 avril 2002.(CP PHOTO\/Jonathan Hayward)<\/p><\/div>\n<p>Apr\u00e8s sa retraite du patinage de vitesse, Marc Gagnon est rest\u00e9 loin de la glace pendant huit ans, jusqu&rsquo;\u00e0 ce qu&rsquo;il d\u00e9cide finalement de retourner \u00e0 ses sources. C&rsquo;est gr\u00e2ce \u00e0 <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jonathan-guilmette\/\">Jonathan Guilmette<\/a>, m\u00e9daill\u00e9 olympique avec qui il a partag\u00e9 le podium aux Jeux de <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2002-salt-lake-city\/\">Salt Lake City 2002<\/a>, qu&rsquo;il a commenc\u00e9 sa carri\u00e8re de coach \u00e0 temps partiel au club Montr\u00e9al International. En 2014, il a rejoint son fr\u00e8re Sylvain au Centre r\u00e9gional canadien d\u2019entra\u00eenement en tant qu&rsquo;entra\u00eeneur en chef en patinage de vitesse sur courte piste aupr\u00e8s de jeunes patineurs \u00e2g\u00e9s de 14 \u00e0 19 ans qui s&rsquo;entrainent pour joindre l&rsquo;\u00e9quipe nationale. Le 12 janvier 2020, Marc Gagnon est mont\u00e9 d&rsquo;un \u00e9chelon en devenant entra\u00eeneur adjoint de l&rsquo;\u00e9quipe canadienne de patinage de vitesse sur courte piste, une transition naturelle et logique vu sa grande exp\u00e9rience en tant que patineur et entra\u00eeneur. Il aura la chance de travailler avec les m\u00eames athl\u00e8tes qu&rsquo;il avait form\u00e9s au CRCE et qui font maintenant partie de l&rsquo;\u00e9quipe nationale.<\/p>\n<p>Visionnez le t\u00e9moignage touchant de Marc Gagnon qui porte un regard sur sa carri\u00e8re :<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1360\" height=\"765\" src=\"https:\/\/www.youtube.com\/embed\/Y80WjVvBX90?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>\u00ab Pendant 10 ans, j\u2019ai eu la chance d\u2019aider des jeunes \u00e0 progresser et \u00e0 atteindre l\u2019\u00e9quipe nationale. Maintenant, je vais essayer de donner tout ce qui me reste comme bagage pour qu\u2019ils puissent r\u00e9ussir \u00e0 un plus haut niveau. Je m\u2019en vais dans la tr\u00e8s haute performance. C\u2019est le temps d\u2019\u00eatre bon ! \u00bb, explique-t-il dans un <a href=\"https:\/\/www.lapresse.ca\/sports\/sports-d-hiver\/2021-01-12\/courte-piste\/marc-gagnon-nomme-entraineur-adjoint-de-l-equipe-nationale.php\">article de La Presse<\/a> suivant l&rsquo;annonce.<\/p>\n<div id=\"attachment_165261\" style=\"width: 696px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-165261\" class=\"wp-image-165261 size-full\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/4b80d024-132c-4e8c-9885-e0441846cc6c_ORIGINAL.jpg?quality=100\" alt=\"Marc Gagnon d'\u00c9quipe Canada donne ses conseils \u00e0 un de ses athl\u00e8tes de patinage de vitesse sur courte piste en tant qu'entra\u00eeneur du Centre r\u00e9gional canadien d'entra\u00eenement.\" width=\"686\" height=\"600\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/4b80d024-132c-4e8c-9885-e0441846cc6c_ORIGINAL.jpg 686w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/4b80d024-132c-4e8c-9885-e0441846cc6c_ORIGINAL.jpg?resize=181,158 181w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/4b80d024-132c-4e8c-9885-e0441846cc6c_ORIGINAL.jpg?resize=424,371 424w\" sizes=\"(max-width: 686px) 100vw, 686px\" \/><p id=\"caption-attachment-165261\" class=\"wp-caption-text\">Marc Gagnon d&rsquo;\u00c9quipe Canada donne ses conseils \u00e0 un de ses athl\u00e8tes de patinage de vitesse sur courte piste en tant qu&rsquo;entra\u00eeneur du Centre r\u00e9gional canadien d&rsquo;entra\u00eenement. Photo : Ben Pelosse\/Journal de Montr\u00e9al<\/p><\/div>\n<p>Pour ce qui est du CRCE, n&rsquo;ayez crainte : Marc Gagnon continuera \u00e0 jouer un r\u00f4le de supervision dans la prochaine ann\u00e9e. De plus, il a r\u00e9cemment recrut\u00e9 <a href=\"https:\/\/develop.olympic.ca\/olympique\/2020\/11\/18\/ou-sont-ils-rendus-marianne-st-gelais\/\">Marianne St-Gelais dans l&rsquo;\u00e9quipe il y a quelques mois en tant qu&rsquo;entra\u00eeneure-adjointe<\/a>. Je ne sais pas pour vous, mais si je voulais me rendre loin en patinage de vitesse sur courte piste, je tenterais de me joindre \u00e0 ce club sans h\u00e9sitation pour apprendre des plus grands du sport!<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/develop.olympic.ca\/olympique\/2020\/11\/18\/ou-sont-ils-rendus-marianne-st-gelais\/\">O\u00f9 sont-ils rendus? | Marianne St-Gelais<\/a><\/strong><\/p>\n<p>\u00ab J\u2019aime vraiment ce que je fais. Quand je me l\u00e8ve \u00e0 cinq heures du matin pour aller travailler, ce n\u2019est pas un fardeau. \u00bb, affirmait Gagnon il y a quelques ann\u00e9es <a href=\"https:\/\/www.journaldemontreal.com\/2017\/03\/03\/marc-gagnon-transmet-sa-passion\">dans un article du Journal de Montr\u00e9al<\/a>.<\/p>\n<p>Vous savez ce que le dicton dit : l&rsquo;avenir appartient \u00e0 ceux qui se l\u00e8vent t\u00f4t! Et \u00e0 le voir aller, on peut dire que Marc Gagnon continue de suivre ses passions jusqu&rsquo;au bout.<\/p>\n<p style=\"text-align: center;\"><strong>O\u00f9 sont-ils rendus? | <a href=\"https:\/\/develop.olympic.ca\/olympique\/2020\/10\/20\/ou-sont-ils-rendus-roseline-filion\/\">Roseline Filion <\/a> | <a href=\"https:\/\/develop.olympic.ca\/olympique\/2020\/12\/02\/ou-sont-ils-rendus-alex-harvey\/\">Alex Harvey<\/a> | <a href=\"https:\/\/develop.olympic.ca\/olympique\/2020\/11\/23\/ou-sont-ils-rendus-joannie-rochette\/\">Joannie Rochette<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/develop.olympic.ca\/olympique\/tag\/ou-sont-ils-rendus\/\">Cliquez ici<\/a>\u00a0pour voir les autres articles de la s\u00e9rie\u00a0<em>O\u00f9 sont-ils rendus?<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans la s\u00e9rie\u00a0O\u00f9 sont-ils rendus?, Olympique.ca se penche sur l\u2019apr\u00e8s-carri\u00e8re sportive de certains des plus grands olympiens d\u2019\u00c9quipe Canada. Bref,&#8230;<\/p>\n","protected":false},"author":49083863,"featured_media":165262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085,1],"tags":[682163992,682163993,18046872,682164337,682163904,682164336,206767583],"post_format":"standard","sport":[51196772],"game":[],"coauthors":[212154357],"class_list":["post-165230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-uncategorized","tag-centre-regional-canadien-dentrainement","tag-entraineur-patinage-de-vitesse","tag-marc-gagnon","tag-ou-sont-ils-rendus-3","tag-ou-sont-ils-rendus","tag-ou-sont-ils-rendus-2","tag-patinage-de-vitesse-courte-piste-2","sport-patinage-de-vitesse-courte-piste"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/a08aa115-4da9-4733-86e2-dc8c120c6e20_ORIGINAL.jpg?quality=100","author_name":["Marie-\u00c8ve Leclerc"],"category_names":["Nouvelles","Uncategorized"],"tag_names":["Centre r\u00e9gional canadien d'entra\u00eenement","Entra\u00eeneur patinage de vitesse","Marc Gagnon","O\u00f9 sont ils rendus","ou sont-ils rendus","O\u00f9-sont-ils-rendus","Patinage de vitesse courte piste"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-GZ0","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2020\/12\/a08aa115-4da9-4733-86e2-dc8c120c6e20_ORIGINAL.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/165230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/49083863"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=165230"}],"version-history":[{"count":19,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/165230\/revisions"}],"predecessor-version":[{"id":170196,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/165230\/revisions\/170196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/165262"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=165230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=165230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=165230"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=165230"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=165230"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=165230"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=165230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}