{"id":166123,"date":"2021-01-08T10:37:11","date_gmt":"2021-01-08T15:37:11","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=166123"},"modified":"2021-03-11T12:14:14","modified_gmt":"2021-03-11T17:14:14","slug":"cynthia-appiah-un-desir-detre-non-seulement-la-meilleure-mais-aussi-la-meilleure-representante","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2021\/01\/08\/cynthia-appiah-un-desir-detre-non-seulement-la-meilleure-mais-aussi-la-meilleure-representante\/","title":{"rendered":"Cynthia Appiah : Un d\u00e9sir d&rsquo;\u00eatre non seulement la meilleure, mais aussi la meilleure repr\u00e9sentante"},"content":{"rendered":"<h2 class=\"lead\">Ma passion pour le sport est en constante \u00e9volution.<\/h2>\n<p>J&rsquo;ai \u00e9t\u00e9 initi\u00e9e au sport de comp\u00e9tition en sixi\u00e8me ann\u00e9e quand j&rsquo;ai tent\u00e9 de me tailler une place au sein de l&rsquo;\u00e9quipe d&rsquo;athl\u00e9tisme de mon \u00e9cole.<\/p>\n<p>J&rsquo;avais pratiqu\u00e9 des sports d&rsquo;\u00e9quipe auparavant, mais cela avait plus \u00e0 voir avec la participation de mes amis qu&rsquo;avec l&rsquo;amour du sport. L&rsquo;athl\u00e9tisme \u00e9tait diff\u00e9rent, par contre, car il me mettait dans un \u00e9tat d&rsquo;esprit unique. Gagne ou perd, j\u2019\u00e9tais la seule responsable.<\/p>\n<p>Ce test de mes habilet\u00e9s m&rsquo;a intrigu\u00e9e plus que n&rsquo;importe quel sport d&rsquo;\u00e9quipe. Ma passion \u00e9tait d&rsquo;\u00eatre <em>la<\/em> meilleure au sprint (100 m et 200 m) et au lancer (lancer du poids). J&rsquo;\u00e9tais trop jeune pour savoir que le sport, c\u2019\u00e9tait plus que \u00e7a. Je pensais qu&rsquo;\u00eatre la meilleure \u00e9tait la seule chose qui comptait dans le sport.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-166125\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-running.jpg?quality=100\" alt=\"Cynthia court sur la piste.\" width=\"1360\" height=\"1472\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-running.jpg 2771w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-running.jpg?resize=146,158 146w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-running.jpg?resize=343,371 343w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-running.jpg?resize=768,831 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-running.jpg?resize=696,754 696w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-running.jpg?resize=1419,1536 1419w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-running.jpg?resize=1892,2048 1892w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><\/p>\n<p>\u00c0 l\u2019\u00e9cole secondaire et \u00e0 l&rsquo;universit\u00e9, j&rsquo;ai continu\u00e9 \u00e0 exceller dans les \u00e9preuves de lancer (en ajoutant le marteau \u00e0 mon r\u00e9pertoire) et ma passion \u00e9tait toujours d&rsquo;\u00eatre la meilleure. Malgr\u00e9 les nombreuses m\u00e9dailles que j&rsquo;ai remport\u00e9es au cours de ma carri\u00e8re \u00e0 l&rsquo;Universit\u00e9 York, j&rsquo;avais l&rsquo;impression qu&rsquo;il manquait quelque chose. J&rsquo;ai atteint un point o\u00f9 je n&rsquo;appr\u00e9ciais plus le sport pour ce qu&rsquo;il \u00e9tait. J&rsquo;\u00e9tais dans une impasse (ce n\u2019\u00e9tait pas la premi\u00e8re ni la derni\u00e8re) et mon mantra pr\u00e9f\u00e9r\u00e9 ne m&rsquo;aidait pas \u00e0 surmonter mon blocage psychologique. Je savais qu\u2019une participation aux Jeux olympiques d\u2019\u00e9t\u00e9 n\u2019\u00e9tait pas r\u00e9aliste. J&rsquo;avais besoin d&rsquo;un changement et c\u2019est le bobsleigh qui m\u2019a offert ce changement gr\u00e2ce \u00e0 de nouveaux d\u00e9fis.<\/p>\n<p>Pendant pr\u00e8s de dix ans, en tant que sp\u00e9cialiste des lancers, je n\u2019avais pas eu \u00e0 porter une attention particuli\u00e8re \u00e0 la nutrition. Mais pour le bobsleigh, j&rsquo;ai d\u00fb r\u00e9duire mon poids de 196 lb (89 kg) \u00e0 170 lb (75 kg) afin de pouvoir glisser sans que mon \u00e9quipe soit disqualifi\u00e9e. De 2013 \u00e0 2015, j&rsquo;ai travaill\u00e9 sur mon alimentation en plus de devenir plus rapide et plus forte et j&rsquo;ai finalement obtenu une place au sein de l&rsquo;\u00e9quipe nationale \u00e0 l&rsquo;automne 2015.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-166126\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-gym.jpg?quality=100\" alt=\"Cynthia Appiah s'entra\u00eene avec des poids libres au gym.\" width=\"1360\" height=\"837\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-gym.jpg 2048w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-gym.jpg?resize=257,158 257w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-gym.jpg?resize=603,371 603w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-gym.jpg?resize=768,473 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-gym.jpg?resize=1226,754 1226w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-gym.jpg?resize=1536,945 1536w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><\/p>\n<p>En seulement trois ans, je suis devenue la freineuse num\u00e9ro un du programme et j&rsquo;\u00e9tais sur le point de participer \u00e0 mes premiers Jeux olympiques \u00e0 <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2018-pyeongchang\/\">PyeongChang 2018<\/a>. Cependant, au cours de la saison olympique, des situations hors de mon contr\u00f4le sont survenues et je me suis retrouv\u00e9e sur les lignes de c\u00f4t\u00e9 en tant que rempla\u00e7ante.<\/p>\n<p>\u00c0 moins d\u2019une blessure \u00e0 l&rsquo;une des athl\u00e8tes de l\u2019\u00e9quipe, je n\u2019allais pas concourir pour le Canada. Mon r\u00eave s\u2019\u00e9tait envol\u00e9 et les encouragements ou les pens\u00e9es positives ne suffisaient pas \u00e0 me sortir du trou noir qui avait \u00e9t\u00e9 cr\u00e9\u00e9. \u00c0 ce moment, j&rsquo;ai d\u00e9cid\u00e9 qu&rsquo;il \u00e9tait temps de mettre fin \u00e0 la poursuite de mon r\u00eave olympique. Je n\u2019avais pas r\u00e9ussi \u00e0 me qualifier pour les Jeux d\u2019\u00e9t\u00e9 et maintenant, malgr\u00e9 le fait qu\u2019ils \u00e9taient \u00e0 ma port\u00e9e, je n\u2019arrivais pas \u00e0 participer aux Jeux d\u2019hiver.<\/p>\n<p>Je m\u2019\u00e9tais convaincue que mon r\u00eave n\u2019allait pas se r\u00e9aliser et que j\u2019\u00e9tais, v\u00e9ritablement, un \u00e9chec.<\/p>\n<p>Pour les partisans qui regardent de la maison, les projecteurs, l\u2019aspect grandiose et le prestige du spectacle que sont les Jeux olympiques produisent des images d&rsquo;athl\u00e8tes qui travaillent d\u2019arrache-pied pour avoir la chance de faire la fiert\u00e9 de leur pays &#8211; et c&rsquo;est vrai. Mais pour chaque athl\u00e8te qui atteint son objectif, il y a davantage d&rsquo;athl\u00e8tes \u00e0 l&rsquo;arri\u00e8re-plan, qui soutiennent le syst\u00e8me sans aucune reconnaissance. Ils sont presque comme une ombre. C\u2019est ce que j\u2019ai ressenti pendant trois semaines en Cor\u00e9e du Sud \u00e0 l\u2019hiver 2018.<\/p>\n<p>Je me suis sentie \u00e9cart\u00e9e de ma propre \u00e9quipe. Je n\u2019ai pas pu loger dans le village des athl\u00e8tes, j\u2019\u00e9tais plut\u00f4t install\u00e9e dans un h\u00f4tel voisin. M\u00eame si j&rsquo;\u00e9tais une athl\u00e8te, mon r\u00f4le officiel aux Jeux \u00e9tait celui de membre du personnel de soutien. En tant que freineuse rempla\u00e7ante, mon r\u00f4le \u00e9tait de prendre part \u00e0 la majorit\u00e9 des descentes d\u2019entra\u00eenement afin que la freineuse principale soit bien repos\u00e9e. Chaque jour, je devais pousser au maximum pour donner aux pilotes une pouss\u00e9e qui se rapprochait le plus possible de celle d\u2019une journ\u00e9e de comp\u00e9tition.<\/p>\n<p>J&rsquo;\u00e9tais l\u00e0 pour soutenir l&rsquo;\u00e9quipe et m&rsquo;assurer que mes co\u00e9quipi\u00e8res \u00e9taient pr\u00eates psychologiquement m\u00eame si j&rsquo;\u00e9tais moi-m\u00eame angoiss\u00e9e. Dans une telle situation, il faut sourire et s\u2019assurer de ne pas montrer \u00e0 vos co\u00e9quipiers \u00e0 quel point vous \u00eates boulevers\u00e9, car vous \u00eates l\u00e0 pour eux maintenant, et non pour vous. Malgr\u00e9 tout, mes co\u00e9quipi\u00e8res savaient que j&rsquo;\u00e9tais frustr\u00e9e et bless\u00e9e par ce qui me semblait \u00eatre une r\u00e9trogradation. J&rsquo;ai d\u00e9test\u00e9 chaque instant. J&rsquo;avais l&rsquo;impression qu&rsquo;une grande injustice avait \u00e9t\u00e9 commise, mais je ne pouvais rien y faire.<\/p>\n<p>Apr\u00e8s PyeongChang, j&rsquo;ai pratiquement d\u00e9cid\u00e9 d&rsquo;arr\u00eater compl\u00e8tement le sport. J\u2019aurais peut-\u00eatre recommenc\u00e9 \u00e0 lancer pour le plaisir, mais je n\u2019avais aucune envie de prendre part \u00e0 des comp\u00e9titions.\u00a0Ce n\u2019est qu\u2019\u00e0 l\u2019insistance de quelques personnes cl\u00e9s &#8211; \u00e0 savoir mes co\u00e9quipiers <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/neville-wright\/\">Neville Wright<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/lascelles-brown\/\">Lascelles Brown<\/a>, l\u2019ancienne freineuse <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/shelley-ann-brown\/\">Shelley-Ann Brown<\/a> et les entra\u00eeneurs <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/lyndon-rush\/\">Lyndon Rush<\/a> et Quin Sekulich &#8211; que j\u2019ai commenc\u00e9 \u00e0 penser \u00e0 tenter ma chance \u00e0 nouveau.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-166127 size-full\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-monobob-training.jpg?quality=100\" alt=\"Cynthia s'entra\u00eene sur la piste de bobsleigh.\" width=\"1360\" height=\"1017\" \/><\/p>\n<p>Ils ont d\u00fb unir leurs efforts pour me convaincre que mon parcours en bobsleigh n&rsquo;\u00e9tait pas termin\u00e9, qu&rsquo;ils comprenaient ma douleur et qu&rsquo;ils savaient que si j\u2019abandonnais, je passerais le reste de ma vie \u00e0 me demander si j\u2019avais fait le bon choix. Ils m&rsquo;ont m\u00eame sugg\u00e9r\u00e9 d&rsquo;essayer l&rsquo;\u00e9cole de pilotage de Lake Placid, dans l&rsquo;\u00c9tat de New York, pour voir si cela stimulerait \u00e0 nouveau mon int\u00e9r\u00eat pour le bobsleigh.<\/p>\n<p>Je ne voulais pas l&rsquo;admettre \u00e0 l&rsquo;\u00e9poque, mais ils avaient raison. Je ne voulais pas me retrouver devant toutes ces questions sans r\u00e9ponses : <em>Aurais-je pu devenir pilote? Aurais-je pu exceller dans ce r\u00f4le? Aurais-je pu revenir \u00e0 la comp\u00e9tition et atteindre mon objectif?<\/em><\/p>\n<p>Cependant, ces questions\u00a0 inspirantes \u00e9taient accompagn\u00e9es de questions n\u00e9gatives : <em>Et si je suis une mauvaise pilote? Et si je me \u00ab\u00a0fais avoir\u00a0\u00bb \u00e0 nouveau? Et si je mets ma vie en suspens pendant les quatre prochaines ann\u00e9es et que je manque \u00e0 nouveau mon coup?<\/em><\/p>\n<p>J&rsquo;ai d\u00fb \u00e9carter ces pens\u00e9es et voir l&rsquo;\u00e9cole de pilotage comme ce qu&rsquo;elle \u00e9tait : une chance d&rsquo;avoir \u00e0 nouveau du plaisir \u00e0 m&rsquo;entra\u00eener et \u00e0 faire du sport de comp\u00e9tition. Une fois revenue du camp de trois semaines, j&rsquo;ai pris la difficile d\u00e9cision de mettre \u00e0 nouveau ma vie en suspens au profit du sport et de tenter \u00e0 nouveau de me qualifier pour les Jeux olympiques, cette fois en tant que pilote.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-166133\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR.jpg?quality=100\" alt=\"\" width=\"1360\" height=\"605\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR.jpg 1920w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR.jpg?resize=280,125 280w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR.jpg?resize=660,294 660w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR.jpg?resize=768,342 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR.jpg?resize=1340,596 1340w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR.jpg?resize=1536,683 1536w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>\u00catre Noire au sein d\u2019un sport majoritairement blanc vous place dans une situation particuli\u00e8re. Il y a encore des points de vue n\u00e9gatifs \u00e0 propos de ce que les Noirs peuvent et ne peuvent pas faire dans ce sport. Certaines personnes \u00e9mettent ouvertement leur opinion comme des faits et nient toute implication raciale. Malheureusement, il y a des personnes qui s&rsquo;accrochent \u00e0 des croyances aussi idiotes et archa\u00efques dans le monde du bobsleigh, en particulier que les Noirs sont de mauvais pilotes de nature.<\/p>\n<p>Une analogie qui est souvent utilis\u00e9e pour aider ceux qui ne sont pas familiers avec le bobsleigh est la croyance qu\u2019au football les joueurs noirs ne peuvent pas \u00eatre de bons quarts-arri\u00e8re, que ces athl\u00e8tes manquent \u00ab d&rsquo;intelligence \u00bb sur le terrain. Ce point de vue est profond\u00e9ment ancr\u00e9 dans certains cercles et, parfois, fait les manchettes. L&rsquo;\u00e9t\u00e9 dernier, <a href=\"https:\/\/www.teamusa.org\/News\/2020\/June\/26\/Even-Olympic-Medals-Cant-Save-You\">la pilote de l&rsquo;\u00e9quipe am\u00e9ricaine Elana Meyers Taylor a \u00e9crit<\/a> \u00e0 propos d&rsquo;un fabricant de bobs qui \u00ab refuse de vendre aux pilotes noirs \u00bb et qui aurait dit \u00ab si je voulais voir un singe conduire un bob, j\u2019irais au zoo\u00a0\u00bb. Suite \u00e0 cet incident, la F\u00e9d\u00e9ration internationale de bobsleigh et de skeleton a mis en place un groupe de travail pour traiter les cas signal\u00e9s de discrimination.<\/p>\n<p>Quand il est question de sports d&rsquo;hiver, le bobsleigh est certainement l&rsquo;un des plus diversifi\u00e9s. Mais il y a encore une sorte de plafond de verre.<\/p>\n<p>Intentionnellement ou non, la plupart des athl\u00e8tes commencent leur carri\u00e8re de bobsleigh en tant que freineurs. Relativement parlant, le co\u00fbt de participation au bobsleigh est moins \u00e9lev\u00e9 pour un freineur et il pourrait donc \u00eatre plus lucratif de demeurer dans ce r\u00f4le. Pour diverses raisons, le nombre d&rsquo;athl\u00e8tes de couleur qui font le saut de freineur \u00e0 pilote est moins \u00e9lev\u00e9. L&rsquo;un des obstacles est le manque de repr\u00e9sentation. Comme ils voient rarement quelqu&rsquo;un qui leur ressemble dans le si\u00e8ge du pilote, plusieurs d\u2019entre eux n&rsquo;aspirent pas \u00e0 changer de r\u00f4le.<\/p>\n<p>Cependant, d\u2019autres peuvent avoir de telles aspirations et ne peuvent tout simplement pas le faire. L&rsquo;intuition est fortement influenc\u00e9e par notre environnement et parfois nous \u00e9laborons des sc\u00e9narios pour nous convaincre que nous ne pouvons pas faire quelque chose. Ainsi, jusqu&rsquo;\u00e0 ce que quelqu&rsquo;un trace la voie, vous cr\u00e9erez parfois vos propres obstacles.<\/p>\n<p>Un autre obstacle est d&rsquo;ordre financier, car le co\u00fbt de devenir pilote est presque prohibitif. Au cours de vos deux premi\u00e8res ann\u00e9es dans le si\u00e8ge avant, vous \u00eates rel\u00e9gu\u00e9 au circuit de comp\u00e9tition le plus bas et devez m\u00e9riter votre place sur le circuit de la Coupe du monde en obtenant des points li\u00e9s \u00e0 la performance. Il n&rsquo;y a pas de bourses en argent sur ces circuits inf\u00e9rieurs. En tant que freineuse de haut niveau, j&rsquo;ai d\u00fb prendre la d\u00e9cision de renoncer \u00e0 une certaine s\u00e9curit\u00e9 financi\u00e8re pour poursuivre ce nouvel objectif de participer \u00e0 <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/beijing-2022\/\">Beijing 2022<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-166129\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-racing.jpg?quality=100\" alt=\"Cynthia Appiah d\u00e9marre sa course de bobsleigh \u00e0 deux.\" width=\"1360\" height=\"1056\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-racing.jpg 1600w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-racing.jpg?resize=204,158 204w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-racing.jpg?resize=478,371 478w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-racing.jpg?resize=768,596 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-racing.jpg?resize=971,754 971w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/Cynthia-Appiah-racing.jpg?resize=1536,1192 1536w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><\/p>\n<p>Cela dit, au cours de la derni\u00e8re d\u00e9cennie, le nombre de pilotes noirs est pass\u00e9 de z\u00e9ro \u00e0 <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2010-vancouver\/\">Vancouver 2010<\/a> \u00e0 quatre \u00e0 <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2014-sotchi\/\">Sotchi 2014<\/a> et PyeongChang 2018. Si je me qualifie pour Beijing 2022, je pourrais aider \u00e0 porter le total \u00e0 sept pilotes noirs (potentiellement deux hommes et cinq femmes).<\/p>\n<p>Ma passion pour le sport a d\u00e9finitivement chang\u00e9. Je veux toujours \u00eatre la meilleure dans l\u2019histoire de mon sport (et je crois sinc\u00e8rement que j&rsquo;en suis capable), mais je veux vraiment \u00eatre un exemple de ce que les athl\u00e8tes noirs peuvent faire. Je veux \u00eatre une preuve visuelle pour les enfants et les jeunes, en particulier les jeunes Noirs, que nous avons notre place dans tous les sports, y compris les sports d&rsquo;hiver.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-166128\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR-2.jpg?quality=100\" alt=\"Citation : Je veux \u00eatre une repr\u00e9sentation visuelle pour la jeunesse, surtout les jeunes noirs, que vous avons notre place dans le sport, y compris les sports d'hiver.\" width=\"1360\" height=\"834\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR-2.jpg 1920w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR-2.jpg?resize=258,158 258w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR-2.jpg?resize=605,371 605w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR-2.jpg?resize=768,471 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR-2.jpg?resize=1230,754 1230w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Quote-InStory-FR-2.jpg?resize=1536,942 1536w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><\/p>\n<p>Le st\u00e9r\u00e9otype selon lequel les Noirs ne r\u00e9ussissent pas bien dans le froid doit \u00eatre supprim\u00e9. Le st\u00e9r\u00e9otype selon lequel les Noirs ne peuvent pas \u00eatre de bons pilotes de bobsleigh doit \u00eatre supprim\u00e9. Le st\u00e9r\u00e9otype selon lequel les athl\u00e8tes noirs ne peuvent pas diriger une \u00e9quipe avec succ\u00e8s doit \u00eatre supprim\u00e9.<\/p>\n<p>Je suis pr\u00eate \u00e0 me retrouver sous les feux de la rampe et \u00e0 montrer au monde ce que je peux faire gr\u00e2ce \u00e0 ma passion.<\/p>\n<p><em>Cynthia Appiah a fait ses d\u00e9buts en Coupe du monde en tant que pilote en janvier 2020. En plus de l&rsquo;\u00e9preuve f\u00e9minine de bob \u00e0 deux, elle esp\u00e8re aussi faire partie des d\u00e9buts olympiques du monobob f\u00e9minin \u00e0 Beijing 2022.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma passion pour le sport est en constante \u00e9volution. J&rsquo;ai \u00e9t\u00e9 initi\u00e9e au sport de comp\u00e9tition en sixi\u00e8me ann\u00e9e quand&#8230;<\/p>\n","protected":false},"author":49083863,"featured_media":166124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[49208064,415984349,682164071,682164067,682164070,682164069,682164195,682163522,682164068],"post_format":"standard","sport":[41495],"game":[],"coauthors":[682164063],"class_list":["post-166123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-bobsleigh-2","tag-cynthia-appiah","tag-diversite-dans-le-sport","tag-diversite-et-inclusion","tag-jeunes-noirs","tag-modele","tag-povs","tag-racisme","tag-representation","sport-bobsleigh"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Feature-Image-FR.jpg?quality=100","author_name":["Cynthia Appiah"],"category_names":["Uncategorized"],"tag_names":["bobsleigh","Cynthia Appiah","Diversit\u00e9 dans le sport","Diversit\u00e9 et inclusion","Jeunes Noirs","Mod\u00e8le","POVs","racisme","Repr\u00e9sentation"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-Hdp","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/01\/DIGITAL-POV-Cynthia-Appiah-v1Feature-Image-FR.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/166123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/49083863"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=166123"}],"version-history":[{"count":1,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/166123\/revisions"}],"predecessor-version":[{"id":166134,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/166123\/revisions\/166134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/166124"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=166123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=166123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=166123"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=166123"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=166123"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=166123"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=166123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}