{"id":169375,"date":"2021-03-07T12:03:38","date_gmt":"2021-03-07T17:03:38","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=169375"},"modified":"2021-03-08T11:00:36","modified_gmt":"2021-03-08T16:00:36","slug":"sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/","title":{"rendered":"Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l&rsquo;ISU"},"content":{"rendered":"<h2 class=\"lead\">Ce dimanche, Courtney Sarault a d\u00e9croch\u00e9 la m\u00e9daille de bronze au 1000 m et l&rsquo;argent en super finale du 3000 m au Championnat du monde de patinage de vitesse sur courte piste de l&rsquo;ISU \u00e0 Dordrecht aux Pays-Bas. Ces deux podiums lui ont valu la seconde place au classement g\u00e9n\u00e9ral chez les femmes.<\/h2>\n<p>L&rsquo;athl\u00e8te de Moncton au Nouveau-Brunswick a tout d&rsquo;abord r\u00e9colt\u00e9 le bronze au 1000 m avec un temps de 1:27,470 secondes. C&rsquo;est Suzanne Shulting des Pays-Bas qui a eu l&rsquo;honneur de monter sur la plus haute marche du podium avec un temps de 1:26,854, talonn\u00e9e par Hanne Desmet de la Belgique qui a obtenu l&rsquo;argent (1:26,993).<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udea8 MEDAL ALERT! \ud83d\udea8<\/p>\n<p>\ud83c\udde8\ud83c\udde6 Courtney Sarault on the World Championship for the second straight day, this time with \ud83e\udd49 bronze in the 1000m! She steals third-place in a photo finish!<a href=\"https:\/\/twitter.com\/hashtag\/FasterForward?src=hash&amp;ref_src=twsrc%5Etfw\">#FasterForward<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/SpeedSkating?src=hash&amp;ref_src=twsrc%5Etfw\">#SpeedSkating<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ShortTrack?src=hash&amp;ref_src=twsrc%5Etfw\">#ShortTrack<\/a> <a href=\"https:\/\/t.co\/qZlU4K8lfY\">pic.twitter.com\/qZlU4K8lfY<\/a><\/p>\n<p>&mdash; Speed Skating Canada | Patinage de Vitesse Canada (@SSC_PVC) <a href=\"https:\/\/twitter.com\/SSC_PVC\/status\/1368571795067072518?ref_src=twsrc%5Etfw\">March 7, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Peu apr\u00e8s, Sarault a particip\u00e9 a la super finale du 3000 m et est repartie la m\u00e9daille d&rsquo;argent au cou gr\u00e2ce \u00e0 son temps de 5:21,773 secondes. \u00c0 nouveau, Shulting a de peu devanc\u00e9 la Canadienne avec un temps de 5:21,602 secondes. Selma Poutsma, \u00e9galement des Pays-Bas, est quant \u00e0 elle repartie avec le bronze, franchissant la ligne d&rsquo;arriv\u00e9e en 5:22,629 secondes.<\/p>\n<p><strong>\u00c0 LIRE:\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/06\/hamelin-champion-du-1-500-m-aux-mondiaux\/\">Hamelin champion du 1500 m aux Mondiaux<\/a><\/strong><\/p>\n<p>Ces r\u00e9sultats concluent une bonne fin de semaine de comp\u00e9tition pour la patineuse de 20 ans. La veille, samedi, elle avait mis la main sur la m\u00e9daille d&rsquo;argent au 1500 m. Elle poss\u00e8de \u00e0 pr\u00e9sent 58 points en son nom, ce qui la place 2e au classement g\u00e9n\u00e9ral du Championnat du monde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce dimanche, Courtney Sarault a d\u00e9croch\u00e9 la m\u00e9daille de bronze au 1000 m et l&rsquo;argent en super finale du 3000&#8230;<\/p>\n","protected":false},"author":101314463,"featured_media":169378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[682164187,203926778,415987789,682164188,1104411,415985381,5599048,206767583,415985347],"post_format":"standard","sport":[51196772],"game":[],"coauthors":[682162723],"class_list":["post-169375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-championnat-du-monde-de-patinage-de-vitesse-courte-piste-de-lisu","tag-courte-piste","tag-courtney-sarault","tag-dordrecht","tag-equipe-canada","tag-patinage","tag-patinage-de-vitesse","tag-patinage-de-vitesse-courte-piste-2","tag-pays-bas","sport-patinage-de-vitesse-courte-piste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l&#039;ISU - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l&#039;ISU - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Ce dimanche, Courtney Sarault a d\u00e9croch\u00e9 la m\u00e9daille de bronze au 1000 m et l&rsquo;argent en super finale du 3000...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-07T17:03:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-08T16:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/03\/Ev4va-bXcAcqlr2.jpeg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"St\u00e9phanie Beaumont\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"St\u00e9phanie Beaumont\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/\"},\"author\":{\"name\":\"St\u00e9phanie Beaumont\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/001b6850e82f6057941b3bedd7238072\"},\"headline\":\"Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l&rsquo;ISU\",\"datePublished\":\"2021-03-07T17:03:38+00:00\",\"dateModified\":\"2021-03-08T16:00:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/\"},\"wordCount\":261,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Ev4va-bXcAcqlr2.jpeg?quality=100\",\"keywords\":[\"Championnat du monde de patinage de vitesse courte piste de l'ISU\",\"Courte piste\",\"Courtney Sarault\",\"Dordrecht\",\"\u00c9quipe canada\",\"patinage\",\"Patinage de vitesse\",\"Patinage de vitesse courte piste\",\"pays-bas\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/\",\"name\":\"Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l'ISU - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Ev4va-bXcAcqlr2.jpeg?quality=100\",\"datePublished\":\"2021-03-07T17:03:38+00:00\",\"dateModified\":\"2021-03-08T16:00:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/001b6850e82f6057941b3bedd7238072\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/03\\\/07\\\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Ev4va-bXcAcqlr2.jpeg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/Ev4va-bXcAcqlr2.jpeg?quality=100\",\"width\":1010,\"height\":568,\"caption\":\"Courtney Sarault a d\u00e9croch\u00e9 de multiples m\u00e9dailles ce dimanche au Championnat du monde de patinage de vitesse courte piste de Dordrecht aux Pays-Bas\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/001b6850e82f6057941b3bedd7238072\",\"name\":\"St\u00e9phanie Beaumont\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3bcf28a833b101d48f9058602c9143788be78a84b6d3adda68b9a1050d883816?s=96&d=identicon&r=g000f13acc675d892aa4755aaed50f98f\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3bcf28a833b101d48f9058602c9143788be78a84b6d3adda68b9a1050d883816?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3bcf28a833b101d48f9058602c9143788be78a84b6d3adda68b9a1050d883816?s=96&d=identicon&r=g\",\"caption\":\"St\u00e9phanie Beaumont\"},\"description\":\"pigiste\",\"sameAs\":[\"http:\\\/\\\/penguinentity.wordpress.com\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/stephbmnt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l'ISU - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/","og_locale":"fr_FR","og_type":"article","og_title":"Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l'ISU - \u00c9quipe Canada","og_description":"Ce dimanche, Courtney Sarault a d\u00e9croch\u00e9 la m\u00e9daille de bronze au 1000 m et l&rsquo;argent en super finale du 3000...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2021-03-07T17:03:38+00:00","article_modified_time":"2021-03-08T16:00:36+00:00","og_image":[{"width":1010,"height":568,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/03\/Ev4va-bXcAcqlr2.jpeg?quality=100","type":"image\/jpeg"}],"author":"St\u00e9phanie Beaumont","twitter_card":"summary_large_image","twitter_misc":{"Written by":"St\u00e9phanie Beaumont","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/"},"author":{"name":"St\u00e9phanie Beaumont","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/001b6850e82f6057941b3bedd7238072"},"headline":"Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l&rsquo;ISU","datePublished":"2021-03-07T17:03:38+00:00","dateModified":"2021-03-08T16:00:36+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/"},"wordCount":261,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/03\/Ev4va-bXcAcqlr2.jpeg?quality=100","keywords":["Championnat du monde de patinage de vitesse courte piste de l'ISU","Courte piste","Courtney Sarault","Dordrecht","\u00c9quipe canada","patinage","Patinage de vitesse","Patinage de vitesse courte piste","pays-bas"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/","url":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/","name":"Sarault nomm\u00e9e vice-championne aux Mondiaux de patinage de vitesse sur courte piste de l'ISU - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/03\/Ev4va-bXcAcqlr2.jpeg?quality=100","datePublished":"2021-03-07T17:03:38+00:00","dateModified":"2021-03-08T16:00:36+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/001b6850e82f6057941b3bedd7238072"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/03\/07\/sarault-nommee-vice-championne-au-mondial-de-patinage-de-vitesse-courte-piste-de-lisu\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/03\/Ev4va-bXcAcqlr2.jpeg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/03\/Ev4va-bXcAcqlr2.jpeg?quality=100","width":1010,"height":568,"caption":"Courtney Sarault a d\u00e9croch\u00e9 de multiples m\u00e9dailles ce dimanche au Championnat du monde de patinage de vitesse courte piste de Dordrecht aux Pays-Bas"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/001b6850e82f6057941b3bedd7238072","name":"St\u00e9phanie Beaumont","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3bcf28a833b101d48f9058602c9143788be78a84b6d3adda68b9a1050d883816?s=96&d=identicon&r=g000f13acc675d892aa4755aaed50f98f","url":"https:\/\/secure.gravatar.com\/avatar\/3bcf28a833b101d48f9058602c9143788be78a84b6d3adda68b9a1050d883816?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3bcf28a833b101d48f9058602c9143788be78a84b6d3adda68b9a1050d883816?s=96&d=identicon&r=g","caption":"St\u00e9phanie Beaumont"},"description":"pigiste","sameAs":["http:\/\/penguinentity.wordpress.com"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/stephbmnt\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/03\/Ev4va-bXcAcqlr2.jpeg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/03\/Ev4va-bXcAcqlr2.jpeg?quality=100","author_name":["St\u00e9phanie Beaumont"],"category_names":["Uncategorized"],"tag_names":["Championnat du monde de patinage de vitesse courte piste de l'ISU","Courte piste","Courtney Sarault","Dordrecht","\u00c9quipe canada","patinage","Patinage de vitesse","Patinage de vitesse courte piste","pays-bas"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-I3R","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/169375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/101314463"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=169375"}],"version-history":[{"count":7,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/169375\/revisions"}],"predecessor-version":[{"id":169433,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/169375\/revisions\/169433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/169378"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=169375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=169375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=169375"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=169375"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=169375"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=169375"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=169375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}