{"id":186625,"date":"2021-07-30T15:11:21","date_gmt":"2021-07-30T19:11:21","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=186625"},"modified":"2021-07-31T09:12:25","modified_gmt":"2021-07-31T13:12:25","slug":"une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/","title":{"rendered":"Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il a fallu passer par le chemin le plus stressant, mais le Canada a n\u00e9anmoins r\u00e9ussi \u00e0 obtenir une autre occasion de grimper sur le podium olympique en soccer f\u00e9minin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le match de quarts de finale entre le Canada et le Br\u00e9sil, disput\u00e9 \u00e0 l&rsquo;occasion de la septi\u00e8me journ\u00e9e de comp\u00e9tition aux Jeux de&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2020-tokyo\/\">Tokyo 2020<\/a>,&nbsp;s&rsquo;est termin\u00e9 0-0 apr\u00e8s les prolongations, si bien qu&rsquo;il a fallu recourir aux tirs pour d\u00e9terminer l&rsquo;identit\u00e9 du vainqueur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La capitaine&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/equipe-canada\/christine-sinclair\/\">Christine Sinclair<\/a> a vu son tir \u00eatre bloqu\u00e9 par la gardienne de but br\u00e9silienne Barbara&nbsp;sur la premi\u00e8re tentative du Canada, donnant l&rsquo;avantage au Br\u00e9sil. Cependant, la gardienne canadienne&nbsp;<a href=\"https:\/\/develop.olympic.ca\/team-canada\/stephanie-labbe\/\">Stephanie Labb\u00e9<\/a>&nbsp;a r\u00e9sist\u00e9 devant les quatri\u00e8me et cinqui\u00e8me tireuses br\u00e9siliennes pour donner la victoire aux siennes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Labb\u00e9 avait \u00e9t\u00e9 appel\u00e9e \u00e0 r\u00e9aliser des arr\u00eats cl\u00e9s un peu plus t\u00f4t dans le match, alors qu&rsquo;elle a notamment plong\u00e9 pour arr\u00eater un tir qui aurait pu s&rsquo;av\u00e9rer le filet vainqueur pour le Br\u00e9sil \u00e0 la 119e minute de jeu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Le fait d&rsquo;avoir pu faire ma part pour aider cette \u00e9quipe \u00e0 avoir le dessus repr\u00e9sente un r\u00e9el moment de fiert\u00e9 pour moi \u00bb, a d\u00e9clar\u00e9 Labb\u00e9 apr\u00e8s le match.<\/p>\n\n\n<p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">STEPH LABBE COMING IN CLUTCH \ud83c\udde8\ud83c\udde6<br><br>Makes the critical save and Canada moves onto the semifinals after beating Brazil in penalty kicks <a href=\"https:\/\/t.co\/y3FNEf3vzs\">pic.twitter.com\/y3FNEf3vzs<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1421062660930609153?ref_src=twsrc%5Etfw\">July 30, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Devant elle, la d\u00e9fenseure centrale&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/equipe-canada\/vanessa-gilles\/\">Vanessa Gilles<\/a>&nbsp;a&nbsp;elle aussi eu une influence importante sur le d\u00e9roulement de la rencontre. L&rsquo;athl\u00e8te de 25 ans, qui a disput\u00e9 son premier match sur une sc\u00e8ne olympique dans le cadre du&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/27\/les-canadiennes-passent-en-quarts-de-finale-au-soccer\/\">nul de 1-1 contre la Grande-Bretagne \u00e0 l\u2019occasion du dernier match du Canada en phase de groupes<\/a>,&nbsp;a \u00e9t\u00e9 solide d\u00e9fensivement du d\u00e9but \u00e0 la fin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle a aussi obtenu la plus belle occasion du match pour le Canada, y allant d&rsquo;une reprise de t\u00eate qui a percut\u00e9 la transversale \u00e0 la 59e minute, en plus de r\u00e9ussir sa tentative, le cinqui\u00e8me du Canada, au cours de la s\u00e9ance de tirs au but. Les autres joueuses qui ont marqu\u00e9 en fusillade pour le Canada sont&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/equipe-canada\/jessie-fleming\/\">Jessie Fleming<\/a>,&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/equipe-canada\/ashley-lawrence\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ashley Lawrence&nbsp;<\/a>et&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/equipe-canada\/adriana-leon\/\">Adriana Leon<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le sentiment de soulagement \u00e9tait palpable \u00e0 la suite des 120 minutes de jeu empreintes de tension, alors que les joueuses canadiennes se sont lanc\u00e9es en masse sur le terrain pour c\u00e9l\u00e9brer l&rsquo;arr\u00eat d\u00e9cisif de Labb\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Les \u00e9motions sont fortes en ce moment, mais quelle performance de l&rsquo;\u00e9quipe, a-t-elle affirm\u00e9. D\u00e9fensivement, nous avons \u00e9t\u00e9 solides contre certaines des meilleures attaquantes au monde. Offensivement, je trouve que nous avons fait du bon travail, nous avons eu de belles occasions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab C&rsquo;est \u00e7a les Jeux olympiques, ce sont des matchs serr\u00e9s qui nous forcent \u00e0 donner un niveau de performance dont nous pouvons \u00eatre vraiment fi\u00e8res. \u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1131\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-3-tokyo2020.jpg?quality=100&amp;w=1131\" alt=\"\" class=\"wp-image-186752\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-3-tokyo2020.jpg 6633w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-3-tokyo2020.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-3-tokyo2020.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-3-tokyo2020.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-3-tokyo2020.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-3-tokyo2020.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-3-tokyo2020.jpg?resize=2048,1365 2048w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><figcaption>L&rsquo;\u00e9quipe canadienne de soccer f\u00e9minin c\u00e9l\u00e8bre une victoire de 4-3 en tirs de barrage contre le Br\u00e9sil aux Jeux olympiques de Tokyo 2020, le 30 juillet 2021. (Photo: AP\/Andre Penner)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9quipe canadienne se pr\u00e9parera maintenant en vue de son duel des demi-finales (lundi 4 h HE) contre les \u00c9tats-Unis, qui ont eu le dessus sur les Pays-Bas aux tirs au but dans un autre match des quarts de finale, vendredi. Les Canadiennes et les Am\u00e9ricaines s&rsquo;\u00e9taient aussi disput\u00e9 une demi-finale \u00e9pique aux <a href=\"http:\/\/www.olympique.ca\/jeux\/2012-londres\/\">Jeux de Londres 2012<\/a>. Rappelons que le&nbsp;Canada&nbsp;a d\u00e9croch\u00e9 la m\u00e9daille de bronze au soccer f\u00e9minin \u00e0&nbsp;Londres 2012 et \u00e0&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2016-rio\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rio 2016<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il a fallu passer par le chemin le plus stressant, mais le Canada a n\u00e9anmoins r\u00e9ussi \u00e0 obtenir une autre&#8230;<\/p>\n","protected":false},"author":55751844,"featured_media":186750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"post_format":"standard","sport":[],"game":[],"coauthors":[374051512],"class_list":["post-186625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Il a fallu passer par le chemin le plus stressant, mais le Canada a n\u00e9anmoins r\u00e9ussi \u00e0 obtenir une autre...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-30T19:11:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-31T13:12:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Squizzato\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Squizzato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/\"},\"author\":{\"name\":\"Steve Boudreau\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fe9c9377a625e32685068f640ff9e166\"},\"headline\":\"Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer\",\"datePublished\":\"2021-07-30T19:11:21+00:00\",\"dateModified\":\"2021-07-31T13:12:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/\"},\"wordCount\":645,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/\",\"name\":\"Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100\",\"datePublished\":\"2021-07-30T19:11:21+00:00\",\"dateModified\":\"2021-07-31T13:12:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fe9c9377a625e32685068f640ff9e166\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/07\\\/30\\\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100\",\"width\":1131,\"height\":754,\"caption\":\"Canada's players celebrate winning 4-3 in a penalty shootout against Brazil during a women's quarterfinal soccer match at the 2020 Summer Olympics, Friday, July 30, 2021, in Rifu, Japan. (AP Photo\\\/Andre Penner)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fe9c9377a625e32685068f640ff9e166\",\"name\":\"Steve Boudreau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=geab05ffb592a23c798f7bf61ed1f5f18\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=g\",\"caption\":\"Steve Boudreau\"},\"description\":\"R\u00e9dacteur, m\u00e9dias sociaux - @Sboudreau\",\"sameAs\":[\"http:\\\/\\\/sboudreau49.wordpress.com\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/sboudreau2013\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/","og_locale":"fr_FR","og_type":"article","og_title":"Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer - \u00c9quipe Canada","og_description":"Il a fallu passer par le chemin le plus stressant, mais le Canada a n\u00e9anmoins r\u00e9ussi \u00e0 obtenir une autre...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2021-07-30T19:11:21+00:00","article_modified_time":"2021-07-31T13:12:25+00:00","og_image":[{"width":1131,"height":754,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100","type":"image\/jpeg"}],"author":"Daniel Squizzato","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Squizzato","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/"},"author":{"name":"Steve Boudreau","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/fe9c9377a625e32685068f640ff9e166"},"headline":"Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer","datePublished":"2021-07-30T19:11:21+00:00","dateModified":"2021-07-31T13:12:25+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/"},"wordCount":645,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/","url":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/","name":"Une dramatique victoire aux tirs propulse le Canada en demi-finales au soccer - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100","datePublished":"2021-07-30T19:11:21+00:00","dateModified":"2021-07-31T13:12:25+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/fe9c9377a625e32685068f640ff9e166"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/07\/30\/une-dramatique-victoire-aux-tirs-propulse-le-canada-en-demi-finales-au-soccer\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100","width":1131,"height":754,"caption":"Canada's players celebrate winning 4-3 in a penalty shootout against Brazil during a women's quarterfinal soccer match at the 2020 Summer Olympics, Friday, July 30, 2021, in Rifu, Japan. (AP Photo\/Andre Penner)"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/fe9c9377a625e32685068f640ff9e166","name":"Steve Boudreau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=geab05ffb592a23c798f7bf61ed1f5f18","url":"https:\/\/secure.gravatar.com\/avatar\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=g","caption":"Steve Boudreau"},"description":"R\u00e9dacteur, m\u00e9dias sociaux - @Sboudreau","sameAs":["http:\/\/sboudreau49.wordpress.com"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/sboudreau2013\/"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100","author_name":["Daniel Squizzato"],"category_names":["Uncategorized"],"tag_names":[],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-My5","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/07\/equipe-canada-soccer-2-tokyo2020.jpeg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/186625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/55751844"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=186625"}],"version-history":[{"count":2,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/186625\/revisions"}],"predecessor-version":[{"id":186753,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/186625\/revisions\/186753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/186750"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=186625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=186625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=186625"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=186625"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=186625"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=186625"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=186625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}