{"id":187518,"date":"2021-08-04T11:04:23","date_gmt":"2021-08-04T15:04:23","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=187518"},"modified":"2021-08-04T13:26:22","modified_gmt":"2021-08-04T17:26:22","slug":"le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/","title":{"rendered":"Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/christine-sinclair\/\">Christine Sinclair<\/a> gravit cette montagne depuis des lustres et voil\u00e0 qu\u2019elle est tout pr\u00e8s d\u2019en atteindre le sommet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 22 ann\u00e9es avec l\u2019\u00e9quipe nationale senior, la capitaine et joueuse embl\u00e9matique du Canada est devenue la buteuse la plus prolifique dans l\u2019histoire du soccer international. Elle a remport\u00e9 le troph\u00e9e Lou-Marsh en tant qu\u2019athl\u00e8te par excellence de l\u2019ann\u00e9e au Canada et elle a \u00e9t\u00e9 intronis\u00e9e \u00e0 titre de membre de l\u2019All\u00e9e des c\u00e9l\u00e9brit\u00e9s canadiennes. Elle a aid\u00e9 le Canada \u00e0 d\u00e9crocher deux m\u00e9dailles de bronze olympiques, \u00e0 <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2012-londres\/\">Londres 2012<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2016-rio\/\">Rio 2016<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, l\u2019athl\u00e8te de 38 ans n\u2019a jamais disput\u00e9 de match pour la m\u00e9daille d\u2019or dans un tournoi international senior de grande envergure. Maintenant, \u00e0 la suite de la <a href=\"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/02\/equipe-canada-jouera-pour-lor-apres-sa-victoire-sur-les-etats-unis\/\">victoire surprise du Canada contre les \u00c9tats-Unis en demi-finales<\/a>, Sinclair et ses co\u00e9quipi\u00e8res auront enfin l\u2019occasion de le faire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans son match des demi-finales, le Canada <a href=\"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/01\/le-canada-cherchera-a-venger-sa-defaite-de-londres-2012-contre-les-etats-unis\/\">aveng\u00e9 sa d\u00e9faite cr\u00e8ve-c\u0153ur aux mains des \u00c9tats-Unis \u00e0 Londres 2012<\/a>. En finale contre la Su\u00e8de (jeudi \u00e0 22 h, HE), les Canadiennes chercheront cette fois \u00e0 se venger de l\u2019\u00e9quipe qui <a href=\"https:\/\/wp.me\/p3DwGH-Dwc\">les a \u00e9limin\u00e9es en huiti\u00e8mes de finale<\/a> \u00e0 la Coupe du Monde F\u00e9minine de la FIFA en 2019.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1131\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128107791.jpg?quality=100&amp;w=1131\" alt=\"\" class=\"wp-image-187524\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128107791.jpg 3416w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128107791.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128107791.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128107791.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128107791.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128107791.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128107791.jpg?resize=2048,1365 2048w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><figcaption>Jessie Fleming c\u00e9l\u00e8bre apr\u00e8s avoir marqu\u00e9 le but gagnant de la rencontre de demi-finale face aux Am\u00e9ricaines aux Jeux olympiques de Tokyo 2020, le 2 ao\u00fbt 2021. (Photo AP\/Fernando Vergara)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ce ne sera pas facile d\u2019y arriver contre une solide formation su\u00e9doise qui a d\u00e9fait les \u00c9tats-Unis 3-0 plus t\u00f4t au cours de cette comp\u00e9tition. Alors que l\u2019\u00e9quipe a disput\u00e9 cinq matchs en 13 jours par temps chaud et humide, il reste \u00e0 voir si les joueuses auront encore de l\u2019\u00e9nergie en r\u00e9serve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peu importe ce qui leur reste, elles donneront tout sur le terrain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous avons fait tout un chemin, a d\u00e9clar\u00e9 l\u2019entra\u00eeneure-chef d\u2019\u00c9quipe Canada Bev Priestman apr\u00e8s la demi-finale. Ce groupe ne se contentera pas d\u2019\u00eatre en finale et de retourner \u00e0 la maison avec l\u2019argent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous avons 22 joueuses qui sont pr\u00eates \u00e0 faire le boulot. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Effectivement, 21 de ces 22 joueuses ont obtenu des minutes de jeu \u00e0 un moment ou l\u2019autre depuis le d\u00e9but du tournoi, signe que Priestman a cherch\u00e9 \u00e0 b\u00e2tir une formation bien \u00e9quilibr\u00e9e. Elle est bien loin l\u2019\u00e9poque o\u00f9 l\u2019\u00e9quipe canadienne se r\u00e9sumait \u00e0 un spectacle en solo, mettant en vedette Sinclair et des actrices secondaires.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1131\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128043500.jpg?quality=100&amp;w=1131\" alt=\"\" class=\"wp-image-187525\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128043500.jpg 7847w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128043500.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128043500.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128043500.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128043500.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128043500.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128043500.jpg?resize=2048,1365 2048w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><figcaption>L&rsquo;\u00e9quipe canadienne de soccer f\u00e9minin aux Jeux olympiques de Tokyo 2020, le 30 juillet 2021. (AP Photo\/Andre Penner)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La d\u00e9fenseure centrale <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/kadeisha-buchanan\/\">Kadeisha Buchanan<\/a> et la d\u00e9fenseure\/milieu de terrain <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/ashley-lawrence\/\">Ashley Lawrence<\/a>, des amies de longue date qui \u00e9voluent toutes deux dans les rangs professionnels en France, sont parmi les meilleures au monde \u00e0 leurs postes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les attaquantes <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/janine-beckie\/\">Janine Beckie<\/a>, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/deanne-rose\/\">Deanne Rose<\/a>, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/adriana-leon\/\">Adriana Leon<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/nichelle-prince\/\">Nichelle Prince<\/a> ont permis au Canada de montrer diff\u00e9rents visages \u00e0 l\u2019avant. Au milieu, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/quinn\/\">Quinn<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jessie-fleming\/\">Jessie Fleming<\/a> apportent de la stabilit\u00e9 \u00e0 l\u2019\u00e9quipe ainsi qu\u2019une bonne vision du jeu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces joueuses qui font partie du noyau actuel \u00e9taient encore des enfants dans les ann\u00e9es 2000, quand Sinclair a men\u00e9 le Canada \u00e0 sa premi\u00e8re pr\u00e9sence olympique \u00e0 vie aux Jeux de <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2008-beijing\/\">Beijing 2008<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elles sont ensuite devenues des adolescentes, regardant avec admiration \u2014 comme nous tous d\u2019ailleurs \u2014 Sinclair et ses contemporaines transporter le Canada sur le podium pour la premi\u00e8re fois \u00e0 Londres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elles sont la preuve vivante et tangible que les efforts de Sinclair, au cours des deux derni\u00e8res d\u00e9cennies, ont \u00e9t\u00e9 percutants sur les g\u00e9n\u00e9rations suivantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autrement dit, Sinclair n\u2019a pas fait qu\u2019inspirer un groupe abstrait de jeunes filles qui allaient peut-\u00eatre un jour vouloir jouer au soccer au plus haut niveau. Ces jeunes filles sont d\u00e9j\u00e0 l\u00e0, devant nos yeux, et elles c\u00f4toient Sinclair tous les jours. Qui plus est, elles sont pr\u00eates \u00e0 disputer la m\u00e9daille d\u2019or olympique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1131\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128105157.jpeg?quality=100&amp;w=1131\" alt=\"\" class=\"wp-image-187178\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128105157.jpeg 2048w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128105157.jpeg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128105157.jpeg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128105157.jpeg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128105157.jpeg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128105157.jpeg?resize=1536,1024 1536w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><figcaption>Janine Beckie aux Jeux olympiques de Tokyo 2020, le 2 ao\u00fbt 2021. (AP Photo\/Fernando Vergara)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab L\u2019objectif \u00e9tait clair, nous voulions changer la couleur de la m\u00e9daille, a not\u00e9 Priestman. Nous avons des tonnes de talent dans cette \u00e9quipe. Le message est clair, ce sont les gagnantes qui gagnent, et il ne fait aucun doute que nous abordons cette finale dans le but d\u2019aller chercher la m\u00e9daille d\u2019or. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peu importe le r\u00e9sultat obtenu \u00e0 l\u2019occasion du match de jeudi, on peut supposer sans crainte de se tromper que ce noyau restera pas mal le m\u00eame dans les ann\u00e9es qui pr\u00e9c\u00e9deront <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/paris-2024\/\">Paris 2024<\/a>. Un noyau auquel viendront se greffer de jeunes joueuses comme <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/kailen-sheridan\/\">Kailen Sheridan<\/a>, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/vanessa-gilles\/\">Vanessa Gilles<\/a>, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/julia-grosso\/\">Julia Grosso<\/a> et Jordyn Huitema, qui ont chacune particip\u00e9 \u00e0 leurs premiers Jeux olympiques \u00e0 Tokyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auront-elles Sinclair encore \u00e0 leurs c\u00f4t\u00e9s? Elle aura 41 ans d\u2019ici les prochains Jeux. Cela dit, elle a quand m\u00eame r\u00e9ussi \u00e0 ajuster sa fa\u00e7onde jouer au fil des ans afin de rester performante, et il est vrai que nous avons vu Formiga s\u2019aligner avec le Br\u00e9sil \u00e0 l\u2019\u00e2ge de 43 ans \u00e0 Tokyo 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u2019une fa\u00e7on ou d\u2019une autre, l\u2019\u00e9quipe canadienne pr\u00e9sente un visage tr\u00e8s diff\u00e9rent par rapport \u00e0 l\u2019\u00e9poque o\u00f9 Sinclair y a fait ses premiers pas. \u00c0 ce moment-l\u00e0, participer aux Jeux olympiques \u00e9tait un objectif en soi. Maintenant, le but est d\u2019acc\u00e9der au podium.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y aura beaucoup de pression \u00e0 g\u00e9rer, beaucoup de travail \u00e0 accomplir. Toutefois, s\u2019il y a une \u00e9quipe qui est capable d\u2019y arriver, c\u2019est celle qui a grandi dans l\u2019ombre bienveillante de Sinclair.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Christine Sinclair gravit cette montagne depuis des lustres et voil\u00e0 qu\u2019elle est tout pr\u00e8s d\u2019en atteindre le sommet. En 22&#8230;<\/p>\n","protected":false},"author":185434531,"featured_media":187523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[26441435,15579445,11631,891098,415713358,165703836,68909591,415984900,415988696,128815032,415988691,1379432,415571438,682164495,713425,682163081],"post_format":"standard","sport":[8591],"game":[193413370],"coauthors":[374051512],"class_list":["post-187518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-adriana-leon","tag-ashley-lawrence","tag-beijing-2008","tag-christine-sinclair","tag-deanne-rose","tag-janine-beckie","tag-jessie-fleming","tag-jordyn-huitema","tag-julia-grosso","tag-kadeisha-buchanan","tag-kailen-sheridan","tag-londres-2012","tag-nichelle-prince","tag-quinn","tag-rio-2016","tag-vanessa-gilles","sport-football","game-tokyo-2020"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"Christine Sinclair gravit cette montagne depuis des lustres et voil\u00e0 qu\u2019elle est tout pr\u00e8s d\u2019en atteindre le sommet. En 22...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T15:04:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T17:26:22+00:00\" \/>\n<meta name=\"author\" content=\"Daniel Squizzato\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128108539.jpg?quality=100\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Squizzato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/\"},\"author\":{\"name\":\"Hope Blackmore\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/129757cda37d804f29e6c50854499b4a\"},\"headline\":\"Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire\",\"datePublished\":\"2021-08-04T15:04:23+00:00\",\"dateModified\":\"2021-08-04T17:26:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/\"},\"wordCount\":974,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/CP128108539.jpg?quality=100\",\"keywords\":[\"Adriana Leon\",\"Ashley Lawrence\",\"beijing 2008\",\"Christine Sinclair\",\"Deanne Rose\",\"Janine Beckie\",\"Jessie Fleming\",\"Jordyn Huitema\",\"Julia Grosso\",\"Kadeisha Buchanan\",\"Kailen Sheridan\",\"Londres 2012\",\"Nichelle Prince\",\"Quinn\",\"Rio 2016\",\"Vanessa Gilles\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/\",\"name\":\"Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/CP128108539.jpg?quality=100\",\"datePublished\":\"2021-08-04T15:04:23+00:00\",\"dateModified\":\"2021-08-04T17:26:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/129757cda37d804f29e6c50854499b4a\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2021\\\/08\\\/04\\\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/CP128108539.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/CP128108539.jpg?quality=100\",\"width\":6949,\"height\":5101,\"caption\":\"Canada forward Christine Sinclair (12) leaps into the arms of forward Jordyn Huitema (19) to celebrate their win in semifinal football action against the United States of America at the Tokyo Olympics in Kashima, Japan, Monday, Aug. 2, 2020. THE CANADIAN PRESS\\\/ Frank Gunn\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/129757cda37d804f29e6c50854499b4a\",\"name\":\"Hope Blackmore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d6b32c627c29127cdd3b4d5cd53cf87d53e783dad7380e957275844d2780265?s=96&d=identicon&r=ge5c2140dea9bc7e8b145ee6979af6ce8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d6b32c627c29127cdd3b4d5cd53cf87d53e783dad7380e957275844d2780265?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d6b32c627c29127cdd3b4d5cd53cf87d53e783dad7380e957275844d2780265?s=96&d=identicon&r=g\",\"caption\":\"Hope Blackmore\"},\"sameAs\":[\"hope\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/hope\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire - \u00c9quipe Canada","og_description":"Christine Sinclair gravit cette montagne depuis des lustres et voil\u00e0 qu\u2019elle est tout pr\u00e8s d\u2019en atteindre le sommet. En 22...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2021-08-04T15:04:23+00:00","article_modified_time":"2021-08-04T17:26:22+00:00","author":"Daniel Squizzato","twitter_card":"summary_large_image","twitter_image":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128108539.jpg?quality=100","twitter_misc":{"Written by":"Daniel Squizzato","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/"},"author":{"name":"Hope Blackmore","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/129757cda37d804f29e6c50854499b4a"},"headline":"Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire","datePublished":"2021-08-04T15:04:23+00:00","dateModified":"2021-08-04T17:26:22+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/"},"wordCount":974,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128108539.jpg?quality=100","keywords":["Adriana Leon","Ashley Lawrence","beijing 2008","Christine Sinclair","Deanne Rose","Janine Beckie","Jessie Fleming","Jordyn Huitema","Julia Grosso","Kadeisha Buchanan","Kailen Sheridan","Londres 2012","Nichelle Prince","Quinn","Rio 2016","Vanessa Gilles"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/","url":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/","name":"Le travail hercul\u00e9en de Sinclair am\u00e8ne \u00c9quipe Canada aux portes de l\u2019histoire - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128108539.jpg?quality=100","datePublished":"2021-08-04T15:04:23+00:00","dateModified":"2021-08-04T17:26:22+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/129757cda37d804f29e6c50854499b4a"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/04\/le-travail-herculeen-de-sinclair-amene-equipe-canada-aux-portes-de-lhistoire\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128108539.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128108539.jpg?quality=100","width":6949,"height":5101,"caption":"Canada forward Christine Sinclair (12) leaps into the arms of forward Jordyn Huitema (19) to celebrate their win in semifinal football action against the United States of America at the Tokyo Olympics in Kashima, Japan, Monday, Aug. 2, 2020. THE CANADIAN PRESS\/ Frank Gunn"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/129757cda37d804f29e6c50854499b4a","name":"Hope Blackmore","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8d6b32c627c29127cdd3b4d5cd53cf87d53e783dad7380e957275844d2780265?s=96&d=identicon&r=ge5c2140dea9bc7e8b145ee6979af6ce8","url":"https:\/\/secure.gravatar.com\/avatar\/8d6b32c627c29127cdd3b4d5cd53cf87d53e783dad7380e957275844d2780265?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d6b32c627c29127cdd3b4d5cd53cf87d53e783dad7380e957275844d2780265?s=96&d=identicon&r=g","caption":"Hope Blackmore"},"sameAs":["hope"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/hope\/"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128108539.jpg?quality=100","author_name":["Daniel Squizzato"],"category_names":["Uncategorized"],"tag_names":["Adriana Leon","Ashley Lawrence","beijing 2008","Christine Sinclair","Deanne Rose","Janine Beckie","Jessie Fleming","Jordyn Huitema","Julia Grosso","Kadeisha Buchanan","Kailen Sheridan","Londres 2012","Nichelle Prince","Quinn","Rio 2016","Vanessa Gilles"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-MMu","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/08\/CP128108539.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/187518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434531"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=187518"}],"version-history":[{"count":2,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/187518\/revisions"}],"predecessor-version":[{"id":187553,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/187518\/revisions\/187553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/187523"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=187518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=187518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=187518"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=187518"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=187518"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=187518"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=187518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}