{"id":191894,"date":"2021-10-26T12:30:10","date_gmt":"2021-10-26T16:30:10","guid":{"rendered":""},"modified":"2022-02-10T23:01:14","modified_gmt":"2022-02-11T04:01:14","slug":"canada-a-coeur-joie-equipe-canada-et-lululemon-devoilent-la-collection-olympique-de-beijing-2022","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2021\/10\/26\/canada-a-coeur-joie-equipe-canada-et-lululemon-devoilent-la-collection-olympique-de-beijing-2022\/","title":{"rendered":"Canada \u00e0 coeur joie : \u00c9quipe Canada et lululemon d\u00e9voilent la collection olympique de Beijing 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quand vous vous sentez \u00e0 votre meilleur, vous donnez le meilleur de vous-m\u00eame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce concept est au c\u0153ur des ensembles Athl\u00e8te que lululemon a con\u00e7us \u00e0 l\u2019intention de la d\u00e9l\u00e9gation canadienne en vue des Jeux olympiques et paralympiques d&rsquo;hiver de Beijing 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il s\u2019agit aussi une p\u00e9riode de transformation pour \u00c9quipe Canada, <a href=\"https:\/\/develop.olympic.ca\/olympique\/presse\/lululemon-sassocie-au-coc-et-au-cpc-comme-habilleur-officiel-dequipe-canada-jusquen-2028\/\">lululemon \u00e9tant r\u00e9cemment devenu l\u2019habilleur officiel des \u00e9quipes olympique et paralympique canadiennes<\/a>. La transformation est int\u00e9gr\u00e9e dans l\u2019ensemble sous la forme d&rsquo;un imprim\u00e9 audacieux qui refl\u00e8te l&rsquo;unicit\u00e9 naturelle de notre symbole national &#8211; la feuille d&rsquo;\u00e9rable &#8211; alors qu&rsquo;elle subit une m\u00e9tamorphose, changeant de forme et de couleur tout au long de sa saison de v\u00e9g\u00e9tation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>\u00c0<\/b><strong><strong> LIRE : <\/strong><a href=\"https:\/\/develop.olympic.ca\/olympique\/?p=191892\"><strong>Questions-r\u00e9ponses avec <\/strong>le concepteur de la collection olympique de Beijing 2022<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec le d\u00e9voilement de la collection \u00c9quipe Canada x lululemon de Beijing 2022, nous avons eu un premier aper\u00e7u de ce que nos athl\u00e8tes porteront quand ils repr\u00e9senteront si fi\u00e8rement notre pays sur la plus grande sc\u00e8ne des sports d&rsquo;hiver. Les partisans peuvent aussi s&rsquo;habiller comme des olympiens en se procurant les morceaux incroyables chez <a href=\"https:\/\/fr.shop.lululemon.com\/equipe-canada?mnid=mn;fr-CA;equipe%20canada\">lululemon<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les morceaux modulables sont destin\u00e9s \u00e0 \u00eatre superpos\u00e9s, combin\u00e9s et modifi\u00e9s par les athl\u00e8tes pour s&rsquo;adapter \u00e0 leur personnalit\u00e9 et \u00e0 leurs besoins individuels, que ce soit pour rester au chaud ou au frais. Autant les Jeux olympiques sont un moment d&rsquo;unit\u00e9, autant l\u2019ensemble permet aux athl\u00e8tes de mettre en valeur leur unicit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors, sans plus tarder, examinons de plus pr\u00e8s certaines des conceptions innovantes et \u00e9volutives.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ceremonie-d-ouverture\">C\u00e9r\u00e9monie d&rsquo;ouverture<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab Je suis tr\u00e8s chanceux d&rsquo;avoir pu participer \u00e0 une partie du processus de conception de la collection olympique. J&rsquo;ai donn\u00e9 mon avis sur la fa\u00e7on dont un athl\u00e8te veut se sentir en portant les v\u00eatements. J&rsquo;\u00e9tais tellement fier parce qu&rsquo;ils ont vraiment pris ces suggestions \u00e0 coeur, et vous pouvez les voir dans les v\u00eatements. <em>\u00bb<\/em><\/p><cite>&#8211; Justin Kripps, Bobsleigh, champion olympique de 2018<\/cite><\/blockquote>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"un athl\u00e8te portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191910\" data-id=\"191910\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Liam-Hickey-lululemon-e1635205838808.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Liam-Hickey-lululemon-e1635205838808.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Liam-Hickey-lululemon-e1635205838808.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Liam-Hickey-lululemon-e1635205838808.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Liam-Hickey-lululemon-e1635205838808.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Liam-Hickey-lululemon-e1635205838808.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Liam-Hickey-lululemon-e1635205838808.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Liam-Hickey-lululemon-e1635205838808.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Le joueur de para-hockey sur glace Liam Hickey portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"Le joueur de hockey John Tavares portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191911\" data-id=\"191911\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-2-e1635205910192.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-2-e1635205910192.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-2-e1635205910192.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-2-e1635205910192.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-2-e1635205910192.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-2-e1635205910192.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-2-e1635205910192.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-2-e1635205910192.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Le joueur de hockey John Tavares portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"John Tavares portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191912\" data-id=\"191912\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-e1635205987257.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-e1635205987257.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-e1635205987257.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-e1635205987257.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-e1635205987257.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-e1635205987257.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-e1635205987257.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-John-Tavares-lululemon-e1635205987257.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Le joueur de hockey John Tavares portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3524\" alt=\"Brigette Lacquette portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191914\" data-id=\"191914\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-2-e1635206106933.jpg?quality=100&amp;w=535\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-2-e1635206106933.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-2-e1635206106933.jpg?resize=112,158 112w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-2-e1635206106933.jpg?resize=263,371 263w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-2-e1635206106933.jpg?resize=768,1083 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-2-e1635206106933.jpg?resize=535,754 535w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-2-e1635206106933.jpg?resize=1090,1536 1090w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-2-e1635206106933.jpg?resize=1453,2048 1453w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">La joueuse de hockey Brigette Lacquette portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1667\" alt=\"La joueuse de hockey Brigette Lacquette portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191915\" data-id=\"191915\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacqutte-lululemon-e1635206173248.jpg?quality=100&amp;w=1131\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacqutte-lululemon-e1635206173248.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacqutte-lululemon-e1635206173248.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacqutte-lululemon-e1635206173248.jpg?resize=556,371 556w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacqutte-lululemon-e1635206173248.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacqutte-lululemon-e1635206173248.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacqutte-lululemon-e1635206173248.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacqutte-lululemon-e1635206173248.jpg?resize=2048,1366 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">La joueuse de hockey Brigette Lacquette portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"L'athl\u00e8te de ski para-alpin Fr\u00e9d\u00e9rique Turgeon portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191916\" data-id=\"191916\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-e1635206270925.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-e1635206270925.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-e1635206270925.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-e1635206270925.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-e1635206270925.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-e1635206270925.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-e1635206270925.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-e1635206270925.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de ski para-alpin Fr\u00e9d\u00e9rique Turgeon portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2499\" height=\"3630\" alt=\"L'athl\u00e8te de snowboard Brooke D'Hondt portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191917\" data-id=\"191917\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-e1635206498562.jpg?quality=100&amp;w=519\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-e1635206498562.jpg 2499w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-e1635206498562.jpg?resize=109,158 109w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-e1635206498562.jpg?resize=255,371 255w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-e1635206498562.jpg?resize=768,1116 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-e1635206498562.jpg?resize=519,754 519w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-e1635206498562.jpg?resize=1057,1536 1057w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-e1635206498562.jpg?resize=1410,2048 1410w\" sizes=\"(max-width: 2499px) 100vw, 2499px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de snowboard Brooke D&rsquo;Hondt portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"La joueuse de hockey Brigette Lacquette portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191918\" data-id=\"191918\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-e1635206560734.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-e1635206560734.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-e1635206560734.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-e1635206560734.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-e1635206560734.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-e1635206560734.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-e1635206560734.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brigette-Lacquette-lululemon-e1635206560734.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">La joueuse de hockey Brigette Lacquette portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2446\" height=\"3112\" alt=\"L'athl\u00e8te de bobsleigh Dawn Richardson Wilson portant l'uniforme de C\u00e9r\u00e9monie d'ouverture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191920\" data-id=\"191920\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-e1635206650192.jpg?quality=100&amp;w=593\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-e1635206650192.jpg 2446w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-e1635206650192.jpg?resize=124,158 124w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-e1635206650192.jpg?resize=292,371 292w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-e1635206650192.jpg?resize=768,977 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-e1635206650192.jpg?resize=593,754 593w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-e1635206650192.jpg?resize=1207,1536 1207w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-e1635206650192.jpg?resize=1610,2048 1610w\" sizes=\"(max-width: 2446px) 100vw, 2446px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de bobsleigh Dawn Richardson Wilson portant l&rsquo;uniforme de C\u00e9r\u00e9monie d&rsquo;ouverture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<div class=\"ad-block text-center alignfull padding-top-0\" aria-hidden=true>\n\t\t\t<div id=\"div-gpt-ad-1644550791057-0\">\n\t\t<script>\n \t\t\t\tdocument.addEventListener('DOMContentLoaded', function () {\n \t\t\t\t\tvar cookieValue = getCookie('coc_user_cookie_policy');\n \t\t\t\t\tif (cookieValue === '{opt_in: true, all_cookies: true}') {\n \t\t\t\t\t\tgoogletag.cmd.push(function () {\n \t\t\t\t\t\t\tgoogletag.display(\"div-gpt-ad-1644550791057-0\");\n \t\t\t\t\t\t});\n\n \t\t\t\t\t}\n \t\t\t\t});\n \t\t<\/script>\n\t\t<\/div>\n\t\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la C\u00e9r\u00e9monie d&rsquo;ouverture, \u00c9quipe Canada sera v\u00eatue de rouge vif avec le manteau en duvet \u00c9quipe Canada 22 superpos\u00e9 au parka transformable \u00c9quipe Canada 22, tous deux hydrofuges et coupe-vent. S&rsquo;il fait trop chaud, il y a des sangles pratiques \u00e0 l&rsquo;int\u00e9rieur du manteau qui permettent de le porter comme un sac \u00e0 dos. De son c\u00f4t\u00e9, le parka est extr\u00eamement convertible, avec plusieurs options de longueur. Les manches peuvent \u00eatre d\u00e9tach\u00e9es pour en faire une veste. Il y a aussi une section inf\u00e9rieure amovible qui peut \u00eatre transform\u00e9e en oreiller de voyage ou en \u00e9charpe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette combinaison sera port\u00e9e sur un haut 1\/2 zipp\u00e9 presque sans couture con\u00e7u en maille pour l\u2019a\u00e9ration et disposant de la technologie Silverescent<sup>TM<\/sup> con\u00e7ue avec la fibre X-STATIC afin d&rsquo;entraver la croissance des bact\u00e9ries causant les odeurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y a deux choix de pantalon; le legging Chase The Chill taille tr\u00e8s haute met en valeur l&rsquo;imprim\u00e9 m\u00e9tamorphique \u00e9rable susmentionn\u00e9 tandis que le pantalon de jogging Surge est de couleur merlot intense.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"podium-medias\">Podium + M\u00e9dias<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab Le syst\u00e8me d&rsquo;habillement modulaire me soutient en tant qu&rsquo;athl\u00e8te en me permettant de r\u00e9pondre au besoins de mon corps \u00e0 tout moment donn\u00e9. Dans mon cas, par exemple, je n&rsquo;aime pas porter beaucoup de couches parce que \u00e7a devient tr\u00e8s humide. Ce syst\u00e8me d&rsquo;habillement me permet de rester au chaud, mais sans avoir trop chaud. <em>\u00bb<\/em><\/p><cite><em>\u2013 <\/em>Dawn Richardson Wilson, Bobsleigh<\/cite><\/blockquote>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"L'athl\u00e8te de bobsleigh Dawn Richardson Wilson portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191922\" data-id=\"191922\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-2-e1635206822417.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-2-e1635206822417.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-2-e1635206822417.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-2-e1635206822417.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-2-e1635206822417.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-2-e1635206822417.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-2-e1635206822417.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-2-e1635206822417.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de bobsleigh Dawn Richardson Wilson portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2816\" height=\"3221\" alt=\"L'athl\u00e8te de bobsleigh Dawn Richardson Wilson portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191925\" data-id=\"191925\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-3-e1635206920565.jpg?quality=100&amp;w=659\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-3-e1635206920565.jpg 2816w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-3-e1635206920565.jpg?resize=138,158 138w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-3-e1635206920565.jpg?resize=324,371 324w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-3-e1635206920565.jpg?resize=768,878 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-3-e1635206920565.jpg?resize=659,754 659w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-3-e1635206920565.jpg?resize=1343,1536 1343w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Dawn-Richardson-Wilson-lululemon-3-e1635206920565.jpg?resize=1790,2048 1790w\" sizes=\"(max-width: 2816px) 100vw, 2816px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de bobsleigh Dawn Richardson Wilson portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"2229\" alt=\"L'athl\u00e8te de bobsleigh Justin Kripps portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191926\" data-id=\"191926\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-e1635207000357.jpg?quality=100&amp;w=846\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-e1635207000357.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-e1635207000357.jpg?resize=177,158 177w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-e1635207000357.jpg?resize=416,371 416w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-e1635207000357.jpg?resize=768,685 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-e1635207000357.jpg?resize=846,754 846w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-e1635207000357.jpg?resize=1536,1369 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-e1635207000357.jpg?resize=2048,1826 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de bobsleigh Justin Kripps portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"L'athl\u00e8te de bobsleigh Justin Kripps portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191928\" data-id=\"191928\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-3-e1635207124516.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-3-e1635207124516.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-3-e1635207124516.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-3-e1635207124516.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-3-e1635207124516.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-3-e1635207124516.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-3-e1635207124516.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-3-e1635207124516.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de bobsleigh Justin Kripps portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1667\" alt=\"L'athl\u00e8te de bobsleigh Justin Kripps portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191927\" data-id=\"191927\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-2-e1635207069640.jpg?quality=100&amp;w=1131\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-2-e1635207069640.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-2-e1635207069640.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-2-e1635207069640.jpg?resize=556,371 556w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-2-e1635207069640.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-2-e1635207069640.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-2-e1635207069640.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-2-e1635207069640.jpg?resize=2048,1366 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de bobsleigh Justin Kripps portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Malheureusement, les athl\u00e8tes canadiens ne pourront profiter de la pr\u00e9sence de leurs amis et des membres de leur famille \u00e0 Beijing 2022 en raison de la pand\u00e9mie en cours. Cependant, quand ils r\u00e9aliseront leur r\u00eave de monter sur le podium olympique, ils porteront un manteau qui leur donnera le sentiment chaud et agr\u00e9able d&rsquo;avoir le soutien de tous les Canadiens. La laine m\u00e9rinos naturelle dans un tricot technique cr\u00e9e une texture 3D offrant plus de chaleur et de confort.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2287\" height=\"3459\" alt=\"L'athl\u00e8te de snowboard Brooke D'Hondt portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191929\" data-id=\"191929\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-2-e1635207297306.jpg?quality=100&amp;w=499\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-2-e1635207297306.jpg 2287w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-2-e1635207297306.jpg?resize=104,158 104w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-2-e1635207297306.jpg?resize=245,371 245w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-2-e1635207297306.jpg?resize=768,1162 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-2-e1635207297306.jpg?resize=499,754 499w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-2-e1635207297306.jpg?resize=1016,1536 1016w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-2-e1635207297306.jpg?resize=1354,2048 1354w\" sizes=\"(max-width: 2287px) 100vw, 2287px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de snowboard Brooke D&rsquo;Hondt portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2137\" height=\"3403\" alt=\"L'athl\u00e8te de snowboard Brooke D'Hondt portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191930\" data-id=\"191930\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-3-e1635207272259.jpg?quality=100&amp;w=473\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-3-e1635207272259.jpg 2137w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-3-e1635207272259.jpg?resize=99,158 99w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-3-e1635207272259.jpg?resize=233,371 233w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-3-e1635207272259.jpg?resize=768,1223 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-3-e1635207272259.jpg?resize=473,754 473w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-3-e1635207272259.jpg?resize=965,1536 965w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Brooke-dHondt-lululemon-3-e1635207272259.jpg?resize=1286,2048 1286w\" sizes=\"(max-width: 2137px) 100vw, 2137px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de snowboard Brooke D&rsquo;Hondt portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2503\" height=\"3150\" alt=\"L'athl\u00e8te de ski acrobatique Cassie Sharpe portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191931\" data-id=\"191931\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-e1635207378168.jpg?quality=100&amp;w=599\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-e1635207378168.jpg 2503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-e1635207378168.jpg?resize=126,158 126w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-e1635207378168.jpg?resize=295,371 295w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-e1635207378168.jpg?resize=768,967 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-e1635207378168.jpg?resize=599,754 599w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-e1635207378168.jpg?resize=1221,1536 1221w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-e1635207378168.jpg?resize=1627,2048 1627w\" sizes=\"(max-width: 2503px) 100vw, 2503px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de ski acrobatique Cassie Sharpe portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"L'athl\u00e8te de ski acrobatique Cassie Sharpe portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191932\" data-id=\"191932\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-2-e1635207440812.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-2-e1635207440812.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-2-e1635207440812.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-2-e1635207440812.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-2-e1635207440812.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-2-e1635207440812.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-2-e1635207440812.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-2-e1635207440812.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de ski acrobatique Cassie Sharpe portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"L'athl\u00e8te de ski acrobatique Cassie Sharpe portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191934\" data-id=\"191934\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-3-e1635207503883.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-3-e1635207503883.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-3-e1635207503883.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-3-e1635207503883.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-3-e1635207503883.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-3-e1635207503883.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-3-e1635207503883.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Cassie-Sharpe-lululemon-3-e1635207503883.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de ski acrobatique Cassie Sharpe portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"L'athl\u00e8te de bobsleigh Justin Kripps portant l'uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191935\" data-id=\"191935\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-4-e1635207557529.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-4-e1635207557529.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-4-e1635207557529.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-4-e1635207557529.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-4-e1635207557529.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-4-e1635207557529.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-4-e1635207557529.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Justin-Kripps-lululemon-4-e1635207557529.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de bobsleigh Justin Kripps portant l&rsquo;uniforme de Podium + M\u00e9dias de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<div class=\"ad-block text-center alignfull padding-top-0\" aria-hidden=true>\n\t\t\t<div id=\"div-gpt-ad-1644550962483-0\">\n\t\t<script>\n \t\t\t\tdocument.addEventListener('DOMContentLoaded', function () {\n \t\t\t\t\tvar cookieValue = getCookie('coc_user_cookie_policy');\n \t\t\t\t\tif (cookieValue === '{opt_in: true, all_cookies: true}') {\n \t\t\t\t\t\tgoogletag.cmd.push(function () {\n \t\t\t\t\t\t\tgoogletag.display(\"div-gpt-ad-1644550962483-0\");\n \t\t\t\t\t\t});\n\n \t\t\t\t\t}\n \t\t\t\t});\n \t\t<\/script>\n\t\t<\/div>\n\t\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Qu&rsquo;ils participent \u00e0 des rencontres avec les m\u00e9dias ou qu&rsquo;ils se prom\u00e8nent simplement dans le Village olympique, les athl\u00e8tes montreront leur fiert\u00e9 canadienne en portant la feuille d&rsquo;\u00e9rable comme jamais auparavant sous la forme de l&rsquo;imprim\u00e9 m\u00e9tamorphique fond\u00e9 sur une vue microscopique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il appara\u00eet \u00e0 la fois sur le manteau court \u00c9quipe Canada 22 et sur le pullover 1\/2 zipp\u00e9 \u00c9quipe Canada 22, qui peut \u00eatre port\u00e9 par-dessus le manteau en duvet extensible Navigation \u00c9quipe Canada 22 qui est coupe-vent et r\u00e9sistant \u00e0 l&rsquo;eau et con\u00e7u avec des canaux d&rsquo;isolation. L&rsquo;imprim\u00e9 figure aussi sur le pantalon Align taille haute.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ceremonie-de-cloture\">C\u00e9r\u00e9monie de cl\u00f4ture<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab La C\u00e9r\u00e9monie d&rsquo;ouverture est ce beau voyage de drapage et d&rsquo;averse de rouge sur le corps. Le revers de la m\u00e9daille est la C\u00e9r\u00e9monie de cl\u00f4ture. Il n&rsquo;y a rien de plus manifeste qu&rsquo;un contraire, et ce contraste est l&rsquo;histoire du blanc de l&rsquo;hiver. Les silhouettes ont une proportion diff\u00e9rente &#8211; il s&rsquo;agit de donner vie \u00e0 l&rsquo;imprim\u00e9 m\u00e9tamorphique \u00e0 l&rsquo;ext\u00e9rieur et, ultimement, \u00e0 l&rsquo;esprit de ce moment particulier, la f\u00eate qu&rsquo;est la C\u00e9r\u00e9monie de cl\u00f4ture. <em>\u00bb<\/em><\/p><cite>\u2013 Audrey Reilly, Directrice de la cr\u00e9ation, lululemon<\/cite><\/blockquote>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"L'athl\u00e8te de patinage artistique Paul Poirier portant l'uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191937\" data-id=\"191937\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-2-e1635207678814.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-2-e1635207678814.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-2-e1635207678814.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-2-e1635207678814.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-2-e1635207678814.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-2-e1635207678814.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-2-e1635207678814.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-2-e1635207678814.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de patinage artistique Paul Poirier portant l&rsquo;uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1667\" alt=\"L'athl\u00e8te de patinage artistique Paul Poirier portant l'uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191938\" data-id=\"191938\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-3-e1635207738767.jpg?quality=100&amp;w=1131\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-3-e1635207738767.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-3-e1635207738767.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-3-e1635207738767.jpg?resize=556,371 556w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-3-e1635207738767.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-3-e1635207738767.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-3-e1635207738767.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-3-e1635207738767.jpg?resize=2048,1366 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de patinage artistique Paul Poirier portant l&rsquo;uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2680\" height=\"2400\" alt=\"L'athl\u00e8te de patinage artistique Piper Gilles portant l'uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191939\" data-id=\"191939\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-lululemon.jpg?quality=100&amp;w=842\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-lululemon.jpg 2680w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-lululemon.jpg?resize=176,158 176w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-lululemon.jpg?resize=414,371 414w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-lululemon.jpg?resize=768,688 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-lululemon.jpg?resize=842,754 842w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-lululemon.jpg?resize=1536,1376 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-lululemon.jpg?resize=2048,1834 2048w\" sizes=\"(max-width: 2680px) 100vw, 2680px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de patinage artistique Piper Gilles portant l&rsquo;uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"1970\" alt=\"L'athl\u00e8te de patinage artistique Paul Poirier portant l'uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191940\" data-id=\"191940\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-e1635207784132.jpg?quality=100&amp;w=957\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-e1635207784132.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-e1635207784132.jpg?resize=201,158 201w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-e1635207784132.jpg?resize=471,371 471w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-e1635207784132.jpg?resize=768,605 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-e1635207784132.jpg?resize=957,754 957w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-e1635207784132.jpg?resize=1536,1210 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Paul-Poirier-lululemon-e1635207784132.jpg?resize=2048,1614 2048w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de patinage artistique Paul Poirier portant l&rsquo;uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2493\" height=\"1731\" alt=\"Les athl\u00e8tes de patinage artistique Piper Gilles et Paul Poirier portant l'uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191944\" data-id=\"191944\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-Paul-Poirier-lululemon-3-e1635207943744.jpg?quality=100&amp;w=1086\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-Paul-Poirier-lululemon-3-e1635207943744.jpg 2493w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-Paul-Poirier-lululemon-3-e1635207943744.jpg?resize=228,158 228w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-Paul-Poirier-lululemon-3-e1635207943744.jpg?resize=534,371 534w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-Paul-Poirier-lululemon-3-e1635207943744.jpg?resize=768,533 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-Paul-Poirier-lululemon-3-e1635207943744.jpg?resize=1086,754 1086w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-Paul-Poirier-lululemon-3-e1635207943744.jpg?resize=1536,1067 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Piper-Gilles-Paul-Poirier-lululemon-3-e1635207943744.jpg?resize=2048,1422 2048w\" sizes=\"(max-width: 2493px) 100vw, 2493px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">Les athl\u00e8tes de patinage artistique Piper Gilles et Paul Poirier portant l&rsquo;uniforme de la C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2500\" height=\"3750\" alt=\"L'athl\u00e8te de ski para-alpin Fr\u00e9d\u00e9rique Turgeon portant l'uniforme de C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.\" class=\"wp-block-jetpack-slideshow_image wp-image-191943\" data-id=\"191943\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-3-e1635207847520.jpg?quality=100&amp;w=503\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-3-e1635207847520.jpg 2500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-3-e1635207847520.jpg?resize=105,158 105w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-3-e1635207847520.jpg?resize=247,371 247w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-3-e1635207847520.jpg?resize=768,1152 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-3-e1635207847520.jpg?resize=503,754 503w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-3-e1635207847520.jpg?resize=1024,1536 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/Team-Canada-Frederique-Turgeon-lululemon-3-e1635207847520.jpg?resize=1365,2048 1365w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><figcaption class=\"wp-block-jetpack-slideshow_caption gallery-caption\">L&rsquo;athl\u00e8te de ski para-alpin Fr\u00e9d\u00e9rique Turgeon portant l&rsquo;uniforme de C\u00e9r\u00e9monie de cl\u00f4ture de Beijing 2022 par lululemon.<\/figcaption><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Pour la c\u00e9l\u00e9bration de la C\u00e9r\u00e9monie de cl\u00f4ture, le <em><\/em>manteau en duvet \u00c9quipe Canada 22 &nbsp;et le<em> <\/em>parka transformable \u00c9quipe Canada 22 sont de retour, mais cette fois dans une version blanche de l&rsquo;imprim\u00e9 m\u00e9tamorphique \u00e9rable. En dessous, on trouve le haut 1\/2 zipp\u00e9 Engineered Warmth avec de la laine&nbsp; m\u00e9rinos \u00e0 l&rsquo;int\u00e9rieur qui se portera avec un pantalon de jogging, \u00e9galement de couleur ivoire. Il existe aussi des versions blanches du chapeau de trappeur matelass\u00e9 et de l&rsquo;\u00e9charpe matelass\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les autres accessoires de l\u2019ensemble, on note une tuque r\u00e9versible en m\u00e9lange de laine qui peut \u00eatre port\u00e9e en rouge ou blanc simplement en la retournant et des mitaines matelass\u00e9es avec une ficelle qui pourraient \u00e9voquer des souvenirs de l&rsquo;enfance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N&rsquo;oubliez pas le <a href=\"http:\/\/bit.ly\/3lPrZT5\">sac bandouli\u00e8re Futur patrimoine<\/a>, dont 10 % des ventes soutiennent la Fondation olympique canadienne et la Fondation paralympique canadienne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lululemon est l\u2019habilleur officiel d&rsquo;\u00c9quipe Canada jusqu&rsquo;aux Jeux olympiques et paralympiques de Los Angeles 2028. Vous pouvez en apprendre plus sur la fa\u00e7on dont les athl\u00e8tes ont \u00e9t\u00e9 impliqu\u00e9s dans le processus de conception et sur certaines des technologies textiles int\u00e9gr\u00e9es \u00e0 la collection en <a href=\"https:\/\/develop.olympic.ca\/olympique\/?p=191892\">lisant nos questions-r\u00e9ponses avec l&rsquo;\u00e9quipe de lululemon<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand vous vous sentez \u00e0 votre meilleur, vous donnez le meilleur de vous-m\u00eame. Ce concept est au c\u0153ur des ensembles&#8230;<\/p>\n","protected":false},"author":52435451,"featured_media":191960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[415986612,415950869,682164695,1104411,682164696,682164694],"post_format":"standard","sport":[],"game":[415986610],"coauthors":[197557601],"class_list":["post-191894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-beijing-2022","tag-collection-olympique","tag-delegation-canadienne","tag-equipe-canada","tag-equipe-canada-lululemon","tag-lululemon","game-beijing-2022"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/MicrosoftTeams-image.jpg?quality=100","author_name":["Paula Nichols"],"category_names":["Nouvelles"],"tag_names":["Beijing 2022","collection olympique","d\u00e9l\u00e9gation canadienne","\u00c9quipe canada","\u00c9quipe Canada lululemon","lululemon"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-NV4","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2021\/10\/MicrosoftTeams-image.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/191894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/52435451"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=191894"}],"version-history":[{"count":8,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/191894\/revisions"}],"predecessor-version":[{"id":203313,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/191894\/revisions\/203313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/191960"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=191894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=191894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=191894"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=191894"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=191894"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=191894"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=191894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}