{"id":211282,"date":"2022-08-06T13:22:35","date_gmt":"2022-08-06T17:22:35","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=211282"},"modified":"2022-08-08T14:56:33","modified_gmt":"2022-08-08T18:56:33","slug":"jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/","title":{"rendered":"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l&rsquo;or et l&rsquo;\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y en a eu deux dans le bassin de plongeon, alors que Mia Vall\u00e9e a poursuivi son ascension fulgurante, et six sur le tapis de lutte, soulign\u00e9es par une performance dominante d&rsquo;Amar Dhesi.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"https:\/\/commonwealthsport.ca\/fr\"><strong>\u00c9quipe Canada aux Jeux du Commonwealth de 2022<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voici un rapide retour sur l&rsquo;action, avec quelques autres Canadiens qui ont poursuivi leur chemin vers le podium :<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Plongeon<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mia Vall\u00e9e a \u00e9t\u00e9 un mod\u00e8le de constance dans la finale du tremplin f\u00e9minin de 1m. Apr\u00e8s avoir remport\u00e9 le bronze dans cette \u00e9preuve aux Championnats du monde de la FINA \u00e0 la fin juin. Elle a mis la main sur la m\u00e9daille d&rsquo;or des Jeux du Commonwealth en totalisant 291,85 points lors de ses cinq plongeons, ce qui lui a donn\u00e9 une marge de victoire de 12,25 points.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">&quot;The Golden trifecta!&quot; <br><br>Canada&#39;s Mia Vall\u00e9e upgrades her bronze and silver from the world championships with a GOLD in the 1m springboard final at <a href=\"https:\/\/twitter.com\/hashtag\/B2022?src=hash&amp;ref_src=twsrc%5Etfw\">#B2022<\/a> \ud83e\udd47\ud83c\udde8\ud83c\udde6 <a href=\"https:\/\/t.co\/QcEO1Y9zzE\">pic.twitter.com\/QcEO1Y9zzE<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1555614320934936578?ref_src=twsrc%5Etfw\">August 5, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s s&rsquo;\u00eatre class\u00e9e deuxi\u00e8me par moins d&rsquo;un demi-point apr\u00e8s le premier plongeon, Vall\u00e9e a pris la premi\u00e8re place et ne l&rsquo;a jamais quitt\u00e9e. Sa co\u00e9quipi\u00e8re Margo Erlam s&rsquo;est class\u00e9e neuvi\u00e8me lors de la finale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/rylan-wiens\/\">Rylan Wiens<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/nathan-zsombor-murray\/\">Nathan Zsombor-Murray<\/a> ont ensuite remport\u00e9 la m\u00e9daille d&rsquo;argent \u00e0 l&rsquo;\u00e9preuve du 10 m synchro masculin. Ils ont amass\u00e9 413,85 points pour leurs six plongeons et ont termin\u00e9 \u00e0 15,93 points des m\u00e9daill\u00e9s d&rsquo;or, les Anglais Matty Lee et Noah Williams. Le duo anglais avait \u00e9t\u00e9 m\u00e9daill\u00e9 d&rsquo;argent aux Championnats du monde de la FINA alors que les Canadiens avaient remport\u00e9 le bronze. Wiens et Zsombor-Murray ont termin\u00e9 avec seulement 1,29 point d&rsquo;avance sur les m\u00e9daill\u00e9s de bronze, Domonic Bedggood et Cassiel Rousseau, d&rsquo;Australie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lutte<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Six Canadiens \u00e9taient en lice pour une m\u00e9daille vendredi, dont quatre luttaient pour l&rsquo;or.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/amar-dhesi\/\">Amar Dhesi<\/a> a \u00e9t\u00e9 le seul \u00e0 remporter une m\u00e9daille d&rsquo;or, par chute, dans l&rsquo;\u00e9preuve masculine de style libre de 125 kg. Il a domin\u00e9 le match contre le Pakistanais Zaman Anwar, marquant ses premiers points apr\u00e8s seulement 30 secondes et portant le score \u00e0 9-2 avant que le match ne se termine en deux minutes et 10 secondes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\ud83e\udd47GOLD\ud83e\udd47<br><br>Absolutely brilliant work from Canada&#39;s Amar Dhesi winning gold in the men&#39;s 125kg <a href=\"https:\/\/twitter.com\/hashtag\/wrestling?src=hash&amp;ref_src=twsrc%5Etfw\">#wrestling<\/a> <a href=\"https:\/\/t.co\/NOxsWKuzOM\">https:\/\/t.co\/NOxsWKuzOM<\/a> <a href=\"https:\/\/t.co\/D2pALewQIy\">pic.twitter.com\/D2pALewQIy<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1555665888350806016?ref_src=twsrc%5Etfw\">August 5, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Godinez Gonazalez a pris l&rsquo;avantage dans la finale des 62 kg f\u00e9minins, prenant une avance de 4-0 sur son adversaire, l&rsquo;Indienne Sakshi Malik, jusqu&rsquo;\u00e0 la pause de mi-match. Mais moins d&rsquo;une minute apr\u00e8s la reprise, Malik a \u00e9pingl\u00e9 la Canadienne pour remporter la victoire par chute et renvoyer Godinez Gonzalez chez elle avec l&rsquo;argent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Linda Morais a \u00e9galement remport\u00e9 une m\u00e9daille d&rsquo;argent dans l&rsquo;\u00e9preuve f\u00e9minine des 68 kg. Elle a perdu contre Blessing Oborududu du Nigeria 5-1 dans cette finale. Lachlan McNeil repartira avec l&rsquo;argent dans l&rsquo;\u00e9preuve masculine de 65 kg en style libre. Il a \u00e9t\u00e9 battu 9-2 par l&rsquo;Indien Bajrang Punia en finale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/hannah-taylor\/\">Hannah Taylor<\/a> a remport\u00e9 le bronze dans l&rsquo;\u00e9preuve f\u00e9minine des 57 kg. Il ne lui a fallu que 35 secondes pour remporter la victoire par chute contre Sophia Ayieta du Kenya. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alex-moore\/\">Alex Moore<\/a> a remport\u00e9 la m\u00e9daille de bronze dans l&rsquo;\u00e9preuve masculine de 86 kg, s&rsquo;imposant 10-0 par sup\u00e9riorit\u00e9 technique en un peu plus d&rsquo;une minute.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Athl\u00e9tisme<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Plusieurs Canadiens auront l&rsquo;occasion de se battre pour le podium ce week-end. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/brendon-rodney\/\">Brendon Rodney<\/a> a termin\u00e9 deuxi\u00e8me de sa demi-finale du 200 m et se dirige vers la finale en tant que cinqui\u00e8me homme le plus rapide avec son temps de 20,68 secondes. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/natasha-mcdonald\/\">Natassha McDonald <\/a>a termin\u00e9 deuxi\u00e8me de sa demi-finale du 200 m devant la Jama\u00efcaine Elaine Thompson-Herah, double championne olympique en titre. Le temps de 23,21 secondes de McDonald la classe sixi\u00e8me avant la finale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/kyra-constantine\/\">Kyra Constantine<\/a> s&rsquo;est class\u00e9e quatri\u00e8me parmi toutes les femmes qui se sont qualifi\u00e9es pour la finale du 400 m avec son meilleur temps de la saison de 51,78 secondes. Michelle Harrison s&rsquo;est qualifi\u00e9e pour la finale du 100 m haies f\u00e9minin. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/lucia-stafford\/\">Lucia Stafford<\/a> s&rsquo;est qualifi\u00e9e pour la finale du 1500 m f\u00e9minin. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/christabel-nettey\/\">Christabel Nettey<\/a> s&rsquo;est qualifi\u00e9e pour la finale du saut en longueur f\u00e9minin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le porte-drapeau de la c\u00e9r\u00e9monie d&rsquo;ouverture, Josh Cassidy, s&rsquo;est class\u00e9 cinqui\u00e8me dans la course masculine T53\/54 de 1500 m en fauteuil roulant, son co\u00e9quipier Alexandre Dupont \u00e9tant juste derri\u00e8re en sixi\u00e8me position.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Volleyball de plage<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;\u00e9tait le jour des quarts de finale dans les tournois f\u00e9minins et masculins. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/sarah-pavan\/\">Sarah Pavan<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/melissa-humana-paredes\/\">Melissa Humana-Paredes<\/a> ont remport\u00e9 une victoire en deux sets (21-9, 21-11) contre le duo sri-lankaise pour acc\u00e9der aux demi-finales de samedi o\u00f9 elles affronteront Alice Zeimann et Shuanna Polley de Nouvelle-Z\u00e9lande. Les Canadiennes sont les championnes en titre des Jeux du Commonwealth.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Watch Sarah Pavan &amp; Melissa Humana-Paredes do what they do best <br><br>Channel 5: <a href=\"https:\/\/t.co\/iobaKmL8uH\">https:\/\/t.co\/iobaKmL8uH<\/a> <a href=\"https:\/\/t.co\/xPhOCZsMwm\">pic.twitter.com\/xPhOCZsMwm<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1555649126955614209?ref_src=twsrc%5Etfw\">August 5, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/sam-schachter\/\">Sam Schachter<\/a> et Daniel Dearing ont battu leurs adversaires de Chypre 2-0 (21-9, 21-11) pour se qualifier pour une demi-finale samedi contre le duo anglais Javier Bello et Joaquin Bello.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Badminton<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/michelle-li\/\">Michelle Li <\/a>a franchi une nouvelle \u00e9tape vers la conqu\u00eate d&rsquo;une deuxi\u00e8me m\u00e9daille d&rsquo;or en carri\u00e8re aux Jeux du Commonwealth. La championne 2014 du simple f\u00e9minin a remport\u00e9 son match de huiti\u00e8me de finale 2-0 (21-10, 21-9) contre Khan Insyirah de Singapour. Le quart de finale de Li aura lieu samedi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le double f\u00e9minin,<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/rachel-honderich\/\"> Rachel Honderich<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/kristen-tsai\/\">Kristen Tsai<\/a> ont \u00e9galement \u00e9t\u00e9 victorieuses dans leur match de huiti\u00e8me de finale, en battant une paire \u00e9cossaise 2-0 (21-12, 21-15).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gymnastique rythmique<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un jour apr\u00e8s avoir remport\u00e9 l&rsquo;or dans l&rsquo;\u00e9preuve par \u00e9quipe, Carmel Kallemaa et Suzanna Shahbazian ont toutes deux termin\u00e9 dans les huit premi\u00e8res places de la finale du concours g\u00e9n\u00e9ral individuel. Kallemaa s&rsquo;est class\u00e9e sixi\u00e8me et Shahbazian huiti\u00e8me. Elles seront de retour au sol samedi pour les finales individuelles.<\/p>\n\n\n<div class=\"table-scrollable-wrapper\">\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th>\u00c9quipe<\/th><th>Or<\/th><th>Argent<\/th><th>Bronze<\/th><th>Total<\/th><\/tr><\/thead><tbody><tr><td>Australie<\/td><td>50<\/td><td>44<\/td><td>46<\/td><td>140<\/td><\/tr><tr><td>Angleterre<\/td><td>47<\/td><td>46<\/td><td>38<\/td><td>131<\/td><\/tr><tr><td><strong>Canada<\/strong><\/td><td><strong>19<\/strong><\/td><td><strong>24<\/strong><\/td><td><strong>24<\/strong><\/td><td><strong>67<\/strong><\/td><\/tr><tr><td>Nouvelle-Z\u00e9lande<\/td><td>17<\/td><td>11<\/td><td>13<\/td><td>41<\/td><\/tr><tr><td>\u00c9cosse<\/td><td>8<\/td><td>8<\/td><td>19<\/td><td>35<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em>Les Jeux du Commonwealth de 2022 se d\u00e9rouleront jusqu\u2019au 8 ao\u00fbt et mettront en vedette 268 athl\u00e8tes canadiens qui concourront dans 18 sports et cinq sports para. Vous pouvez suivre l\u2019action en direct sur&nbsp;<a href=\"https:\/\/gem.cbc.ca\/\">CBC Gem<\/a>,&nbsp;<a href=\"http:\/\/cbcsports.ca\/\">cbcsports.ca<\/a>&nbsp;et l\u2019application CBC Sports pour les appareils<a href=\"https:\/\/apps.apple.com\/ca\/app\/cbc-sports\/id1001665907\">&nbsp;iOS<\/a>&nbsp;et&nbsp;<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=ca.cbc.android.sports&amp;hl=en_CA&amp;gl=US\">Android.<\/a>&nbsp;Certaines comp\u00e9titions seront \u00e9galement diffus\u00e9es sur les&nbsp;<a href=\"https:\/\/www.cbc.ca\/sports\/commonwealthgames\/tv-schedule\">cha\u00eenes de t\u00e9l\u00e9vision de CBC<\/a>&nbsp;les week-ends.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit&#8230;<\/p>\n","protected":false},"author":52435451,"featured_media":211285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[682162650,415984548,415984540,682165337,1104411,27239858,415983994,2245510,2480962,184985458],"post_format":"standard","sport":[48770,16258,9127036,415983001,181823658,10149896],"game":[],"coauthors":[197557601],"class_list":["post-211282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-682162650","tag-athletisme","tag-badminton","tag-birmigham","tag-equipe-canada","tag-jeux-du-commonwealth","tag-lutte","tag-medaille","tag-plongeon","tag-volleyball-de-plage-2","sport-athletisme","sport-badminton","sport-gymnastique-artistique","sport-lutte","sport-sports-aquatiques-plongeon","sport-volleyball-de-plage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l&#039;or et l&#039;\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8 - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l&#039;or et l&#039;\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8\" \/>\n<meta property=\"og:description\" content=\"Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-06T17:22:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-08T18:56:33+00:00\" \/>\n<meta name=\"author\" content=\"Paula Nichols\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l&#039;or et l&#039;\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8\" \/>\n<meta name=\"twitter:description\" content=\"Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/08\/comonwealth-jour-8-e1659806483414.png\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula Nichols\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/\"},\"author\":{\"name\":\"Paula Nichols\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/3c314bd10dc37d246fe1858c04d5089c\"},\"headline\":\"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l&rsquo;or et l&rsquo;\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8\",\"datePublished\":\"2022-08-06T17:22:35+00:00\",\"dateModified\":\"2022-08-08T18:56:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/\"},\"wordCount\":1217,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/comonwealth-jour-8-e1659806483414.png\",\"keywords\":[\"2022\",\"Athl\u00e9tisme\",\"Badminton\",\"birmigham\",\"\u00c9quipe canada\",\"Jeux du Commonwealth\",\"Lutte\",\"m\u00e9daille\",\"plongeon\",\"Volleyball de plage\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/\",\"name\":\"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l'or et l'\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8 - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/comonwealth-jour-8-e1659806483414.png\",\"datePublished\":\"2022-08-06T17:22:35+00:00\",\"dateModified\":\"2022-08-08T18:56:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/3c314bd10dc37d246fe1858c04d5089c\"},\"description\":\"Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/08\\\/06\\\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/comonwealth-jour-8-e1659806483414.png\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/comonwealth-jour-8-e1659806483414.png\",\"width\":2160,\"height\":1220},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/3c314bd10dc37d246fe1858c04d5089c\",\"name\":\"Paula Nichols\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=gf6876353c4226c9b0e52b96b76e72cac\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=g\",\"caption\":\"Paula Nichols\"},\"description\":\"Manager of Content and Research for the Canadian Olympic Committee and a lifelong fan of the Olympic Games and the athletes who compete at them.\",\"sameAs\":[\"pnichols\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/pnichols\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l'or et l'\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8 - \u00c9quipe Canada","description":"Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/","og_locale":"fr_FR","og_type":"article","og_title":"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l'or et l'\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8","og_description":"Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.","og_url":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2022-08-06T17:22:35+00:00","article_modified_time":"2022-08-08T18:56:33+00:00","author":"Paula Nichols","twitter_card":"summary_large_image","twitter_title":"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l'or et l'\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8","twitter_description":"Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.","twitter_image":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/08\/comonwealth-jour-8-e1659806483414.png","twitter_misc":{"Written by":"Paula Nichols","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/"},"author":{"name":"Paula Nichols","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/3c314bd10dc37d246fe1858c04d5089c"},"headline":"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l&rsquo;or et l&rsquo;\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8","datePublished":"2022-08-06T17:22:35+00:00","dateModified":"2022-08-08T18:56:33+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/"},"wordCount":1217,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/08\/comonwealth-jour-8-e1659806483414.png","keywords":["2022","Athl\u00e9tisme","Badminton","birmigham","\u00c9quipe canada","Jeux du Commonwealth","Lutte","m\u00e9daille","plongeon","Volleyball de plage"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/","url":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/","name":"Jeux du Commonwealth 2022 : Vall\u00e9e plonge vers l'or et l'\u00e9quipe canadienne remporte 8 m\u00e9dailles au Jour 8 - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/08\/comonwealth-jour-8-e1659806483414.png","datePublished":"2022-08-06T17:22:35+00:00","dateModified":"2022-08-08T18:56:33+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/3c314bd10dc37d246fe1858c04d5089c"},"description":"Au Jour 8 de comp\u00e9tition des Jeux du Commonwealth 2022 \u00e0 Birmingham, en Angleterre, les athl\u00e8tes canadiens ont remport\u00e9 huit m\u00e9dailles.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/08\/06\/jeux-du-commonwealth-2022-vallee-plonge-vers-lor-et-lequipe-canadienne-remporte-8-medailles-au-jour-8\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/08\/comonwealth-jour-8-e1659806483414.png","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/08\/comonwealth-jour-8-e1659806483414.png","width":2160,"height":1220},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/3c314bd10dc37d246fe1858c04d5089c","name":"Paula Nichols","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=gf6876353c4226c9b0e52b96b76e72cac","url":"https:\/\/secure.gravatar.com\/avatar\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83aa2ad476fcd1071d58a474c9a2f51716b807e2406ca3aeaa032882e7f0346a?s=96&d=identicon&r=g","caption":"Paula Nichols"},"description":"Manager of Content and Research for the Canadian Olympic Committee and a lifelong fan of the Olympic Games and the athletes who compete at them.","sameAs":["pnichols"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/pnichols\/"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/08\/comonwealth-jour-8-e1659806483414.png","author_name":["Paula Nichols"],"category_names":["Uncategorized"],"tag_names":["2022","Athl\u00e9tisme","Badminton","birmigham","\u00c9quipe canada","Jeux du Commonwealth","Lutte","m\u00e9daille","plongeon","Volleyball de plage"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-SXM","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/08\/comonwealth-jour-8-e1659806483414.png","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/211282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/52435451"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=211282"}],"version-history":[{"count":3,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/211282\/revisions"}],"predecessor-version":[{"id":211342,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/211282\/revisions\/211342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/211285"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=211282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=211282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=211282"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=211282"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=211282"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=211282"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=211282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}