{"id":213356,"date":"2022-10-21T16:47:04","date_gmt":"2022-10-21T20:47:04","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=213356"},"modified":"2022-10-24T12:27:44","modified_gmt":"2022-10-24T16:27:44","slug":"coupe-du-monde-de-ski-big-air-noah-porter-maclennan-gagne-largent","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2022\/10\/21\/coupe-du-monde-de-ski-big-air-noah-porter-maclennan-gagne-largent\/","title":{"rendered":"Coupe du monde de big air : Porter MacLennan en argent, Baird en bronze"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le skieur acrobatique canadien Noah Porter MacLennan a remport\u00e9 la m\u00e9daille d&rsquo;argent \u00e0 la premi\u00e8re Coupe du monde FIS de ski big air de la saison \u00e0 Coire, en Suisse. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jasmine-baird\/\">Jasmine Baird<\/a> a gagn\u00e9 la m\u00e9daille de bronze de l&rsquo;\u00e9preuve f\u00e9minine de la Coupe du monde FIS de snowboard big air au m\u00eame endroit. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de la finale de l&rsquo;\u00e9preuve masculine de ski big air pr\u00e9sent\u00e9e vendredi, Noah Porter MacLennan a cumul\u00e9 un total de 180,00 points pour conclure derri\u00e8re le Norv\u00e9gien Birk Ruud gagnant avec 188,75 points. L&rsquo;Am\u00e9ricain Troy Podmilsak a pris le troisi\u00e8me rang concluant \u00e0 0,25 point de la deuxi\u00e8me place. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">SILVER for Noah Porter Maclennan \ud83e\udd48 \ud83c\udde8\ud83c\udde6<br><br>The 19-year-old wins his first World Cup medal at the first event of the season \ud83d\udd25 <a href=\"https:\/\/t.co\/JiSxZ9FKQy\">pic.twitter.com\/JiSxZ9FKQy<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1583550662922555392?ref_src=twsrc%5Etfw\">October 21, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Porter MacLennan, \u00e2g\u00e9 de 19 ans, a fait preuve d&rsquo;une belle constance tout au cours de la finale o\u00f9 les athl\u00e8tes effectuent trois sauts not\u00e9s sur 100, mais o\u00f9 seuls les deux meilleurs sont cumul\u00e9s pour d\u00e9terminer le classement final. Il occupait le quatri\u00e8me rang apr\u00e8s son premier saut qui lui a valu un pointage de 82,50 points. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Canadien a \u00e9lev\u00e9 la barre lors de son deuxi\u00e8me saut r\u00e9coltant 90,00 points, ce qui lui a permis de demeurer en quatri\u00e8me place. Il a r\u00e9cidiv\u00e9 \u00e0 sa derni\u00e8re tentative, r\u00e9coltant encore une fois 90,00 points pour grimper au classement et prendre le deuxi\u00e8me rang de la comp\u00e9tition. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il s&rsquo;agit d&rsquo;une premi\u00e8re m\u00e9daille de Coupe du monde en carri\u00e8re pour le jeune athl\u00e8te qui avait termin\u00e9 au pied du podium aux Championnats du monde juniors en 2019. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">What a day for Noah Porter Maclennan \ud83c\udde8\ud83c\udde6<br><br>\u2705 First career World Cup medal <br>\u2705 Canada&#39;s first FIS World Cup medal of the 2022-23 season <br>\u2705 One of the COOLEST trophies ever <a href=\"https:\/\/t.co\/yUex8bZAh6\">pic.twitter.com\/yUex8bZAh6<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1583552876000923648?ref_src=twsrc%5Etfw\">October 21, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/olivia-asselin\/\">Olivia Asselin<\/a> \u00e9tait de la finale f\u00e9minine de ski big air o\u00f9 elle a pris le quatri\u00e8me rang. Apr\u00e8s un bon premier saut, la skieuse acrobatique a connu des difficult\u00e9s \u00e0 ses deux autres tentatives, r\u00e9coltant des notes de moins de 20 points aux deux occasions. Prenant \u00e9galement part \u00e0 la finale, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/megan-oldham\/\">Megan Oldham<\/a> n&rsquo;a pas conclu la comp\u00e9tition apr\u00e8s avoir rat\u00e9 ses deux premiers sauts. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Jasmine Baird troisi\u00e8me en snowboard big air<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Samedi, lors de l&rsquo;\u00e9preuve f\u00e9minine de snowboard big air, Baird a atteint le podium \u00e0 la conclusion de ses trois sauts. Elle a scell\u00e9 sa troisi\u00e8me place avec un <em>cab double underflip weddle<\/em> et un <em>backside 720 weddle<\/em> pour un pointage de 131,25 points. Anna\u00a0Gasser de l&rsquo;Autriche, championne olympique de l&rsquo;\u00e9preuve, a obtenu un pointage de 164,75 pour conclure derri\u00e8re la Japonaise Reira\u00a0Iwabuchi qui a termin\u00e9 la comp\u00e9tition avec un impressionnant total de 180,75 points.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Jasmine Baird is starting her season on the podium \ud83e\udd49<br><br>The Canadian finished 3rd in the women&#39;s big air final in Switzerland <br><br>Watch more: <a href=\"https:\/\/t.co\/ZEtLuS8XWq\">https:\/\/t.co\/ZEtLuS8XWq<\/a> <a href=\"https:\/\/t.co\/GHaFjjvFkD\">pic.twitter.com\/GHaFjjvFkD<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1584386699114709002?ref_src=twsrc%5Etfw\">October 24, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La prochaine Coupe du monde de snowboard big air aura lieu \u00e0 Edmonton, en Alberta, les 9 et 10 d\u00e9cembre, alors que la prochaine Coupe du monde de ski big air se d\u00e9roulera le16 d\u00e9cembre \u00e0 Copper Mountain, aux \u00c9tats-Unis. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 LIRE : <a href=\"https:\/\/develop.olympic.ca\/olympique\/2022\/02\/19\/les-etoiles-montantes-dequipe-canada-revelees-a-beijing-2022\/\">Les \u00e9toiles montantes d\u2019\u00c9quipe Canada r\u00e9v\u00e9l\u00e9es \u00e0 Beijing 2022<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le skieur acrobatique canadien Noah Porter MacLennan a remport\u00e9 la m\u00e9daille d&rsquo;argent \u00e0 la premi\u00e8re Coupe du monde FIS de&#8230;<\/p>\n","protected":false},"author":185434513,"featured_media":213377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[1492254,57236,415984420,415988186,682165395,682164729,13328337,682165396],"post_format":"standard","sport":[181823549],"game":[],"coauthors":[682164273],"class_list":["post-213356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-big-air","tag-coupe-du-monde","tag-coupe-du-monde-fis","tag-megan-oldham","tag-noah-porter-maclennan","tag-olivia-asselin","tag-ski-acrobatique","tag-ski-big-air","sport-ski-ski-acrobatique"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/10\/312178539_639367421250320_356801056327792860_n-e1666388353876.jpg?quality=100","author_name":["Audrey Lacroix"],"category_names":["Nouvelles"],"tag_names":["Big air","Coupe du monde","Coupe du monde FIS","Megan Oldham","Noah Porter Maclennan","Olivia Asselin","Ski acrobatique","Ski big air"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-Tve","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/10\/312178539_639367421250320_356801056327792860_n-e1666388353876.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/213356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434513"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=213356"}],"version-history":[{"count":21,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/213356\/revisions"}],"predecessor-version":[{"id":213474,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/213356\/revisions\/213474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/213377"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=213356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=213356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=213356"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=213356"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=213356"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=213356"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=213356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}