{"id":215890,"date":"2022-12-17T10:05:08","date_gmt":"2022-12-17T15:05:08","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=215890"},"modified":"2022-12-19T16:15:39","modified_gmt":"2022-12-19T21:15:39","slug":"lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/","title":{"rendered":"Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles samedi, l&rsquo;\u00e9quipe canadienne a ajout\u00e9 trois m\u00e9dailles \u00e0 sa r\u00e9colte dimanche \u00e0 la Coupe du monde de patinage de vitesse sur courte piste \u00e0 Amalty, au Kazakhstan. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9quipe masculine a remport\u00e9 l&rsquo;or au relais 5 000 m, l&rsquo;\u00e9quipe f\u00e9minine a mis la main sur la m\u00e9daille d&rsquo;argent au relais 3000 m et Steven Dubois a enlev\u00e9 l&rsquo;argent au 1000 m. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9quipe compos\u00e9e de William Dandjinou, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/pascal-dion\/\">Pascal Dion<\/a>,&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/maxime-laou\/\">Maxime Laoun<\/a> et&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jordan-pierre-gilles\/\">Jordan Pierre-Gilles<\/a> a devanc\u00e9 l&rsquo;\u00e9quipe des Pays-Bas par 0,44 seconde pour remporter l&rsquo;or \u00e0 Almaty, au Kazakhstan. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Pays-Bas et le Canada \u00e9taient au coude \u00e0 coude avant que Jordan Pierre-Gilles ne prenne un l\u00e9ger avantage en sortant son patin gauche pour franchir la ligne d&rsquo;arriv\u00e9e en premier. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Rounding things off in Almaty \ud83d\udfe2<br><br>The moment Canada edged ahead of Netherlands for Men&#39;s 5000m Relay success &#8211; again!<a href=\"https:\/\/twitter.com\/hashtag\/ShortTrackSkating?src=hash&amp;ref_src=twsrc%5Etfw\">#ShortTrackSkating<\/a> <a href=\"https:\/\/t.co\/cXK879bYvB\">pic.twitter.com\/cXK879bYvB<\/a><\/p>&mdash; ISU Speed Skating (@ISU_Speed) <a href=\"https:\/\/twitter.com\/ISU_Speed\/status\/1604445127409377287?ref_src=twsrc%5Etfw\">December 18, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9quipe de relais du Japon a remport\u00e9 le bronze dans cette \u00e9preuve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au relais f\u00e9minin, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/danae-blais\/\">Dana\u00e9 Blais<\/a>,&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/kim-boutin\/\">Kim Boutin<\/a>, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/courtney-sarault\/\">Courtney Sarault<\/a> et Renee Marie Steenge ont gagn\u00e9 la m\u00e9daille d&rsquo;argent, concluant derri\u00e8re la Cor\u00e9e du Sud. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/steven-dubois\/\">Steven Dubois<\/a> a remport\u00e9 sa deuxi\u00e8me m\u00e9daille d&rsquo;argent du week-end au 1000 m masculin, franchissant la ligne d&rsquo;arriv\u00e9e apr\u00e8s Ji Won Park de la Cor\u00e9e du Sud, mais gagnant une belle bataille contre le Letton Roberts Kruzbergs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Samedi, Courtney Sarault a mis la main sur la m\u00e9daille d\u2019or de l\u2019\u00e9preuve du 1500 m. La Canadienne a termin\u00e9 au sommet du podium devant la Belge Hanne Desmet et la Cor\u00e9enne Suk Hee Shim.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Our own <a href=\"https:\/\/twitter.com\/court_sarault?ref_src=twsrc%5Etfw\">@court_sarault<\/a>  wins gold in the 1500m at the World Cup #4  in Almaty, while <a href=\"https:\/\/twitter.com\/stevendubois3?ref_src=twsrc%5Etfw\">@stevendubois3<\/a>  takes home silver in the 500m. <a href=\"https:\/\/twitter.com\/hashtag\/shorttrack?src=hash&amp;ref_src=twsrc%5Etfw\">#shorttrack<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/worldcup?src=hash&amp;ref_src=twsrc%5Etfw\">#worldcup<\/a> <a href=\"https:\/\/twitter.com\/CBCOlympics?ref_src=twsrc%5Etfw\">@CBCOlympics<\/a> <a href=\"https:\/\/twitter.com\/RC_Sports?ref_src=twsrc%5Etfw\">@RC_Sports<\/a> <a href=\"https:\/\/t.co\/8nBw71zX0s\">pic.twitter.com\/8nBw71zX0s<\/a><\/p>&mdash; Speed Skating Canada | Patinage de Vitesse Canada (@SSC_PVC) <a href=\"https:\/\/twitter.com\/SSC_PVC\/status\/1604083872530108416?ref_src=twsrc%5Etfw\">December 17, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est donc une deuxi\u00e8me m\u00e9daille d\u2019or en carri\u00e8re sur le circuit de la Coupe du monde pour Sarault apr\u00e8s celle remport\u00e9e au 1000 m la semaine derni\u00e8re, aussi \u00e0 Almaty.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 LIRE&nbsp;: <a href=\"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/10\/courtney-sarault-victorieuse-au-kazakhstan-sur-1000-m\/\">Plusieurs m\u00e9dailles pour \u00c9quipe Canada dont l\u2019or pour Kim Boutin et les \u00e9quipes de relais au Kazakhstan<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chez les hommes, Steven Dubois s&rsquo;est d\u00e9marqu\u00e9 avec une m\u00e9daille d\u2019argent au 500 m.&nbsp; Il a d\u00fb conc\u00e9der la premi\u00e8re place au Polonais Diane Sellier, alors que le Kazakh Denis Nikisha a compl\u00e9t\u00e9 le podium.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">SILVER for Steven \ud83e\udd48<br><br>In a close one, <a href=\"https:\/\/twitter.com\/stevendubois3?ref_src=twsrc%5Etfw\">@stevendubois3<\/a> raced to a silver medal in the men&#39;s 500m at the ISU Short Track Speed Skating World Cup<br><br>More: <a href=\"https:\/\/t.co\/HDRbMthM1m\">https:\/\/t.co\/HDRbMthM1m<\/a> <a href=\"https:\/\/t.co\/cJHGXFTxs9\">pic.twitter.com\/cJHGXFTxs9<\/a><\/p>&mdash; CBC Olympics (@CBCOlympics) <a href=\"https:\/\/twitter.com\/CBCOlympics\/status\/1604113204510044160?ref_src=twsrc%5Etfw\">December 17, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les patineurs et patineuses profiteront maintenant d\u2019un cong\u00e9 de comp\u00e9titions pendant les F\u00eates avant de reprendre l\u2019action au d\u00e9but du mois de f\u00e9vrier en Allemagne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles samedi, l&rsquo;\u00e9quipe canadienne a ajout\u00e9 trois m\u00e9dailles \u00e0 sa r\u00e9colte dimanche \u00e0 la Coupe du&#8230;<\/p>\n","protected":false},"author":112974483,"featured_media":215925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[415987789,682164930,682163133,274601109,682162881,415984374,213799330,682165405,415985100,682164657],"post_format":"standard","sport":[51196772],"game":[],"coauthors":[682164302,415988788],"class_list":["post-215890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-courtney-sarault","tag-danae-blais-2","tag-jordan-pierre-gilles","tag-kim-boutin","tag-maxime-laoun","tag-pascal-dion","tag-patinage-de-vitesse-sur-courte-piste","tag-renee-marie-steenge","tag-steven-dubois","tag-william-dandjinou","sport-patinage-de-vitesse-courte-piste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles samedi, l&#039;\u00e9quipe canadienne a ajout\u00e9 trois m\u00e9dailles \u00e0 sa r\u00e9colte dimanche \u00e0 la Coupe du monde de patinage de vitesse sur courte piste \u00e0 Amalty, au Kazakhstan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles samedi, l&#039;\u00e9quipe canadienne a ajout\u00e9 trois m\u00e9dailles \u00e0 sa r\u00e9colte dimanche \u00e0 la Coupe du monde de patinage de vitesse sur courte piste \u00e0 Amalty, au Kazakhstan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-17T15:05:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-19T21:15:39+00:00\" \/>\n<meta name=\"author\" content=\"Gabriel Chagnon, Oph\u00e9lie Fortin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L\u2019or pour Sarault et l\u2019argent pour Dubois au Kazakhstan\" \/>\n<meta name=\"twitter:description\" content=\"\u00c9quipe Canada a remport\u00e9 deux m\u00e9dailles lors de la premi\u00e8re journ\u00e9e de la Coupe du Monde de patinage de vitesse courte piste qui se d\u00e9roule cette fin de semaine \u00e0 Almaty, au Kazakhstan.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/patinage-de-vitesse-courte-piste.png\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Chagnon, Oph\u00e9lie Fortin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/\"},\"author\":{\"name\":\"Oph\u00e9lie Fortin\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/1236d6d549bfe8370e678fb9897f8d93\"},\"headline\":\"Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan\",\"datePublished\":\"2022-12-17T15:05:08+00:00\",\"dateModified\":\"2022-12-19T21:15:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/\"},\"wordCount\":456,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/12\\\/patinage-de-vitesse-courte-piste.png\",\"keywords\":[\"Courtney Sarault\",\"Dana\u00e9 Blais\",\"Jordan Pierre-Gilles\",\"Kim Boutin\",\"Maxime Laoun\",\"Pascal Dion\",\"patinage de vitesse sur courte piste\",\"renee marie steenge\",\"Steven Dubois\",\"william dandjinou\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/\",\"name\":\"Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/12\\\/patinage-de-vitesse-courte-piste.png\",\"datePublished\":\"2022-12-17T15:05:08+00:00\",\"dateModified\":\"2022-12-19T21:15:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/1236d6d549bfe8370e678fb9897f8d93\"},\"description\":\"Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles samedi, l'\u00e9quipe canadienne a ajout\u00e9 trois m\u00e9dailles \u00e0 sa r\u00e9colte dimanche \u00e0 la Coupe du monde de patinage de vitesse sur courte piste \u00e0 Amalty, au Kazakhstan.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2022\\\/12\\\/17\\\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/12\\\/patinage-de-vitesse-courte-piste.png\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/12\\\/patinage-de-vitesse-courte-piste.png\",\"width\":1946,\"height\":1122},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/1236d6d549bfe8370e678fb9897f8d93\",\"name\":\"Oph\u00e9lie Fortin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=ge0503e975a6e55c1c1c01f55b9c366de\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=g\",\"caption\":\"Oph\u00e9lie Fortin\"},\"sameAs\":[\"http:\\\/\\\/lecalculot.wordpress.com\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/opheliefortin23\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan - \u00c9quipe Canada","description":"Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles samedi, l'\u00e9quipe canadienne a ajout\u00e9 trois m\u00e9dailles \u00e0 sa r\u00e9colte dimanche \u00e0 la Coupe du monde de patinage de vitesse sur courte piste \u00e0 Amalty, au Kazakhstan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/","og_locale":"fr_FR","og_type":"article","og_title":"Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan","og_description":"Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles samedi, l'\u00e9quipe canadienne a ajout\u00e9 trois m\u00e9dailles \u00e0 sa r\u00e9colte dimanche \u00e0 la Coupe du monde de patinage de vitesse sur courte piste \u00e0 Amalty, au Kazakhstan.","og_url":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2022-12-17T15:05:08+00:00","article_modified_time":"2022-12-19T21:15:39+00:00","author":"Gabriel Chagnon, Oph\u00e9lie Fortin","twitter_card":"summary_large_image","twitter_title":"L\u2019or pour Sarault et l\u2019argent pour Dubois au Kazakhstan","twitter_description":"\u00c9quipe Canada a remport\u00e9 deux m\u00e9dailles lors de la premi\u00e8re journ\u00e9e de la Coupe du Monde de patinage de vitesse courte piste qui se d\u00e9roule cette fin de semaine \u00e0 Almaty, au Kazakhstan.","twitter_image":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/patinage-de-vitesse-courte-piste.png","twitter_misc":{"Written by":"Gabriel Chagnon, Oph\u00e9lie Fortin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/"},"author":{"name":"Oph\u00e9lie Fortin","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/1236d6d549bfe8370e678fb9897f8d93"},"headline":"Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan","datePublished":"2022-12-17T15:05:08+00:00","dateModified":"2022-12-19T21:15:39+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/"},"wordCount":456,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/patinage-de-vitesse-courte-piste.png","keywords":["Courtney Sarault","Dana\u00e9 Blais","Jordan Pierre-Gilles","Kim Boutin","Maxime Laoun","Pascal Dion","patinage de vitesse sur courte piste","renee marie steenge","Steven Dubois","william dandjinou"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/","url":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/","name":"Patinage de vitesse courte piste : l\u2019or pour Sarault et le relais masculin au Kazakhstan - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/patinage-de-vitesse-courte-piste.png","datePublished":"2022-12-17T15:05:08+00:00","dateModified":"2022-12-19T21:15:39+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/1236d6d549bfe8370e678fb9897f8d93"},"description":"Apr\u00e8s avoir remport\u00e9 deux m\u00e9dailles samedi, l'\u00e9quipe canadienne a ajout\u00e9 trois m\u00e9dailles \u00e0 sa r\u00e9colte dimanche \u00e0 la Coupe du monde de patinage de vitesse sur courte piste \u00e0 Amalty, au Kazakhstan.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/17\/lor-pour-sarault-et-largent-pour-dubois-au-kazakhstan\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/patinage-de-vitesse-courte-piste.png","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/patinage-de-vitesse-courte-piste.png","width":1946,"height":1122},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/1236d6d549bfe8370e678fb9897f8d93","name":"Oph\u00e9lie Fortin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=ge0503e975a6e55c1c1c01f55b9c366de","url":"https:\/\/secure.gravatar.com\/avatar\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5ac0a6c0e6384234130a5f201aea051a1e98759ec513f9d3e6ca9ff6b6f5d223?s=96&d=identicon&r=g","caption":"Oph\u00e9lie Fortin"},"sameAs":["http:\/\/lecalculot.wordpress.com"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/opheliefortin23\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/patinage-de-vitesse-courte-piste.png","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/12\/patinage-de-vitesse-courte-piste.png","author_name":["Gabriel Chagnon","Oph\u00e9lie Fortin"],"category_names":["Nouvelles"],"tag_names":["Courtney Sarault","Dana\u00e9 Blais","Jordan Pierre-Gilles","Kim Boutin","Maxime Laoun","Pascal Dion","patinage de vitesse sur courte piste","renee marie steenge","Steven Dubois","william dandjinou"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-Ua6","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/215890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/112974483"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=215890"}],"version-history":[{"count":16,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/215890\/revisions"}],"predecessor-version":[{"id":216076,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/215890\/revisions\/216076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/215925"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=215890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=215890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=215890"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=215890"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=215890"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=215890"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=215890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}