{"id":217082,"date":"2023-01-28T10:11:59","date_gmt":"2023-01-28T15:11:59","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=217082"},"modified":"2023-01-30T11:00:49","modified_gmt":"2023-01-30T16:00:49","slug":"ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/","title":{"rendered":"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l&rsquo;or et l&rsquo;argent \u00e0 Val Saint-C\u00f4me"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/mikael-kingsbury\/\">Mika\u00ebl Kingsbury<\/a> continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d&rsquo;or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d&rsquo;argent samedi soir \u00e0 l&rsquo;\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 un peu plus de 100 kilom\u00e8tres de sa ville natale, le natif de Deux-Montagnes \u00e9tait aux anges apr\u00e8s avoir d\u00e9croch\u00e9 la m\u00e9daille d&rsquo;or lors de sa derni\u00e8re descente samedi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019athl\u00e8te qu\u00e9b\u00e9cois a r\u00e9colt\u00e9 un total de 85,37 points pour se m\u00e9riter les grands honneurs devant une foule locale acquise \u00e0 sa cause. Il devance de fa\u00e7on significative le champion olympique en titre, le Su\u00e9dois Walter Wallberg, m\u00e9daill\u00e9e d&rsquo;argent avec 81,69 points. Le Japonais Ikuma Horishima gagne la m\u00e9daille de bronze (81,36).<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The crowd went wild watching their hero <a href=\"https:\/\/twitter.com\/MikaelKingsbury?ref_src=twsrc%5Etfw\">@MikaelKingsbury<\/a> storm to his career\u2019s 77th World Cup victory, and his fourth here <a href=\"https:\/\/twitter.com\/ValStCome?ref_src=twsrc%5Etfw\">@ValStCome<\/a> , with this perfectly clean big final run! \ud83d\ude80 85.37\u00a0pts and a big round of applause from the happy fans on site \ud83d\udc4f\ud83d\udc4f\ud83d\udc4f <a href=\"https:\/\/twitter.com\/hashtag\/moguls?src=hash&amp;ref_src=twsrc%5Etfw\">#moguls<\/a> <a href=\"https:\/\/t.co\/TzqtV2PhrY\">pic.twitter.com\/TzqtV2PhrY<\/a><\/p>&mdash; FISfreestyle (@FISfreestyle) <a href=\"https:\/\/twitter.com\/FISfreestyle\/status\/1619186206163746818?ref_src=twsrc%5Etfw\">January 28, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Il s&rsquo;agi d&rsquo;une 77e victoire sur le circuit de Coupe du monde pour le skieur acrobatique canadien qui domine le classement g\u00e9n\u00e9ral de la FIS cette saison. Il signe aussi sa quatri\u00e8me victoire \u00e0 Val Saint-C\u00f4me. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 LIRE : <a href=\"https:\/\/develop.olympic.ca\/olympique\/2022\/12\/16\/quatrieme-podium-consecutif-pour-mikael-kingsbury\/\">Quatri\u00e8me podium cons\u00e9cutif pour Mika\u00ebl Kingsbury<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les Canadiens Elliot Vaillancourt (76,63) et Louis-David Chalifoux (76,52) ont compl\u00e9t\u00e9 le top-10 respectivement \u00e0 la neuvi\u00e8me et \u00e0 la dixi\u00e8me position. Chez les femmes, Maia Schwinghammer a connu le meilleur r\u00e9sultat de sa carri\u00e8re avec une cinqui\u00e8me place et un pointage total de 72,92.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Deuxi\u00e8me m\u00e9daille en autant de jours<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9preuve des bosses en parall\u00e8le a cl\u00f4tur\u00e9 samedi soir un \u00e9v\u00e9nement \u00e9pique et palpitant \u00e0 Val St-C\u00f4me. Mika\u00ebl Kingsbury a termin\u00e9 la journ\u00e9e en deuxi\u00e8me position pour obtenir son 110e podium en carri\u00e8re en Coupe du monde. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette fois, c&rsquo;est le Su\u00e9dois Walter Wallberg qui est sorti vainqueur de la super finale. L\u00e9g\u00e8rement en retard apr\u00e8s le premier saut, Kingsbury a pris trop de vitesse dans la portion interm\u00e9diaire et il a pr\u00e9f\u00e9r\u00e9 ne pas prendre le deuxi\u00e8me saut en fin de parcours conf\u00e9rant ainsi la victoire \u00e0 Wallberg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Su\u00e9dois Filip Gravenfors a compl\u00e9t\u00e9 le podium apr\u00e8s avoir d\u00e9fait Matt Graham de l&rsquo;Australie dans la petite finale. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Huge congrats to <a href=\"https:\/\/twitter.com\/walterwallberg?ref_src=twsrc%5Etfw\">@walterwallberg<\/a> \ud83c\uddf8\ud83c\uddea on his first World Cup win, as he went toe-to-toe with <a href=\"https:\/\/twitter.com\/MikaelKingsbury?ref_src=twsrc%5Etfw\">@MikaelKingsbury<\/a> \ud83c\udde8\ud83c\udde6 in Val St. Come and walked away the winner &#8211; becoming just the third skier to beat Kingsbury on \ud83c\udde8\ud83c\udde6 soil in the last 22 events in CAN.<br><br>Results &#8211; <a href=\"https:\/\/t.co\/g4vivJJLY7\">https:\/\/t.co\/g4vivJJLY7<\/a> <a href=\"https:\/\/t.co\/3xdJWjMw8t\">pic.twitter.com\/3xdJWjMw8t<\/a><\/p>&mdash; FISfreestyle (@FISfreestyle) <a href=\"https:\/\/twitter.com\/FISfreestyle\/status\/1619540887251599360?ref_src=twsrc%5Etfw\">January 29, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Elliot Vaillancourt (10e), Julien Viel (11e) et Louis-David Chalifoux (14e) ont \u00e9t\u00e9 les autres finalistes canadiens. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9preuves de ski de bosses de la Coupe du monde de ski acrobatique FIS se d\u00e9placent \u00e0 Deer Valley, aux \u00c9tats-Unis, la semaine prochaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d&rsquo;or vendredi, il a&#8230;<\/p>\n","protected":false},"author":185434525,"featured_media":217219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[91766,415984420,682164680,13328337,415987930],"post_format":"standard","sport":[181823549],"game":[],"coauthors":[682164531],"class_list":["post-217082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-bosses","tag-coupe-du-monde-fis","tag-mikael-kingsbury-2","tag-ski-acrobatique","tag-ski-acrobatique-bosses","sport-ski-ski-acrobatique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l&#039;or et l&#039;argent \u00e0 Val Saint-C\u00f4me - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d&#039;or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d&#039;argent samedi soir \u00e0 l&#039;\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l&#039;or et l&#039;argent \u00e0 Val Saint C\u00f4me\" \/>\n<meta property=\"og:description\" content=\"Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d&#039;or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d&#039;argent samedi soir \u00e0 l&#039;\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-28T15:11:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-30T16:00:49+00:00\" \/>\n<meta name=\"author\" content=\"Elom Defly\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l&#039;or et l&#039;argent \u00e0 Val Saint C\u00f4me\" \/>\n<meta name=\"twitter:description\" content=\"Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d&#039;or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d&#039;argent samedi soir \u00e0 l&#039;\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/01\/CP165764839-e1675005079703.jpg?quality=100\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elom Defly\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/\"},\"author\":{\"name\":\"Elom Defly\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/5b491cdf06afbbe638941dce9982b3f7\"},\"headline\":\"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l&rsquo;or et l&rsquo;argent \u00e0 Val Saint-C\u00f4me\",\"datePublished\":\"2023-01-28T15:11:59+00:00\",\"dateModified\":\"2023-01-30T16:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/\"},\"wordCount\":454,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/CP165758989-e1674930046158.jpg?quality=100\",\"keywords\":[\"bosses\",\"Coupe du monde FIS\",\"Mikael Kingsbury\",\"Ski acrobatique\",\"ski acrobatique bosses\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/\",\"name\":\"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l'or et l'argent \u00e0 Val Saint-C\u00f4me - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/CP165758989-e1674930046158.jpg?quality=100\",\"datePublished\":\"2023-01-28T15:11:59+00:00\",\"dateModified\":\"2023-01-30T16:00:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/5b491cdf06afbbe638941dce9982b3f7\"},\"description\":\"Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d'or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d'argent samedi soir \u00e0 l'\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/01\\\/28\\\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/CP165758989-e1674930046158.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/01\\\/CP165758989-e1674930046158.jpg?quality=100\",\"width\":1080,\"height\":610,\"caption\":\"THE CANADIAN PRESS\\\/Sean Kilpatrick\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/5b491cdf06afbbe638941dce9982b3f7\",\"name\":\"Elom Defly\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3006bfc26567720f8cb6f4ae2894013a3ec3ec196e594085f51e4ebdcf56a8a?s=96&d=identicon&r=g4959d09f453ee453d33a248177fad8b3\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3006bfc26567720f8cb6f4ae2894013a3ec3ec196e594085f51e4ebdcf56a8a?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f3006bfc26567720f8cb6f4ae2894013a3ec3ec196e594085f51e4ebdcf56a8a?s=96&d=identicon&r=g\",\"caption\":\"Elom Defly\"},\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/elomdefly\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l'or et l'argent \u00e0 Val Saint-C\u00f4me - \u00c9quipe Canada","description":"Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d'or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d'argent samedi soir \u00e0 l'\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/","og_locale":"fr_FR","og_type":"article","og_title":"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l'or et l'argent \u00e0 Val Saint C\u00f4me","og_description":"Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d'or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d'argent samedi soir \u00e0 l'\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec.","og_url":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2023-01-28T15:11:59+00:00","article_modified_time":"2023-01-30T16:00:49+00:00","author":"Elom Defly","twitter_card":"summary_large_image","twitter_title":"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l'or et l'argent \u00e0 Val Saint C\u00f4me","twitter_description":"Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d'or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d'argent samedi soir \u00e0 l'\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec.","twitter_image":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/01\/CP165764839-e1675005079703.jpg?quality=100","twitter_misc":{"Written by":"Elom Defly","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/"},"author":{"name":"Elom Defly","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/5b491cdf06afbbe638941dce9982b3f7"},"headline":"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l&rsquo;or et l&rsquo;argent \u00e0 Val Saint-C\u00f4me","datePublished":"2023-01-28T15:11:59+00:00","dateModified":"2023-01-30T16:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/"},"wordCount":454,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/01\/CP165758989-e1674930046158.jpg?quality=100","keywords":["bosses","Coupe du monde FIS","Mikael Kingsbury","Ski acrobatique","ski acrobatique bosses"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/","url":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/","name":"Ski acrobatique\u00a0: Mika\u00ebl Kingsbury remporte l'or et l'argent \u00e0 Val Saint-C\u00f4me - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/01\/CP165758989-e1674930046158.jpg?quality=100","datePublished":"2023-01-28T15:11:59+00:00","dateModified":"2023-01-30T16:00:49+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/5b491cdf06afbbe638941dce9982b3f7"},"description":"Mika\u00ebl Kingsbury continue d\u2019ajouter des titres \u00e0 son palmar\u00e8s d\u00e9j\u00e0 impressionnant. Apr\u00e8s avoir remport\u00e9 la m\u00e9daille d'or vendredi, il a m\u00e9rit\u00e9 une m\u00e9daille d'argent samedi soir \u00e0 l'\u00e9preuve des bosses en parall\u00e8le de la Coupe du monde de ski acrobatique de Val St-C\u00f4me, au Qu\u00e9bec.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/28\/ski-acrobatique-mikael-kingsbury-decroche-la-medaille-dor-a-la-maison\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/01\/CP165758989-e1674930046158.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/01\/CP165758989-e1674930046158.jpg?quality=100","width":1080,"height":610,"caption":"THE CANADIAN PRESS\/Sean Kilpatrick"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/5b491cdf06afbbe638941dce9982b3f7","name":"Elom Defly","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f3006bfc26567720f8cb6f4ae2894013a3ec3ec196e594085f51e4ebdcf56a8a?s=96&d=identicon&r=g4959d09f453ee453d33a248177fad8b3","url":"https:\/\/secure.gravatar.com\/avatar\/f3006bfc26567720f8cb6f4ae2894013a3ec3ec196e594085f51e4ebdcf56a8a?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3006bfc26567720f8cb6f4ae2894013a3ec3ec196e594085f51e4ebdcf56a8a?s=96&d=identicon&r=g","caption":"Elom Defly"},"url":"https:\/\/develop.olympic.ca\/olympique\/author\/elomdefly\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/01\/CP165758989-e1674930046158.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/01\/CP165758989-e1674930046158.jpg?quality=100","author_name":["Elom Defly"],"category_names":["Nouvelles"],"tag_names":["bosses","Coupe du monde FIS","Mikael Kingsbury","Ski acrobatique","ski acrobatique bosses"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-Utk","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/217082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434525"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=217082"}],"version-history":[{"count":18,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/217082\/revisions"}],"predecessor-version":[{"id":217223,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/217082\/revisions\/217223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/217219"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=217082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=217082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=217082"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=217082"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=217082"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=217082"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=217082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}