{"id":229083,"date":"2023-09-28T14:59:30","date_gmt":"2023-09-28T18:59:30","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=229083"},"modified":"2023-09-28T14:59:32","modified_gmt":"2023-09-28T18:59:32","slug":"une-histoire-de-gentillesse-alexandria-loutitt","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/","title":{"rendered":"Une histoire de gentillesse : Alexandria Loutitt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lorsqu\u2019elle a vu des personnes sauter \u00e0 ski aux Jeux olympiques de <a href=\"https:\/\/develop.olympic.ca\/olympique\/games\/2010-vancouver\/\">Vancouver 2010<\/a>, la petite\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/alexandria-loutitt\/\">Alexandria Loutitt<\/a>, qui avait six ans, a voulu \u00eatre comme eux. \u00c0 neuf ans, elle a essay\u00e9 ce sport et l\u2019a ador\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab C\u2019\u00e9tait magique, j\u2019ai su tout de suite que je voulais faire \u00e7a. \u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"610\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-2-e1677696382222.jpg?quality=100&amp;w=1080\" alt=\"Alexandria Loutitt effectue un saut \u00e0 ski.\" class=\"wp-image-218382\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-2-e1677696382222.jpg 1080w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-2-e1677696382222.jpg?resize=280,158 280w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-2-e1677696382222.jpg?resize=657,371 657w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-2-e1677696382222.jpg?resize=768,434 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">La Canadienne Alexandria Loutitt s&rsquo;envole dans les airs lors de l&rsquo;\u00e9preuve de saut \u00e0 ski sur tremplin normal aux Championnats du monde de ski nordique \u00e0 Planica, en Slov\u00e9nie, le jeudi 23 f\u00e9vrier 2023. (Photo AP \/ Darko Bandic)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est vers cette \u00e9poque que Loutitt d\u00e9coupa les anneaux olympiques pour les accrocher sur la porte de sa chambre. C&rsquo;\u00e9tait un rappel important de ne pas oublier son r\u00eave. Elle aime l\u2019aventure et dit qu\u2019elle \u00ab cherche de sensations fortes \u00bb. Elle adore voyager, rencontrer de nouvelles personnes, essayer de nouvelles choses et faire du saut \u00e0 ski, car c\u2019est tr\u00e8s amusant!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais \u00e0 14 ans, Alex a d\u00fb prendre une d\u00e9cision difficile. Les pistes de Calgary o\u00f9 elle s\u2019entra\u00eenait au saut \u00e0 ski ont ferm\u00e9. C\u2019\u00e9taient les seules au Canada qui pouvaient l\u2019aider \u00e0 devenir assez bonne pour se rendre aux Jeux olympiques. Elle devait choisir : aller seule en Europe pour suivre son r\u00eave ou rester au Canada? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab C\u2019\u00e9tait difficile, car je n\u2019\u00e9tais pas encore assez bonne pour les Jeux olympiques ou la Coupe du monde. J\u2019\u00e9tais trop jeune pour savoir de quoi j\u2019\u00e9tais vraiment capable et c\u2019\u00e9tait un gros risque. \u00bb Elle a d\u00e9cid\u00e9 de suivre son r\u00eave malgr\u00e9 tout.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alex est all\u00e9e en Allemagne, \u00e0 environ 7 500 km de sa famille rest\u00e9e \u00e0 Calgary. L\u00e0-bas, elle a v\u00e9cu avec des familles d\u2019accueil et a beaucoup travaill\u00e9 pour s\u2019am\u00e9liorer. Apr\u00e8s deux ans, elle a rejoint l\u2019\u00e9quipe nationale de d\u00e9veloppement. C\u2019\u00e9tait un grand pas vers l\u2019\u00e9quipe nationale. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1131\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/KL_20220208_23704.jpg?quality=100&amp;w=1131\" alt=\"Les membres de l'\u00e9quipe canadienne du saut \u00e0 ski par \u00e9quipes mixtes, Alexandria Loutitt, Matthew Soukup, Abigail Strate et Mackenzie Boyd-Clowes se tiennent les mains et l\u00e8vent celles-ci dans les airs en portant leur m\u00e9daille de bronze autour du cou sur le podium de l'\u00e9preuve aux Jeux de Beijing 2022.\" class=\"wp-image-202796\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/KL_20220208_23704.jpg 1200w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/KL_20220208_23704.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/KL_20220208_23704.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/KL_20220208_23704.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2022\/02\/KL_20220208_23704.jpg?resize=1131,754 1131w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><figcaption class=\"wp-element-caption\">Les sauteurs \u00e0 ski d&rsquo;\u00c9quipe Canada Alexandria Loutitt, Matthew Soukup, Abigail Strate et Mackenzie Boyd-Clowes re\u00e7oivent leur m\u00e9daille de bronze du saut \u00e0 ski par \u00e9quipes mixtes des Jeux olympiques d&rsquo;hiver de Beijing 2022, le 8 f\u00e9vrier 2022. Photo par Kevin Light\/COC <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Alex a relev\u00e9 tous les d\u00e9fis avec courage et ses efforts ont \u00e9t\u00e9 r\u00e9compens\u00e9s lorsqu&rsquo;elle a gagn\u00e9 <a href=\"https:\/\/develop.olympic.ca\/olympique\/2022\/02\/07\/equipe-canada-gagne-le-bronze-a-la-premiere-epreuve-mixte-par-equipes-de-saut-a-ski\/\">une m\u00e9daille de bronze pour le Canada<\/a> aux Jeux olympiques d\u2019hiver de\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/games\/beijing-2022\/\">Beijing 2022<\/a>. C\u2019\u00e9tait un \u00e9v\u00e9nement tr\u00e8s sp\u00e9cial, car c\u2019\u00e9tait la premi\u00e8re fois que le Canada avait une \u00e9preuves par \u00e9quipes mixtes en <a href=\"http:\/\/develop.olympic.ca\/olympique\/sports\/ski-saut-a-ski\/\">saut \u00e0 ski<\/a> aux Jeux olympiques. Avec son \u00e9quipe, Alex a aussi remport\u00e9 la toute premi\u00e8re m\u00e9daille olympique du Canada dans cette discipline. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alex continue de faire des choses incroyables et de battre des records. En plus d\u2019\u00eatre la <a href=\"https:\/\/develop.olympic.ca\/olympique\/2023\/03\/01\/alexandria-loutitt-championne-du-monde-de-grand-tremplin-en-saut-a-ski\/\">premi\u00e8re Canadienne \u00e0 \u00eatre championne du monde de saut \u00e0 ski<\/a>, elle est aussi la premi\u00e8re Canadienne \u00e0 gagner un titre mondial junior et <a href=\"https:\/\/develop.olympic.ca\/olympique\/2023\/01\/13\/loutitt-remporte-la-toute-premiere-victoire-du-canada-en-coupe-du-monde-en-saut-a-ski-feminin\/\">un titre de la Coupe du monde<\/a> de saut \u00e0 ski.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maintenant, Alex veut aider les autres et soutenir la prochaine g\u00e9n\u00e9ration d\u2019athl\u00e8tes. Elle fait partie de la Premi\u00e8re Nation Gwich\u2019in. Elle vient d&rsquo;une lign\u00e9e d&rsquo;athl\u00e8tes olympiques autochtones; les athl\u00e8tes de ski de fond\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/sharon-firth\/\">Sharon Firth<\/a>\u00a0and\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/shirley-firth-larsson\/\">Shirley Firth-Larsson<\/a>\u00a0sont ses cousines \u00e9loign\u00e9es. Apr\u00e8s les Jeux olympiques,\u00a0Sharon\u00a0est m\u00eame devenue sa mentore.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"923\" height=\"753\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/Alex-Loutitt-e1684180532896.jpg?quality=100&amp;w=923\" alt=\"Alexandria Loutitt avec le drapeau autochtone canadien.\" class=\"wp-image-221978\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/Alex-Loutitt-e1684180532896.jpg 923w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/Alex-Loutitt-e1684180532896.jpg?resize=194,158 194w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/Alex-Loutitt-e1684180532896.jpg?resize=455,371 455w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2019\/06\/Alex-Loutitt-e1684180532896.jpg?resize=768,627 768w\" sizes=\"(max-width: 923px) 100vw, 923px\" \/><figcaption class=\"wp-element-caption\">Alexandria Loutitt pose avec le drapeau autochtone canadien lors d&rsquo;une comp\u00e9tition de la Coupe du monde FIS de saut \u00e0 ski en Autriche en f\u00e9vrier 2023. (@alex_loutitt\/Instagram)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Alex pense que sa culture l\u2019aide \u00e0 rester forte et concentr\u00e9e sur ses objectifs. Les efforts et\u00a0les valeurs de sa famille, qui a surmont\u00e9 la discrimination, la motivent encore plus \u00e0 travailler fort. Alex est un bel exemple \u00e0 suivre. Elle pense que sa famille a beaucoup contribu\u00e9 \u00e0 son succ\u00e8s. Son grand-p\u00e8re, qui a surv\u00e9cu aux pensionnats autochtones, a r\u00e9ussi dans la vie. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Je pense que si on tire des le\u00e7ons des moments difficiles, on peut devenir plus fort et mieux surmonter les d\u00e9fis. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019elle monte sur le podium, Alex porte toujours ses mocassins porte-bonheur pr\u00e9f\u00e9r\u00e9s en fourrure de lapin. Elle est tr\u00e8s fi\u00e8re de partager sa culture autochtone avec le monde entier et de pouvoir informer les autres \u00e0 ce sujet. Parfois, des gens disent des choses blessantes sans faire expr\u00e8s, par ignorance. Au lieu de s\u2019\u00e9nerver, elle essaie de leur expliquer leur erreur. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Ils ne peuvent pas tout savoir, alors j\u2019essaie de leur parler de ma culture et de mon histoire, de celle de ma famille et du Canada. \u00bb <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CuKDX2po4MU\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CuKDX2po4MU\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CuKDX2po4MU\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Alexandria (Alex) Loutitt | OLY (@alex_loutitt)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est important pour Alex d\u2019expliquer ses origines Gwich\u2019in avec douceur et patience. Elle pense que se f\u00e2cher ne fait pas avancer les choses et pr\u00e9f\u00e8re \u00eatre gentille et patiente. Bien s\u00fbr, c\u2019est parfois difficile, mais elle sait que ses efforts en valent la peine.Alex a un conseil important \u00e0 donner \u00e0 ceux qui ont des r\u00eaves ou des objectifs. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Si les gens te disent que tu ne peux pas faire quelque chose, c\u2019est parce qu\u2019ils pensent qu\u2019ils n\u2019y arriveraient pas \u00e0 ta place. Si tu \u00e9coutes toujours ceux qui te d\u00e9couragent, tu finiras par les croire, m\u00eame s\u2019ils ont tort. \u00bb <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quand elle \u00e9tait petite, certains pensaient qu\u2019elle ne pourrait jamais aller aux Jeux olympiques, et pourtant, elle a r\u00e9alis\u00e9 ses r\u00eaves les plus fous. Elle dit que c\u2019est important d\u2019avoir des amis et une famille qui croient en nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 LIRE \u00c9GALEMENT : <a href=\"https:\/\/develop.olympic.ca\/olympique\/2023\/06\/20\/le-planchiste-autochtone-liam-gill-a-une-influence-determinante-sur-les-jeunes-du-nord-et-sur-sa-propre-vie-grace-a-un-projet-inspirant\/\">Le planchiste autochtone Liam Gill a une influence d\u00e9terminante sur les jeunes du Nord et sur sa propre vie gr\u00e2ce \u00e0 un projet inspirant<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>L&rsquo;histoire d&rsquo;Alexandria Loutitt a \u00e9t\u00e9 initialement pr\u00e9sent\u00e9e dans le cadre de la <a href=\"https:\/\/develop.olympic.ca\/olympique\/education\/resources\/heritageautochtone\/\"><strong>s\u00e9rie H\u00e9ritages autochtones dans le sport <\/strong><\/a>du Programme scolaire olympique canadien, aux c\u00f4t\u00e9s de l&rsquo;histoire du planchiste <em><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/liam-gill\/\">Liam Gill<\/a><\/em>. Les ressources disponibles au lien ci-dessus sont propos\u00e9es \u00e0 deux niveaux de lecture diff\u00e9rents et sont accompagn\u00e9es de questions de discussion et d&rsquo;activit\u00e9s d&rsquo;apprentissage.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu\u2019elle a vu des personnes sauter \u00e0 ski aux Jeux olympiques de Vancouver 2010, la petite\u00a0Alexandria Loutitt, qui avait six&#8230;<\/p>\n","protected":false},"author":185434513,"featured_media":218693,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[682162742,1],"tags":[682166226,682162790,415984757,415986612,682166227,415988876,12670004,415987879],"post_format":"standard","sport":[181823548],"game":[],"coauthors":[682165373],"class_list":["post-229083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evergreen","category-uncategorized","tag-alex-loutitt","tag-alexandria-loutitt","tag-autochtone","tag-beijing-2022","tag-histoire-autochtone","tag-premieres-nations","tag-saut-a-ski","tag-saut-a-ski-canada","sport-ski-saut-a-ski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une histoire de gentillesse : Alexandria Loutitt - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"description\" content=\"L&#039;histoire d&#039;Alexandria Loutitt a \u00e9t\u00e9 initialement pr\u00e9sent\u00e9e dans le cadre de la s\u00e9rie H\u00e9ritages autochtones dans le sport du Programme scolaire olympique canadien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une histoire de gentillesse : Alexandria Loutitt\" \/>\n<meta property=\"og:description\" content=\"L&#039;histoire d&#039;Alexandria Loutitt a \u00e9t\u00e9 initialement pr\u00e9sent\u00e9e dans le cadre de la s\u00e9rie H\u00e9ritages autochtones dans le sport du Programme scolaire olympique canadien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-28T18:59:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-28T18:59:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sian O\u2019Hara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@alacroix\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sian O\u2019Hara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/\"},\"author\":{\"name\":\"alacroix\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\"},\"headline\":\"Une histoire de gentillesse : Alexandria Loutitt\",\"datePublished\":\"2023-09-28T18:59:30+00:00\",\"dateModified\":\"2023-09-28T18:59:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/\"},\"wordCount\":1053,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100\",\"keywords\":[\"Alex Loutitt\",\"Alexandria Loutitt\",\"autochtone\",\"Beijing 2022\",\"histoire autochtone\",\"Premi\u00e8res nations\",\"saut \u00e0 ski\",\"Saut \u00e0 ski Canada\"],\"articleSection\":[\"Evergreen\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/\",\"name\":\"Une histoire de gentillesse : Alexandria Loutitt - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100\",\"datePublished\":\"2023-09-28T18:59:30+00:00\",\"dateModified\":\"2023-09-28T18:59:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\"},\"description\":\"L'histoire d'Alexandria Loutitt a \u00e9t\u00e9 initialement pr\u00e9sent\u00e9e dans le cadre de la s\u00e9rie H\u00e9ritages autochtones dans le sport du Programme scolaire olympique canadien.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2023\\\/09\\\/28\\\/une-histoire-de-gentillesse-alexandria-loutitt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100\",\"width\":1080,\"height\":609,\"caption\":\"Alexandria Loutitt, du Canada, est photographi\u00e9e avec sa m\u00e9daille apr\u00e8s avoir gagn\u00e9 l'\u00e9preuve f\u00e9minine de grand tremplin de saut \u00e0 ski aux Championnats du monde de ski nordique \u00e0 Planica, en Slov\u00e9nie, le mercredi 1er mars 2023. (AP Photo\\\/Darko Bandic)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\",\"name\":\"alacroix\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g800804460851aa471230f61e1a6a77dc\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g\",\"caption\":\"alacroix\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/alacroix\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/alacroix\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une histoire de gentillesse : Alexandria Loutitt - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"L'histoire d'Alexandria Loutitt a \u00e9t\u00e9 initialement pr\u00e9sent\u00e9e dans le cadre de la s\u00e9rie H\u00e9ritages autochtones dans le sport du Programme scolaire olympique canadien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/","og_locale":"fr_FR","og_type":"article","og_title":"Une histoire de gentillesse : Alexandria Loutitt","og_description":"L'histoire d'Alexandria Loutitt a \u00e9t\u00e9 initialement pr\u00e9sent\u00e9e dans le cadre de la s\u00e9rie H\u00e9ritages autochtones dans le sport du Programme scolaire olympique canadien.","og_url":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_published_time":"2023-09-28T18:59:30+00:00","article_modified_time":"2023-09-28T18:59:32+00:00","og_image":[{"width":1080,"height":609,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100","type":"image\/jpeg"}],"author":"Sian O\u2019Hara","twitter_card":"summary_large_image","twitter_creator":"@alacroix","twitter_misc":{"Written by":"Sian O\u2019Hara","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/"},"author":{"name":"alacroix","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7"},"headline":"Une histoire de gentillesse : Alexandria Loutitt","datePublished":"2023-09-28T18:59:30+00:00","dateModified":"2023-09-28T18:59:32+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/"},"wordCount":1053,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100","keywords":["Alex Loutitt","Alexandria Loutitt","autochtone","Beijing 2022","histoire autochtone","Premi\u00e8res nations","saut \u00e0 ski","Saut \u00e0 ski Canada"],"articleSection":["Evergreen","Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/","url":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/","name":"Une histoire de gentillesse : Alexandria Loutitt - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100","datePublished":"2023-09-28T18:59:30+00:00","dateModified":"2023-09-28T18:59:32+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7"},"description":"L'histoire d'Alexandria Loutitt a \u00e9t\u00e9 initialement pr\u00e9sent\u00e9e dans le cadre de la s\u00e9rie H\u00e9ritages autochtones dans le sport du Programme scolaire olympique canadien.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2023\/09\/28\/une-histoire-de-gentillesse-alexandria-loutitt\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100","width":1080,"height":609,"caption":"Alexandria Loutitt, du Canada, est photographi\u00e9e avec sa m\u00e9daille apr\u00e8s avoir gagn\u00e9 l'\u00e9preuve f\u00e9minine de grand tremplin de saut \u00e0 ski aux Championnats du monde de ski nordique \u00e0 Planica, en Slov\u00e9nie, le mercredi 1er mars 2023. (AP Photo\/Darko Bandic)"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7","name":"alacroix","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g800804460851aa471230f61e1a6a77dc","url":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g","caption":"alacroix"},"sameAs":["https:\/\/x.com\/alacroix"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/alacroix\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2023\/03\/Alexandria-Loutitt-4-e1677856043985.jpg?quality=100","author_name":["Sian O\u2019Hara"],"category_names":["Evergreen","Uncategorized"],"tag_names":["Alex Loutitt","Alexandria Loutitt","autochtone","Beijing 2022","histoire autochtone","Premi\u00e8res nations","saut \u00e0 ski","Saut \u00e0 ski Canada"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-XAT","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/229083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434513"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=229083"}],"version-history":[{"count":4,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/229083\/revisions"}],"predecessor-version":[{"id":229098,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/229083\/revisions\/229098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/218693"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=229083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=229083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=229083"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=229083"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=229083"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=229083"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=229083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}