{"id":246936,"date":"2024-06-20T14:29:19","date_gmt":"2024-06-20T18:29:19","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=246936"},"modified":"2024-11-21T20:39:08","modified_gmt":"2024-11-22T01:39:08","slug":"lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/","title":{"rendered":"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c9quipe&nbsp;Canada&nbsp;amorcera les Jeux de <a href=\"https:\/\/develop.olympic.ca\/olympique\/games\/paris-2024\/\">Paris 2024<\/a> en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/games\/2020-tokyo\/\">Tokyo 2020<\/a>&nbsp;qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019entra\u00eeneure-chef Bev Priestman dit qu\u2019elle pr\u00e9f\u00e8re qu\u2019il en soit ainsi. En s\u2019adressant aux m\u00e9dias \u00e0 la suite d\u2019une s\u00e9rie de matchs amicaux contre l\u2019\u00e9quipe nationale mexicaine au d\u00e9but du mois de juin, Priestman a ouvertement parl\u00e9 des hauts et des bas de l\u2019\u00e9quipe dans les ann\u00e9es qui ont suivi son triomphe des derniers Jeux olympiques, ce qui l\u2019a amen\u00e9e \u00e0 faire un s\u00e9rieux examen de conscience sur son approche et celle de l\u2019\u00e9quipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Je pense que nous avons perdu notre chemin, n\u2019est-ce pas? Nous avons eu des ann\u00e9es remarquables en 2021 et 2022, nous avons alors connu de tr\u00e8s bonnes s\u00e9quences et ensuite, pour une raison ou une autre, nous avons perdu notre chemin. Personnellement, j\u2019ai perdu mon chemin au chapitre de mes valeurs et de mes principes, ainsi que de ma capacit\u00e9 \u00e0 voir la for\u00eat qui se cachait derri\u00e8re les arbres \u00bb, a d\u00e9clar\u00e9 Priestman avec franchise.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Ce qui me rend fi\u00e8re quand je suis en bordure du terrain, c\u2019est quand je vois sur le terrain des valeurs comme ne jamais abandonner. \u00catre une bonne co\u00e9quipi\u00e8re. Le respect. L\u2019humilit\u00e9. Travailler plus fort que toutes les autres \u00e9quipes. Ce sont toutes l\u00e0 des choses qui sont dans l\u2019ADN de cette formation. Ces valeurs-l\u00e0 ne proviennent pas seulement de&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/christine-sinclair\/\">Christine Sinclair<\/a>&nbsp;ou&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/sophie-schmidt\/\">Sophie Schmidt<\/a>.&nbsp;Il y a toute une g\u00e9n\u00e9ration qui a \u00e9t\u00e9 l\u00e0 avant, comme&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/diana-matheson\/\">Diana Matheson<\/a>,&nbsp;qui a instaur\u00e9&nbsp;[ces valeurs]&nbsp;dans cette \u00e9quipe et nous ne pouvons absolument pas nous permettre de les perdre. \u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-adriana.jpg?quality=100\" alt=\"Adriana Leon fait un geste \u00e0 une co\u00e9quipi\u00e8re .\" class=\"wp-image-246943\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-adriana.jpg 1024w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-adriana.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-adriana.jpg?resize=556,371 556w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-adriana.jpg?resize=768,512 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Adriana Leon fait un geste \u00e0 une co\u00e9quipi\u00e8re lors du match contre le Mexique \u00e0 Toronto, le 4 juin 2024. Photo de Simran Sandhra.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Alors qu\u2019est-il arriv\u00e9 \u00e0 la Coupe du Monde?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous avons eu trop peur de prendre des risques. J\u2019ai eu trop peur de prendre des risques, a affirm\u00e9 Priestman. Maintenant, nous avons corrig\u00e9 tout \u00e7a et \u00e7a nous permet d\u2019avancer. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce qui est non n\u00e9gociable aux yeux de Priestman \u00e0 l\u2019approche de&nbsp;Paris 2024, c\u2019est ce retour aux valeurs et \u00e0 l\u2019identit\u00e9 de base de l\u2019\u00e9quipe. Mettre de l\u2019avant ces valeurs a \u00e9t\u00e9 au coeur du message qu\u2019elle a livr\u00e9 aux joueuses \u00e0 l\u2019occasion du match du 4 juin \u00e0&nbsp;Toronto,&nbsp;qui \u00e9tait non seulement le deuxi\u00e8me affrontement de l\u2019\u00e9quipe dans le cadre de sa derni\u00e8re s\u00e9rie de matchs au pays avant son d\u00e9part, mais a aussi servi de journ\u00e9e de c\u00e9l\u00e9bration de la Fiert\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9quipe&nbsp;Canada&nbsp;s\u2019est pr\u00e9sent\u00e9e sur le terrain avec des maillots de la Fiert\u00e9 et on avait d\u00e9cor\u00e9 les abords de la surface de jeu avec les couleurs du drapeau de la Fiert\u00e9. Pour les joueuses, c\u00e9l\u00e9brer la Fiert\u00e9 repr\u00e9sente une extension tr\u00e8s naturelle de la plus importante des valeurs fondamentales de l\u2019\u00e9quipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab L\u2019unit\u00e9 est quelque chose dont nous parlons constamment, a d\u00e9clar\u00e9 l\u2019\u00e9toile montante Simi Awujo apr\u00e8s le&nbsp;match.Pour \u00c9quipe Canada, l\u2019unit\u00e9 veut dire non seulement les joueuses sur le terrain, mais les membres de l\u2019organisation au grand complet, et les partisans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab C\u2019est tellement une belle c\u00e9l\u00e9bration, et c\u2019en est une qui est importante, a d\u00e9clar\u00e9 <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/shelina-zadorsky\/\">Shelina Zadorsky<\/a>, qui a particip\u00e9 \u00e0 son 100e match avec \u00c9quipe Canada le 4 juin. Notre \u00e9quipe, en l\u2019absence d\u2019un meilleur terme, se fait une fiert\u00e9 d\u2019offrir un milieu vraiment ouvert et inclusif, o\u00f9 nous voulons que tout le monde soit soi-m\u00eame et s\u2019exprime avec confiance. Nous sommes chacune aim\u00e9es et accept\u00e9es dans ce milieu \u2014 et nous voulons que \u00e7a s\u2019\u00e9tende \u00e0 nos partisans aussi. \u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1131\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/Simran-Shelina-Z.jpg?quality=100&amp;w=1131\" alt=\"Shelina Zadorsky debout sur le terrain. \" class=\"wp-image-246944\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/Simran-Shelina-Z.jpg 4500w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/Simran-Shelina-Z.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/Simran-Shelina-Z.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/Simran-Shelina-Z.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/Simran-Shelina-Z.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/Simran-Shelina-Z.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/Simran-Shelina-Z.jpg?resize=2048,1365 2048w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><figcaption class=\"wp-element-caption\">Shelina Zadorsky fait sa 100e apparition pour \u00c9quipe Canada le 4 juin 2024 \u00e0 Toronto. Photo de Simran Sandhra.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Toutes les personnes, autant au sein du personnel que chez les joueuses, qui s\u2019am\u00e8nent dans notre milieu sont libres d\u2019\u00eatre qui elles sont, a indiqu\u00e9 Priestman. Je crois que c\u2019est vraiment important que les jeunes, nos partisans et notre pays puissent le voir et le ressentir. Parce que je crois que nous sommes des mod\u00e8les \u00e0 suivre, nous sommes une source d\u2019inspiration pour les jeunes. [C\u00e9l\u00e9brer la Fiert\u00e9]&nbsp;est quelque chose qui nous tient \u00e0 coeur. \u00bb&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019accent que met&nbsp;Priestman sur les valeurs fait aussi en sorte qu\u2019il lui incombe de g\u00e9rer le d\u00e9licat processus de s\u00e9lection de l\u2019\u00e9quipe olympique de la fa\u00e7on la plus transparente possible.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autant au cours de la victoire de 2-0 contre le Mexique \u00e0 Montr\u00e9al qu\u2019\u00e0 l\u2019occasion de la nulle de 1-1 \u00e0&nbsp;Toronto, Priestman a fait l\u2019essai de diff\u00e9rentes formations et diff\u00e9rentes combinaisons. La profondeur qu\u2019on retrouve au sein d\u2019\u00c9quipe Canada et l\u2019effort suppl\u00e9mentaire que les joueuses ont donn\u00e9 dans le but d\u2019\u00eatre retenues dans l\u2019\u00e9quipe ont compliqu\u00e9 la t\u00e2che de Priestman. Ici aussi, elle pr\u00e9f\u00e8re qu\u2019il en soit ainsi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Ma philosophie, \u00e7\u2019a toujours \u00e9t\u00e9 d&rsquo;\u00eatre honn\u00eate, a-t-elle soulign\u00e9.&nbsp;[Les joueuses]&nbsp;savent que je me soucie d\u2019elles en tant que personnes. Elles savent que leurs co\u00e9quipi\u00e8res se soucient d\u2019elles en tant que personnes. En fin de compte, il y a un groupe de joueuses qui sont de classe mondiale et qui ne pourront pas aller&nbsp;[\u00e0&nbsp;Paris 2024].&nbsp;Malheureusement, parfois \u2014 je l\u2019ai souvent d\u00e9j\u00e0 dit \u2014 ce ne seront pas n\u00e9cessairement les 18 meilleures joueuses, mais ce sera peut-\u00eatre la meilleure formation possible. \u00c0 la fin, c\u2019est \u00e7a le d\u00e9fi et nous allons devoir regarder des gens dans les yeux et avoir ce genre de discussion. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u2019il n\u2019en tenait qu\u2019\u00e0 Priestman, sa formation s\u2019\u00e9tendrait au-del\u00e0 de la limite de 18 joueuses en vue des Jeux, notamment en raison des risques de blessures, mais aussi parce que \u00e7a donnerait \u00e0 des joueuses plus jeunes l\u2019occasion de gagner de l\u2019exp\u00e9rience \u00e0 l\u2019\u00e9chelle internationale en pr\u00e9vision des prochaines Coupes du Monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le match du 4 juin \u00e0 Toronto a \u00e9t\u00e9 une belle illustration du risque de blessures qui est toujours pr\u00e9sent dans un match de soccer. Un contact physique particuli\u00e8rement agressif aux d\u00e9pens de&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jordyn-huitema\/\">Jordyn Huitema<\/a>&nbsp;l\u2019a projet\u00e9e en touche, o\u00f9 elle est rest\u00e9e durant de longues minutes. L\u2019entra\u00eeneur-chef mexicain&nbsp;Pedro L\u00f3pez&nbsp;a pr\u00e9sent\u00e9 des excuses au nom de son \u00e9quipe pendant la conf\u00e9rence de presse d\u2019apr\u00e8s-match.&nbsp;Karen Luna,&nbsp;la d\u00e9fenseure mexicaine qui a initi\u00e9 le contact, a seulement re\u00e7u un carton jaune.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Priestman rappelle cependant qu\u2019il ne faut pas trop s\u2019attarder aux aspects du jeu qui sont hors de son contr\u00f4le, comme les d\u00e9cisions d\u2019arbitre, et il s\u2019agit plut\u00f4t de se concentrer sur ce qu\u2019on peut contr\u00f4ler.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1132\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-celebration-soccer.jpg?quality=100&amp;w=1132\" alt=\"Des joueuses d'\u00c9quipe Canada c\u00e9l\u00e8brent ensemble sur le terrain.\" class=\"wp-image-246945\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-celebration-soccer.jpg 5000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-celebration-soccer.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-celebration-soccer.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-celebration-soccer.jpg?resize=768,511 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-celebration-soccer.jpg?resize=1132,754 1132w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-celebration-soccer.jpg?resize=1536,1023 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-celebration-soccer.jpg?resize=2048,1364 2048w\" sizes=\"(max-width: 1132px) 100vw, 1132px\" \/><figcaption class=\"wp-element-caption\">Des joueuses d&rsquo;\u00c9quipe Canada c\u00e9l\u00e8brent ensemble, le 4 juin 2024. Photo  Simran Sandhra.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Il y a des apprentissages \u00e0 faire apr\u00e8s chaque match. Je me concentre exclusivement sur le processus. Je dois continuer \u00e0 mettre ces apprentissages en pratique et quand il y a des d\u00e9cisions difficiles \u00e0 prendre, il faut y aller avec ses convictions et avoir le courage de le faire. Je l\u2019ai appris \u00e0 la dure ces 12 derniers mois et c\u2019est ce qui a fait partie des impond\u00e9rables qui nous ont aid\u00e9es \u00e0 Tokyo. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9quipe&nbsp;Canada&nbsp;pourrait aussi \u00eatre port\u00e9e \u00e0 Paris 2024 par l\u2019effervescence sans pr\u00e9c\u00e9dent que conna\u00eet actuellement le sport f\u00e9minin au Canada. Dans la derni\u00e8re ann\u00e9e, il y a non seulement eu la premi\u00e8re saison compl\u00e8te de la Ligue professionnelle de hockey f\u00e9minin et l\u2019annonce de l\u2019arriv\u00e9e d\u2019une \u00e9quipe de la&nbsp;WNBA&nbsp;\u00e0 Toronto, mais aussi l\u2019annonce que la Super Ligue du Nord (SLN), la premi\u00e8re ligue professionnelle de soccer f\u00e9minin au Canada, disputera sa premi\u00e8re saison en 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Je pense que l\u2019animation qu\u2019il y a dans le monde du sport f\u00e9minin dans son ensemble au Canada est vraiment formidable et d\u2019\u00eatre impliqu\u00e9e dans tout \u00e7a en ce moment repr\u00e9sente quelque chose de vraiment sp\u00e9cial. Aussi, le fait de savoir que pour les g\u00e9n\u00e9rations futures, \u00e7a ne pourra qu\u2019aller de mieux en mieux. Les Canadiens adorent les sports f\u00e9minins, alors je trouve que le fait d\u2019\u00eatre une ambassadrice pour tout \u00e7a et d\u2019en faire partie, c\u2019est tout un&nbsp;honneur \u00bb, a d\u00e9clar\u00e9 Zadorsky.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour sa part, l\u2019entra\u00eeneur-chef mexicain a souhait\u00e9 la meilleure des chances \u00e0 la nouvelle ligue canadienne, affirmant qu\u2019environ 85 % des joueuses faisant partie de l\u2019\u00e9quipe nationale \u00e9voluent dans la ligue professionnelle f\u00e9minine du Mexique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Priestman affirme que la SLN aura d\u2019\u00e9normes retomb\u00e9es positives pour le d\u00e9veloppement du soccer f\u00e9minin au&nbsp;Canada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab J\u2019ai tellement h\u00e2te. Je suis&nbsp;super, super emball\u00e9e, a dit Priestman. Quand vous revenez au pays avec votre m\u00e9daille d\u2019or comme \u00e7\u2019a \u00e9t\u00e9 le cas en 2021, s\u2019il y a une chose que vous aimeriez voir se mat\u00e9rialiser, c\u2019est bien une ligue comme celle-l\u00e0. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ligue ne se mettra en branle qu\u2019apr\u00e8s&nbsp;Paris 2024,&nbsp;mais elle risque s\u00fbrement d\u2019avoir des r\u00e9percussions en vue de&nbsp;<a href=\"https:\/\/develop.olympic.ca\/olympique\/games\/los-angeles-2028\/\">LA 2028<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9quipe&nbsp;Canada&nbsp;fera partie du groupe A \u00e0 l\u2019occasion du prochain tournoi olympique, avec la France, la Colombie et la Nouvelle-Z\u00e9lande. Le premier match de la phase de groupes aura lieu le jeudi 25 juillet contre la Nouvelle-Z\u00e9lande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9quipe&nbsp;Canada&nbsp;fait actuellement partie d\u2019un groupe de seulement trois pays au monde \u00e0 avoir remport\u00e9 trois m\u00e9dailles au soccer f\u00e9minin, ayant rafl\u00e9 le bronze \u00e0 <a href=\"https:\/\/develop.olympic.ca\/olympique\/jeux\/2012-londres\/\">Londres 2012<\/a> et&nbsp;<a href=\"https:\/\/develop.olympic.ca\/games\/2016-rio\/\">Rio 2016<\/a>&nbsp;avant de remporter la m\u00e9daille d\u2019or \u00e0 Tokyo 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9quipe&nbsp;Canada&nbsp;amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la&#8230;<\/p>\n","protected":false},"author":185434513,"featured_media":246942,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085,1],"tags":[682166197,891098,9815342,1104411,415985124,682165233,415983997,682166814,1693,59666586,682167029,682167027],"post_format":"standard","sport":[8591],"game":[415985140],"coauthors":[682165743],"class_list":["post-246936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-uncategorized","tag-bev-priestman","tag-christine-sinclair","tag-diana-matheson","tag-equipe-canada","tag-paris-2024","tag-pride","tag-shelina-zadorsky","tag-simi-awujo","tag-soccer","tag-sophie-schmidt","tag-tcia-play-pillar","tag-team-canada-impact-agenda","sport-football","game-paris-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024 - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"\u00c9quipe\u00a0Canada\u00a0amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de\u00a0Tokyo 2020\u00a0qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024\" \/>\n<meta property=\"og:description\" content=\"\u00c9quipe\u00a0Canada\u00a0amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de\u00a0Tokyo 2020\u00a0qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T18:29:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-22T01:39:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caela Fenton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024\" \/>\n<meta name=\"twitter:description\" content=\"\u00c9quipe\u00a0Canada\u00a0amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de\u00a0Tokyo 2020\u00a0qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100\" \/>\n<meta name=\"twitter:creator\" content=\"@alacroix\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Caela Fenton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/\"},\"author\":{\"name\":\"alacroix\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\"},\"headline\":\"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024\",\"datePublished\":\"2024-06-20T18:29:19+00:00\",\"dateModified\":\"2024-11-22T01:39:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/\"},\"wordCount\":1795,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/06\\\/simran-team-shot-e1718721853538.jpg?quality=100\",\"keywords\":[\"Bev Priestman\",\"Christine Sinclair\",\"Diana Matheson\",\"\u00c9quipe canada\",\"Paris 2024\",\"pride\",\"Shelina Zadorsky\",\"simi awujo\",\"Soccer\",\"Sophie Schmidt\",\"TCIA - Play Pillar\",\"Team Canada Impact Agenda\"],\"articleSection\":[\"Nouvelles\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/\",\"name\":\"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024 - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/06\\\/simran-team-shot-e1718721853538.jpg?quality=100\",\"datePublished\":\"2024-06-20T18:29:19+00:00\",\"dateModified\":\"2024-11-22T01:39:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\"},\"description\":\"\u00c9quipe\u00a0Canada\u00a0amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de\u00a0Tokyo 2020\u00a0qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/06\\\/20\\\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/06\\\/simran-team-shot-e1718721853538.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/06\\\/simran-team-shot-e1718721853538.jpg?quality=100\",\"width\":1080,\"height\":608,\"caption\":\"Photo : Simran Sandhra\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\",\"name\":\"alacroix\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g800804460851aa471230f61e1a6a77dc\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g\",\"caption\":\"alacroix\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/alacroix\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/alacroix\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024 - \u00c9quipe Canada","description":"\u00c9quipe\u00a0Canada\u00a0amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de\u00a0Tokyo 2020\u00a0qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024","og_description":"\u00c9quipe\u00a0Canada\u00a0amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de\u00a0Tokyo 2020\u00a0qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.","og_url":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2024-06-20T18:29:19+00:00","article_modified_time":"2024-11-22T01:39:08+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100","type":"image\/jpeg"}],"author":"Caela Fenton","twitter_card":"summary_large_image","twitter_title":"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024","twitter_description":"\u00c9quipe\u00a0Canada\u00a0amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de\u00a0Tokyo 2020\u00a0qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.","twitter_image":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100","twitter_creator":"@alacroix","twitter_misc":{"Written by":"Caela Fenton","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/"},"author":{"name":"alacroix","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7"},"headline":"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024","datePublished":"2024-06-20T18:29:19+00:00","dateModified":"2024-11-22T01:39:08+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/"},"wordCount":1795,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100","keywords":["Bev Priestman","Christine Sinclair","Diana Matheson","\u00c9quipe canada","Paris 2024","pride","Shelina Zadorsky","simi awujo","Soccer","Sophie Schmidt","TCIA - Play Pillar","Team Canada Impact Agenda"],"articleSection":["Nouvelles","Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/","url":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/","name":"L\u2019\u00e9quipe de soccer f\u00e9minin d\u2019\u00c9quipe\u00a0Canada\u00a0mettra ses valeurs de l\u2019avant \u00e0\u00a0Paris 2024 - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100","datePublished":"2024-06-20T18:29:19+00:00","dateModified":"2024-11-22T01:39:08+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7"},"description":"\u00c9quipe\u00a0Canada\u00a0amorcera les Jeux de Paris 2024 en tant que m\u00e9daill\u00e9e d\u2019or olympique en titre au soccer f\u00e9minin. Toutefois, \u00e0 la suite d\u2019une s\u00e9quence difficile apr\u00e8s les Jeux de\u00a0Tokyo 2020\u00a0qui a vu l\u2019\u00e9quipe \u00eatre \u00e9limin\u00e9e pr\u00e9matur\u00e9ment de la Coupe du Monde F\u00e9minine de la FIFA, les Canadiennes seront quelque peu consid\u00e9r\u00e9es comme des n\u00e9glig\u00e9es au moment d\u2019entreprendre le tournoi olympique cet \u00e9t\u00e9.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/06\/20\/lequipe-de-soccer-feminin-dequipe-canada-mettra-ses-valeurs-de-lavant-a-paris-2024\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100","width":1080,"height":608,"caption":"Photo : Simran Sandhra"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7","name":"alacroix","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g800804460851aa471230f61e1a6a77dc","url":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g","caption":"alacroix"},"sameAs":["https:\/\/x.com\/alacroix"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/alacroix\/"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100","author_name":["Caela Fenton"],"category_names":["Nouvelles","Uncategorized"],"tag_names":["Bev Priestman","Christine Sinclair","Diana Matheson","\u00c9quipe canada","Paris 2024","pride","Shelina Zadorsky","simi awujo","Soccer","Sophie Schmidt","TCIA - Play Pillar","Team Canada Impact Agenda"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-12eQ","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/06\/simran-team-shot-e1718721853538.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/246936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434513"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=246936"}],"version-history":[{"count":9,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/246936\/revisions"}],"predecessor-version":[{"id":256333,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/246936\/revisions\/256333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/246942"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=246936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=246936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=246936"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=246936"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=246936"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=246936"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=246936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}