{"id":253036,"date":"2024-08-03T19:46:56","date_gmt":"2024-08-03T23:46:56","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=253036"},"modified":"2024-08-03T19:46:57","modified_gmt":"2024-08-03T23:46:57","slug":"le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/","title":{"rendered":"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Parfois dans le sport, une \u00e9quipe obtient plus que ce qu&rsquo;elle m\u00e9rite ; d&rsquo;autres fois, c&rsquo;est moins. Pour l&rsquo;\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/games\/paris-2024\/\">Paris 2024<\/a>, c&rsquo;\u00e9tait d\u00e9finitivement la seconde option.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 une domination pendant la majeure partie du quart de finale de samedi contre l&rsquo;Allemagne, le Canada a perdu aux tirs au but. Cela signifie que, pour la premi\u00e8re fois depuis <a href=\"https:\/\/develop.olympic.ca\/olympique\/games\/2008-beijing\/\">Beijing 2008<\/a>, le Canada quittera les Jeux olympiques sans m\u00e9daille en soccer f\u00e9minin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais pour l&rsquo;\u00e9quipe qui <a href=\"https:\/\/develop.olympic.ca\/olympique\/2021\/08\/06\/equipe-canada-medaille-podium-soccer-feminin-jeux-olympiques-tokyo-2020\/\">a remport\u00e9 l&rsquo;or \u00e0 Tokyo 2020<\/a>, atteindre les quarts de finale \u00e9tait d\u00e9j\u00e0 un exploit. Une controverse li\u00e9e aux drones au d\u00e9but des Jeux de Paris a conduit \u00e0 la suspension de l&rsquo;entra\u00eeneuse Bev Priestman et \u00e0 une d\u00e9duction de six points pour l&rsquo;\u00e9quipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cela signifiait que l&rsquo;\u00e9quipe devait gagner tous ses trois matchs de phase de groupes pour avoir une chance d&rsquo;atteindre les quarts de finale. Et en restant concentr\u00e9e sur ce qu&rsquo;elle pouvait contr\u00f4ler, l&rsquo;\u00e9quipe a pr\u00e9cis\u00e9ment fait cela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Notre \u00e9quipe a fait un travail incroyable pour ignorer les distractions \u00bb, a d\u00e9clar\u00e9\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/janine-beckie\/\">Janine Beckie<\/a>. \u00ab Notre personnel a \u00e9t\u00e9 absolument incroyable, ouvert, disponible, peu importe ce dont nous avions besoin, ils travaillent 24 heures sur 24. \u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1131\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244575_454e13.jpg?quality=100&amp;w=1131\" alt=\"Les joueuses du Canada posent pour une photo.\" class=\"wp-image-253041\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244575_454e13.jpg 2160w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244575_454e13.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244575_454e13.jpg?resize=556,371 556w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244575_454e13.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244575_454e13.jpg?resize=1131,754 1131w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244575_454e13.jpg?resize=1536,1024 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244575_454e13.jpg?resize=2048,1365 2048w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/><figcaption class=\"wp-element-caption\">Les joueuses du Canada posent pour une photo avant le quart de finale f\u00e9minin entre le Canada et l&rsquo;Allemagne aux Jeux olympiques d&rsquo;\u00e9t\u00e9 2024, le samedi 3 ao\u00fbt 2024, au Stade de Marseille \u00e0 Marseille, France. (Photo AP\/Daniel Cole)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Beckie est entr\u00e9e en jeu \u00e0 la mi-temps du quart de finale, apr\u00e8s ce qui semblait \u00eatre une blessure de la capitaine <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jessie-fleming\/\">Jessie Fleming<\/a>. Bien que l&rsquo;Allemagne ait eu l&rsquo;avantage pendant une grande partie de la premi\u00e8re mi-temps, l&rsquo;ajout de Beckie, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/adriana-leon\/\">Adriana Leon<\/a>,\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/evelyne-viens\/\">Evelyne Viens<\/a>\u00a0et\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/cloe-lacasse\/\">Clo\u00e9 Lacasse<\/a> a invers\u00e9 la tendance en faveur du Canada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que le Canada ait intensifi\u00e9 la pression offensive, il n&rsquo;a pas r\u00e9ussi \u00e0 marquer pendant les 90 minutes r\u00e9glementaires ni les 30 minutes de prolongation. Cela les a laiss\u00e9s \u00e0 la merci de la loterie la plus \u00e9puisante du soccer, les tirs au but.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et bien que l&rsquo;\u00e9quipe ait triomph\u00e9 deux fois aux tirs au but \u00e0 Tokyo, y compris lors du match pour la m\u00e9daille d&rsquo;or, ce ne fut pas le cas \u00e0 Paris. Beckie et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/quinn\/\">Quinn<\/a> ont marqu\u00e9 leurs tirs, mais l&rsquo;Allemagne a remport\u00e9 la victoire 4-2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Tr\u00e8s fier de la performance \u00bb, a d\u00e9clar\u00e9 l&rsquo;entra\u00eeneur int\u00e9rimaire Andy Spence. \u00ab L&rsquo;\u00e9lan que les joueuses ont apport\u00e9 \u00e9tait formidable ; malheureusement, nous n&rsquo;avons pas r\u00e9ussi \u00e0 franchir la ligne. \u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"754\" width=\"1132\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244725.jpg?quality=100&amp;w=1132\" alt=\"Felicitas Rauch d'Allemagne se bat pour le ballon avec Ashley Lawrence.\" class=\"wp-image-252932\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244725.jpg 2160w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244725.jpg?resize=237,158 237w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244725.jpg?resize=557,371 557w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244725.jpg?resize=768,512 768w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244725.jpg?resize=1132,754 1132w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244725.jpg?resize=1536,1023 1536w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244725.jpg?resize=2048,1364 2048w\" sizes=\"(max-width: 1132px) 100vw, 1132px\" \/><figcaption class=\"wp-element-caption\">Felicitas Rauch d&rsquo;Allemagne se bat pour le ballon avec Ashley Lawrence du Canada lors d&rsquo;un match de quart de finale f\u00e9minin entre le Canada et l&rsquo;Allemagne aux Jeux olympiques d&rsquo;\u00e9t\u00e9 2024, le samedi 3 ao\u00fbt 2024, au Stade de Marseille \u00e0 Marseille, France. (Photo AP\/Julio Cortez)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dans l&rsquo;\u00e9motion qui a suivi le match, Spence \u2014 propuls\u00e9 dans un r\u00f4le qu&rsquo;il n&rsquo;aurait pas imagin\u00e9 \u2014 n&rsquo;a eu que des points positifs \u00e0 offrir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Tout ce que je pouvais leur dire, c&rsquo;\u00e9tait \u00e0 quel point j&rsquo;\u00e9tais immens\u00e9ment fier de tout le monde, joueuses et staff \u00bb, a d\u00e9clar\u00e9 Spence. \u00ab En fin de compte, ces moments peuvent soit vous renforcer, soit vous briser, et je pense qu&rsquo;avec cette \u00e9quipe, cela va absolument les renforcer. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors que des v\u00e9t\u00e9ranes comme Beckie et Fleming ont fourni du leadership tout au long du tournoi, il y a \u00e9galement eu des performances remarquables de joueuses qui pourraient jouer un r\u00f4le important pour le Canada \u00e0 l&rsquo;avenir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viens, qui participe \u00e0 ses deuxi\u00e8mes Jeux olympiques, a affirm\u00e9 sa place en tant que part essentielle de l&rsquo;attaque du Canada. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/gabrielle-carle\/\">Gabrielle Carle<\/a>, qui participe elle aussi \u00e0 ses deuxi\u00e8mes Jeux, a \u00e9t\u00e9 une addition de derni\u00e8re minute au noyau de l&rsquo;\u00e9quipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 LIRE : <a href=\"https:\/\/develop.olympic.ca\/olympique\/2024\/07\/31\/contre-toute-attente-les-joueuses-canadiennes-poursuivent-leur-chemin-en-soccer-feminin\/\">Contre toute attente, les joueuses canadiennes poursuivent leur chemin en soccer f\u00e9minin<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et une paire de recrues olympiques,\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jade-rose\/\">Jade Rose<\/a>\u00a0, 21 ans, et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/simi-awujo\/\">Simi Awujo<\/a>, 20 ans, se sont fermement \u00e9tablies comme des \u00e9l\u00e9ments cl\u00e9s dans les ann\u00e9es \u00e0 venir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O\u00f9 s&rsquo;int\u00e9greront-elles ? Et comment cette \u00e9quipe se pr\u00e9sentera-t-elle alors qu&rsquo;elle cherchera \u00e0 revenir sur le podium \u00e0\u00a0<a href=\"https:\/\/develop.olympic.ca\/olympique\/tag\/los-angeles-2028\/\">Los Angeles 2028<\/a> ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Je suis s\u00fbre que les gens auront des questions \u00e0 l&rsquo;avenir \u00bb, a d\u00e9clar\u00e9 Beckie. \u00ab Nous devons juste continuer \u00e0 avancer pas \u00e0 pas, nous d\u00e9connecter puis nous regrouper. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parfois dans le sport, une \u00e9quipe obtient plus que ce qu&rsquo;elle m\u00e9rite ; d&rsquo;autres fois, c&rsquo;est moins. Pour l&rsquo;\u00e9quipe f\u00e9minine&#8230;<\/p>\n","protected":false},"author":185434513,"featured_media":253042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085,1],"tags":[26441435,15579445,682166834,682164285,682166896,682166911,367576454,682166198,165703836,68909591,415984900,415988696,128815032,415988691,415571438,415985124,682166931,682164495,682166814,1693,682166946,25678,682163081],"post_format":"standard","sport":[8591],"game":[415985140],"coauthors":[374051512],"class_list":["post-253036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-uncategorized","tag-adriana-leon","tag-ashley-lawrence","tag-cloe-lacasse-2","tag-evelyne-viens","tag-feature","tag-feature-fr","tag-gabrielle-carle","tag-jade-rose","tag-janine-beckie","tag-jessie-fleming","tag-jordyn-huitema","tag-julia-grosso","tag-kadeisha-buchanan","tag-kailen-sheridan","tag-nichelle-prince","tag-paris-2024","tag-paris-sport-recap-fr","tag-quinn","tag-simi-awujo","tag-soccer","tag-soccer-feature","tag-team-canada","tag-vanessa-gilles","sport-football","game-paris-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"Parfois dans le sport, une \u00e9quipe obtient plus que ce qu&#039;elle m\u00e9rite ; d&#039;autres fois, c&#039;est moins. Pour l&#039;\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0Paris 2024, c&#039;\u00e9tait d\u00e9finitivement la seconde option.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception\" \/>\n<meta property=\"og:description\" content=\"Parfois dans le sport, une \u00e9quipe obtient plus que ce qu&#039;elle m\u00e9rite ; d&#039;autres fois, c&#039;est moins. Pour l&#039;\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0Paris 2024, c&#039;\u00e9tait d\u00e9finitivement la seconde option.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-03T23:46:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-03T23:46:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244576-e1722725592876.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Squizzato\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception\" \/>\n<meta name=\"twitter:description\" content=\"Parfois dans le sport, une \u00e9quipe obtient plus que ce qu&#039;elle m\u00e9rite ; d&#039;autres fois, c&#039;est moins. Pour l&#039;\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0Paris 2024, c&#039;\u00e9tait d\u00e9finitivement la seconde option.\" \/>\n<meta name=\"twitter:creator\" content=\"@alacroix\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Squizzato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/\"},\"author\":{\"name\":\"alacroix\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\"},\"headline\":\"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception\",\"datePublished\":\"2024-08-03T23:46:56+00:00\",\"dateModified\":\"2024-08-03T23:46:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/\"},\"wordCount\":769,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/CP215244576-e1722725592876.jpg?quality=100\",\"keywords\":[\"Adriana Leon\",\"Ashley Lawrence\",\"Cloe Lacasse\",\"Evelyne Viens\",\"feature\",\"Feature FR\",\"Gabrielle Carle\",\"Jade Rose\",\"Janine Beckie\",\"Jessie Fleming\",\"Jordyn Huitema\",\"Julia Grosso\",\"Kadeisha Buchanan\",\"Kailen Sheridan\",\"Nichelle Prince\",\"Paris 2024\",\"paris sport recap FR\",\"Quinn\",\"simi awujo\",\"Soccer\",\"soccer feature\",\"team canada\",\"Vanessa Gilles\"],\"articleSection\":[\"Nouvelles\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/\",\"name\":\"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/CP215244576-e1722725592876.jpg?quality=100\",\"datePublished\":\"2024-08-03T23:46:56+00:00\",\"dateModified\":\"2024-08-03T23:46:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\"},\"description\":\"Parfois dans le sport, une \u00e9quipe obtient plus que ce qu'elle m\u00e9rite ; d'autres fois, c'est moins. Pour l'\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0Paris 2024, c'\u00e9tait d\u00e9finitivement la seconde option.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2024\\\/08\\\/03\\\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/CP215244576-e1722725592876.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/CP215244576-e1722725592876.jpg?quality=100\",\"width\":2048,\"height\":1153,\"caption\":\"AP Photo\\\/Julio Cortez\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d90f198d7060e6386b5e1cc25e0844c7\",\"name\":\"alacroix\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g800804460851aa471230f61e1a6a77dc\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g\",\"caption\":\"alacroix\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/alacroix\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/alacroix\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception - \u00c9quipe Canada","description":"Parfois dans le sport, une \u00e9quipe obtient plus que ce qu'elle m\u00e9rite ; d'autres fois, c'est moins. Pour l'\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0Paris 2024, c'\u00e9tait d\u00e9finitivement la seconde option.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/","og_locale":"fr_FR","og_type":"article","og_title":"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception","og_description":"Parfois dans le sport, une \u00e9quipe obtient plus que ce qu'elle m\u00e9rite ; d'autres fois, c'est moins. Pour l'\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0Paris 2024, c'\u00e9tait d\u00e9finitivement la seconde option.","og_url":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2024-08-03T23:46:56+00:00","article_modified_time":"2024-08-03T23:46:57+00:00","og_image":[{"width":2048,"height":1153,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244576-e1722725592876.jpg?quality=100","type":"image\/jpeg"}],"author":"Daniel Squizzato","twitter_card":"summary_large_image","twitter_title":"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception","twitter_description":"Parfois dans le sport, une \u00e9quipe obtient plus que ce qu'elle m\u00e9rite ; d'autres fois, c'est moins. Pour l'\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0Paris 2024, c'\u00e9tait d\u00e9finitivement la seconde option.","twitter_creator":"@alacroix","twitter_misc":{"Written by":"Daniel Squizzato","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/"},"author":{"name":"alacroix","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7"},"headline":"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception","datePublished":"2024-08-03T23:46:56+00:00","dateModified":"2024-08-03T23:46:57+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/"},"wordCount":769,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244576-e1722725592876.jpg?quality=100","keywords":["Adriana Leon","Ashley Lawrence","Cloe Lacasse","Evelyne Viens","feature","Feature FR","Gabrielle Carle","Jade Rose","Janine Beckie","Jessie Fleming","Jordyn Huitema","Julia Grosso","Kadeisha Buchanan","Kailen Sheridan","Nichelle Prince","Paris 2024","paris sport recap FR","Quinn","simi awujo","Soccer","soccer feature","team canada","Vanessa Gilles"],"articleSection":["Nouvelles","Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/","url":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/","name":"Le parcours improbable du Canada en soccer f\u00e9minin se termine avec une d\u00e9ception - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244576-e1722725592876.jpg?quality=100","datePublished":"2024-08-03T23:46:56+00:00","dateModified":"2024-08-03T23:46:57+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7"},"description":"Parfois dans le sport, une \u00e9quipe obtient plus que ce qu'elle m\u00e9rite ; d'autres fois, c'est moins. Pour l'\u00e9quipe f\u00e9minine canadienne de soccer au Jour 8 de\u00a0Paris 2024, c'\u00e9tait d\u00e9finitivement la seconde option.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2024\/08\/03\/le-parcours-improbable-du-canada-en-soccer-feminin-se-termine-avec-une-deception\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244576-e1722725592876.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244576-e1722725592876.jpg?quality=100","width":2048,"height":1153,"caption":"AP Photo\/Julio Cortez"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d90f198d7060e6386b5e1cc25e0844c7","name":"alacroix","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g800804460851aa471230f61e1a6a77dc","url":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e0ddf63fe2e2c4d0fddcd921861b6c99f402bce42ec31af5ad39247ab324836?s=96&d=identicon&r=g","caption":"alacroix"},"sameAs":["https:\/\/x.com\/alacroix"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/alacroix\/"}]}},"jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244576-e1722725592876.jpg?quality=100","featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/08\/CP215244576-e1722725592876.jpg?quality=100","author_name":["Daniel Squizzato"],"category_names":["Nouvelles","Uncategorized"],"tag_names":["Adriana Leon","Ashley Lawrence","Cloe Lacasse","Evelyne Viens","feature","Feature FR","Gabrielle Carle","Jade Rose","Janine Beckie","Jessie Fleming","Jordyn Huitema","Julia Grosso","Kadeisha Buchanan","Kailen Sheridan","Nichelle Prince","Paris 2024","paris sport recap FR","Quinn","simi awujo","Soccer","soccer feature","team canada","Vanessa Gilles"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-13Pe","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/253036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434513"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=253036"}],"version-history":[{"count":5,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/253036\/revisions"}],"predecessor-version":[{"id":253055,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/253036\/revisions\/253055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/253042"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=253036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=253036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=253036"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=253036"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=253036"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=253036"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=253036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}