{"id":260089,"date":"2025-04-17T17:01:17","date_gmt":"2025-04-17T21:01:17","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?p=260089"},"modified":"2025-04-17T17:01:19","modified_gmt":"2025-04-17T21:01:19","slug":"equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/","title":{"rendered":"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l&rsquo;IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie. Le Canada a termin\u00e9 deuxi\u00e8me du groupe A lors du tour pr\u00e9liminaire, tandis que le Japon a termin\u00e9 deuxi\u00e8me du groupe B.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En quatre matchs pr\u00e9liminaires, les Canadiennes ont marqu\u00e9 17 buts, dont huit par le premier trio men\u00e9 par la capitaine <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/marie-philip-poulin\/\">Marie-Philip Poulin<\/a>. Le Japon s\u2019est montr\u00e9 tr\u00e8s disciplin\u00e9 lors de la ronde pr\u00e9liminaire, n\u2019\u00e9copant que de deux p\u00e9nalit\u00e9s (le Canada, \u00e0 titre comparatif, en a pris cinq dans son seul match contre la Tch\u00e9quie).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LIRE : <a href=\"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/14\/equipe-canada-retrouve-le-chemin-de-la-victoire-contre-la-tchequie\/\">\u00c9quipe Canada retrouve le chemin de la victoire contre la Tch\u00e9quie<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le match marquait une \u00e9tape importante pour Poulin alors qu&rsquo;elle est devenue seulement la quatri\u00e8me joueuse \u00e0 atteindre le cap des 200 matchs avec l\u2019\u00e9quipe nationale f\u00e9minine, rejoignant ainsi <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/hayley-wickenheiser\/\">Hayley Wickenheiser<\/a>, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/jayna-hefford\/\">Jayna Hefford<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/caroline-ouellette\/\">Caroline Ouellette<\/a> dans ce club s\u00e9lect.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/claire-thompson\/\">Claire Thompson<\/a> a ouvert la marque pour le Canada avec un magnifique tir voil\u00e9, aid\u00e9e par <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/reneta-fast\/\">Renata Fast<\/a> et <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/emily-clark\/\">Emily Clark<\/a>. Il s\u2019agissait \u00e9galement du 50e match de Thompson avec l\u2019\u00e9quipe nationale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelques instants plus tard, Jennifer Gardiner a inscrit son quatri\u00e8me but du tournoi, d\u00e9jouant la gardienne japonaise Miyuu Masuhara, sur une passe de Thompson.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LIRE : <a href=\"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/04\/la-veterane-de-lequipe-canadienne-de-hockey-feminin-brianne-jenner-fait-preuve-de-sagesse-et-de-leadership\/\">La v\u00e9t\u00e9rane de l\u2019\u00e9quipe canadienne de hockey f\u00e9minin, Brianne Jenner, fait preuve de sagesse et de leadership<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La premi\u00e8re p\u00e9riode s\u2019est conclue avec une avance de 2-0 pour le Canada, qui menait \u00e9galement 11-2 au chapitre des tirs au but.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-instagram wp-block-embed-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DIjxwLvpyzw\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:658px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/DIjxwLvpyzw\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/DIjxwLvpyzw\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by IIHF Women\u2019s Worlds (@iihfwomen)<\/a><\/p><\/div><\/blockquote><script async src=\"\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En deuxi\u00e8me p\u00e9riode, Mei Miura a marqu\u00e9 l\u2019histoire en inscrivant le tout premier but du Japon contre \u00c9quipe Canada, profitant d\u2019une \u00e9chapp\u00e9e pour battre la gardienne <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/kristen-campbell\/\">Kristen Campbell<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais 90 secondes plus tard, <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/ella-shelton\/\">Ella Shelton<\/a> a redonn\u00e9 une avance de deux buts aux Canadiennes gr\u00e2ce \u00e0 un filet, assist\u00e9e de Daryl Watts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puis ce fut au tour de <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/sarah-fillier\/\">Sarah Fillier<\/a> d\u2019inscrire son premier but du tournoi, aid\u00e9e par <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/natalie-spooner\/\">Natalie Spooner<\/a> et Fast.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Japon, pourtant l\u2019\u00e9quipe la moins p\u00e9nalis\u00e9e du tournoi, a ensuite offert un avantage num\u00e9rique au Canada, qui n\u2019a pas perdu de temps pour en profiter. Julia Gosling a d\u00e9coch\u00e9 un tir rapide de l\u2019enclave pour porter le pointage \u00e0 5-1, sur des passes de Poulin et Fast.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Japon a ensuite obtenu un jeu de puissance lorsque <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/emma-maltais\/\">Emma Maltais<\/a> a \u00e9t\u00e9 punie pour avoir fait tr\u00e9bucher, mais l\u2019unit\u00e9 de d\u00e9savantage num\u00e9rique du Canada a continu\u00e9 d\u2019\u00eatre parfaite depuis le d\u00e9but du tournoi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9quipe Canada a retrait\u00e9 au vestiaire apr\u00e8s la deuxi\u00e8me p\u00e9riode avec une avance de 5-1, dominant largement le Japon au chapitre des tirs, 30 contre 3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LIRE : <a href=\"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/07\/cette-occasion-est-un-privilege-emma-maltais-parle-de-sa-presence-au-sein-dequipe-canada-et-de-leffet-de-la-lphf\/\">\u00ab Cette occasion est un privil\u00e8ge \u00bb : Emma Maltais parle de sa pr\u00e9sence au sein d\u2019\u00c9quipe Canada et de l\u2019effet de la LPHF<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Canada a repris l\u00e0 o\u00f9 il avait laiss\u00e9 en d\u00e9but de troisi\u00e8me, alors que Jennifer Gardiner a inscrit son deuxi\u00e8me but du match, aid\u00e9e par Kristin O\u2019Neill. Peu apr\u00e8s, Fillier a elle aussi marqu\u00e9 son deuxi\u00e8me de la soir\u00e9e, filant \u00e0 travers la d\u00e9fense japonaise pour loger une superbe rondelle dans le filet, avec l\u2019aide de <a href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/jocelyne-larocque\/\">Jocelyne Larocque<\/a>. Et quelques secondes plus tard, Clark a trouv\u00e9 le fond du filet pour la premi\u00e8re fois dans ce tournoi, portant la marque \u00e0 huit buts pour le Canada. <a href=\"https:\/\/develop.olympic.ca\/olympique\/team-canada\/blayre-turnbull\/\">Blayre Turnbull<\/a> a obtenu une mention d\u2019aide sur le jeu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais le Canada n\u2019avait pas dit son dernier mot. Dans la derni\u00e8re minute de jeu, la d\u00e9fenseure Sophie Jaques a marqu\u00e9 son deuxi\u00e8me but du tournoi pour clore la rencontre en beaut\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le temps s\u2019est \u00e9coul\u00e9 apr\u00e8s 60 minutes de jeu, avec un pointage final de 9-1 en faveur du Canada, qui a compl\u00e8tement domin\u00e9 la feuille de tir avec 62 tirs contre seulement 6 pour le Japon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Miura a \u00e9t\u00e9 nomm\u00e9e joueuse du match du c\u00f4t\u00e9 du Japon, soulignant son but historique. Pour le Canada, c\u2019est Shelton qui a m\u00e9rit\u00e9 cet honneur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Canada affrontera la Finlande en dem-finale ce samedi. Le d\u00e9but de la rencontre en pr\u00e9vu pour 13h. L&rsquo;autre duel opposera les \u00c9tats-Unis au pays h\u00f4te, la Tch\u00e9quie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l&rsquo;IIHF, qui&#8230;<\/p>\n","protected":false},"author":185434584,"featured_media":260094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085,1],"tags":[415984778,32156877,682167179,682167178,682164820,682167163,682164819,415984744,682164815,1104411,682167185,10152628,415984533,31403584,682167159,162948260,682166648,682165058,682164818,32094883,163158314,415984774,682164814,682167161],"post_format":"standard","sport":[891977],"game":[],"coauthors":[682165841],"class_list":["post-260089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-uncategorized","tag-blayre-turnbull","tag-caroline-ouellette","tag-ceske-budejovice","tag-championnat-mondial-feminin-de-liihf","tag-claire-thompson","tag-daryl-watts","tag-ella-shelton","tag-emily-clark","tag-emma-maltais","tag-equipe-canada","tag-equipe-nationale-feminine","tag-hayley-wickenheiser","tag-hockey-sur-glace","tag-jayna-hefford","tag-jennifer-gardiner","tag-jocelyne-larocque","tag-julia-gosling","tag-kristen-campbell","tag-kristin-oneill","tag-marie-philip-poulin","tag-natalie-spooner","tag-renata-fast","tag-sarah-fillier","tag-sophie-jacques","sport-hockey-sur-glace"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon - \u00c9quipe Canada<\/title>\n<meta name=\"description\" content=\"\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l&#039;IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon\" \/>\n<meta property=\"og:description\" content=\"\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l&#039;IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-17T21:01:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-17T21:01:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"6000\" \/>\n\t<meta property=\"og:image:height\" content=\"3380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fran\u00e7ois Lafleur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon\" \/>\n<meta name=\"twitter:description\" content=\"\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l&#039;IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fran\u00e7ois Lafleur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/\"},\"author\":{\"name\":\"flafleur\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d62fdaa3be30601a34e8ac8de2abea9b\"},\"headline\":\"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon\",\"datePublished\":\"2025-04-17T21:01:17+00:00\",\"dateModified\":\"2025-04-17T21:01:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/\"},\"wordCount\":782,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/04\\\/canvsjapan1-e1744922004376.jpg?quality=100\",\"keywords\":[\"Blayre Turnbull\",\"Caroline Ouellette\",\"ceske budejovice\",\"championnat mondial f\u00e9minin de l'iihf\",\"Claire Thompson\",\"Daryl Watts\",\"ella shelton\",\"Emily Clark\",\"emma maltais\",\"\u00c9quipe canada\",\"\u00e9quipe nationale f\u00e9minine\",\"Hayley Wickenheiser\",\"Hockey sur glace\",\"Jayna Hefford\",\"Jennifer Gardiner\",\"Jocelyne Larocque\",\"Julia Gosling\",\"Kristen Campbell\",\"kristin o&#039;neill\",\"Marie-Philip Poulin\",\"Natalie Spooner\",\"Renata Fast\",\"sarah fillier\",\"Sophie Jacques\"],\"articleSection\":[\"Nouvelles\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/\",\"name\":\"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/04\\\/canvsjapan1-e1744922004376.jpg?quality=100\",\"datePublished\":\"2025-04-17T21:01:17+00:00\",\"dateModified\":\"2025-04-17T21:01:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d62fdaa3be30601a34e8ac8de2abea9b\"},\"description\":\"\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l'IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2025\\\/04\\\/17\\\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/04\\\/canvsjapan1-e1744922004376.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/04\\\/canvsjapan1-e1744922004376.jpg?quality=100\",\"width\":6000,\"height\":3380},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/d62fdaa3be30601a34e8ac8de2abea9b\",\"name\":\"flafleur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89fdac808769e38f5b527febb2f9d67f3707718c1f171d26806d9dc8af3839f7?s=96&d=identicon&r=ge24091abc4413be89fd3cecae5a226fa\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89fdac808769e38f5b527febb2f9d67f3707718c1f171d26806d9dc8af3839f7?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89fdac808769e38f5b527febb2f9d67f3707718c1f171d26806d9dc8af3839f7?s=96&d=identicon&r=g\",\"caption\":\"flafleur\"},\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/flafleur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon - \u00c9quipe Canada","description":"\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l'IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon","og_description":"\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l'IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie.","og_url":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2025-04-17T21:01:17+00:00","article_modified_time":"2025-04-17T21:01:19+00:00","og_image":[{"width":6000,"height":3380,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100","type":"image\/jpeg"}],"author":"Fran\u00e7ois Lafleur","twitter_card":"summary_large_image","twitter_title":"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon","twitter_description":"\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l'IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie.","twitter_image":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100","twitter_misc":{"Written by":"Fran\u00e7ois Lafleur","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/"},"author":{"name":"flafleur","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d62fdaa3be30601a34e8ac8de2abea9b"},"headline":"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon","datePublished":"2025-04-17T21:01:17+00:00","dateModified":"2025-04-17T21:01:19+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/"},"wordCount":782,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100","keywords":["Blayre Turnbull","Caroline Ouellette","ceske budejovice","championnat mondial f\u00e9minin de l'iihf","Claire Thompson","Daryl Watts","ella shelton","Emily Clark","emma maltais","\u00c9quipe canada","\u00e9quipe nationale f\u00e9minine","Hayley Wickenheiser","Hockey sur glace","Jayna Hefford","Jennifer Gardiner","Jocelyne Larocque","Julia Gosling","Kristen Campbell","kristin o&#039;neill","Marie-Philip Poulin","Natalie Spooner","Renata Fast","sarah fillier","Sophie Jacques"],"articleSection":["Nouvelles","Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/","url":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/","name":"\u00c9quipe Canada passe en demi-finale gr\u00e2ce \u00e0 une victoire contre le Japon - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100","datePublished":"2025-04-17T21:01:17+00:00","dateModified":"2025-04-17T21:01:19+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d62fdaa3be30601a34e8ac8de2abea9b"},"description":"\u00c9quipe Canada a vaincu le Japon 9-1 en quart de finale jeudi au Championnat mondial f\u00e9minin 2025 de l'IIHF, qui se d\u00e9roule \u00e0 \u010cesk\u00e9 Bud\u011bjovice, en Tch\u00e9quie.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2025\/04\/17\/equipe-canada-passe-en-demi-finale-grace-a-une-victoire-contre-le-japon\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100","width":6000,"height":3380},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/d62fdaa3be30601a34e8ac8de2abea9b","name":"flafleur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/89fdac808769e38f5b527febb2f9d67f3707718c1f171d26806d9dc8af3839f7?s=96&d=identicon&r=ge24091abc4413be89fd3cecae5a226fa","url":"https:\/\/secure.gravatar.com\/avatar\/89fdac808769e38f5b527febb2f9d67f3707718c1f171d26806d9dc8af3839f7?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/89fdac808769e38f5b527febb2f9d67f3707718c1f171d26806d9dc8af3839f7?s=96&d=identicon&r=g","caption":"flafleur"},"url":"https:\/\/develop.olympic.ca\/olympique\/author\/flafleur\/"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100","author_name":["Fran\u00e7ois Lafleur"],"category_names":["Nouvelles","Uncategorized"],"tag_names":["Blayre Turnbull","Caroline Ouellette","ceske budejovice","championnat mondial f\u00e9minin de l'iihf","Claire Thompson","Daryl Watts","ella shelton","Emily Clark","emma maltais","\u00c9quipe canada","\u00e9quipe nationale f\u00e9minine","Hayley Wickenheiser","Hockey sur glace","Jayna Hefford","Jennifer Gardiner","Jocelyne Larocque","Julia Gosling","Kristen Campbell","kristin o&#039;neill","Marie-Philip Poulin","Natalie Spooner","Renata Fast","sarah fillier","Sophie Jacques"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-15EZ","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2025\/04\/canvsjapan1-e1744922004376.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/260089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/185434584"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=260089"}],"version-history":[{"count":5,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/260089\/revisions"}],"predecessor-version":[{"id":260095,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/260089\/revisions\/260095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/260094"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=260089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=260089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=260089"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=260089"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=260089"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=260089"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=260089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}