{"id":96986,"date":"2014-09-23T19:37:34","date_gmt":"2014-09-23T23:37:34","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=96986"},"modified":"2014-10-08T08:37:20","modified_gmt":"2014-10-08T12:37:20","slug":"la-retraite-pour-michael-gilday","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/","title":{"rendered":"La retraite pour Michael Gilday"},"content":{"rendered":"<h1>L&rsquo;athl\u00e8te olympique <a title=\"Michael Gilday\" href=\"http:\/\/develop.olympic.ca\/team-canada\/michael-gilday\/\">Michael Gilday<\/a> a officiellement annonc\u00e9 sa retraite du patinage de vitesse sur courte piste mardi.<\/h1>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" width=\"550\">\n<p>Merci <a href=\"https:\/\/twitter.com\/ykgday\">@ykgday<\/a> : L\u2019Olympien Michael Gilday annonce sa retraite du patinage de vitesse &#8211; <a href=\"http:\/\/t.co\/RnV0xx6sLk\">http:\/\/t.co\/RnV0xx6sLk<\/a> <a href=\"http:\/\/t.co\/nQT28LWd1d\">pic.twitter.com\/nQT28LWd1d<\/a><\/p>\n<p>&mdash; SSC\/PVC (@SSC_PVC) <a href=\"https:\/\/twitter.com\/SSC_PVC\/status\/514514560418861056\">September 23, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Gilday, d\u00e9tenteur de la marque mondiale au 1000 m de 2007 \u00e0 2009, quitte avec le record du monde au relais masculin en poche obtenu en compagnie de <a title=\"Charles Hamelin\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/charles-hamelin\/\">Charles Hamelin<\/a>, <a title=\"Fran\u00e7ois Hamelin\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/francois-hamelin\/\">Fran\u00e7ois Hamelin<\/a> et <a title=\"Olivier Jean\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/olivier-jean\/\">Olivier Jean<\/a> en 2012.<\/p>\n<blockquote><p>\u00c0 LIRE : <a href=\"http:\/\/develop.olympic.ca\/olympique\/2013\/12\/10\/une-journee-dans-la-vie-du-patineur-de-vitesse-sur-courte-piste-michael-gilday\/\">Une journ\u00e9e dans la vie du patineur de vitesse sur courte piste Michael Gilday<\/a><\/p><\/blockquote>\n<p>En f\u00e9vrier dernier, aux Jeux olympiques de Sotchi, Gilday et ses co\u00e9quipiers ont termin\u00e9 en cinqui\u00e8me position au relais par \u00e9quipe. Le natif de Yellowknife avait \u00e9galement pris le 17e rang au 1500 m.<\/p>\n<p>\u00ab Tout au long de ma carri\u00e8re, j\u2019ai d\u00e9finitivement v\u00e9cu plus de bons que de moins bons moments, mais ce f\u00fbt un honneur et un privil\u00e8ge de porter la feuille d\u2019\u00e9rable et de repr\u00e9senter le Canada aux Jeux olympiques, aux Championnats du monde et sur le circuit de la Coupe du monde \u00bb, a d\u00e9clar\u00e9 le nouveau retrait\u00e9.<\/p>\n<p>L&rsquo;athl\u00e8te de 27 ans d\u00e9tient toujours le record national au 1500 m (2:06.57) qu&rsquo;il avait \u00e9tabli en 2009.<\/p>\n<p>Gilday totalise 30 m\u00e9dailles de Coupe du monde, dont sept d&rsquo;or.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;athl\u00e8te olympique Michael Gilday a officiellement annonc\u00e9 sa retraite du patinage de vitesse sur courte piste mardi. Merci @ykgday :&#8230;<\/p>\n","protected":false},"author":55751844,"featured_media":96992,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16085],"tags":[2443,25751757,30800930,2062,16081,42718829,5747445,5850],"post_format":"standard","sport":[51196772],"game":[191933058],"coauthors":[197551639],"class_list":["post-96986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-canada","tag-charles-hamelin","tag-francois-hamelin","tag-japan","tag-jeux","tag-michael-gilday","tag-olivier-jean","tag-united-states","sport-patinage-de-vitesse-courte-piste","game-2014-sotchi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La retraite pour Michael Gilday - \u00c9quipe Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La retraite pour Michael Gilday - \u00c9quipe Canada\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;athl\u00e8te olympique Michael Gilday a officiellement annonc\u00e9 sa retraite du patinage de vitesse sur courte piste mardi. Merci @ykgday :...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-23T23:37:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-08T12:37:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/09\/05811021.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"2872\" \/>\n\t<meta property=\"og:image:height\" content=\"2003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Steve Boudreau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steve Boudreau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/\"},\"author\":{\"name\":\"Steve Boudreau\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fe9c9377a625e32685068f640ff9e166\"},\"headline\":\"La retraite pour Michael Gilday\",\"datePublished\":\"2014-09-23T23:37:34+00:00\",\"dateModified\":\"2014-10-08T12:37:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/\"},\"wordCount\":211,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/09\\\/05811021.jpg?quality=100\",\"keywords\":[\"Canada\",\"Charles Hamelin\",\"Fran\u00e7ois Hamelin\",\"Japan\",\"Jeux\",\"Michael Gilday\",\"Olivier Jean\",\"United States\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/\",\"name\":\"La retraite pour Michael Gilday - \u00c9quipe Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/09\\\/05811021.jpg?quality=100\",\"datePublished\":\"2014-09-23T23:37:34+00:00\",\"dateModified\":\"2014-10-08T12:37:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fe9c9377a625e32685068f640ff9e166\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/2014\\\/09\\\/23\\\/la-retraite-pour-michael-gilday\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/09\\\/05811021.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/09\\\/05811021.jpg?quality=100\",\"width\":2872,\"height\":2003},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#\\\/schema\\\/person\\\/fe9c9377a625e32685068f640ff9e166\",\"name\":\"Steve Boudreau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=geab05ffb592a23c798f7bf61ed1f5f18\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=g\",\"caption\":\"Steve Boudreau\"},\"description\":\"R\u00e9dacteur, m\u00e9dias sociaux - @Sboudreau\",\"sameAs\":[\"http:\\\/\\\/sboudreau49.wordpress.com\"],\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/author\\\/sboudreau2013\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La retraite pour Michael Gilday - \u00c9quipe Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/","og_locale":"fr_FR","og_type":"article","og_title":"La retraite pour Michael Gilday - \u00c9quipe Canada","og_description":"L&rsquo;athl\u00e8te olympique Michael Gilday a officiellement annonc\u00e9 sa retraite du patinage de vitesse sur courte piste mardi. Merci @ykgday :...","og_url":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/","og_site_name":"\u00c9quipe Canada","article_published_time":"2014-09-23T23:37:34+00:00","article_modified_time":"2014-10-08T12:37:20+00:00","og_image":[{"width":2872,"height":2003,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/09\/05811021.jpg?quality=100","type":"image\/jpeg"}],"author":"Steve Boudreau","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Steve Boudreau","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/#article","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/"},"author":{"name":"Steve Boudreau","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/fe9c9377a625e32685068f640ff9e166"},"headline":"La retraite pour Michael Gilday","datePublished":"2014-09-23T23:37:34+00:00","dateModified":"2014-10-08T12:37:20+00:00","mainEntityOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/"},"wordCount":211,"commentCount":0,"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/09\/05811021.jpg?quality=100","keywords":["Canada","Charles Hamelin","Fran\u00e7ois Hamelin","Japan","Jeux","Michael Gilday","Olivier Jean","United States"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/","url":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/","name":"La retraite pour Michael Gilday - \u00c9quipe Canada","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/09\/05811021.jpg?quality=100","datePublished":"2014-09-23T23:37:34+00:00","dateModified":"2014-10-08T12:37:20+00:00","author":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/fe9c9377a625e32685068f640ff9e166"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/2014\/09\/23\/la-retraite-pour-michael-gilday\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/09\/05811021.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/09\/05811021.jpg?quality=100","width":2872,"height":2003},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/develop.olympic.ca\/olympique\/#\/schema\/person\/fe9c9377a625e32685068f640ff9e166","name":"Steve Boudreau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=geab05ffb592a23c798f7bf61ed1f5f18","url":"https:\/\/secure.gravatar.com\/avatar\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/336c6be93b523130336d384227371a495c6bb9057a12c48ad1770e1a6a57006b?s=96&d=identicon&r=g","caption":"Steve Boudreau"},"description":"R\u00e9dacteur, m\u00e9dias sociaux - @Sboudreau","sameAs":["http:\/\/sboudreau49.wordpress.com"],"url":"https:\/\/develop.olympic.ca\/olympique\/author\/sboudreau2013\/"}]}},"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/09\/05811021.jpg?quality=100","author_name":["Steve Boudreau"],"category_names":["Nouvelles"],"tag_names":["Canada","Charles Hamelin","Fran\u00e7ois Hamelin","Japan","Jeux","Michael Gilday","Olivier Jean","United States"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-pei","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/09\/05811021.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/96986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/55751844"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=96986"}],"version-history":[{"count":3,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/96986\/revisions"}],"predecessor-version":[{"id":96995,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/96986\/revisions\/96995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/96992"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=96986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=96986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=96986"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=96986"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=96986"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=96986"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=96986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}