{"id":98257,"date":"2014-12-17T13:13:52","date_gmt":"2014-12-17T18:13:52","guid":{"rendered":"http:\/\/develop.olympic.ca\/olympique\/?p=98257"},"modified":"2014-12-18T16:26:51","modified_gmt":"2014-12-18T21:26:51","slug":"top-2014-lenvers-de-la-medaille","status":"publish","type":"post","link":"https:\/\/develop.olympic.ca\/olympique\/2014\/12\/17\/top-2014-lenvers-de-la-medaille\/","title":{"rendered":"Top 2014: L\u2019envers de la m\u00e9daille"},"content":{"rendered":"<p><strong><em>Pendant le mois de d\u00e9cembre, Olympique.ca fait le d\u00e9compte des moments sportifs canadiens qui ont marqu\u00e9 2014.<\/em><\/strong><\/p>\n<h1>J\u2019ai eu l\u2019immense chance et le grand privil\u00e8ge d\u2019assister \u00e0 toutes les soir\u00e9es de comp\u00e9tition de patinage artistique des Jeux de Sotchi, sauf deux, au palais des sports de glace Iceberg o\u00f9 j\u2019ai \u00e9t\u00e9 t\u00e9moin de plusieurs grands moments de mon sport pr\u00e9f\u00e9r\u00e9, et j\u2019en suis tr\u00e8s reconnaissante.<\/h1>\n<p><a title=\"Meagan Duhamel\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/meagan-duhamel\/\">Meagan Duhamel<\/a> et <a title=\"Eric Radford\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/eric-radford\/\">Eric Radford<\/a> sont les premiers \u00e0 m\u2019avoir donn\u00e9 des frissons avec leur programme court de l\u2019\u00e9preuve par \u00e9quipe. C\u2019\u00e9tait une prestation de calibre olympique o\u00f9 se mariaient parfaitement les patineurs, la musique, la chor\u00e9graphie et les \u00e9l\u00e9ments. La musique \u00e9tait une composition d\u2019Eric lui-m\u00eame en hommage \u00e0 son entra\u00eeneur, le regrett\u00e9 Paul Wirtz. Le caract\u00e8re intime de la trame sonore ajoutait \u00e0 l\u2019\u00e9motion d\u2019un <a href=\"https:\/\/www.youtube.com\/watch?v=7YCQagrq5gc\">programme autrement techniquement r\u00e9ussi<\/a>.<\/p>\n<p>La qualit\u00e9 des patineurs canadiens n\u2019a pas fait d\u00e9faut lorsque <a title=\"Kirsten Moore-Towers\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/kirsten-moore-towers\/\">Kirsten Moore-Towers<\/a> et <a title=\"Dylan Moscovitch\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/dylan-moscovitch\/\">Dylan Moscovitch<\/a> les ont remplac\u00e9s pour le programme libre en couple. <a title=\"Kevin Reynolds\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/kevin-reynolds\/\">Kevin Reynolds<\/a> a mis l\u2019\u00e9paule \u00e0 la roue pour d\u00e9crocher la m\u00e9daille d\u2019argent en livrant un programme libre \u00e0 trois quadruples sauts.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1360\" data-carousel-extra='null' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1360px; height: 610px;\" data-original-width=\"1360\" data-original-height=\"610\" > <div class=\"gallery-group images-1\" style=\"width: 907px; height: 610px;\" data-original-width=\"907\" data-original-height=\"610\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2014\/12\/17\/top-2014-lenvers-de-la-medaille\/5patsochi\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"903\"> <meta itemprop=\"height\" content=\"606\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"98262\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/5patsochi.jpg?quality=100\" data-orig-size=\"1000,671\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"5patsochi\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/5patsochi.jpg?quality=100&#038;w=553\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/5patsochi.jpg?quality=100&#038;w=1000\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/5patsochi.jpg?quality=100&#038;w=903&#038;h=606&#038;strip&#038;resize=903%2C606\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/5patsochi.jpg 1000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/5patsochi.jpg?resize=235,158 235w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/5patsochi.jpg?resize=553,371 553w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/5patsochi.jpg?resize=768,515 768w\" width=\"903\" height=\"606\" loading=\"lazy\" data-original-width=\"903\" data-original-height=\"606\" itemprop=\"http:\/\/schema.org\/image\" title=\"5patsochi\" alt=\"Patrick Chan\" style=\"width: 903px; height: 606px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Patrick Chan <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 453px; height: 610px;\" data-original-width=\"453\" data-original-height=\"610\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2014\/12\/17\/top-2014-lenvers-de-la-medaille\/1megericsochi\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"449\"> <meta itemprop=\"height\" content=\"301\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"98258\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/1megericsochi.jpg?quality=100\" data-orig-size=\"1000,671\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1megericsochi\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/1megericsochi.jpg?quality=100&#038;w=553\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/1megericsochi.jpg?quality=100&#038;w=1000\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/1megericsochi.jpg?quality=100&#038;w=449&#038;h=301&#038;strip&#038;resize=449%2C301\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/1megericsochi.jpg 1000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/1megericsochi.jpg?resize=235,158 235w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/1megericsochi.jpg?resize=553,371 553w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/1megericsochi.jpg?resize=768,515 768w\" width=\"449\" height=\"301\" loading=\"lazy\" data-original-width=\"449\" data-original-height=\"301\" itemprop=\"http:\/\/schema.org\/image\" title=\"1megericsochi\" alt=\"Meagan Duhamel and Eric Radford\" style=\"width: 449px; height: 301px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Meagan Duhamel and Eric Radford <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2014\/12\/17\/top-2014-lenvers-de-la-medaille\/2kirdylsochi\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"449\"> <meta itemprop=\"height\" content=\"301\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"98259\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/2kirdylsochi.jpg?quality=100\" data-orig-size=\"1000,671\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"2kirdylsochi\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/2kirdylsochi.jpg?quality=100&#038;w=553\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/2kirdylsochi.jpg?quality=100&#038;w=1000\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/2kirdylsochi.jpg?quality=100&#038;w=449&#038;h=301&#038;strip&#038;resize=449%2C301\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/2kirdylsochi.jpg 1000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/2kirdylsochi.jpg?resize=235,158 235w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/2kirdylsochi.jpg?resize=553,371 553w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/2kirdylsochi.jpg?resize=768,515 768w\" width=\"449\" height=\"301\" loading=\"lazy\" data-original-width=\"449\" data-original-height=\"301\" itemprop=\"http:\/\/schema.org\/image\" title=\"2kirdylsochi\" alt=\"Kirsten Moore-Towers and Dylan Moscovitch\" style=\"width: 449px; height: 301px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Kirsten Moore-Towers and Dylan Moscovitch <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1360px; height: 306px;\" data-original-width=\"1360\" data-original-height=\"306\" > <div class=\"gallery-group images-1\" style=\"width: 454px; height: 306px;\" data-original-width=\"454\" data-original-height=\"306\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2014\/12\/17\/top-2014-lenvers-de-la-medaille\/3kevsochi\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"450\"> <meta itemprop=\"height\" content=\"302\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"98260\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/3kevsochi.jpg?quality=100\" data-orig-size=\"1000,671\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;COC&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"3kevsochi\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/3kevsochi.jpg?quality=100&#038;w=553\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/3kevsochi.jpg?quality=100&#038;w=1000\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/3kevsochi.jpg?quality=100&#038;w=450&#038;h=302&#038;strip&#038;resize=450%2C302\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/3kevsochi.jpg 1000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/3kevsochi.jpg?resize=235,158 235w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/3kevsochi.jpg?resize=553,371 553w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/3kevsochi.jpg?resize=768,515 768w\" width=\"450\" height=\"302\" loading=\"lazy\" data-original-width=\"450\" data-original-height=\"302\" itemprop=\"http:\/\/schema.org\/image\" title=\"3kevsochi\" alt=\"Kevin Reynolds\" style=\"width: 450px; height: 302px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Kevin Reynolds <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 453px; height: 306px;\" data-original-width=\"453\" data-original-height=\"306\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2014\/12\/17\/top-2014-lenvers-de-la-medaille\/4kaetsochi\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"449\"> <meta itemprop=\"height\" content=\"302\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"98261\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/4kaetsochi.jpg?quality=100\" data-orig-size=\"1000,671\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"4kaetsochi\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/4kaetsochi.jpg?quality=100&#038;w=553\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/4kaetsochi.jpg?quality=100&#038;w=1000\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/4kaetsochi.jpg?quality=100&#038;w=449&#038;h=302&#038;strip&#038;resize=449%2C302\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/4kaetsochi.jpg 1000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/4kaetsochi.jpg?resize=235,158 235w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/4kaetsochi.jpg?resize=553,371 553w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/4kaetsochi.jpg?resize=768,515 768w\" width=\"449\" height=\"302\" loading=\"lazy\" data-original-width=\"449\" data-original-height=\"302\" itemprop=\"http:\/\/schema.org\/image\" title=\"4kaetsochi\" alt=\"Kaetlyn Osmond.\" style=\"width: 449px; height: 302px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Kaetlyn Osmond. <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 453px; height: 306px;\" data-original-width=\"453\" data-original-height=\"306\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/develop.olympic.ca\/olympique\/2014\/12\/17\/top-2014-lenvers-de-la-medaille\/6tesscosochi\/#main\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"449\"> <meta itemprop=\"height\" content=\"302\"> <img decoding=\"async\" data-recalc-dims=\"1\" class=\"\" data-attachment-id=\"98263\" data-orig-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/6tesscosochi.jpg?quality=100\" data-orig-size=\"1000,671\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;COC&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"6tesscosochi\" data-image-description=\"\" data-medium-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/6tesscosochi.jpg?quality=100&#038;w=553\" data-large-file=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/6tesscosochi.jpg?quality=100&#038;w=1000\" src=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/6tesscosochi.jpg?quality=100&#038;w=449&#038;h=302&#038;strip&#038;resize=449%2C302\" srcset=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/6tesscosochi.jpg 1000w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/6tesscosochi.jpg?resize=235,158 235w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/6tesscosochi.jpg?resize=553,371 553w, https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/6tesscosochi.jpg?resize=768,515 768w\" width=\"449\" height=\"302\" loading=\"lazy\" data-original-width=\"449\" data-original-height=\"302\" itemprop=\"http:\/\/schema.org\/image\" title=\"6tesscosochi\" alt=\"Tessa Virtue et Scott Moir\" style=\"width: 449px; height: 302px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Tessa Virtue et Scott Moir <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p>\u00c9tant moi aussi de Terre-Neuve, j\u2019ai \u00e9t\u00e9 envahie par la fiert\u00e9 en voyant <a title=\"Kaetlyn Osmond\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/kaetlyn-osmond\/\">Kaetlyn Osmond<\/a> patiner avec <a href=\"https:\/\/www.youtube.com\/watch?v=j8acE4tICJA\">sensibilit\u00e9 et \u00e9l\u00e9gance<\/a> malgr\u00e9 la pression, lors de l\u2019\u00e9preuve par \u00e9quipe, et sauter sur le podium main dans la main avec un groupe tiss\u00e9 serr\u00e9 qui n\u2019avait pas peur d\u2019exprimer son enthousiasme.<\/p>\n<p>Je ne me souviens pas d\u2019avoir \u00e9t\u00e9 aussi nerveuse qu\u2019en regardant le <a href=\"https:\/\/www.youtube.com\/watch?v=fuy6vDcBCWQ\">programme court<\/a> de <a title=\"Patrick Chan\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/patrick-chan\/\">Patrick Chan<\/a>. Patrick est l\u2019un des meilleurs patineurs de tous les temps, et il incarne tout ce que j\u2019aime de ce sport. Je voulais juste qu\u2019il patine aussi bien que je sais qu\u2019il en est capable. Il n\u2019a peut-\u00eatre pas obtenu le r\u00e9sultat escompt\u00e9, mais une paire de m\u00e9dailles d\u2019argent, c\u2019est quand m\u00eame pas mal.<\/p>\n<p>J\u2019\u00e9tais aussi tr\u00e8s contente de le voir profiter au maximum de l\u2019exp\u00e9rience olympique en encourageant bruyamment l\u2019\u00e9quipe f\u00e9minine de hockey en compagnie de <a title=\"Scott Moir\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/scott-moir\/\">Scott Moir<\/a> pendant la finale!<\/p>\n<p>Parlant de Scott Moir, <a title=\"Tessa Virtue\" href=\"http:\/\/develop.olympic.ca\/olympique\/team-canada\/tessa-virtue\/\">Tessa Virtue<\/a> et lui ont \u00e9t\u00e9 tout simplement spectaculaires. Quand je l\u2019ai vue pour la premi\u00e8re fois \u00e0 l\u2019automne, leur <a href=\"https:\/\/www.youtube.com\/watch?v=Kq-e_Jkf91s\">danse courte jazz\u00e9e<\/a> m\u2019a tout de suite conquise. En f\u00e9vrier, c\u2019\u00e9tait devenu une prestation vraiment sp\u00e9ciale.<\/p>\n<p>Parce qu\u2019ils avaient \u00e9t\u00e9 deuxi\u00e8mes toute la saison, je savais bien qu\u2019ils ne gagneraient pas la m\u00e9daille d\u2019or, alors j\u2019en ai profit\u00e9 pour appr\u00e9cier <a href=\"https:\/\/www.youtube.com\/watch?v=yqM6-Fh-o-0\">leur performance<\/a> autant qu\u2019eux. Je me trouve tr\u00e8s chanceuse que ma carri\u00e8re olympique co\u00efncide avec la leur.<\/p>\n<p>Mon seul regret est de ne pas avoir \u00e9t\u00e9 pr\u00e9sente lorsque Scott a fait ses adieux \u00e0 la patinoire olympique.<\/p>\n<div class=\"embed-twitter\">\n<blockquote class=\"twitter-tweet\" width=\"550\">\n<p>Scott Moir is kissing the Olympic Rings. <a href=\"http:\/\/t.co\/oZcv0E9V72\">pic.twitter.com\/oZcv0E9V72<\/a><\/p>\n<p>&mdash; Lori Ewing (@Ewingsports) <a href=\"https:\/\/twitter.com\/Ewingsports\/status\/435504824113983489\">February 17, 2014<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pendant le mois de d\u00e9cembre, Olympique.ca fait le d\u00e9compte des moments sportifs canadiens qui ont marqu\u00e9 2014. J\u2019ai eu l\u2019immense&#8230;<\/p>\n","protected":false},"author":52435451,"featured_media":98271,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6357361],"tags":[9797765,28002365,2443,36012031,31978987,2062,28002364,31030545,5882780,5882778,113141831],"post_format":"standard","sport":[2636692],"game":[191933058],"coauthors":[197557601],"class_list":["post-98257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sur-le-radar","tag-2014-winter-olympics","tag-andrew-poje","tag-canada","tag-eric-radford","tag-grand-prix-of-figure-skating-final","tag-japan","tag-kaitlyn-weaver","tag-piper-gilles","tag-scott-moir","tag-tessa-virtue","tag-top-2014","sport-patinage-artistique","game-2014-sotchi"],"acf":[],"featured_image_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/fs.jpg?quality=100","author_name":["Paula Nichols"],"category_names":["Sur le radar"],"tag_names":["2014 Winter Olympics","Andrew Poje","Canada","Eric Radford","Grand Prix of Figure Skating Final","Japan","Kaitlyn Weaver","Piper Gilles","Scott Moir","Tessa Virtue","top-2014"],"video_embed_code":"","facebook_video_embed_code":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pbmyEP-pyN","jetpack_featured_media_url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2014\/12\/fs.jpg?quality=100","_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/98257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/users\/52435451"}],"replies":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/comments?post=98257"}],"version-history":[{"count":2,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/98257\/revisions"}],"predecessor-version":[{"id":98265,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts\/98257\/revisions\/98265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/98271"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=98257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/categories?post=98257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=98257"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/post_format?post=98257"},{"taxonomy":"sport","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sport?post=98257"},{"taxonomy":"game","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/game?post=98257"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coauthors?post=98257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}