{"id":252009,"date":"2024-07-31T07:47:10","date_gmt":"2024-07-31T11:47:10","guid":{"rendered":"https:\/\/develop.olympic.ca\/olympique\/?post_type=press&#038;p=252009"},"modified":"2024-07-31T08:11:57","modified_gmt":"2024-07-31T12:11:57","slug":"declararion-du-coc-sur-la-decision-du-tas","status":"publish","type":"press","link":"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/","title":{"rendered":"D\u00e9clararion du COC sur la d\u00e9cision du TAS\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">PARIS (31 juillet 2024) \u2013 Le Comit\u00e9 olympique canadien et Canada Soccer remercient le comit\u00e9 sp\u00e9cial du Tribunal Arbitral du Sport pour l\u2019audience rapide tenue dans la proc\u00e9dure qui nous concerne. Bien que nous soyons d\u00e9\u00e7us du r\u00e9sultat de notre appel, nous f\u00e9licitons les joueuses pour l\u2019incroyable r\u00e9silience et le courage dont elles ont fait preuve pendant ce tournoi et nous avons h\u00e2te de les encourager dans le match d\u2019aujourd\u2019hui contre la Colombie.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">-30-<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CONTACTS POUR LES M\u00c9DIAS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thomas Hall<br>Chef de presse d\u2019\u00c9quipe Canada<br>WhatsApp : +1 (514) 709-1054<br>Courriel :&nbsp;<a href=\"mailto:thall@olympic.ca\">thall@olympique.ca<\/a>&nbsp;\/&nbsp;<a href=\"mailto:communications@olympic.ca\">communications@olympique.ca<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paulo Senra<br>Chef des communications et du contenu<br>Canada Soccer<br>WhatsApp: +1 (416) 882-7919<br>Courriel:&nbsp;<a href=\"mailto:psenra@canadasoccer.com\">psenra@canadasoccer.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PARIS (31 juillet 2024) \u2013 Le Comit\u00e9 olympique canadien et Canada Soccer remercient le comit\u00e9 sp\u00e9cial du Tribunal Arbitral du&#8230;<\/p>\n","protected":false},"featured_media":235945,"template":"","format":"standard","tags":[],"type-of-press":[184353519],"press-topic":[682165168],"years":[682166484],"class_list":["post-252009","press","type-press","status-publish","format-standard","has-post-thumbnail","hentry","type-of-press-declarations","press-topic-paris-2024","years-682166484"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9clararion du COC sur la d\u00e9cision du TAS\u00a0 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9clararion du COC sur la d\u00e9cision du TAS\u00a0 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"PARIS (31 juillet 2024) \u2013 Le Comit\u00e9 olympique canadien et Canada Soccer remercient le comit\u00e9 sp\u00e9cial du Tribunal Arbitral du...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T12:11:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/01\/WEB_COC_DECLARATION_183c5b.jpg?quality=100\" \/>\n\t<meta property=\"og:image:width\" content=\"5584\" \/>\n\t<meta property=\"og:image:height\" content=\"3143\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"psaltsman\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/declararion-du-coc-sur-la-decision-du-tas\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/declararion-du-coc-sur-la-decision-du-tas\\\/\",\"name\":\"D\u00e9clararion du COC sur la d\u00e9cision du TAS\u00a0 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/declararion-du-coc-sur-la-decision-du-tas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/declararion-du-coc-sur-la-decision-du-tas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/WEB_COC_DECLARATION_183c5b.jpg?quality=100\",\"datePublished\":\"2024-07-31T11:47:10+00:00\",\"dateModified\":\"2024-07-31T12:11:57+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/declararion-du-coc-sur-la-decision-du-tas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/declararion-du-coc-sur-la-decision-du-tas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/WEB_COC_DECLARATION_183c5b.jpg?quality=100\",\"contentUrl\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/WEB_COC_DECLARATION_183c5b.jpg?quality=100\",\"width\":5584,\"height\":3143},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9clararion du COC sur la d\u00e9cision du TAS\u00a0 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9clararion du COC sur la d\u00e9cision du TAS\u00a0 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"PARIS (31 juillet 2024) \u2013 Le Comit\u00e9 olympique canadien et Canada Soccer remercient le comit\u00e9 sp\u00e9cial du Tribunal Arbitral du...","og_url":"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","article_modified_time":"2024-07-31T12:11:57+00:00","og_image":[{"width":5584,"height":3143,"url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/01\/WEB_COC_DECLARATION_183c5b.jpg?quality=100","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"psaltsman"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/","url":"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/","name":"D\u00e9clararion du COC sur la d\u00e9cision du TAS\u00a0 - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/#primaryimage"},"image":{"@id":"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/#primaryimage"},"thumbnailUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/01\/WEB_COC_DECLARATION_183c5b.jpg?quality=100","datePublished":"2024-07-31T11:47:10+00:00","dateModified":"2024-07-31T12:11:57+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/develop.olympic.ca\/olympique\/presse\/declararion-du-coc-sur-la-decision-du-tas\/#primaryimage","url":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/01\/WEB_COC_DECLARATION_183c5b.jpg?quality=100","contentUrl":"https:\/\/develop.olympic.ca\/olympique\/wp-content\/uploads\/sites\/2\/2024\/01\/WEB_COC_DECLARATION_183c5b.jpg?quality=100","width":5584,"height":3143},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/252009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":2,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/252009\/revisions"}],"predecessor-version":[{"id":252019,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/252009\/revisions\/252019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media\/235945"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=252009"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=252009"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=252009"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=252009"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=252009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}