{"id":73007,"date":"2012-06-07T11:48:24","date_gmt":"2012-06-07T15:50:52","guid":{"rendered":"http:\/\/develop.olympic.ca\/?p=33122"},"modified":"2012-06-07T11:48:24","modified_gmt":"2012-06-07T15:50:52","slug":"general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne","status":"publish","type":"press","link":"https:\/\/develop.olympic.ca\/olympique\/presse\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\/","title":{"rendered":"General Mills Canada renouvelle son engagement envers l&#039;\u00c9quipe olympique canadienne"},"content":{"rendered":"<p><strong>TORONTO <\/strong>&#8211; Le Comit\u00e9 olympique canadien a annonc\u00e9 aujourd&rsquo;hui que General Mills Canada prolonge son partenariat en vigueur depuis une d\u00e9cennie avec l&rsquo;\u00c9quipe olympique canadienne pour une dur\u00e9e de quatre ans.<\/p>\n<p>\u00ab\u00a0En misant sur nos valeurs communes, General Mills Canada a su \u00eatre un partenaire de premier ordre pour l&rsquo;\u00c9quipe olympique canadienne au cours de la derni\u00e8re d\u00e9cennie, affirme Christopher Overholt, chef de la direction et secr\u00e9taire g\u00e9n\u00e9ral du Comit\u00e9 olympique canadien. Le renouvellement de notre partenariat visant \u00e0 soutenir les athl\u00e8tes est une nouvelle preuve de notre engagement envers un Canada plus fort et en sant\u00e9.\u00a0\u00bb<\/p>\n<p>Le renouvellement du partenariat repousse l&rsquo;\u00e9ch\u00e9ance de l&rsquo;entente existante de 2013 \u00e0 2016 et permet de continuer \u00e0 assurer un soutien essentiel aux athl\u00e8tes canadiens jusqu&rsquo;aux Jeux de Sotchi 2014, de Rio 2016 et au-del\u00e0.<\/p>\n<p>\u00ab\u00a0C&rsquo;est avec une immense fiert\u00e9 que General Mills Canada continue \u00e0 appuyer nos athl\u00e8tes et \u00e0 faire conna\u00eetre leur histoire aux Canadiens d&rsquo;un oc\u00e9an \u00e0 l&rsquo;autre, soutient Dave Homer, pr\u00e9sident, General Mills Canada. Notre partenariat est fructueux et il aidera \u00e0 inspirer une nouvelle g\u00e9n\u00e9ration de Canadiens plus forts et en meilleure sant\u00e9. Il s&rsquo;agit d&rsquo;une combinaison gagnante et d&rsquo;un investissement pour l&rsquo;ensemble du pays.\u00a0\u00bb<\/p>\n<p>Gr\u00e2ce \u00e0 leur campagne \u00ab\u00a0Encouragez nos athl\u00e8tes de tout votre c\u0153ur\u00a0\u00bb, General Mills Canada a jou\u00e9 un r\u00f4le cl\u00e9 dans l&rsquo;expression de l&rsquo;appui massif aux athl\u00e8tes canadiens pendant les Jeux olympiques d&rsquo;hiver de 2010 \u00e0 Vancouver, Jeux o\u00f9 le Canada a connu le plus de succ\u00e8s \u00e0 ce jour.<\/p>\n<p>\u00ab\u00a0Quel athl\u00e8te ne voudrait pas voir sa photo sur une bo\u00eete de Cheerios, se questionne Ken Perreira, double Olympien canadien. General Mills a donn\u00e9 un bon coup de main aux Canadiens en les aidant \u00e0 mieux conna\u00eetre leurs athl\u00e8tes. C&rsquo;est fantastique qu&rsquo;ils continuent \u00e0 nous soutenir.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Les entreprises partenaires jouent un r\u00f4le cl\u00e9 en aidant les athl\u00e8tes \u00e0 obtenir des ressources dont ils ont besoin pour r\u00e9aliser leur r\u00eave olympique, affirme Crispin Duenas, Olympien des Jeux de 2008. Nous devons tout donner afin d&rsquo;\u00eatre les meilleurs, et c&rsquo;est extraordinaire de voir un partenaire qui fait la m\u00eame chose.\u00a0\u00bb<\/p>\n<p><strong>AU SUJET DU COMIT\u00c9 OLYMPIQUE CANADIEN<\/strong><\/p>\n<p>Le Comit\u00e9 olympique canadien voit au succ\u00e8s de l&rsquo;\u00c9quipe olympique canadienne et \u00e0 l&rsquo;avancement des valeurs olympiques au Canada.<\/p>\n<p>Organisme ind\u00e9pendant financ\u00e9 principalement par des fonds priv\u00e9s, le Comit\u00e9 olympique canadien fournit aux athl\u00e8tes d&rsquo;\u00e9lite canadiens les ressources dont ils ont besoin pour \u00eatre tous les jours au meilleur de leur forme afin de tout donner.<\/p>\n<p>Fer de lance du Mouvement olympique au Canada, le Comit\u00e9 olympique canadien travaille avec les f\u00e9d\u00e9rations nationales de sport pour pr\u00e9parer l&rsquo;\u00e9quipe pour les Jeux olympiques, les Jeux olympiques de la jeunesse et les Jeux panam\u00e9ricains.<\/p>\n<p>En racontant l&rsquo;histoire de nos athl\u00e8tes, nous inspirons tous les Canadiens et Canadiennes par la force du sport\u00a0: 24 heures sur 24, 7 jours sur 7, 365 jours sur 365.<\/p>\n<p>&#8211; 30 &#8211;<\/p>\n<p><strong>Bureau de presse du Comit\u00e9 olympique canadien:<\/strong><br \/>\nJane Almeida<br \/>\nGestionnaire, Relations avec les m\u00e9dias<br \/>\nT\u00e9l. : 416-324-4120<br \/>\nCell. : 416-540-1788<br \/>\nCourriel :\u00a0<a href=\"mailto:jalmeida@olympic.ca\" target=\"_blank\">jalmeida@olympic.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORONTO &#8211; Le Comit\u00e9 olympique canadien a annonc\u00e9 aujourd&rsquo;hui que General Mills Canada prolonge son partenariat en vigueur depuis une&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","format":"standard","tags":[],"type-of-press":[496138],"press-topic":[],"years":[],"class_list":["post-73007","press","type-press","status-publish","format-standard","hentry","type-of-press-communiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>General Mills Canada renouvelle son engagement envers l&#039;\u00c9quipe olympique canadienne - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/presse\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"General Mills Canada renouvelle son engagement envers l&#039;\u00c9quipe olympique canadienne - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"TORONTO &#8211; Le Comit\u00e9 olympique canadien a annonc\u00e9 aujourd&rsquo;hui que General Mills Canada prolonge son partenariat en vigueur depuis une...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/presse\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\\\/\",\"name\":\"General Mills Canada renouvelle son engagement envers l&#039;\u00c9quipe olympique canadienne - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2012-06-07T15:50:52+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"General Mills Canada renouvelle son engagement envers l&#039;\u00c9quipe olympique canadienne - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/presse\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\/","og_locale":"fr_FR","og_type":"article","og_title":"General Mills Canada renouvelle son engagement envers l&#039;\u00c9quipe olympique canadienne - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"TORONTO &#8211; Le Comit\u00e9 olympique canadien a annonc\u00e9 aujourd&rsquo;hui que General Mills Canada prolonge son partenariat en vigueur depuis une...","og_url":"https:\/\/develop.olympic.ca\/olympique\/presse\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/presse\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\/","url":"https:\/\/develop.olympic.ca\/olympique\/presse\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\/","name":"General Mills Canada renouvelle son engagement envers l&#039;\u00c9quipe olympique canadienne - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"datePublished":"2012-06-07T15:50:52+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/presse\/general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne-general-mills-canada-renouvelle-son-engagement-envers-lequipe-olympique-canadienne\/"]}]},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":0,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73007\/revisions"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=73007"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=73007"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=73007"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=73007"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=73007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}