{"id":73018,"date":"2012-05-16T11:48:40","date_gmt":"2012-05-17T13:11:51","guid":{"rendered":"http:\/\/develop.olympic.ca\/?p=31471"},"modified":"2012-05-16T11:48:40","modified_gmt":"2012-05-17T13:11:51","slug":"le-diner-conference-avec-jacques-rogge-promet-detre-memorable","status":"publish","type":"press","link":"https:\/\/develop.olympic.ca\/olympique\/presse\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\/","title":{"rendered":"Le d\u00eener-conf\u00e9rence avec Jacques Rogge promet d&#039;\u00eatre m\u00e9morable"},"content":{"rendered":"<p><strong>QU\u00c9BEC<\/strong> &#8211; Les gens de Qu\u00e9bec ont eu aujourd&rsquo;hui un avant-go\u00fbt des immenses efforts d\u00e9ploy\u00e9s afin de pr\u00e9parer le d\u00eener-conf\u00e9rence du 22 mai prochain, dont le conf\u00e9rencier d&rsquo;honneur sera Jacques Rogge, pr\u00e9sident du Comit\u00e9 international olympique (CIO). C&rsquo;est dans le cadre de la semaine entourant le prestigieux Congr\u00e8s international SportAccord que M. Rogge sera pr\u00e9sent dans la capitale nationale accompagn\u00e9 de nombreux dirigeants du Comit\u00e9 international olympique. Le pr\u00e9sident du Comit\u00e9 olympique canadien, Marcel Aubut, a fourni quelques pr\u00e9cisions sur cette importante collecte de fonds visant \u00e0 soutenir les jeunes athl\u00e8tes qu\u00e9b\u00e9cois et canadiens de haute performance\u00a0:<\/p>\n<p>\u00ab\u00a0Les pr\u00e9paratifs sont au stade final et \u00e0 chaque jour qui passe, je suis de plus en plus motiv\u00e9 par la g\u00e9n\u00e9rosit\u00e9 et la d\u00e9termination de ceux qui ex\u00e9cutent cette t\u00e2che monumentale, a dit M.\u00a0Aubut. \u00a0Je suis particuli\u00e8rement fier de dire que le milieu des affaires du Qu\u00e9bec a combl\u00e9 mes plus grands espoirs en mati\u00e8re de solidarit\u00e9 pour cette cause louable.\u00a0\u00bb<\/p>\n<p>Seront donc r\u00e9unis lors de ce d\u00eener, 120 athl\u00e8tes canadiens, fiers gagnants de 33 m\u00e9dailles d&rsquo;or, 31 m\u00e9dailles d&rsquo;argent et 19 m\u00e9dailles de bronze aux Jeux olympiques. L&rsquo;ensemble des leaders du monde des affaires du Qu\u00e9bec et de l&rsquo;est du Canada feront aussi partie des 4 000 participants. Le pr\u00e9sident et chef de la direction de Bell Canada et BCE, George Cope, \u00a0a accept\u00e9 d&rsquo;agir comme pr\u00e9sident d&rsquo;honneur pour cet \u00e9v\u00e9nement d&rsquo;envergure.<\/p>\n<p>M. Aubut a donn\u00e9 quelques chiffres sur l&rsquo;\u00e9v\u00e9nement, notamment\u00a0:<\/p>\n<ul>\n<li>des mets d\u00e9licats pr\u00e9par\u00e9s avec\u00a0:<\/li>\n<ul>\n<li>650 kilos de viande ;<\/li>\n<li>175 kilos de fromage ;<\/li>\n<li>250 kilos de poissons, homards et fruits de mer ;<\/li>\n<li>425 kilos de l\u00e9gumes frais ;<\/li>\n<li>75 litres de sirop d&rsquo;\u00e9rable ;<\/li>\n<li>4\u00a0200 \u0153ufs de caille ;<\/li>\n<li>la chaleur de 24 fours et la fra\u00eecheur de quatre camions r\u00e9frig\u00e9r\u00e9s de 53 pieds ;<\/li>\n<li>les talents culinaires de 7 grands chefs et 120 cuisiniers et la dext\u00e9rit\u00e9 de 275 serveurs ;<\/li>\n<li>l&rsquo;aide et le soutien de plus de 200 b\u00e9n\u00e9voles ;<\/li>\n<li>le confort de 4\u00a0100 chaises et 410 tables dans un espace \u00e9quivalant \u00e0 pr\u00e8s de quatre terrains de football\u00a0;<\/li>\n<li>l&rsquo;utilisation de 14 300 verres, 24 600 ustensiles et 26 600 assiettes\u00a0;<\/li>\n<li>l&rsquo;installation de124 haut-parleurs, plus de 100 moteurs d&rsquo;accrochage, 750 pi. carr\u00e9 d&rsquo;\u00e9cran LED, 2000 pi. carr\u00e9 d&rsquo;\u00e9crans de projection, 9 projecteurs vid\u00e9o, 200 projecteurs motoris\u00e9s, 300 projecteurs conventionnels,100 projecteurs LED, 8 camions de 53 pi. d&rsquo;\u00e9quipement technique\u00a0;<\/li>\n<li>le tout n\u00e9cessitant 3 000 heures de travail sur le terrain et plus de 3 000 heures de production.<\/li>\n<\/ul>\n<\/ul>\n<p>Tous ces ingr\u00e9dients seront r\u00e9unis dans une production grandiose mettant en sc\u00e8ne des vedettes internationales bien ancr\u00e9es \u00e0 Qu\u00e9bec dont Stephan Moccio, Nadja et Mario Pelchat.\u00a0 Le volet artistique pr\u00e9sentera \u00e9galement un num\u00e9ro culturel orchestr\u00e9 par le Cirque du Soleil.<\/p>\n<p>Selon Claude Rousseau, co-pr\u00e9sident du comit\u00e9 organisateur de l&rsquo;\u00e9v\u00e9nement, \u00ab\u00a0pour Qu\u00e9bec, c&rsquo;est le plus important \u00e9v\u00e9nement du genre jamais r\u00e9alis\u00e9.\u00a0Le d\u00e9fi est \u00e9norme, mais l&rsquo;\u00e9quipe mise en place saura le relever et \u00e9crira l&rsquo;histoire. \u00bb<\/p>\n<p><strong>AU SUJET DU COMIT\u00c9 OLYMPIQUE CANADIEN<\/strong><\/p>\n<p>Le Comit\u00e9 olympique canadien voit au succ\u00e8s de l&rsquo;\u00c9quipe olympique canadienne et \u00e0 l&rsquo;avancement des valeurs olympiques au Canada.<\/p>\n<p>Organisme ind\u00e9pendant financ\u00e9 principalement par des fonds priv\u00e9s, le Comit\u00e9 olympique canadien fournit aux athl\u00e8tes d&rsquo;\u00e9lite canadiens les ressources dont ils ont besoin pour \u00eatre tous les jours au meilleur de leur forme afin de tout donner.<\/p>\n<p>Fer de lance du Mouvement olympique au Canada, le Comit\u00e9 olympique canadien travaille avec les f\u00e9d\u00e9rations nationales de sport pour pr\u00e9parer l&rsquo;\u00e9quipe pour les Jeux olympiques, les Jeux olympiques de la jeunesse et les Jeux panam\u00e9ricains.<\/p>\n<p>En racontant l&rsquo;histoire de nos athl\u00e8tes, nous inspirons tous les Canadiens et Canadiennes par la force du sport\u00a0: 24 heures sur 24, 7 jours sur 7, 365 jours sur 365.<\/p>\n<p>&#8211; 30 &#8211;<\/p>\n<p><strong>Bureau de presse du Comit\u00e9 olympique canadien\u00a0:<\/strong><\/p>\n<p>Jane Almeida<br \/>\nG\u00e9rante des relations avec les m\u00e9dias<br \/>\nT\u00e9l.: 416-324-4120<br \/>\nCell.: 416-540-1788<br \/>\nCourriel: <a href=\"mailto:jalmeida@olympic.ca\">jalmeida@olympic.ca<\/a><\/p>\n<p>Dimitri Soudas<br \/>\nExecutive Director Communications<br \/>\nT\u00e9l.: 416-324-4136<br \/>\nCell.: 289-388-6419<br \/>\nCourriel:\u00a0<a href=\"mailto:dsoudas@olympic.ca\">dsoudas@olympic.ca<\/a><\/p>\n<p>Pierre Morasse<br \/>\nT\u00e9l.\u00a0: 418-529-8441<br \/>\nCell.\u00a0: 418-922-2589\/<br \/>\nCourriel:\u00a0<a href=\"mailto:pierremorasse204@hotmail.com\">pierremorasse204@hotmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>QU\u00c9BEC &#8211; Les gens de Qu\u00e9bec ont eu aujourd&rsquo;hui un avant-go\u00fbt des immenses efforts d\u00e9ploy\u00e9s afin de pr\u00e9parer le d\u00eener-conf\u00e9rence&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","format":"standard","tags":[],"type-of-press":[496138],"press-topic":[],"years":[],"class_list":["post-73018","press","type-press","status-publish","format-standard","hentry","type-of-press-communiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le d\u00eener-conf\u00e9rence avec Jacques Rogge promet d&#039;\u00eatre m\u00e9morable - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/presse\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le d\u00eener-conf\u00e9rence avec Jacques Rogge promet d&#039;\u00eatre m\u00e9morable - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"QU\u00c9BEC &#8211; Les gens de Qu\u00e9bec ont eu aujourd&rsquo;hui un avant-go\u00fbt des immenses efforts d\u00e9ploy\u00e9s afin de pr\u00e9parer le d\u00eener-conf\u00e9rence...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/presse\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\\\/\",\"name\":\"Le d\u00eener-conf\u00e9rence avec Jacques Rogge promet d&#039;\u00eatre m\u00e9morable - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2012-05-17T13:11:51+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le d\u00eener-conf\u00e9rence avec Jacques Rogge promet d&#039;\u00eatre m\u00e9morable - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/presse\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\/","og_locale":"fr_FR","og_type":"article","og_title":"Le d\u00eener-conf\u00e9rence avec Jacques Rogge promet d&#039;\u00eatre m\u00e9morable - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"QU\u00c9BEC &#8211; Les gens de Qu\u00e9bec ont eu aujourd&rsquo;hui un avant-go\u00fbt des immenses efforts d\u00e9ploy\u00e9s afin de pr\u00e9parer le d\u00eener-conf\u00e9rence...","og_url":"https:\/\/develop.olympic.ca\/olympique\/presse\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/presse\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\/","url":"https:\/\/develop.olympic.ca\/olympique\/presse\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\/","name":"Le d\u00eener-conf\u00e9rence avec Jacques Rogge promet d&#039;\u00eatre m\u00e9morable - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"datePublished":"2012-05-17T13:11:51+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/presse\/le-diner-conference-avec-jacques-rogge-promet-detre-memorable\/"]}]},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":0,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73018\/revisions"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=73018"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=73018"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=73018"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=73018"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=73018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}