{"id":73028,"date":"2012-04-20T20:53:50","date_gmt":"2012-04-25T00:53:27","guid":{"rendered":"http:\/\/develop.olympic.ca\/?p=29494"},"modified":"2012-04-20T20:53:50","modified_gmt":"2012-04-25T00:53:27","slug":"lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens","status":"publish","type":"press","link":"https:\/\/develop.olympic.ca\/olympique\/presse\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\/","title":{"rendered":"L&#039;agence laur\u00e9ate de plusieurs prix fera la promotion des athl\u00e8tes olympiques canadiens"},"content":{"rendered":"<p>Les r\u00e9cits inspirants des meilleurs athl\u00e8tes du Canada et de leur parcours olympique parviendront aux Canadiens par l&rsquo;interm\u00e9diaire d&rsquo;une \u00e9quipe laur\u00e9ate de plusieurs prix. En effet, le Comit\u00e9 olympique canadien (COC) a annonc\u00e9 aujourd&rsquo;hui que l&rsquo;agence OMD Canada sera d\u00e9sormais son agence de planification m\u00e9diatique et d&rsquo;achats de m\u00e9dias; ce partenariat entre en vigueur imm\u00e9diatement.<\/p>\n<p>\u00ab OMD repr\u00e9sente r\u00e9ellement le choix parfait pour nous aider \u00e0 raconter les r\u00e9cits de nos athl\u00e8tes \u00bb, a d\u00e9clar\u00e9 Derek Kent, chef du marketing du Comit\u00e9 olympique canadien. \u00ab Sa passion pour l&rsquo;\u00c9quipe olympique canadienne, son exp\u00e9rience des marques sportives et sa feuille de route remarquable en font un excellent atout pour donner de l&rsquo;envergure au lancement de la campagne de notre marque pour Londres 2012.<\/p>\n<p>Un des plus importants sp\u00e9cialistes des communications m\u00e9diatiques d&rsquo;influence au monde, OMD est une division de Omnicom Group Inc. (NYSE : OMC), une entreprise chef de file mondiale dans les services de publicit\u00e9, de marketing et de communications. Les r\u00e9seaux de la marque Omnicom ainsi que les nombreuses agences sp\u00e9cialis\u00e9es offrent des services de publicit\u00e9, de planification m\u00e9diatique et d&rsquo;achats strat\u00e9giques de m\u00e9dias, de marketing num\u00e9rique et interactif, de marketing direct et promotionnel, de relations publiques et d&rsquo;autres services de communications sp\u00e9cialis\u00e9es \u00e0 plus de 5 000 clients dans plus de 100 pays. OMD est \u00e9galement une agence s\u0153ur de Proximity, agence attitr\u00e9e du Comit\u00e9 olympique canadien en mati\u00e8re de m\u00e9dias cr\u00e9atifs et num\u00e9riques.<\/p>\n<p>\u00ab L&rsquo;exp\u00e9rience d&rsquo;OMD dans le domaine des sports et avec les partenaires olympiques McDonald&rsquo;s et Visa nous donne les comp\u00e9tences n\u00e9cessaires pour d\u00e9velopper la marque de l&rsquo;\u00c9quipe olympique canadienne et la positionner comme elle se doit, c&rsquo;est-\u00e0-dire comme l&rsquo;une des marques de plus grande envergure au pays \u00bb, a d\u00e9clar\u00e9 Cathy Collier, directrice g\u00e9n\u00e9rale d&rsquo;OMD au Canada. \u00ab Un nombre important de partenaires m\u00e9diatiques sont emball\u00e9s et se sont engag\u00e9s \u00e0 aider \u00e0 raconter cette remarquable histoire d&rsquo;excellence canadienne. \u00bb<\/p>\n<p>OMD Canada, qui compte plus de 250 employ\u00e9s dans ses trois bureaux de Vancouver, de Toronto et de Montr\u00e9al, fournira une vue d&rsquo;ensemble strat\u00e9gique pour toutes les activit\u00e9s de planification et de n\u00e9gociation m\u00e9diatiques, mais aussi d&rsquo;achat de m\u00e9dias. Avec sa vaste exp\u00e9rience aupr\u00e8s des organismes sans but lucratif, OMD sera un partenaire cl\u00e9 qui verra \u00e0 faire entendre le message de la marque du COC aux Canadiens, et ce, sur plusieurs plateformes m\u00e9diatiques.<\/p>\n<p>Bureau de presse du Comit\u00e9<br \/>\nolympique canadien :<\/p>\n<p>Jane Almeida<br \/>\nG\u00e9rante des relations avec les m\u00e9dias<br \/>\nT\u00e9l.: 416-324-4120<br \/>\nCell.: 416-540-1788<br \/>\nCourriel: jalmeida@olympic.ca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9cits inspirants des meilleurs athl\u00e8tes du Canada et de leur parcours olympique parviendront aux Canadiens par l&rsquo;interm\u00e9diaire d&rsquo;une \u00e9quipe&#8230;<\/p>\n","protected":false},"featured_media":0,"template":"","format":"standard","tags":[],"type-of-press":[496138],"press-topic":[],"years":[],"class_list":["post-73028","press","type-press","status-publish","format-standard","hentry","type-of-press-communiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;agence laur\u00e9ate de plusieurs prix fera la promotion des athl\u00e8tes olympiques canadiens - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/presse\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;agence laur\u00e9ate de plusieurs prix fera la promotion des athl\u00e8tes olympiques canadiens - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:description\" content=\"Les r\u00e9cits inspirants des meilleurs athl\u00e8tes du Canada et de leur parcours olympique parviendront aux Canadiens par l&rsquo;interm\u00e9diaire d&rsquo;une \u00e9quipe...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/presse\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Mark Nadolny\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\\\/\",\"name\":\"L&#039;agence laur\u00e9ate de plusieurs prix fera la promotion des athl\u00e8tes olympiques canadiens - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"datePublished\":\"2012-04-25T00:53:27+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/presse\\\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L&#039;agence laur\u00e9ate de plusieurs prix fera la promotion des athl\u00e8tes olympiques canadiens - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/presse\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\/","og_locale":"fr_FR","og_type":"article","og_title":"L&#039;agence laur\u00e9ate de plusieurs prix fera la promotion des athl\u00e8tes olympiques canadiens - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_description":"Les r\u00e9cits inspirants des meilleurs athl\u00e8tes du Canada et de leur parcours olympique parviendront aux Canadiens par l&rsquo;interm\u00e9diaire d&rsquo;une \u00e9quipe...","og_url":"https:\/\/develop.olympic.ca\/olympique\/presse\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes","Written by":"Mark Nadolny"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/develop.olympic.ca\/olympique\/presse\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\/","url":"https:\/\/develop.olympic.ca\/olympique\/presse\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\/","name":"L&#039;agence laur\u00e9ate de plusieurs prix fera la promotion des athl\u00e8tes olympiques canadiens - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"datePublished":"2012-04-25T00:53:27+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/develop.olympic.ca\/olympique\/presse\/lagence-laureate-de-plusieurs-prix-fera-la-promotion-des-athletes-olympiques-canadiens\/"]}]},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/types\/press"}],"version-history":[{"count":0,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press\/73028\/revisions"}],"wp:attachment":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/media?parent=73028"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags?post=73028"},{"taxonomy":"type-of-press","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/type-of-press?post=73028"},{"taxonomy":"press-topic","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press-topic?post=73028"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/years?post=73028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}