{"id":682162494,"count":5,"description":"","link":"https:\/\/develop.olympic.ca\/olympique\/tag\/madison-mailey\/","name":"Madison Mailey","slug":"madison-mailey","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madison Mailey Archives - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/develop.olympic.ca\/olympique\/tag\/madison-mailey\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madison Mailey Archives - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/develop.olympic.ca\/olympique\/tag\/madison-mailey\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/tag\\\/madison-mailey\\\/\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/tag\\\/madison-mailey\\\/\",\"name\":\"Madison Mailey Archives - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/#website\",\"url\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/\",\"name\":\"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique\",\"description\":\"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/develop.olympic.ca\\\/olympique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madison Mailey Archives - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/develop.olympic.ca\/olympique\/tag\/madison-mailey\/","og_locale":"fr_FR","og_type":"article","og_title":"Madison Mailey Archives - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","og_url":"https:\/\/develop.olympic.ca\/olympique\/tag\/madison-mailey\/","og_site_name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/develop.olympic.ca\/olympique\/tag\/madison-mailey\/","url":"https:\/\/develop.olympic.ca\/olympique\/tag\/madison-mailey\/","name":"Madison Mailey Archives - \u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","isPartOf":{"@id":"https:\/\/develop.olympic.ca\/olympique\/#website"},"inLanguage":"fr-FR"},{"@type":"WebSite","@id":"https:\/\/develop.olympic.ca\/olympique\/#website","url":"https:\/\/develop.olympic.ca\/olympique\/","name":"\u00c9quipe Canada | Site officiel de l&#039;\u00e9quipe olympique","description":"Votre source pour l\u2019\u00c9quipe olympique canadienne. Retrouvez les r\u00e9cits, vid\u00e9os et photos des athl\u00e8tes canadiens, sports olympiques, Jeux olympiques de 2020 et bien plus!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/develop.olympic.ca\/olympique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags\/682162494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/posts?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/athletes?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/games?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/sports?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/videos?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/photos?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/press?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/resources?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/partners?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/positions?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/board-members?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/staff?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/olympic-initiatives?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/venues?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/one-team?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coc_hall_of_fame?tags=682162494"},{"href":"https:\/\/develop.olympic.ca\/olympique\/wp-json\/wp\/v2\/coc_webinars?tags=682162494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}